{"id":19762,"date":"2022-02-23T14:26:32","date_gmt":"2022-02-23T13:26:32","guid":{"rendered":"https:\/\/www.tadano.com\/benelux\/%term%\/%cat%\/ac-2-040-1\/"},"modified":"2026-06-24T07:34:38","modified_gmt":"2026-06-24T07:34:38","slug":"ac-2-040-1","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/benelux\/fr\/lifting-equipment\/all-terrain-cranes\/ac-2-040-1\/","title":{"rendered":"AC 2.040-1"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 0 50%; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/26841e667e485ad0\/hero-img_tadano_AC2040-1_cutout_front.png, https:\/\/mediahub.tadano.com\/m\/26841e667e485ad0\/hero_2x-img_tadano_AC2040-1_cutout_front.png 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/benelux\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/benelux\/fr\/\">Accueil<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">AC 2.040-1<\/h1>\n\n\n\n<p>Elle est dot\u00e9e d&rsquo;une fl\u00e8che enti\u00e8rement hydraulique qui peut se t\u00e9lescoper sous charge, ainsi que d&rsquo;extraordinaires capacit\u00e9s de grue-taxi assur\u00e9es par une conception qui minimise le poids.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/benelux\/fr\/ventes-services\/ventes\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Comparer les produits<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"fr\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"8\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"18\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">S\u00e9lectionner un produit<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">S\u00e9lectionner un produit<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"19762\" data-group=\"\">AC 2.040-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"22154\" data-group=\"\">AC 3.060-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"22131\" data-group=\"\">AC 4.070-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"28663\" data-group=\"\">AC 4.070HL-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"28917\" data-group=\"\">AC 4.070L-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4857\" data-group=\"\">AC 4.080-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"19359\" data-group=\"\">AC 5.130-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"19365\" data-group=\"\">AC 5.160-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"22148\" data-group=\"\">AC 5.250-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"28533\" data-group=\"\">AC 5.250L-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"19379\" data-group=\"\">AC 6.300-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4870\" data-group=\"\">AC 7.450-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"19340\" data-group=\"\">AC 8.500-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">S\u00e9lectionner un produit<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">S\u00e9lectionner un produit<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"19762\" data-group=\"\">AC 2.040-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"22154\" data-group=\"\">AC 3.060-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"22131\" data-group=\"\">AC 4.070-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"28663\" data-group=\"\">AC 4.070HL-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"28917\" data-group=\"\">AC 4.070L-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4857\" data-group=\"\">AC 4.080-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"19359\" data-group=\"\">AC 5.130-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"19365\" data-group=\"\">AC 5.160-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"22148\" data-group=\"\">AC 5.250-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"28533\" data-group=\"\">AC 5.250L-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"19379\" data-group=\"\">AC 6.300-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4870\" data-group=\"\">AC 7.450-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"19340\" data-group=\"\">AC 8.500-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                          <li>\n                <a href=\"#media\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M22.9683 1.53906H3.74603C2.22944 1.53906 1 2.7685 1 4.28509V23.5073C1 25.0239 2.22944 26.2533 3.74603 26.2533H22.9683C24.4848 26.2533 25.7143 25.0239 25.7143 23.5073V4.28509C25.7143 2.7685 24.4848 1.53906 22.9683 1.53906Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.55116 11.1483C9.68861 11.1483 10.6107 10.2263 10.6107 9.08882C10.6107 7.95138 9.68861 7.0293 8.55116 7.0293C7.41372 7.0293 6.49164 7.95138 6.49164 9.08882C6.49164 10.2263 7.41372 11.1483 8.55116 11.1483Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M25.715 18.0135L18.8499 11.1484L3.7467 26.2516\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Galerie<\/span>\n                <\/a>\n              <\/li>\n                                                  <li>\n                <a href=\"#360\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M13.3571 26.2514C20.1818 26.2514 25.7143 20.7189 25.7143 13.8943C25.7143 7.06959 20.1818 1.53711 13.3571 1.53711C6.53248 1.53711 1 7.06959 1 13.8943C1 20.7189 6.53248 26.2514 13.3571 26.2514Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M1 13.0703H25.7143\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M13.3572 1.53711C16.9632 4.92093 19.0125 9.31227 19.1238 13.8943C19.0125 18.4762 16.9632 22.8676 13.3572 26.2514C9.75114 22.8676 7.70185 18.4762 7.59048 13.8943C7.70185 9.31227 9.75114 4.92093 13.3572 1.53711V1.53711Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Vue 360\u00b0<\/span>\n                <\/a>\n              <\/li>\n            \n            \n                          <li class=\"scaled-metric\">\n                <a href=\"https:\/\/mediahub.tadano.com\/m\/2e6d559244a08912\/original\/doc_tadano_AC2040-1_datasheet_metric_en_de_fr_it_es_pt_ru.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Fiche<\/span>\n                <\/a>\n              <\/li>\n                                      <li class=\"scaled-imperial\">\n                <a href=\"https:\/\/mediahub.tadano.com\/m\/2418582c505a1671\/original\/doc_tadano_AC2040-1_datasheet_imperial_en.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Fiche<\/span>\n                <\/a>\n              <\/li>\n            \n            \n            \n                          <li>\n                <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/a-propos\/contactez-nous\/\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" version=\"1.1\" width=\"30\" height=\"30\" x=\"0\" y=\"0\" viewBox=\"0 0 440.965 440.965\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M341.508,36.207C305.582,12.648,263.549,0.116,220.587,0.154C98.892,0.271,0.235,98.832,0,220.527    c-0.046,42.838,12.652,84.721,36.48,120.32L0.853,426.18c-2.189,5.469,0.47,11.677,5.939,13.867c2.544,1.018,5.383,1.018,7.928,0    l85.333-35.627c101.679,66.676,238.158,38.3,304.834-63.379S443.187,102.883,341.508,36.207z M220.801,419.567    c-0.071,0-0.142,0-0.213,0v0.213h-0.001c-40.532-0.319-80.02-12.886-113.28-36.053c-1.754-1.224-3.835-1.893-5.973-1.92    c-1.338-0.264-2.715-0.264-4.053,0l-66.774,28.587l27.947-66.56c1.424-3.37,1.022-7.236-1.067-10.24    c-23.487-33.021-36.09-72.545-36.053-113.067C21.216,110.482,110.329,21.178,220.374,21.06    c110.044-0.118,199.349,88.995,199.467,199.04C419.959,330.145,330.846,419.449,220.801,419.567z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M288.514,162.764c-4.633-33.756-33.865-58.657-67.927-57.864c-36.795-0.118-66.752,29.552-66.987,66.347    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667c0.471-25.209,21.289-45.263,46.499-44.792    c25.21,0.471,45.263,21.289,44.792,46.499c-0.465,24.874-20.759,44.796-45.637,44.8c-5.891,0-10.667,4.776-10.667,10.667v47.787    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667v-37.973C267.907,233.206,293.543,199.416,288.514,162.764z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <circle cx=\"219.697\" cy=\"325.147\" r=\"11.675\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <\/g><\/svg>\n\n                  <\/div>\n                  <span class=\"text\">Demande d&rsquo;info<\/span>\n                <\/a>\n              <\/li>\n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n             \n\n\n<div class=\"container \">\n  <div class=\"product-details\">\n    <div class=\"product-specs\">\n\n      <div class=\"title\">\n        <div class=\"left\">\n                      <h2>Sp\u00e9cifications du produit<\/h2>\n                  <\/div>\n        <div class=\"right\">\n                        <div class=\"radio\">\n                                <label for=\"met\" class=\"met\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">M\u00e9trique<\/span>\n                <\/label>\n                <label for=\"imp\" class=\"imp\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Imp\u00e9rial<\/span>\n                <\/label>\n            <\/div>\n            \n\n        <\/div>\n      <\/div>\n\n      \n        <ul>\n\n                                  <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Capacit\u00e9 max. de la grue<\/strong>\n                          <span>40&nbsp;USt<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Longueur de fl\u00e8che principale<\/strong>\n                          <span>34.3&nbsp;ft &#8211; 115.5&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Rallonge de fl\u00e8che<\/strong>\n                          <span>29.5&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Hauteur de t\u00eate max.<\/strong>\n                          <span>154.2&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Contrepoids max.<\/strong>\n                          <span>14,300&nbsp;lb<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Bases de calage<\/strong>\n                          <span>21.2&nbsp;ft x 19.7&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Traction du c\u00e2ble du treuil<\/strong>\n                          <span>7,500&nbsp;lb<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">MAX Radius<\/strong>\n                          <span>125.0&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Dimensions<\/strong>\n                          <span>L:&nbsp;36.5&nbsp;ft W:&nbsp;8.4&nbsp;ft H:&nbsp;11.8&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Capacit\u00e9 max. de la grue<\/strong>\n                          <span>40&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Longueur de fl\u00e8che principale<\/strong>\n                          <span>10.5&nbsp;m &#8211; 35.2&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Rallonge de fl\u00e8che<\/strong>\n                          <span>9&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Hauteur de t\u00eate max.<\/strong>\n                          <span>47&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Contrepoids max.<\/strong>\n                          <span>6.5&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Bases de calage<\/strong>\n                          <span>6.45&nbsp;m x 6.00&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Traction du c\u00e2ble du treuil<\/strong>\n                          <span>3.4&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Rayon max.<\/strong>\n                          <span>38&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Dimensions<\/strong>\n                          <span>L:&nbsp;11.14&nbsp;m W:&nbsp;2.55&nbsp;m H:&nbsp;3.60&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Essieux<\/strong>\n                          <span>2<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Moteur<\/strong>\n                          <span>Cummins<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Entra\u00eenement<\/strong>\n                          <span>4&nbsp;x 2&nbsp;x 4&nbsp;( 4&nbsp;x 4&nbsp;x 4)<\/span>\n                        <\/li>\n                      \n        <\/ul>\n\n                  <style type=\"text\/css\">\n            @media screen and (min-width: 1360px) {\n              .hero-section .green-solutions {\n                display: block!important;\n              }\n            }\n          <\/style>\n        \n       \n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">description DU PRODUIT<\/h2>\n\n\n\n<p><strong><strong>Le d\u00e9but de quelque chose de grand<\/strong><\/strong>.<\/p>\n\n\n\n<p>Les grandes choses commencent souvent par de petites \u2013 tel est le r\u00f4le de l&rsquo;AC 2.040-1, premi\u00e8re grue d\u00e9velopp\u00e9e conjointement chez Tadano. La grue offre le meilleur des deux mondes, notamment gr\u00e2ce au syst\u00e8me de contr\u00f4le IC-1 Plus, qui permet \u00e0 la machine de toujours profiter de la capacit\u00e9 de levage maximale dont elle dispose, quelle que soit la configuration actuelle de ses stabilisateurs. Parmi les autres exemples, citons le E-Pack pour une utilisation de la grue sans \u00e9mission, le syst\u00e8me de cam\u00e9ra unique Surround View qui facilite le positionnement sur le site de travail et rend les d\u00e9placements plus s\u00fbrs, et Flex Base, un syst\u00e8me permettant aux stabilisateurs d&rsquo;\u00eatre \u00e9tendus \u00e0 n&rsquo;importe quel point de leur port\u00e9e. De plus, son exceptionnel ch\u00e2ssis lui conf\u00e8re non seulement une \u00e9norme capacit\u00e9 de franchissement de pentes et une bonne acc\u00e9l\u00e9ration, mais aussi un fonctionnement tr\u00e8s silencieux. Et pour rendre les choses encore plus pratiques, la grue reste dans la limite des 12 tonnes de charge par essieu, m\u00eame avec 1,1 tonne de contrepoids. Autre point fort : sa fl\u00e8che robuste, qui en fait l&rsquo;unit\u00e9 \u00e0 deux essieux la plus puissante du march\u00e9 dans les positions de fl\u00e8che raides. Avec la fl\u00e8che enti\u00e8rement d\u00e9ploy\u00e9e \u00e0 35,2 m\u00e8tres, elle peut soulever des charges allant jusqu&rsquo;\u00e0 7,6 tonnes dans un rayon de huit m\u00e8tres &#8211; ce qu&rsquo;aucune autre grue de cette cat\u00e9gorie ne peut faire.<\/p>\n\n\n\n<section class=\"product-360-view\" id=\"360\">\n\n      <script type=\"text\/javascript\">\n      const ThreeSixtyFrameCount = 31;\n      const ThreeSixtyImagePath = 'https:\/\/www.tadano.com\/benelux\/wp-content\/themes\/tadano\/assets\/dist\/images\/360-view\/AC2040-1\/360\/';\n    <\/script>\n\n    <div class=\"container\">\n      <div class=\"interactive-view\">\n        <h2>VUE 360\u00b0 INT\u00c9RACTIVE<\/h2>\n\n                  <div class=\"view-selector\">\n\n            <div data-view=\"view-exterior\" class=\"active\">Exterior<\/div>\n\n                          <div data-view=\"view-lower-cabin\">Lower cabin<\/div>\n            \n                          <div data-view=\"view-upper-cabin\">Upper cabin<\/div>\n            \n          <\/div>\n        \n        <div class=\"views-wrapper\">\n\n                      <div id=\"view-lower-cabin\" class=\"iframe\">\n              <iframe src=\"https:\/\/www.tadano.com\/\/wp-content\/themes\/tadano\/template-parts\/components\/cabin-views\/tadano_ac_lc\/index.htm\" frameborder=\"0\" allowfullscreen=\"\" allow=\"vr\"><\/iframe>\n            <\/div>\n          \n                      <div id=\"view-upper-cabin\" class=\"iframe\">\n              <iframe src=\"https:\/\/www.tadano.com\/\/wp-content\/themes\/tadano\/template-parts\/components\/cabin-views\/tadano_ac_uc\/index.htm\" frameborder=\"0\" allowfullscreen=\"\" allow=\"vr\"><\/iframe>\n            <\/div>\n          \n          <div id=\"view-exterior\" class=\"active\">\n            <div class=\"view-holder\">\n                          <\/div>\n            <div class=\"wrap-360\">\n              <div class=\"threesixty car\">\n                <div class=\"spinner\">\n                    <span style=\"opacity:0.2\">0%<\/span>\n                <\/div>\n                <ol class=\"threesixty_images\"><\/ol>\n              <\/div>\n            <\/div>\n            \n                      <\/div>\n\n        <\/div>\n          \n        \n      <\/div>\n    <\/div>\n\n    \n    <script>\n     \/\/ Target the view-selector divs\n     const selectors = document.querySelectorAll('.view-selector div');\n\n     \/\/ Add a 'click' event listener to all the selectors\n     selectors.forEach(selector => {\n          selector.addEventListener('click', function(event){\n               \/\/ Remove 'active' class from all selectors\n               selectors.forEach(selector => {\n                    selector.classList.remove('active');\n\n                    \/\/ Also remove 'active' class from all views,\n                    \/\/ But first check if the view actually exists\n                    let view = document.querySelector('#' + selector.dataset.view);\n                    if(view) {\n                        view.classList.remove('active');\n                    }\n               })\n\n               \/\/ Add 'active' class to the clicked selector\n               this.classList.add('active');\n\n               \/\/ Add 'active' class to the view corresponding to clicked selector\n               \/\/ After checking if the view actually exists\n               let view = document.querySelector('#' + this.dataset.view);\n               if(view) {\n                   view.classList.add('active');\n               }\n          })\n     });\n    <\/script>\n\n<\/section>\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Galerie m\u00e9dia<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/37d0dd8f3e7bf308\/gallery_full-img_tadano_AC2040-1_road.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/37d0dd8f3e7bf308\/gallery_thumb-img_tadano_AC2040-1_road.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/65018034a2aa0699\/gallery_full-img_tadano_AC2040-1_rollout.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/65018034a2aa0699\/gallery_thumb-img_tadano_AC2040-1_rollout.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/76c72e0f5bad04dd\/gallery_full-img_tadano_AC2040-1_incl-e-Pack_beauty_01.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/76c72e0f5bad04dd\/gallery_thumb-img_tadano_AC2040-1_incl-e-Pack_beauty_01.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n<div class=\"cta-block\">\n    <div class=\"container\">\n    <div class=\"left\">\n      <ul class=\"btn-list\">\n        <li><a href=\"https:\/\/www.tadano.com\/benelux\/fr\/a-propos\/contactez-nous\/\" class=\"btn btn-light\">Contactez-nous<\/a><\/li>\n      <\/ul>\n    <\/div>\n    <div class=\"right\">\n                          <ul class=\"btn-list\">\n                            \n                                  <li class=\"scaled-metric\"><a href=\"https:\/\/mediahub.tadano.com\/m\/2e6d559244a08912\/original\/doc_tadano_AC2040-1_datasheet_metric_en_de_fr_it_es_pt_ru.pdf\" class=\"btn btn-outline-white\">Fiche technique<\/a><\/li>\n                  <li class=\"scaled-imperial\"><a href=\"https:\/\/mediahub.tadano.com\/m\/2418582c505a1671\/original\/doc_tadano_AC2040-1_datasheet_imperial_en.pdf\" class=\"btn btn-outline-white\">Fiche technique<\/a><\/li>\n                              \n                              \n          <\/ul>\n            <\/div>\n  <\/div>\n<\/div>\n\n  <section class=\"tadano-advantage\">\n    <div class=\"bg-logo\" style=\"background-image: url(https:\/\/www.tadano.com\/benelux\/wp-content\/themes\/tadano\/assets\/dist\/images\/logo-min.svg);\"><\/div>\n    <div class=\"container\">\n      <div class=\"text-holder\">\n        <h2>L\u2019AVANTAGE TADANO<\/h2>\n        <p><p>La r\u00e9putation l\u00e9gendaire de Tadano en mati\u00e8re de qualit\u00e9 et d\u2019innovation explique notre position de leader dans le secteur du levage. Une ing\u00e9nierie d\u2019excellence et la qualit\u00e9 sup\u00e9rieure de la conception et des composants, associ\u00e9es \u00e0 un service de premier ordre, g\u00e9n\u00e8rent un taux de rendement sup\u00e9rieur et les co\u00fbts d\u2019exploitation fixes et variables les plus bas sur le march\u00e9 par rapport aux grues de marque concurrente.<\/p>\n<\/p>\n        <div class=\"wp-block-buttons\">\n          <div class=\"wp-block-button is-style-btn-outline-white\"><a href=\"https:\/\/www.tadano.com\/benelux\/fr\/a-propos\/\" class=\"wp-block-button__link\">En savoir plus<\/a><\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/section>\n\n\n\n  <section class=\"green-solutions related-products\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>Green Solutions<\/h2>\n      <\/div>\n      <div class=\"r-products\">\n      \n                <div class=\"r-product-single \">\n                                      <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/technologies\/carburants-diesel-de-substitution\/\">\n                                      <div class=\"img-holder\">\n                                              <div class=\"bg-stretch\" >\n                          <span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/img-thumb\/HVO.jpg, https:\/\/assets.onetadano.com\/celum_assets\/img-thumb-2x\/HVO.jpg 2x\"><\/span>\n                        <\/div>\n                                          <\/div>\n                    <div class=\"text-block\">\n                      <strong class=\"title\">HVO<\/strong>\n                    <\/div>\n                  <\/a>\n                <\/div>\n\n            \n                <div class=\"r-product-single \">\n                                      <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/technologies\/e-pack\/\">\n                                      <div class=\"img-holder\">\n                                              <div class=\"bg-stretch\" >\n                          <span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/img-thumb\/Tadano+E-Pack.jpg, https:\/\/assets.onetadano.com\/celum_assets\/img-thumb-2x\/Tadano+E-Pack.jpg 2x\"><\/span>\n                        <\/div>\n                                          <\/div>\n                    <div class=\"text-block\">\n                      <strong class=\"title\">e-PACK<\/strong>\n                    <\/div>\n                  <\/a>\n                <\/div>\n\n            \n                <div class=\"r-product-single \">\n                                      <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/technologies\/systeme-eco-mode\/\">\n                                      <div class=\"img-holder\">\n                                              <div class=\"bg-stretch\" >\n                          <span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/img-thumb\/AdobeStock_90649266.jpg, https:\/\/assets.onetadano.com\/celum_assets\/img-thumb-2x\/AdobeStock_90649266.jpg 2x\"><\/span>\n                        <\/div>\n                                          <\/div>\n                    <div class=\"text-block\">\n                      <strong class=\"title\">Eco-Mode<\/strong>\n                    <\/div>\n                  <\/a>\n                <\/div>\n\n            \n                <div class=\"r-product-single \">\n                                      <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/technologies\/start-stop\/\">\n                                      <div class=\"img-holder\">\n                                              <div class=\"bg-stretch\" >\n                          <span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/img-thumb\/START_STOP_Kabine_Motiv_10122021_B.jpg, https:\/\/assets.onetadano.com\/celum_assets\/img-thumb-2x\/START_STOP_Kabine_Motiv_10122021_B.jpg 2x\"><\/span>\n                        <\/div>\n                                          <\/div>\n                    <div class=\"text-block\">\n                      <strong class=\"title\">Start\/Stop<\/strong>\n                    <\/div>\n                  <\/a>\n                <\/div>\n\n                  <\/div>\n    <\/div>\n\n    <style type=\"text\/css\">\n      .green-solutions .r-product-single .img-holder .bg-stretch {\n        background-size: cover;\n      }\n      .green-solutions .r-product-single.no-link a {\n        cursor: default;\n      }\n      .green-solutions .r-product-single.no-link .title::before {\n        display: none;\n      }\n      .green-solutions .r-product-single.no-link:hover .text-block {\n          background: #fff;\n      }\n      @media screen and (min-width: 1360px) {\n        .hero-section .green-solutions {\n          display: block!important;\n        }\n      }\n      \n    <\/style>\n  <\/section>\n\n\n\n\n\n\n\n\n\n\n  <section class=\"related-products related-pages\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>Pages en relation<\/h2>\n      <\/div>\n\n      <div class='r-products'>\n                  \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/benelux\/fr\/lifting-equipment\/city-cranes\/ac-3-045-1-city\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/25047804cba4e93b\/img_thumb-img_tadano_AC3045CITY_Sideview.png, https:\/\/mediahub.tadano.com\/m\/25047804cba4e93b\/img_thumb_2x-img_tadano_AC3045CITY_Sideview.png 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">AC 3.045-1 City<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                                                \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/benelux\/fr\/lifting-equipment\/all-terrain-cranes\/ac-4-080-1\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/1c3f529e333f7382\/img_thumb-img_tadano_AC4080_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/1c3f529e333f7382\/img_thumb_2x-img_tadano_AC4080_cutout_side.png 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">AC 4.080-1<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                        <\/div>\n        \n    <\/div>\n  <\/section>\n  \n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>Actualit\u00e9s<\/h2>\n                        \n                  <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/a-propos\/news-list\/\" class=\"link-more\">EXPLORER TOUTES les News<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/news\/grues-pick-carry-rx-empattement-extensible-pour-des-performances-maximales\/\">\n                  <strong class=\"title\">Grues Pick &amp; Carry RX : empattement extensible pour des performances maximales<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Mai\/28\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/news\/nouvelle-ac-5-250l-2-pour-s-v-m-m\/\">\n                  <strong class=\"title\">Nouvelle AC 5.250L-2 pour S.V.M.M.<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Mai\/28\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/news\/premiere-livraison-dune-snake-26-en-france\/\">\n                  <strong class=\"title\">Premi\u00e8re livraison d&rsquo;une Snake 26 en France<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Mai\/19\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/news\/une-nouvelle-ac-7-450-1-pour-adekma\/\">\n                  <strong class=\"title\">Une nouvelle AC 7.450-1 pour ADEKMA<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">F\u00e9v\/24\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/news\/sotrama-recoit-la-premiere-tadano-ac-5-250l-2-en-france\/\">\n                  <strong class=\"title\">Sotrama recoit la premi\u00e8re Tadano AC 5.250L-2 en France<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Oct\/17\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/news\/la-nouvelle-octoplus-30\/\">\n                  <strong class=\"title\">La nouvelle Octoplus 30<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Sep\/25\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/news\/tadano-finalise-lacquisition-de-lactivite-systemes-de-transport-de-la-societe-ihi-transport-machinery\/\">\n                  <strong class=\"title\">Tadano finalise l\u2019acquisition de l\u2019activit\u00e9 Syst\u00e8mes de transport de la soci\u00e9t\u00e9 IHI Transport Machinery<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Juil\/01\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/news\/tadano-at-bauma-2025\/\">\n                  <strong class=\"title\">Tadano \u00e0 la bauma 2025<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Avr\/07\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/news\/the-new-ac-4-070hl-1-and-ac-5-120h-1-tadano-hybrid-cranes\/\">\n                  <strong class=\"title\">Les nouvelles grues hybrides Tadano AC 4.070HL-1 et AC 5.120H-1<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Avr\/07\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/benelux\/fr\/news\/pm-oil-steel-et-valla-a-la-bauma-2025\/\">\n                  <strong class=\"title\">PM, Oil &amp; Steel et Valla \u00e0 la bauma 2025<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Avr\/07\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  ","protected":false},"featured_media":0,"template":"","lifting-equipment":[18],"class_list":["post-19762","products","type-products","status-publish","hentry","lifting-equipment-all-terrain-cranes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AC 2.040-1 - Benelux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/benelux\/fr\/lifting-equipment\/all-terrain-cranes\/ac-2-040-1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AC 2.040-1 - Benelux\" \/>\n<meta property=\"og:description\" content=\"description DU PRODUIT Le d\u00e9but de quelque chose de grand. Les grandes choses commencent souvent par de petites \u2013 tel est le r\u00f4le de l&rsquo;AC 2.040-1, premi\u00e8re grue d\u00e9velopp\u00e9e conjointement chez Tadano. La grue offre le meilleur des deux mondes, notamment gr\u00e2ce au syst\u00e8me de contr\u00f4le IC-1 Plus, qui permet \u00e0 la machine de toujours [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/benelux\/fr\/lifting-equipment\/all-terrain-cranes\/ac-2-040-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Benelux\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T07:34:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/benelux\\\/fr\\\/lifting-equipment\\\/all-terrain-cranes\\\/ac-2-040-1\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/benelux\\\/fr\\\/lifting-equipment\\\/all-terrain-cranes\\\/ac-2-040-1\\\/\",\"name\":\"AC 2.040-1 - Benelux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/benelux\\\/en\\\/#website\"},\"datePublished\":\"2022-02-23T13:26:32+00:00\",\"dateModified\":\"2026-06-24T07:34:38+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/benelux\\\/fr\\\/lifting-equipment\\\/all-terrain-cranes\\\/ac-2-040-1\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/benelux\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/benelux\\\/en\\\/\",\"name\":\"Benelux\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/benelux\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AC 2.040-1 - Benelux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/benelux\/fr\/lifting-equipment\/all-terrain-cranes\/ac-2-040-1\/","og_locale":"fr_FR","og_type":"article","og_title":"AC 2.040-1 - Benelux","og_description":"description DU PRODUIT Le d\u00e9but de quelque chose de grand. Les grandes choses commencent souvent par de petites \u2013 tel est le r\u00f4le de l&rsquo;AC 2.040-1, premi\u00e8re grue d\u00e9velopp\u00e9e conjointement chez Tadano. La grue offre le meilleur des deux mondes, notamment gr\u00e2ce au syst\u00e8me de contr\u00f4le IC-1 Plus, qui permet \u00e0 la machine de toujours [&hellip;]","og_url":"https:\/\/www.tadano.com\/benelux\/fr\/lifting-equipment\/all-terrain-cranes\/ac-2-040-1\/","og_site_name":"Benelux","article_modified_time":"2026-06-24T07:34:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/benelux\/fr\/lifting-equipment\/all-terrain-cranes\/ac-2-040-1\/","url":"https:\/\/www.tadano.com\/benelux\/fr\/lifting-equipment\/all-terrain-cranes\/ac-2-040-1\/","name":"AC 2.040-1 - Benelux","isPartOf":{"@id":"https:\/\/www.tadano.com\/benelux\/en\/#website"},"datePublished":"2022-02-23T13:26:32+00:00","dateModified":"2026-06-24T07:34:38+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/benelux\/fr\/lifting-equipment\/all-terrain-cranes\/ac-2-040-1\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/benelux\/en\/#website","url":"https:\/\/www.tadano.com\/benelux\/en\/","name":"Benelux","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/benelux\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/benelux\/fr\/wp-json\/wp\/v2\/products\/19762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/benelux\/fr\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/benelux\/fr\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":2,"href":"https:\/\/www.tadano.com\/benelux\/fr\/wp-json\/wp\/v2\/products\/19762\/revisions"}],"predecessor-version":[{"id":31356,"href":"https:\/\/www.tadano.com\/benelux\/fr\/wp-json\/wp\/v2\/products\/19762\/revisions\/31356"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/benelux\/fr\/wp-json\/wp\/v2\/media?parent=19762"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/benelux\/fr\/wp-json\/wp\/v2\/lifting-equipment?post=19762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}