{"id":2626,"date":"2025-06-18T13:50:37","date_gmt":"2025-06-18T13:50:37","guid":{"rendered":"https:\/\/www.tadano.com\/eastern-europe-cis\/news\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\/"},"modified":"2025-06-18T13:50:38","modified_gmt":"2025-06-18T13:50:38","slug":"weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht","status":"publish","type":"news","link":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\/","title":{"rendered":"Weiland setzt auf Tadano AC 6.300-1 und AC 5.160-1 f\u00fcr wertvolle Fracht"},"content":{"rendered":"<section class=\"video-block\">\n  <div class=\"video-box\">\n        <a aria-labelledby=\"video-txt\" data-fancybox href=\"https:\/\/youtu.be\/74WIN3P2vmc\" class=\"video\">\n      <span class=\"play-btn\"><\/span>\n              <div class=\"bg-stretch\" >\n          <span data-srcset=\"https:\/\/img.youtube.com\/vi\/74WIN3P2vmc\/hqdefault.jpg, https:\/\/img.youtube.com\/vi\/74WIN3P2vmc\/hqdefault.jpg 2x\"><\/span>\n        <\/div>\n          <\/a>\n    <div class=\"video-txt\">\n                    <a href=\"https:\/\/youtu.be\/74WIN3P2vmc\" class=\"video-link\">Jetzt ansehen<\/a>\n          <\/div>\n  <\/div>\n<\/section>\n\n\n<p>Die \u201eGro\u00dfe Vegetative Skulptur\u201c wurde 1955 von Bernhard Heiliger \u2013 einem der bedeutendsten deutschen Bildhauer der Nachkriegszeit \u2013 geschaffen. Eine der f\u00fcnf originalgetreuen Kopien dieses Meisterwerks hatte ihren Platz bisher in einem Innenhof der Universit\u00e4tsklinik Heidelberg auf dem Campus Neuenheimer Feld. Da die umgebenden Geb\u00e4ude umfassend saniert werden sollten, musste die f\u00fcnf Tonnen schwere Skulptur aus Sicherheitsgr\u00fcnden jedoch ihren angestammten Standort verlassen und in den Skulpturenpark der Orthop\u00e4dischen Klinik am Universit\u00e4tsklinikum Heidelberg in Schlierbach umziehen. Beauftragte \u201eUmzugsfirma\u201c war die Weiland Kran &amp; Transport GmbH aus Lampertheim, die mit dem AC 5.160-1 und dem AC 6.300-1 dabei auf ein Tadano Duo setzte.<\/p>\n\n\n\n<p>\u201eF\u00fcr unseren brandneuen AC 6.300-1 war dieser Job seine Einsatzpremiere\u201c, berichtet Kranfahrer Alonso Domenico, der mit diesem Kran die Skulptur aus dem Innenhof herausheben sollte. Die Maschine kam einsatzf\u00e4hig mit 80m Hauptausleger inklusive Hakenflasche innerhalb der 12 Tonnen Achslastgrenze am Einsatzort an. Somit konnte der Genehmigungsaufwand auf ein Minimum reduziert werden. Aufgrund seiner transportoptimierten Gegengewichtskonfigurationen ist der AC 6.300-1 extrem flexibel und konnte von Weiland bei diesem Hub wirtschaftlich als 250-Tonner eingesetzt werden. Damit war er immer noch ausreichend stark, um die f\u00fcnf Tonnen schwere und knapp zwei Meter hohe Skulptur zu heben.<strong><\/strong><\/p>\n\n\n\n<p><strong>\u201eEin echtes Sahnest\u00fcckchen\u201c<\/strong><\/p>\n\n\n\n<p>\u201eDer AC 6.300-1 ist eine \u00fcberaus flexible Maschine, die man f\u00fcr solche H\u00fcbe sehr gut nutzen kann: Mit seinem 80-Meter-Hauptausleger und seiner soliden Traglasttabelle ist der AC 6.300-1 der perfekte Kran f\u00fcr effizientes Arbeiten in der H\u00f6he oder wenn gro\u00dfe Reichweite gefordert ist\u201c, erkl\u00e4rt Alonso Domenico. Und Reichweite war bei diesem Job durchaus gefragt: Denn die gro\u00dfe Herausforderung bei diesem Job war die Entfernung, \u00fcber die der Hub zu erfolgen hatte: Da sich die Skulptur wie erw\u00e4hnt in einem Innenhof befand, musste der AC 6.300-1 die inklusive Fundament und sch\u00fctzender Holzverkleidung rund f\u00fcnf Tonnen schwere Last bei \u00fcber 40 Meter Ausladung mittels Einweisern blind \u00fcber die 8 Meter hohe Geb\u00e4udekante heben \u2013 und das gelang dem eingespielten Weiland Team mit ihrem AC 6.300-1 wie erwartet v\u00f6llig problemlos: \u201eVon der Bedienung und Steuerung her entpuppte sich der AC 6.300-1 bei diesem Einsatz als echtes Sahnest\u00fcckchen. Er hat richtig gut funktioniert \u2013 so wie es sein soll\u201c, lobt Alonso Domenico den Kran. Wie geplant konnte er die Skulptur aus dem Innenhof \u00fcber die Geb\u00e4uded\u00e4cher hinwegheben und hinter einem bereitstehenden Transport-LKW hochkant stehend absetzen. Anschlie\u00dfend wurde die Skulptur auf dem Boden in liegende Position gebracht und auf die Ladefl\u00e4che des LKWs gehoben.<\/p>\n\n\n\n<p><strong>Einhub am neuen Standort mit AC 5.160-1 in Spezial-Ausf\u00fchrung<\/strong><\/p>\n\n\n\n<p>Dieser brachte die Skulptur nach Schlierbach in den Skulpturenpark der Orthop\u00e4dischen Universit\u00e4tsklinik Heidelberg. Dort wurde die Plastik bereits von Weiland Kranfahrer Thomas Eisenberg mit seinem ganz speziellen Tadano AC 5.160-1 erwartet. Denn dieser verf\u00fcgt \u00fcber eine individuelle Ballastierung, mit der Tadano den Kran auf Wunsch von Weiland ausgestattet hat: Sie erm\u00f6glicht es, den 5-Achser als Taxi-Kran mit 8,5 Tonnen Gegengewicht bei Einhaltung der 12-Tonnen-Achslast einzusetzen. \u201eDas war f\u00fcr diesen Job einfach perfekt, weil der AC 5.160-1 mit dem Teilballast vollkommen ausreichend f\u00fcr das Lastgewicht und die Ausladung konfigurierbar war\u201c, erkl\u00e4rt Thomas Eisenberg.<\/p>\n\n\n\n<p>Und auch sonst wei\u00df er nur Gutes \u00fcber seinen AC 5.160-1 zu berichten: \u201eDer Kran ist sehr feinf\u00fchlig, es l\u00e4sst sich alles sehr gut ein- und aussteuern und das Fahrgef\u00fchl ist bei Tadano ohnehin extrem gut,\u201c f\u00fchrt der routinierte Kranfahrer aus, f\u00fcr den dieser Einsatz auch wegen der perfekten Wetterverh\u00e4ltnisse ohne Wind ein perfekter Arbeitstag war: Er konnte die Skulptur ganz entspannt mit seinem AC 5.160-1 vom LKW abheben, mit einer Ausladung von 28 Metern \u00fcber die Aushubstelle f\u00fcr das Fundament schwenken und dort punktgenau ablassen.<\/p>\n\n\n\n<p><strong>Umzug an einem Tag erledigt<\/strong><\/p>\n\n\n\n<p>Insgesamt dauerte der Einsatz 8 Stunden: von morgens 6 Uhr bis nachmittags 13 Uhr \u2013 und war damit wie geplant an einem einzigen Tag erledigt. Entsprechend zufrieden zeigte sich auch Uwe Behrendt, Projektleiter Verm\u00f6gen und Bau des Landes Baden-W\u00fcrttemberg: \u201eEs hat alles reibungslos funktioniert \u2013 so wie immer, wenn die Firma Weiland bei uns einen Job zu erledigen hat.\u201c<\/p>\n","protected":false},"featured_media":0,"parent":0,"template":"","news_topics":[19],"class_list":["post-2626","news","type-news","status-publish","hentry","news_topics-job-story"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weiland setzt auf Tadano AC 6.300-1 und AC 5.160-1 f\u00fcr wertvolle Fracht<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weiland setzt auf Tadano AC 6.300-1 und AC 5.160-1 f\u00fcr wertvolle Fracht\" \/>\n<meta property=\"og:description\" content=\"Die \u201eGro\u00dfe Vegetative Skulptur\u201c wurde 1955 von Bernhard Heiliger \u2013 einem der bedeutendsten deutschen Bildhauer der Nachkriegszeit \u2013 geschaffen. Eine der f\u00fcnf originalgetreuen Kopien dieses Meisterwerks hatte ihren Platz bisher in einem Innenhof der Universit\u00e4tsklinik Heidelberg auf dem Campus Neuenheimer Feld. Da die umgebenden Geb\u00e4ude umfassend saniert werden sollten, musste die f\u00fcnf Tonnen schwere Skulptur [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\/\" \/>\n<meta property=\"og:site_name\" content=\"Eastern Europe &amp; CIS\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T13:50:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\\\/\",\"name\":\"Weiland setzt auf Tadano AC 6.300-1 und AC 5.160-1 f\u00fcr wertvolle Fracht\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/en\\\/#website\"},\"datePublished\":\"2025-06-18T13:50:37+00:00\",\"dateModified\":\"2025-06-18T13:50:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weiland setzt auf Tadano AC 6.300-1 und AC 5.160-1 f\u00fcr wertvolle Fracht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/en\\\/\",\"name\":\"Eastern Europe &amp; CIS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weiland setzt auf Tadano AC 6.300-1 und AC 5.160-1 f\u00fcr wertvolle Fracht","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\/","og_locale":"de_DE","og_type":"article","og_title":"Weiland setzt auf Tadano AC 6.300-1 und AC 5.160-1 f\u00fcr wertvolle Fracht","og_description":"Die \u201eGro\u00dfe Vegetative Skulptur\u201c wurde 1955 von Bernhard Heiliger \u2013 einem der bedeutendsten deutschen Bildhauer der Nachkriegszeit \u2013 geschaffen. Eine der f\u00fcnf originalgetreuen Kopien dieses Meisterwerks hatte ihren Platz bisher in einem Innenhof der Universit\u00e4tsklinik Heidelberg auf dem Campus Neuenheimer Feld. Da die umgebenden Geb\u00e4ude umfassend saniert werden sollten, musste die f\u00fcnf Tonnen schwere Skulptur [&hellip;]","og_url":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\/","og_site_name":"Eastern Europe &amp; CIS","article_modified_time":"2025-06-18T13:50:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\/","url":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\/","name":"Weiland setzt auf Tadano AC 6.300-1 und AC 5.160-1 f\u00fcr wertvolle Fracht","isPartOf":{"@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/en\/#website"},"datePublished":"2025-06-18T13:50:37+00:00","dateModified":"2025-06-18T13:50:38+00:00","breadcrumb":{"@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/weiland-setzt-auf-tadano-ac-6-300-1-und-ac-5-160-1-fuer-wertvolle-fracht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/"},{"@type":"ListItem","position":2,"name":"Weiland setzt auf Tadano AC 6.300-1 und AC 5.160-1 f\u00fcr wertvolle Fracht"}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/en\/#website","url":"https:\/\/www.tadano.com\/eastern-europe-cis\/en\/","name":"Eastern Europe &amp; CIS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/eastern-europe-cis\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/news\/2626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/news\/2626\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/media?parent=2626"}],"wp:term":[{"taxonomy":"news_topics","embeddable":true,"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/news_topics?post=2626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}