{"id":2723,"date":"2025-10-22T16:16:37","date_gmt":"2025-10-22T14:16:37","guid":{"rendered":"https:\/\/www.tadano.com\/eastern-europe-cis\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/"},"modified":"2025-10-22T16:16:37","modified_gmt":"2025-10-22T14:16:37","slug":"mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1","status":"publish","type":"news","link":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/","title":{"rendered":"Mammoet meistert Einsatz in schwindelerregender H\u00f6he mit Tadano CC 38.650-1"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mediahub.tadano.com\/m\/4d037d30cd3fd66d\/original\/img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p><strong>Die drei Rabobank Logos waren seit 2009 fester Bestandteil des 185 Meter hohen Aussichtsturms Euromast im Rotterdamer Floriadepark. Nachdem der Werbevertrag zwischen der Bank und Euromast 2025 jedoch ausgelaufen war, sollten die acht Meter hohen Logos aus einer H\u00f6he von 174 Metern wieder entfernt und sicher zur\u00fcck auf den Boden gebracht werden. Beauftragt mit dieser anspruchsvollen Mission wurde der Krandienstleister Mammoet, der dabei auf seinen Tadano CC 38.650-1 Gittermast-Raupenkran setzte. Auftraggeber war die Licht en Reclame Consultants BV.<\/strong><\/p>\n\n\n\n<p>\u201eWir haben uns bei diesem nicht allt\u00e4glichen Job aus zwei Gr\u00fcnden f\u00fcr den CC 38.650-1 entschieden: Zum einen, weil er die ben\u00f6tigte H\u00f6he von 174 Metern problemlos erreichen kann und zum anderen, weil er dank seiner kompakten Bauweise unter den beengten Platzverh\u00e4ltnissen alle erforderlichen Man\u00f6ver ausf\u00fchren konnte\u201c, erkl\u00e4rt Stefan Plugge, Projektmanager bei Mammoet Nederland.<\/p>\n\n\n\n<p>F\u00fcr den Transport des CC 38.650-1 von der nur wenige Kilometer entfernten Mammoet-Niederlassung in Schiedam ben\u00f6tigte das Team insgesamt 38 Transporte. Allerdings mussten Ausleger und Verl\u00e4ngerung bereits in Schiedam vormontiert werden, da der Platz auf der Baustelle hierf\u00fcr nicht ausreichte. Aus diesem Grund musste auch der Hilfskran vor dem CC 38.650-1 platziert werden und nicht, wie \u00fcblich, neben dem Raupenkran.<\/p>\n\n\n\n<p><strong>Just-in-time-Lieferung der Kranbauteile<\/strong><\/p>\n\n\n\n<p>Die Enge vor Ort und der nicht minder enge Zeitplan erforderten eine akribische Materiallogistik, da es im gesamten Baustellenbereich keinerlei Abstellm\u00f6glichkeiten f\u00fcr die Kranbauteile gab, sodass alles just in time geliefert werden musste \u2013 was f\u00fcr die Kranprofis von Mammoet jedoch kein sonderlich gro\u00dfes Problem darstellte. Dank der Routine der f\u00fcnf Monteure war der Aufbau des Krans daher auch nach nur vier Tagen erledigt. Mit einer Ausnahme: Aufgrund des starken Windes konnte der Ausleger erst am f\u00fcnften Tag aufgerichtet werden. Hierf\u00fcr wurde der CC 38.650-1 in SWSL 96-96 Konfiguration mit 250 Tonnen Gegengewicht ger\u00fcstet. F\u00fcr die H\u00fcbe selbst konnte der Kran jedoch auf den Superlift verzichten, da die Logos \u201elediglich\u201c jeweils 1,8 Tonnen auf die Waage brachten.<\/p>\n\n\n\n<p><strong>Pr\u00e4zise Rangierarbeit zwischen Baum und Laterne<\/strong><\/p>\n\n\n\n<p>Leicht waren die H\u00fcbe trotz des relativ geringen Gewichts der drei Logos allerdings nicht. Denn das Mammoet-Team sah sich vor Ort mit zwei Hindernissen konfrontiert: einem Baum und einem Laternenpfahl, die beide nicht entfernt werden konnten. Sie schr\u00e4nkten den Schwenkradius ganz erheblich ein: \u201eWeil es keine einzige Kranposition gab, in der wir von den Aufnahmepunkten der Lasten zu den Absetzpunkten bei einem Arbeitsradius von 45 Metern schwenken konnten, musste der Kran immer wieder zwischen Schwenken und Fahren wechseln\u201c, erkl\u00e4r Lex Bosman, Supervisor. Dank der ausgesprochen guten Man\u00f6vrierf\u00e4higkeit des CC 38.650-1 lie\u00df sich der Kran dabei zwischen Baum und Laternenpfahl jedoch so pr\u00e4zise hin- und her rangieren, dass er die beiden Hindernisse zu keiner Zeit touchierte.<\/p>\n\n\n\n<p><strong>Job zur Zufriedenheit aller erledigt<\/strong><\/p>\n\n\n\n<p>So ist es dem Team im perfekten Zusammenspiel von Mensch und Maschine gelungen, innerhalb des zur Verf\u00fcgung stehenden Zeitfensters von 6:00 Uhr bis 10:00 Uhr alle drei Rabobank-Logos sicher zu entfernen und den Euromast wieder p\u00fcnktlich f\u00fcr den regul\u00e4ren Publikumsverkehr freizugeben. Und nach vier Tagen Kran-Abbau war der ganze \u201eSpuk\u201c vor dem Euromast dann auch schon wieder vorbei und der Job zur vollsten Zufriedenheit aller Beteiligten erledigt. Die Stellen, an denen zuvor die Rabobank-Logos prangten, sind zurzeit \u00fcbrigens noch frei \u2013 falls demn\u00e4chst die Logos eines neuen Werbepartners zu montieren sein sollten, wei\u00df man in Rotterdam jedenfalls schon jetzt, wer das kann.<\/p>\n\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Mediengalerie<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/6b9c249119665105\/gallery_full-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/6b9c249119665105\/gallery_thumb-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/103481196091c74d\/gallery_full-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/103481196091c74d\/gallery_thumb-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/3e2fe88de37000f\/gallery_full-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/3e2fe88de37000f\/gallery_thumb-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/32147f41085e11d2\/gallery_full-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/32147f41085e11d2\/gallery_thumb-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/469560459c6f0428\/gallery_full-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/469560459c6f0428\/gallery_thumb-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/5b87ac2298eef93e\/gallery_full-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/5b87ac2298eef93e\/gallery_thumb-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/7c151b2dad30d620\/gallery_full-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/7c151b2dad30d620\/gallery_thumb-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/4d037d30cd3fd66d\/gallery_full-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/4d037d30cd3fd66d\/gallery_thumb-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/6c6e1b75c4e19f44\/gallery_full-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/6c6e1b75c4e19f44\/gallery_thumb-img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>","protected":false},"featured_media":0,"parent":0,"template":"","news_topics":[19],"class_list":["post-2723","news","type-news","status-publish","hentry","news_topics-job-story"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mammoet meistert Einsatz in schwindelerregender H\u00f6he mit Tadano CC 38.650-1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mammoet meistert Einsatz in schwindelerregender H\u00f6he mit Tadano CC 38.650-1\" \/>\n<meta property=\"og:description\" content=\"Die drei Rabobank Logos waren seit 2009 fester Bestandteil des 185 Meter hohen Aussichtsturms Euromast im Rotterdamer Floriadepark. Nachdem der Werbevertrag zwischen der Bank und Euromast 2025 jedoch ausgelaufen war, sollten die acht Meter hohen Logos aus einer H\u00f6he von 174 Metern wieder entfernt und sicher zur\u00fcck auf den Boden gebracht werden. Beauftragt mit dieser [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Eastern Europe &amp; CIS\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediahub.tadano.com\/m\/4d037d30cd3fd66d\/original\/img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\\\/\",\"name\":\"Mammoet meistert Einsatz in schwindelerregender H\u00f6he mit Tadano CC 38.650-1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediahub.tadano.com\\\/m\\\/4d037d30cd3fd66d\\\/original\\\/img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\",\"datePublished\":\"2025-10-22T14:16:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediahub.tadano.com\\\/m\\\/4d037d30cd3fd66d\\\/original\\\/img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\",\"contentUrl\":\"https:\\\/\\\/mediahub.tadano.com\\\/m\\\/4d037d30cd3fd66d\\\/original\\\/img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mammoet meistert Einsatz in schwindelerregender H\u00f6he mit Tadano CC 38.650-1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/en\\\/\",\"name\":\"Eastern Europe &amp; CIS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mammoet meistert Einsatz in schwindelerregender H\u00f6he mit Tadano CC 38.650-1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/","og_locale":"de_DE","og_type":"article","og_title":"Mammoet meistert Einsatz in schwindelerregender H\u00f6he mit Tadano CC 38.650-1","og_description":"Die drei Rabobank Logos waren seit 2009 fester Bestandteil des 185 Meter hohen Aussichtsturms Euromast im Rotterdamer Floriadepark. Nachdem der Werbevertrag zwischen der Bank und Euromast 2025 jedoch ausgelaufen war, sollten die acht Meter hohen Logos aus einer H\u00f6he von 174 Metern wieder entfernt und sicher zur\u00fcck auf den Boden gebracht werden. Beauftragt mit dieser [&hellip;]","og_url":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/","og_site_name":"Eastern Europe &amp; CIS","og_image":[{"url":"https:\/\/mediahub.tadano.com\/m\/4d037d30cd3fd66d\/original\/img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/","url":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/","name":"Mammoet meistert Einsatz in schwindelerregender H\u00f6he mit Tadano CC 38.650-1","isPartOf":{"@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/#primaryimage"},"image":{"@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/#primaryimage"},"thumbnailUrl":"https:\/\/mediahub.tadano.com\/m\/4d037d30cd3fd66d\/original\/img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg","datePublished":"2025-10-22T14:16:37+00:00","breadcrumb":{"@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/#primaryimage","url":"https:\/\/mediahub.tadano.com\/m\/4d037d30cd3fd66d\/original\/img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg","contentUrl":"https:\/\/mediahub.tadano.com\/m\/4d037d30cd3fd66d\/original\/img_tadano_Mammoet_CC-38-650-1_Job-Story.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/mammoet-meistert-einsatz-in-schwindelerregender-hohe-mit-tadano-cc-38-650-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/"},{"@type":"ListItem","position":2,"name":"Mammoet meistert Einsatz in schwindelerregender H\u00f6he mit Tadano CC 38.650-1"}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/en\/#website","url":"https:\/\/www.tadano.com\/eastern-europe-cis\/en\/","name":"Eastern Europe &amp; CIS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/eastern-europe-cis\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/news\/2723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/news\/2723\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/media?parent=2723"}],"wp:term":[{"taxonomy":"news_topics","embeddable":true,"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/news_topics?post=2723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}