{"id":2730,"date":"2025-10-29T15:06:18","date_gmt":"2025-10-29T14:06:18","guid":{"rendered":"https:\/\/www.tadano.com\/eastern-europe-cis\/news\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\/"},"modified":"2025-10-29T15:06:18","modified_gmt":"2025-10-29T14:06:18","slug":"san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru","status":"publish","type":"news","link":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\/","title":{"rendered":"San Lorenzo und Tadano meistern erfolgreichen Ersteinsatz des CC 38.650-1 in Peru"},"content":{"rendered":"<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Mediengalerie<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/1357cf4d70b6a412\/gallery_full-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.JPG\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/1357cf4d70b6a412\/gallery_thumb-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.JPG);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/7fcc6c96c7da10ee\/gallery_full-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/7fcc6c96c7da10ee\/gallery_thumb-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/1a30c7e4c3809332\/gallery_full-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.JPG\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/1a30c7e4c3809332\/gallery_thumb-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.JPG);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/5b26eb3ef922b72e\/gallery_full-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/5b26eb3ef922b72e\/gallery_thumb-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/66356b4372c81a17\/gallery_full-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/66356b4372c81a17\/gallery_thumb-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/6b4f6fa0a51e4031\/gallery_full-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/6b4f6fa0a51e4031\/gallery_thumb-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/5bc7034dca1dba59\/gallery_full-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/5bc7034dca1dba59\/gallery_thumb-img_Tadano_Job-Story_San-Lorenzo_CC-38-650-1.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n\n<p><strong>Br\u00fctende Hitze am Tag, eisige K\u00e4lte in der Nacht \u2013 mit diesen rauen Wetterbedingungen sahen sich das vierk\u00f6pfige Tadano-Team und der CC 38.650-1 Gittermastraupenkran in der peruanischen Kupfermine Cerro Verde konfrontiert. Der brandneue Kran des peruanischen Krandienstleister San Lorenzo sollte dort ein 247 Tonnen schweres Teilst\u00fcck f\u00fcr ein F\u00f6rderband errichten, das Kies und Gestein vom Boden der Mine nach oben transportiert. Aufbau, Inbetriebnahme und \u00dcbergabe des Krans \u00fcbernahm das Tadano Team ebenso wie die Schulung der San Lorenzo Mitarbeiter zum Bedienen ihres neuen CC 38.650-1.<\/strong><\/p>\n\n\n\n<p>\u201eWir haben uns bei diesem strapazi\u00f6sen Einsatz f\u00fcr den vielseitigen CC 38.650-1 entschieden, weil er eine sehr starke und vor allem robuste Maschine ist, die den verschlei\u00dfintensiven Bedingungen in solch einer Mine auf Dauer standhalten kann. Das hat auch die peruanische T\u00dcV-Beh\u00f6rde best\u00e4tigt, die den Tadano CC 38.650-1 als uneingeschr\u00e4nkt einsatzf\u00e4hig f\u00fcr alle Minen in S\u00fcdamerika freigegeben hat. Zudem lie\u00df sich der Kran dank seiner konsequenten Transportoptimierung vergleichsweise einfach auf die schwer zug\u00e4ngliche Baustelle verbringen\u201c, erl\u00e4utert S\u00f6nke Eichhorn von der Technischen Schulung bei Tadano, der f\u00fcr diesen Job eigens aus Zweibr\u00fccken angereist war.<\/p>\n\n\n\n<p>Gemeinsam mit seinen Tadano Kollegen Domagoj Bozic, Jiar Solis und Leandro Henrique Ribeiro Oliveira sollte er daf\u00fcr sorgen, dass der Kran innerhalb von sechs Wochen in der Konfiguration SSL_1 mit 84 Meter Hauptausleger, Vario SL-System, Doppelhakenflasche, 225 Tonnen Gegengewicht und 245 Tonnen SL-Gegengewicht aufgebaut in der Mine steht. \u201e\u00dcblicherweise ist der CC 38.650-1 nat\u00fcrlich in wenigen Tagen aufgebaut. Wir haben diesen Job jedoch als gemeinsamen Erst-Aufbau mit dem Kunden inklusive Schulung f\u00fcr das San&nbsp;Lorenzo-Team und unsere Mitarbeiter genutzt\u201c, erkl\u00e4rt S\u00f6nke Eichhorn die ungew\u00f6hnlich lange Aufbauzeit.<\/p>\n\n\n\n<p><strong>Gesundheits-Check und Sicherheitseinweisung f\u00fcr das Team<\/strong><\/p>\n\n\n\n<p>Doch erst einmal musste der Kran von Deutschland nach Peru verschifft werden. Im Hafen von Lima wurde er zun\u00e4chst auf das San Lorenzo Werksgel\u00e4nde in Arequipa gebracht und von dort mit 28 LKWs zur Cerro Verde Mine auf 2700 Meter H\u00f6he transportiert. Das Tadano Team musste zuvor allerdings noch einen Zwischenstopp im Krankenhaus des Minenbetreibers Cerro Verde einlegen. \u201eHier wurden wir medizinisch untersucht, um sicherzustellen, dass wir gesund und k\u00f6rperlich fit genug f\u00fcr die anstrengende Arbeit in dieser rauen Umgebung sind\u201c, berichtet S\u00f6nke Eichhorn. Nachdem alle die Untersuchung bestanden hatten, wurde das Team im Cerro Verde Schulungszentrum \u00fcber die Arbeits- und Sicherheitsvorschriften in der Mine informiert. \u201eDie Arbeit dort ist nicht ungef\u00e4hrlich und die Vorschriften daher entsprechend streng\u201c, erkl\u00e4rt S\u00f6nke Eichhorn, der die Baustelle als sehr rau, extrem laut und staubig empfunden hat \u2013 ein echter H\u00e4rtetest f\u00fcr Mensch und Maschine, wie er meint.<\/p>\n\n\n\n<p><strong>Aufbau ohne Probleme<\/strong><\/p>\n\n\n\n<p>Trotz dieser widrigen Umgebung ist es dem Team gelungen, den Erstaufbau des Krans inklusive Schulungsprogramm in der vorgesehenen Zeit durchzuf\u00fchren und mit der Montage des F\u00f6rderbandes zu beginnen. Zur Unterst\u00fctzung beim Aufbau des CC 38.650-1 kam ein Tadano AC 5.220-1 als Hilfskran zum Einsatz, der die Fahrt in die Mine auf eigener Achse bew\u00e4ltigt hatte, und der mit den extremen Bedingungen vor Ort ebenso gut zurechtkam wie der Raupenkran. Fertig montiert, platzierte der CC 38.650-1 ein erstes 80 Meter langes und 247 Tonnen schweres Teilst\u00fcck des F\u00f6rderbandes auf zwei zuvor errichtete Pfeiler. Dieses Prozedere wird sich noch etliche Male wiederholen, bis das F\u00f6rderband in kompletter L\u00e4nge von 900 Metern aufgebaut ist und den Boden der Mine erreicht hat.<\/p>\n\n\n\n<p><strong>Gro\u00dfes Lob f\u00fcr Tadano<\/strong><\/p>\n\n\n\n<p>W\u00e4hrend das Tadano Team mittlerweile l\u00e4ngst wieder die Heimreise angetreten hat, wird der CC 38.650-1 noch f\u00fcr weitere f\u00fcnf Jahre in der Mine bleiben. \u201eArbeit haben wir dort mehr als genug f\u00fcr ihn\u201c, versichert Service Manager Victor Condori bei San&nbsp;Lorenzo, der dem Tadano Schulungs-Team ein gro\u00dfes Lob ausspricht: \u201eWir wissen es sehr zu sch\u00e4tzen, dass S\u00f6nke und seine Kollegen die Strapazen auf sich genommen haben, um uns beim Erstaufbau des CC 38.650-1 unter den schwierigen Bedingungen in unserer Mine zu unterst\u00fctzen. Die Zusammenarbeit war perfekt und wir h\u00e4tten uns keine bessere Einweisung w\u00fcnschen k\u00f6nnen\u201c, spricht er f\u00fcr das gesamte San&nbsp;Lorenzo Team.<\/p>\n","protected":false},"featured_media":0,"parent":0,"template":"","news_topics":[19],"class_list":["post-2730","news","type-news","status-publish","hentry","news_topics-job-story"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Lorenzo und Tadano meistern erfolgreichen Ersteinsatz des CC 38.650-1 in Peru<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Lorenzo und Tadano meistern erfolgreichen Ersteinsatz des CC 38.650-1 in Peru\" \/>\n<meta property=\"og:description\" content=\"Br\u00fctende Hitze am Tag, eisige K\u00e4lte in der Nacht \u2013 mit diesen rauen Wetterbedingungen sahen sich das vierk\u00f6pfige Tadano-Team und der CC 38.650-1 Gittermastraupenkran in der peruanischen Kupfermine Cerro Verde konfrontiert. Der brandneue Kran des peruanischen Krandienstleister San Lorenzo sollte dort ein 247 Tonnen schweres Teilst\u00fcck f\u00fcr ein F\u00f6rderband errichten, das Kies und Gestein vom [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\/\" \/>\n<meta property=\"og:site_name\" content=\"Eastern Europe &amp; CIS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\\\/\",\"name\":\"San Lorenzo und Tadano meistern erfolgreichen Ersteinsatz des CC 38.650-1 in Peru\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/en\\\/#website\"},\"datePublished\":\"2025-10-29T14:06:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/news\\\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Lorenzo und Tadano meistern erfolgreichen Ersteinsatz des CC 38.650-1 in Peru\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/en\\\/\",\"name\":\"Eastern Europe &amp; CIS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/eastern-europe-cis\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Lorenzo und Tadano meistern erfolgreichen Ersteinsatz des CC 38.650-1 in Peru","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\/","og_locale":"de_DE","og_type":"article","og_title":"San Lorenzo und Tadano meistern erfolgreichen Ersteinsatz des CC 38.650-1 in Peru","og_description":"Br\u00fctende Hitze am Tag, eisige K\u00e4lte in der Nacht \u2013 mit diesen rauen Wetterbedingungen sahen sich das vierk\u00f6pfige Tadano-Team und der CC 38.650-1 Gittermastraupenkran in der peruanischen Kupfermine Cerro Verde konfrontiert. Der brandneue Kran des peruanischen Krandienstleister San Lorenzo sollte dort ein 247 Tonnen schweres Teilst\u00fcck f\u00fcr ein F\u00f6rderband errichten, das Kies und Gestein vom [&hellip;]","og_url":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\/","og_site_name":"Eastern Europe &amp; CIS","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\/","url":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\/","name":"San Lorenzo und Tadano meistern erfolgreichen Ersteinsatz des CC 38.650-1 in Peru","isPartOf":{"@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/en\/#website"},"datePublished":"2025-10-29T14:06:18+00:00","breadcrumb":{"@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/news\/san-lorenzo-und-tadano-meistern-erfolgreichen-ersteinsatz-des-cc-38-650-1-in-peru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/"},{"@type":"ListItem","position":2,"name":"San Lorenzo und Tadano meistern erfolgreichen Ersteinsatz des CC 38.650-1 in Peru"}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/eastern-europe-cis\/en\/#website","url":"https:\/\/www.tadano.com\/eastern-europe-cis\/en\/","name":"Eastern Europe &amp; CIS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/eastern-europe-cis\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/news\/2730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/news\/2730\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/media?parent=2730"}],"wp:term":[{"taxonomy":"news_topics","embeddable":true,"href":"https:\/\/www.tadano.com\/eastern-europe-cis\/de\/wp-json\/wp\/v2\/news_topics?post=2730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}