{"id":11080,"date":"2021-07-28T07:25:07","date_gmt":"2021-07-28T07:25:07","guid":{"rendered":"https:\/\/www.tadano.com\/europe\/acerca-de\/"},"modified":"2026-06-26T12:03:43","modified_gmt":"2026-06-26T12:03:43","slug":"acerca-de","status":"publish","type":"page","link":"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/","title":{"rendered":"Acerca de"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 0 100%; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/3e5371e3560f257f\/hero-img_tadano_bauma_booth_opening-4.jpg, https:\/\/mediahub.tadano.com\/m\/3e5371e3560f257f\/hero_2x-img_tadano_bauma_booth_opening-4.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder \">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/europe\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">Qui\u00e9nes somos<\/h1>\n\n\n\n<p>Tadano se dedica a proporcionar soluciones de elevaci\u00f3n excepcionales e innovadoras que satisfacen una amplia variedad de necesidades de clientes de todo el mundo.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Nuestra misi\u00f3n<\/h2>\n\n\n\n<p>El eslogan de Tadano, \u00abReaching new heights\u00bb, representa nuestro compromiso por superar las expectativas de los clientes y promover un futuro sostenible. A trav\u00e9s de equipos de elevaci\u00f3n y acceso l\u00edderes en el mundo, ofrecemos tecnolog\u00eda innovadora y seguridad, fomentando el progreso y la prosperidad de nuestros clientes y la sociedad. Al ampliar continuamente los l\u00edmites de lo posible, Tadano se compromete a crear valor que contribuya a un mundo mejor y un futuro m\u00e1s brillante.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nuestra filosof\u00eda<\/h2>\n\n\n\n<p>El Grupo Tadano se ci\u00f1e a su Filosof\u00eda Corporativa deSozo (Creaci\u00f3n), Hoshi (Contribuci\u00f3n) y Kyoryoku (Cooperaci\u00f3n), creyendo firmemente que una empresa s\u00f3lo puede existir con \u00e9xito si est\u00e1 en armon\u00eda con la sociedad y las personas. Con este objetivo, Tadano y su personal contribuyen al desarrollo de las comunidades locales e internacionales, y promueven actividades empresariales que ayuden a proteger el medio ambiente. Nosotros tambi\u00e9n trabajamos para maximizar el valor corporativo y satisfacer y superar las expectativas de las partes interesadas.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading alignfull\">Sozo (Creaci\u00f3n)<\/h3>\n\n\n\n<p class=\"has-small-font-size\">Crearemos innovando y sinti\u00e9ndonos orgullosos de nuestros productos de alta calidad.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Hoshi (Contribuci\u00f3n)<\/h3>\n\n\n\n<p class=\"has-small-font-size\">Contribuiremos al \u00e9xito de nuestros clientes y serviremos a la sociedad.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Kyoryoku (Cooperaci\u00f3n)<\/h3>\n\n\n\n<p class=\"has-small-font-size\">Cooperaremos para asegurar nuestra felicidad y fortalecer los lazos entre nosotros.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Nuestros valores<\/h2>\n\n\n\n<p>Los valores fundamentales de Tadano son \u00abSeguridad, Calidad y Eficiencia, basados en el cumplimiento\u00bb (C+SQE). Damos la m\u00e1xima prioridad a la seguridad de la sociedad y de todos los que fabrican y utilizan nuestros productos y servicios. Buscamos mejorar la calidad, tanto la de nuestros productos y servicios como nuestras operaciones empresariales. Mejoramos la eficiencia de nuestras propias operaciones empresariales, adem\u00e1s de contribuir a mejorar la eficiencia empresarial de nuestros clientes. <\/p>\n\n\n\n<p>El cumplimiento proporciona la base que permite a Tadano actualizar la seguridad, la calidad y la eficiencia, ya que actuamos con equidad y honestidad y mantenemos un alto sentido de la \u00e9tica.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:68px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.tadano.co.jp\/en\/history\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/v5.airtableusercontent.com\/v3\/u\/54\/54\/1782489600000\/BrCOP5GDRfzSBGNQhWOckw\/XyVmzkwKJ_LuRTNlANtSwAub6D5K6V11MGMvdex5uzm837WQxfmQEpEXUMGKA4qYKUrDgZNHYy69WQkc1tUZsVoXIf4HeIp7vutYY_ym3-p-g0--UZZFl6qnGCyvEcjlHqGbqpk_-lLgWzO4sxTt_w\/hlli-90NlVGWw-7Uv-jtNBR3EjSrUh5lCzESVoaxNRg\" alt=\"\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h1 class=\"wp-block-heading\">LA HISTORIA DE TADANO<\/h1>\n\n\n\n<p>Desde sus or\u00edgenes en 1919, cuando su fundador Masuo Tadano decidi\u00f3 contribuir a la sociedad mediante innovaciones en el campo de la soldadura, hasta su ascenso como l\u00edder mundial en el sector de los equipos de elevaci\u00f3n, la historia de Tadano se caracteriza por la excelencia t\u00e9cnica, una visi\u00f3n audaz y un crecimiento continuo. Moldeada por hitos pioneros en Jap\u00f3n, Alemania, Italia y Estados Unidos, en particular gracias al legado de Demag, Faun, Manitex y otros, Tadano lleva m\u00e1s de un siglo siendo fuente de innovaciones en el campo de las gr\u00faas. Descubra c\u00f3mo los avances tecnol\u00f3gicos, la expansi\u00f3n global y el compromiso con la calidad han definido la trayectoria de Tadano y han situado a la empresa a la vanguardia del sector mundial de la elevaci\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.tadano.co.jp\/en\/history\/\" target=\"_blank\" rel=\"noreferrer noopener\">DESCUBRA LA HISTORIA DE TADANO<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong><strong>Excelencia en la fabricaci\u00f3n en Europa<\/strong><\/strong><\/strong><\/h2>\n\n\n\n<p>La red de fabricaci\u00f3n europea de Tadano combina ingenier\u00eda de precisi\u00f3n, experiencia industrial y capacidades de producci\u00f3n integradas. Nuestras instalaciones en Alemania, Italia y Ruman\u00eda desempe\u00f1an un papel fundamental en el suministro de soluciones de elevaci\u00f3n fiables y de alto rendimiento a clientes en toda Europa y en el resto del mundo.<\/p>\n\n\n\n<p>Cada ubicaci\u00f3n aporta competencias \u00fanicas, operando bajo est\u00e1ndares unificados de calidad, seguridad e innovaci\u00f3n de Tadano.<\/p>\n\n\n\n<div class=\"wp-block-group is-style-background-blue-gradient\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\"><strong><strong><strong>Zweibr\u00fccken, Alemania<\/strong><\/strong><\/strong><\/h2>\n\n\n\n<div style=\"height:54px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h3 class=\"wp-block-heading\"><strong><strong>Parte de Tadano desde<\/strong><\/strong><\/h3>\n\n\n\n<p>2019<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Superficie del sitio<\/strong><\/h3>\n\n\n\n<p>172,500\u33a1<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Superficie de producci\u00f3n<\/h3>\n\n\n\n<p>44,000\u33a1<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Productos principales<\/strong><\/h3>\n\n\n\n<p>Grandes gr\u00faas todoterreno, gr\u00faas sobre orugas con brazo en celos\u00eda<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mediahub.tadano.com\/m\/48b01699f4a05126\/original\/img_tadano_aerial_dinglertrasse.jpg\" alt=\"\"\/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Zweibr\u00fccken es uno de los principales centros de fabricaci\u00f3n europeos de Tadano para gr\u00faas m\u00f3viles de gran tama\u00f1o. La planta demuestra nuestra experiencia en elevaci\u00f3n pesada en Europa, combinando ingenier\u00eda avanzada con capacidades de producci\u00f3n a gran escala.<\/p>\n\n\n\n<p><strong><strong><strong>Capacidades principales<\/strong><\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fabricaci\u00f3n de gr\u00faas todoterreno de gran tama\u00f1o y gr\u00faas sobre orugas con pluma de celos\u00eda<\/li>\n\n\n\n<li>L\u00edneas avanzadas de producci\u00f3n y montaje<\/li>\n\n\n\n<li>Pruebas y validaci\u00f3nes de calidad exhaustivas<\/li>\n\n\n\n<li>Departamento de soldadura reconocido<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-style-background-white\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"we-re-a-studio-in-berlin-with-an-international-practice-in-architecture-urban-planning-and-interior-design-we-believe-in-sharing-knowledge-and-promoting-dialogue-to-increase-the-creative-potential-of-collaboration\"><strong><strong><strong>Lauf an der Pegnitz, Alemania<\/strong><\/strong><\/strong><\/h2>\n\n\n\n<div style=\"height:54px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mediahub.tadano.com\/m\/61d53d168cd78ed1\/original\/img_tadano_aerial_lauf.jpg\" alt=\"\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h3 class=\"wp-block-heading\"><strong><strong>Parte de Tadano desde<\/strong><\/strong><\/h3>\n\n\n\n<p>1990<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Superficie del sitio<\/strong><\/h3>\n\n\n\n<p>198,242\u33a1<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Superficie de producci\u00f3n<\/h3>\n\n\n\n<p>56,222\u33a1<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Productos principales<\/strong><\/h3>\n\n\n\n<p>Gr\u00faa todoterreno<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Lauf an der Pegnitz es un importante centro de desarrollo y producci\u00f3n dentro de la red europea de Tadano. La planta apoya la innovaci\u00f3n en ingenier\u00eda y los procesos de fabricaci\u00f3n especializados para gr\u00faas todoterreno y gr\u00faas City.<\/p>\n\n\n\n<p><strong><strong><strong><strong><strong><strong>Capacidades principales<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fabricaci\u00f3n de gr\u00faas todoterreno y gr\u00faas City<\/li>\n\n\n\n<li>L\u00edneas avanzadas de producci\u00f3n y montaje<\/li>\n\n\n\n<li>Pruebas y validaci\u00f3nes de calidad exhaustivas<\/li>\n\n\n\n<li>Log\u00edstica integrada de repuestos y soporte<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-style-default\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\"><strong><strong>San Cesario sul Panaro (PM &#8211; OIL&amp;STEEL), Italia<\/strong><\/strong><\/h2>\n\n\n\n<div style=\"height:54px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mediahub.tadano.com\/m\/7eddfe2fae88d1f3\/original\/img_tadano_aerial_pm.jpg\" alt=\"\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h3 class=\"wp-block-heading\"><strong><strong>Parte de Tadano desde<\/strong><\/strong><\/h3>\n\n\n\n<p>2025<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Superficie del sitio<\/strong><\/h3>\n\n\n\n<p>27,941\u33a1<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Superficie de producci\u00f3n<\/h3>\n\n\n\n<p>13,282m<sup>2<\/sup><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Productos principales<\/strong><\/h3>\n\n\n\n<p>Gr\u00faas hidr\u00e1ulicas articuladas<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mediahub.tadano.com\/m\/42f2b3968e0f91c4\/original\/img_tadano_aerial_cesaria.jpg\" alt=\"\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h3 class=\"wp-block-heading\"><strong><strong>Parte de Tadano desde<\/strong><\/strong><\/h3>\n\n\n\n<p>2025<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Superficie del sitio<\/strong><\/h3>\n\n\n\n<p>22,897m<sup>2<\/sup><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Superficie de producci\u00f3n<\/h3>\n\n\n\n<p>6,210m<sup>2<\/sup><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Productos principales<\/strong><\/h3>\n\n\n\n<p>Plataformas a\u00e9reas<\/p>\n<\/div>\n<\/div>\n\n\n\n<p><strong>San Cesario sul Panaro (PM), Italia<\/strong><\/p>\n\n\n\n<p>La planta de San Cesario sul Panaro, dedicada a las gr\u00faas articuladas, se basa en d\u00e9cadas de experiencia en elevaci\u00f3n hidr\u00e1ulica. El centro combina las funciones de investigaci\u00f3n, producci\u00f3n y servicio en un \u00fanico lugar.<\/p>\n\n\n\n<p><strong><strong><strong><strong><strong><strong>Capacidades principales<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dise\u00f1o y fabricaci\u00f3n de gr\u00faas articuladas hidr\u00e1ulicas<\/li>\n\n\n\n<li>Ingenier\u00eda interna y personalizaci\u00f3n de productos<\/li>\n\n\n\n<li>Producci\u00f3n y control de calidad integrados<\/li>\n\n\n\n<li>Servicio y soporte posventa en toda Europa<\/li>\n<\/ul>\n\n\n\n<p><strong><strong>San Cesario sul Panaro (Oil &amp; Steel), Italia<\/strong><\/strong><\/p>\n\n\n\n<p>Esta planta de Tadano est\u00e1 especializada en plataformas a\u00e9reas y soluciones de acceso en altura. Con solidas capacidades de ingenier\u00eda y un fuerte enfoque en la seguridad operativa, el centro complementa la cartera de soluciones de elevaci\u00f3n de Tadano.<\/p>\n\n\n\n<p><strong><strong><strong><strong><strong><strong>Capacidades principales<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fabricaci\u00f3n de plataformas a\u00e9reas montadas sobre cami\u00f3n<\/li>\n\n\n\n<li>Fabricaci\u00f3n de equipos de acceso compactos y sobre orugas<\/li>\n\n\n\n<li>Ingenier\u00eda de productos centrada en la seguridad<\/li>\n\n\n\n<li>Red dedicada de servicio y asistencia t\u00e9cnica<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-style-background-white\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\"><strong><strong>Piacenza (Valla), Italia<\/strong><\/strong><\/h2>\n\n\n\n<div style=\"height:54px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h3 class=\"wp-block-heading\"><strong><strong>Parte de Tadano desde<\/strong><\/strong><\/h3>\n\n\n\n<p>2025<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Superficie del sitio<\/strong><\/h3>\n\n\n\n<p>2,500m<sup>2<\/sup><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Superficie de producci\u00f3n<\/h3>\n\n\n\n<p>2,100m<sup>2<\/sup><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Productos principales<\/strong><\/h3>\n\n\n\n<p>Gr\u00faas Pick &amp; Carry<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mediahub.tadano.com\/asset\/c8bd96fd-4beb-4908-a035-28cf519e72f8\/img_tadano_valla_factory_38.jpg\" alt=\"\"\/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Las operaciones de fabricaci\u00f3n de Tadano en Piacenza se centran en gr\u00faas el\u00e9ctricas industriales pick &amp; carry, dise\u00f1adas para la manipulaci\u00f3n de precisi\u00f3n y entornos con espacio reducido. La planta es reconocida por ser pionera y continuar desarrollando y fabricando gr\u00faas compactas altamente innovadoras y soluciones de elevaci\u00f3n el\u00e9ctricas sostenibles.<\/p>\n\n\n\n<p><strong><strong><strong><strong><strong><strong>Capacidades principales<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Producci\u00f3n de gr\u00faas industriales pick &amp; carry totalmente el\u00e9ctricas<\/li>\n\n\n\n<li>Equipos de elevaci\u00f3n 100 % alimentados por bater\u00eda y con cero emisiones<\/li>\n\n\n\n<li>Soluciones ultracompactas para aplicaciones especializadas<\/li>\n\n\n\n<li>Procesos de fabricaci\u00f3n de alta precisi\u00f3n de \u00faltima generaci\u00f3n<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-style-default\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\"><strong><strong><strong>Arad (PM), Ruman\u00eda<\/strong><\/strong><\/strong><\/h2>\n\n\n\n<div style=\"height:54px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mediahub.tadano.com\/m\/6966ca2d8c7b8d61\/original\/img_tadano_aerial_romania.jpg\" alt=\"\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h3 class=\"wp-block-heading\"><strong><strong>Parte de Tadano desde<\/strong><\/strong><\/h3>\n\n\n\n<p>2025<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong>Superficie del sitio<\/strong><\/strong><\/h3>\n\n\n\n<p>9,780m<sup>2<\/sup><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Superficie de producci\u00f3n<\/h3>\n\n\n\n<p>7,680m<sup>2<\/sup><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong>Productos principales<\/strong><\/strong><\/h3>\n\n\n\n<p>Piezas de recambio y componentes para gr\u00faas y plataformas a\u00e9reas<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>La planta de Arad refuerza la presencia de Tadano en Europa mediante la producci\u00f3n de componentes clave para las gr\u00faas articuladas Tadano (serie PM). Estrat\u00e9gicamente ubicada en Europa del Este, la instalaci\u00f3n mejora la eficiencia productivay la resiliencia de la cadena de suministro dentro de la red de Tadano.<\/p>\n\n\n\n<p><strong><strong><strong><strong><strong><strong>Capacidades principales<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fabricaci\u00f3n de componentes para gr\u00faas articuladas Tadano serie PM<\/li>\n\n\n\n<li>Fabricaci\u00f3n de metales de precisi\u00f3n y ensamblajes estructurales<\/li>\n\n\n\n<li>Procesos de producci\u00f3n con control de calidad alineados con los est\u00e1ndares de Tadano<\/li>\n\n\n\n<li>Soporte integrado a la cadena de suministro para las operaciones europeas<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong><strong><strong>Una red europea integrada<\/strong><\/strong><\/strong><\/strong><\/h2>\n\n\n\n<p>En conjunto, estas instalaciones forman un ecosistema manufactureroeuropeo cohesionado, basado en est\u00e1ndares compartidos, excelencia en ingenier\u00eda y disciplina operativa.<\/p>\n\n\n\n<p>A trav\u00e9s de la experiencia local y la integraci\u00f3n global, Tadano garantiza:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Calidad constante de los productos<\/li>\n\n\n\n<li>Desarrollo tecnol\u00f3gico avanzado<\/li>\n\n\n\n<li>Fiabilidad en las entregas<\/li>\n\n\n\n<li>S\u00f3lido soporte regional al cliente<\/li>\n<\/ul>\n\n\n\n<div style=\"height:65px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>Noticias<\/h2>\n        <p>Dive into the latest news and developments from the Tadano Group.<\/p>                \n                  <a href=\"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/news-list\/\" class=\"link-more\">EXPLORAR TODAS las noticias<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/es\/news\/la-nueva-grua-todo-terreno-tadano-ac-5-250l-2\/\">\n                  <strong class=\"title\">La nueva gr\u00faa todo terreno Tadano AC 5.250L-2<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Feb\/17\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/es\/news\/grua-tadano-ac-7-450-1-cumple-doble-funcion-en-wisconsin\/\">\n                  <strong class=\"title\">GR\u00daA TADANO AC 7.450-1 cumple doble funci\u00f3n en Wisconsin<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Nov\/12\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/es\/news\/la-nueva-tadano-ac-5-250-2-convence-con-soluciones-innovadoras\/\">\n                  <strong class=\"title\">La nueva Tadano AC 5.250-2 convence con soluciones innovadoras<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  ","protected":false},"excerpt":{"rendered":"<p>Nuestra misi\u00f3n El eslogan de Tadano, \u00abReaching new heights\u00bb, representa nuestro compromiso por superar las expectativas de los clientes y promover un futuro sostenible. A trav\u00e9s de equipos de elevaci\u00f3n y acceso l\u00edderes en el mundo, ofrecemos tecnolog\u00eda innovadora y seguridad, fomentando el progreso y la prosperidad de nuestros clientes y la sociedad. Al ampliar [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11080","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acerca de - Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acerca de - Europe\" \/>\n<meta property=\"og:description\" content=\"Nuestra misi\u00f3n El eslogan de Tadano, \u00abReaching new heights\u00bb, representa nuestro compromiso por superar las expectativas de los clientes y promover un futuro sostenible. A trav\u00e9s de equipos de elevaci\u00f3n y acceso l\u00edderes en el mundo, ofrecemos tecnolog\u00eda innovadora y seguridad, fomentando el progreso y la prosperidad de nuestros clientes y la sociedad. Al ampliar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-26T12:03:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/v5.airtableusercontent.com\/v3\/u\/54\/54\/1782489600000\/BrCOP5GDRfzSBGNQhWOckw\/XyVmzkwKJ_LuRTNlANtSwAub6D5K6V11MGMvdex5uzm837WQxfmQEpEXUMGKA4qYKUrDgZNHYy69WQkc1tUZsVoXIf4HeIp7vutYY_ym3-p-g0--UZZFl6qnGCyvEcjlHqGbqpk_-lLgWzO4sxTt_w\/hlli-90NlVGWw-7Uv-jtNBR3EjSrUh5lCzESVoaxNRg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/acerca-de\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/acerca-de\\\/\",\"name\":\"Acerca de - Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/acerca-de\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/acerca-de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/v5.airtableusercontent.com\\\/v3\\\/u\\\/54\\\/54\\\/1782489600000\\\/BrCOP5GDRfzSBGNQhWOckw\\\/XyVmzkwKJ_LuRTNlANtSwAub6D5K6V11MGMvdex5uzm837WQxfmQEpEXUMGKA4qYKUrDgZNHYy69WQkc1tUZsVoXIf4HeIp7vutYY_ym3-p-g0--UZZFl6qnGCyvEcjlHqGbqpk_-lLgWzO4sxTt_w\\\/hlli-90NlVGWw-7Uv-jtNBR3EjSrUh5lCzESVoaxNRg\",\"datePublished\":\"2021-07-28T07:25:07+00:00\",\"dateModified\":\"2026-06-26T12:03:43+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/acerca-de\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/acerca-de\\\/#primaryimage\",\"url\":\"https:\\\/\\\/v5.airtableusercontent.com\\\/v3\\\/u\\\/54\\\/54\\\/1782489600000\\\/BrCOP5GDRfzSBGNQhWOckw\\\/XyVmzkwKJ_LuRTNlANtSwAub6D5K6V11MGMvdex5uzm837WQxfmQEpEXUMGKA4qYKUrDgZNHYy69WQkc1tUZsVoXIf4HeIp7vutYY_ym3-p-g0--UZZFl6qnGCyvEcjlHqGbqpk_-lLgWzO4sxTt_w\\\/hlli-90NlVGWw-7Uv-jtNBR3EjSrUh5lCzESVoaxNRg\",\"contentUrl\":\"https:\\\/\\\/v5.airtableusercontent.com\\\/v3\\\/u\\\/54\\\/54\\\/1782489600000\\\/BrCOP5GDRfzSBGNQhWOckw\\\/XyVmzkwKJ_LuRTNlANtSwAub6D5K6V11MGMvdex5uzm837WQxfmQEpEXUMGKA4qYKUrDgZNHYy69WQkc1tUZsVoXIf4HeIp7vutYY_ym3-p-g0--UZZFl6qnGCyvEcjlHqGbqpk_-lLgWzO4sxTt_w\\\/hlli-90NlVGWw-7Uv-jtNBR3EjSrUh5lCzESVoaxNRg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/\",\"name\":\"Europe\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acerca de - Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/","og_locale":"es_ES","og_type":"article","og_title":"Acerca de - Europe","og_description":"Nuestra misi\u00f3n El eslogan de Tadano, \u00abReaching new heights\u00bb, representa nuestro compromiso por superar las expectativas de los clientes y promover un futuro sostenible. A trav\u00e9s de equipos de elevaci\u00f3n y acceso l\u00edderes en el mundo, ofrecemos tecnolog\u00eda innovadora y seguridad, fomentando el progreso y la prosperidad de nuestros clientes y la sociedad. Al ampliar [&hellip;]","og_url":"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/","og_site_name":"Europe","article_modified_time":"2026-06-26T12:03:43+00:00","og_image":[{"url":"https:\/\/v5.airtableusercontent.com\/v3\/u\/54\/54\/1782489600000\/BrCOP5GDRfzSBGNQhWOckw\/XyVmzkwKJ_LuRTNlANtSwAub6D5K6V11MGMvdex5uzm837WQxfmQEpEXUMGKA4qYKUrDgZNHYy69WQkc1tUZsVoXIf4HeIp7vutYY_ym3-p-g0--UZZFl6qnGCyvEcjlHqGbqpk_-lLgWzO4sxTt_w\/hlli-90NlVGWw-7Uv-jtNBR3EjSrUh5lCzESVoaxNRg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/","url":"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/","name":"Acerca de - Europe","isPartOf":{"@id":"https:\/\/www.tadano.com\/europe\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/#primaryimage"},"image":{"@id":"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/#primaryimage"},"thumbnailUrl":"https:\/\/v5.airtableusercontent.com\/v3\/u\/54\/54\/1782489600000\/BrCOP5GDRfzSBGNQhWOckw\/XyVmzkwKJ_LuRTNlANtSwAub6D5K6V11MGMvdex5uzm837WQxfmQEpEXUMGKA4qYKUrDgZNHYy69WQkc1tUZsVoXIf4HeIp7vutYY_ym3-p-g0--UZZFl6qnGCyvEcjlHqGbqpk_-lLgWzO4sxTt_w\/hlli-90NlVGWw-7Uv-jtNBR3EjSrUh5lCzESVoaxNRg","datePublished":"2021-07-28T07:25:07+00:00","dateModified":"2026-06-26T12:03:43+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/europe\/es\/acerca-de\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/#primaryimage","url":"https:\/\/v5.airtableusercontent.com\/v3\/u\/54\/54\/1782489600000\/BrCOP5GDRfzSBGNQhWOckw\/XyVmzkwKJ_LuRTNlANtSwAub6D5K6V11MGMvdex5uzm837WQxfmQEpEXUMGKA4qYKUrDgZNHYy69WQkc1tUZsVoXIf4HeIp7vutYY_ym3-p-g0--UZZFl6qnGCyvEcjlHqGbqpk_-lLgWzO4sxTt_w\/hlli-90NlVGWw-7Uv-jtNBR3EjSrUh5lCzESVoaxNRg","contentUrl":"https:\/\/v5.airtableusercontent.com\/v3\/u\/54\/54\/1782489600000\/BrCOP5GDRfzSBGNQhWOckw\/XyVmzkwKJ_LuRTNlANtSwAub6D5K6V11MGMvdex5uzm837WQxfmQEpEXUMGKA4qYKUrDgZNHYy69WQkc1tUZsVoXIf4HeIp7vutYY_ym3-p-g0--UZZFl6qnGCyvEcjlHqGbqpk_-lLgWzO4sxTt_w\/hlli-90NlVGWw-7Uv-jtNBR3EjSrUh5lCzESVoaxNRg"},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/europe\/en\/#website","url":"https:\/\/www.tadano.com\/europe\/en\/","name":"Europe","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/europe\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/pages\/11080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/comments?post=11080"}],"version-history":[{"count":5,"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/pages\/11080\/revisions"}],"predecessor-version":[{"id":16361,"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/pages\/11080\/revisions\/16361"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/media?parent=11080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}