{"id":11165,"date":"2022-10-10T14:28:46","date_gmt":"2022-10-10T12:28:46","guid":{"rendered":"https:\/\/www.tadano.com\/europe\/%term%\/%cat%\/ac-4-070-2\/"},"modified":"2026-01-06T09:39:48","modified_gmt":"2026-01-06T09:39:48","slug":"ac-4-070-2","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/europe\/es\/lifting-equipment\/all-terrain-cranes\/ac-4-070-2\/","title":{"rendered":"AC 4.070-2"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 0 0; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/720748b9f6549697\/hero-img_tadano_AC4070-2_cutout_front.png, https:\/\/mediahub.tadano.com\/m\/720748b9f6549697\/hero_2x-img_tadano_AC4070-2_cutout_front.png 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/europe\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">AC 4.070-2<\/h1>\n\n\n\n<p>La AC 4.070-2 es la gr\u00faa m\u00e1s compacta de su clase, que adem\u00e1s sienta nuevos est\u00e1ndares al presentar las mejores capacidades de elevaci\u00f3n en muchos \u00e1mbitos. Gracias a su amplio equipamiento de serie y a una gama de accesorios flexible, es tan adecuada como gr\u00faa auxiliar vers\u00e1til para el montaje de grandes gr\u00faas como para tareas de construcci\u00f3n en zonas urbanas.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/europe\/es\/ventas-y-servicios\/ventas\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Comparar productos<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"es\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"16\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"39\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11167\" data-group=\"\">AC 2.040-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11151\" data-group=\"\">AC 3.060-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11165\" data-group=\"\">AC 4.070-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11027\" data-group=\"\">AC 4.080-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11164\" data-group=\"\">AC 5.130-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11163\" data-group=\"\">AC 5.160-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11160\" data-group=\"\">AC 5.250-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"12695\" data-group=\"\">AC 5.250L-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11161\" data-group=\"\">AC 6.300-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11032\" data-group=\"\">AC 7.450-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11173\" data-group=\"\">AC 8.500-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11167\" data-group=\"\">AC 2.040-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11151\" data-group=\"\">AC 3.060-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11165\" data-group=\"\">AC 4.070-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11027\" data-group=\"\">AC 4.080-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11164\" data-group=\"\">AC 5.130-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11163\" data-group=\"\">AC 5.160-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11160\" data-group=\"\">AC 5.250-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"12695\" data-group=\"\">AC 5.250L-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11161\" data-group=\"\">AC 6.300-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11032\" data-group=\"\">AC 7.450-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11173\" data-group=\"\">AC 8.500-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                          <li>\n                <a href=\"#media\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M22.9683 1.53906H3.74603C2.22944 1.53906 1 2.7685 1 4.28509V23.5073C1 25.0239 2.22944 26.2533 3.74603 26.2533H22.9683C24.4848 26.2533 25.7143 25.0239 25.7143 23.5073V4.28509C25.7143 2.7685 24.4848 1.53906 22.9683 1.53906Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.55116 11.1483C9.68861 11.1483 10.6107 10.2263 10.6107 9.08882C10.6107 7.95138 9.68861 7.0293 8.55116 7.0293C7.41372 7.0293 6.49164 7.95138 6.49164 9.08882C6.49164 10.2263 7.41372 11.1483 8.55116 11.1483Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M25.715 18.0135L18.8499 11.1484L3.7467 26.2516\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Galer\u00eda<\/span>\n                <\/a>\n              <\/li>\n                                                  <li>\n                <a href=\"#360\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M13.3571 26.2514C20.1818 26.2514 25.7143 20.7189 25.7143 13.8943C25.7143 7.06959 20.1818 1.53711 13.3571 1.53711C6.53248 1.53711 1 7.06959 1 13.8943C1 20.7189 6.53248 26.2514 13.3571 26.2514Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M1 13.0703H25.7143\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M13.3572 1.53711C16.9632 4.92093 19.0125 9.31227 19.1238 13.8943C19.0125 18.4762 16.9632 22.8676 13.3572 26.2514C9.75114 22.8676 7.70185 18.4762 7.59048 13.8943C7.70185 9.31227 9.75114 4.92093 13.3572 1.53711V1.53711Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Vista de 360\u00ba<\/span>\n                <\/a>\n              <\/li>\n            \n            \n                          <li class=\"scaled-metric\">\n                <a href=\"https:\/\/mediahub.tadano.com\/m\/5347808ca4c9945f\/original\/doc_tadano_AC4070-2_datasheet_metric_en_de_fr_it_es_pt_ru.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Especifi&shy;caciones<\/span>\n                <\/a>\n              <\/li>\n                                      <li class=\"scaled-imperial\">\n                <a href=\"https:\/\/mediahub.tadano.com\/m\/5749fb899603e6c4\/original\/doc_tadano_AC4070-2_datasheet_imperial_en.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Especifi&shy;caciones<\/span>\n                <\/a>\n              <\/li>\n            \n            \n            \n                          <li>\n                <a href=\"https:\/\/www.tadano.com\/en\/about\/contact-us\/\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" version=\"1.1\" width=\"30\" height=\"30\" x=\"0\" y=\"0\" viewBox=\"0 0 440.965 440.965\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M341.508,36.207C305.582,12.648,263.549,0.116,220.587,0.154C98.892,0.271,0.235,98.832,0,220.527    c-0.046,42.838,12.652,84.721,36.48,120.32L0.853,426.18c-2.189,5.469,0.47,11.677,5.939,13.867c2.544,1.018,5.383,1.018,7.928,0    l85.333-35.627c101.679,66.676,238.158,38.3,304.834-63.379S443.187,102.883,341.508,36.207z M220.801,419.567    c-0.071,0-0.142,0-0.213,0v0.213h-0.001c-40.532-0.319-80.02-12.886-113.28-36.053c-1.754-1.224-3.835-1.893-5.973-1.92    c-1.338-0.264-2.715-0.264-4.053,0l-66.774,28.587l27.947-66.56c1.424-3.37,1.022-7.236-1.067-10.24    c-23.487-33.021-36.09-72.545-36.053-113.067C21.216,110.482,110.329,21.178,220.374,21.06    c110.044-0.118,199.349,88.995,199.467,199.04C419.959,330.145,330.846,419.449,220.801,419.567z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M288.514,162.764c-4.633-33.756-33.865-58.657-67.927-57.864c-36.795-0.118-66.752,29.552-66.987,66.347    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667c0.471-25.209,21.289-45.263,46.499-44.792    c25.21,0.471,45.263,21.289,44.792,46.499c-0.465,24.874-20.759,44.796-45.637,44.8c-5.891,0-10.667,4.776-10.667,10.667v47.787    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667v-37.973C267.907,233.206,293.543,199.416,288.514,162.764z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <circle cx=\"219.697\" cy=\"325.147\" r=\"11.675\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <\/g><\/svg>\n\n                  <\/div>\n                  <span class=\"text\">Pedir info&shy;rmaci\u00f3n<\/span>\n                <\/a>\n              <\/li>\n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n             \n\n\n<div class=\"container \">\n  <div class=\"product-details\">\n    <div class=\"product-specs\">\n\n      <div class=\"title\">\n        <div class=\"left\">\n                      <h2>Especificaciones del producto<\/h2>\n                  <\/div>\n        <div class=\"right\">\n                        <div class=\"radio\">\n                                <label for=\"met\" class=\"met\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">M\u00e9trico<\/span>\n                <\/label>\n                <label for=\"imp\" class=\"imp\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Imperial<\/span>\n                <\/label>\n            <\/div>\n            \n\n        <\/div>\n      <\/div>\n\n      \n        <ul>\n\n                                  <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Capacidad m\u00e1x. de la gr\u00faa<\/strong>\n                          <span>75&nbsp;USt<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Longitud de la pluma principal<\/strong>\n                          <span>34.1&nbsp;ft &#8211; 164.0&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Extensi\u00f3n de pluma<\/strong>\n                          <span>5.9&nbsp;ft \/ 21.3&nbsp;ft \/ 29.5&nbsp;ft &#8211; 52.5&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Altura m\u00e1x. cabeza pluma<\/strong>\n                          <span>223.0&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Contrapeso m\u00e1ximo<\/strong>\n                          <span>26,200&nbsp;lbs<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Bases de estabilizaci\u00f3n<\/strong>\n                          <span>26.5&nbsp;ft  x  21.3&nbsp;ft  <\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Tiro de la l\u00ednea de elevaci\u00f3n<\/strong>\n                          <span>15,040&nbsp;lbs<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">MAX Radius<\/strong>\n                          <span>137.8&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Dimensiones<\/strong>\n                          <span>L:&nbsp;38.4&nbsp;ft W:&nbsp;8.4&nbsp;ft H:&nbsp;12.4&nbsp;ft <\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Capacidad m\u00e1x. de la gr\u00faa<\/strong>\n                          <span>70&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Longitud de la pluma principal<\/strong>\n                          <span>10.4&nbsp;m &#8211; 50&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Extensi\u00f3n de pluma<\/strong>\n                          <span>1.8&nbsp;m \/ 6.5&nbsp;m \/ 9&nbsp;m &#8211; 16&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Altura m\u00e1x. cabeza pluma<\/strong>\n                          <span>69&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Contrapeso m\u00e1ximo<\/strong>\n                          <span>11.9&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Bases de estabilizaci\u00f3n<\/strong>\n                          <span>8.08&nbsp;m x 6.48&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Tiro de la l\u00ednea de elevaci\u00f3n<\/strong>\n                          <span>6.8&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Radio m\u00e1x.<\/strong>\n                          <span>42&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Dimensiones<\/strong>\n                          <span>L:&nbsp;11.69&nbsp;m W:&nbsp;2.55&nbsp;m H:&nbsp;3.79&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Ejes<\/strong>\n                          <span>4<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Motor<\/strong>\n                          <span>Mercedes-Benz<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">transmisi\u00f3n<\/strong>\n                          <span>8&nbsp;x 4&nbsp;x 8&nbsp;(8&nbsp;x 6&nbsp;x 8)<\/span>\n                        <\/li>\n                      \n        <\/ul>\n\n                  <style type=\"text\/css\">\n            @media screen and (min-width: 1360px) {\n              .hero-section .green-solutions {\n                display: block!important;\n              }\n            }\n          <\/style>\n        \n       \n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Descripci\u00f3n del producto<\/h2>\n\n\n\n<p>Especialmente impresionante: Con una carga por eje de 12 toneladas, la AC 4.070-2 puede transportar su contrapeso m\u00e1ximo de 11,9 toneladas, pero incluso con una carga por eje de 10 toneladas puede llevar consigo 4,4 toneladas. Esto hace que la AC 4.070-2 sea una gr\u00faa taxi extremadamente vers\u00e1til. Sus capacidades de carga no son menos impresionantes: Con una longitud de pluma principal de 50 metros y un alcance de 10 metros, la gr\u00faa puede elevar unas impresionantes 7,3 toneladas. Ninguna otra gr\u00faa de su clase alcanza esta capacidad de carga. Y, con una longitud total de 11,7 metros, es adem\u00e1s la gr\u00faa de 4 ejes m\u00e1s compacta de su clase en el mercado.<\/p>\n\n\n\n<p>Caracter\u00edsticas t\u00e9cnicas destacadas como el sistema de control de gr\u00faa inteligente IC-1 Plus, la soluci\u00f3n telem\u00e1tica IC-1 Remote opcional, los estabilizadores Flex Base de ajuste continuo y la preparaci\u00f3n E-Pack opcional para un funcionamiento de la gr\u00faa sin emisiones, as\u00ed como el sistema de c\u00e1maras Surround View hacen que la Tadano AC 4.070-2 sea la gr\u00faa de referencia en su clase.<\/p>\n\n\n\n<section class=\"product-360-view\" id=\"360\">\n\n      <script type=\"text\/javascript\">\n      const ThreeSixtyFrameCount = 36;\n      const ThreeSixtyImagePath = 'https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/360-view\/AC4070-2\/360\/';\n    <\/script>\n\n    <div class=\"container\">\n      <div class=\"interactive-view\">\n        <h2>Vista interactiva de 360\u00ba<\/h2>\n\n                  <div class=\"view-selector\">\n\n            <div data-view=\"view-exterior\" class=\"active\">Exterior<\/div>\n\n                          <div data-view=\"view-lower-cabin\">Lower cabin<\/div>\n            \n                          <div data-view=\"view-upper-cabin\">Upper cabin<\/div>\n            \n          <\/div>\n        \n        <div class=\"views-wrapper\">\n\n                      <div id=\"view-lower-cabin\" class=\"iframe\">\n              <iframe src=\"https:\/\/www.tadano.com\/\/wp-content\/themes\/tadano\/template-parts\/components\/cabin-views\/tadano_ac_lc\/index.htm\" frameborder=\"0\" allowfullscreen=\"\" allow=\"vr\"><\/iframe>\n            <\/div>\n          \n                      <div id=\"view-upper-cabin\" class=\"iframe\">\n              <iframe src=\"https:\/\/www.tadano.com\/\/wp-content\/themes\/tadano\/template-parts\/components\/cabin-views\/tadano_ac_uc\/index.htm\" frameborder=\"0\" allowfullscreen=\"\" allow=\"vr\"><\/iframe>\n            <\/div>\n          \n          <div id=\"view-exterior\" class=\"active\">\n            <div class=\"view-holder\">\n                          <\/div>\n            <div class=\"wrap-360\">\n              <div class=\"threesixty car\">\n                <div class=\"spinner\">\n                    <span style=\"opacity:0.2\">0%<\/span>\n                <\/div>\n                <ol class=\"threesixty_images\"><\/ol>\n              <\/div>\n            <\/div>\n            \n                      <\/div>\n\n        <\/div>\n          \n        \n      <\/div>\n    <\/div>\n\n    \n    <script>\n     \/\/ Target the view-selector divs\n     const selectors = document.querySelectorAll('.view-selector div');\n\n     \/\/ Add a 'click' event listener to all the selectors\n     selectors.forEach(selector => {\n          selector.addEventListener('click', function(event){\n               \/\/ Remove 'active' class from all selectors\n               selectors.forEach(selector => {\n                    selector.classList.remove('active');\n\n                    \/\/ Also remove 'active' class from all views,\n                    \/\/ But first check if the view actually exists\n                    let view = document.querySelector('#' + selector.dataset.view);\n                    if(view) {\n                        view.classList.remove('active');\n                    }\n               })\n\n               \/\/ Add 'active' class to the clicked selector\n               this.classList.add('active');\n\n               \/\/ Add 'active' class to the view corresponding to clicked selector\n               \/\/ After checking if the view actually exists\n               let view = document.querySelector('#' + this.dataset.view);\n               if(view) {\n                   view.classList.add('active');\n               }\n          })\n     });\n    <\/script>\n\n<\/section>\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Galer\u00eda de medios<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/6eea823999d2f847\/gallery_full-img_tadano_AC4070-2_road-2.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/6eea823999d2f847\/gallery_thumb-img_tadano_AC4070-2_road-2.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n<div class=\"cta-block\">\n    <div class=\"container\">\n    <div class=\"left\">\n      <ul class=\"btn-list\">\n        <li><a href=\"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/contactenos\/\" class=\"btn btn-light\">CONT\u00c1CTENOS<\/a><\/li>\n      <\/ul>\n    <\/div>\n    <div class=\"right\">\n                          <ul class=\"btn-list\">\n                            \n                                  <li class=\"scaled-metric\"><a href=\"https:\/\/mediahub.tadano.com\/m\/5347808ca4c9945f\/original\/doc_tadano_AC4070-2_datasheet_metric_en_de_fr_it_es_pt_ru.pdf\" class=\"btn btn-outline-white\">Hoja de especificaciones<\/a><\/li>\n                  <li class=\"scaled-imperial\"><a href=\"https:\/\/mediahub.tadano.com\/m\/5749fb899603e6c4\/original\/doc_tadano_AC4070-2_datasheet_imperial_en.pdf\" class=\"btn btn-outline-white\">Hoja de especificaciones<\/a><\/li>\n                              \n                              \n          <\/ul>\n            <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n\n\n\n\n\n\n\n\n\n  <section class=\"related-products related-pages\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>P\u00e1ginas relacionadas<\/h2>\n      <\/div>\n\n      <div class='r-products'>\n                  \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/europe\/es\/lifting-equipment\/all-terrain-cranes\/ac-4-080-1\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/1c3f529e333f7382\/img_thumb-img_tadano_AC4080_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/1c3f529e333f7382\/img_thumb_2x-img_tadano_AC4080_cutout_side.png 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">AC 4.080-1<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                        <\/div>\n        \n    <\/div>\n  <\/section>\n  \n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>Noticias<\/h2>\n                        \n                  <a href=\"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/news-list\/\" class=\"link-more\">EXPLORAR TODAS las noticias<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/es\/news\/la-nueva-grua-todo-terreno-tadano-ac-5-250l-2\/\">\n                  <strong class=\"title\">La nueva gr\u00faa todo terreno Tadano AC 5.250L-2<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Feb\/17\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/es\/news\/grua-tadano-ac-7-450-1-cumple-doble-funcion-en-wisconsin\/\">\n                  <strong class=\"title\">GR\u00daA TADANO AC 7.450-1 cumple doble funci\u00f3n en Wisconsin<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Nov\/12\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/es\/news\/la-nueva-tadano-ac-5-250-2-convence-con-soluciones-innovadoras\/\">\n                  <strong class=\"title\">La nueva Tadano AC 5.250-2 convence con soluciones innovadoras<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  ","protected":false},"featured_media":0,"template":"","lifting-equipment":[39],"class_list":["post-11165","products","type-products","status-publish","hentry","lifting-equipment-all-terrain-cranes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AC 4.070-2 - Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/all-terrain-cranes\/ac-4-070-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AC 4.070-2 - Europe\" \/>\n<meta property=\"og:description\" content=\"Descripci\u00f3n del producto Especialmente impresionante: Con una carga por eje de 12 toneladas, la AC 4.070-2 puede transportar su contrapeso m\u00e1ximo de 11,9 toneladas, pero incluso con una carga por eje de 10 toneladas puede llevar consigo 4,4 toneladas. Esto hace que la AC 4.070-2 sea una gr\u00faa taxi extremadamente vers\u00e1til. Sus capacidades de carga [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/all-terrain-cranes\/ac-4-070-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-06T09:39:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/lifting-equipment\\\/all-terrain-cranes\\\/ac-4-070-2\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/lifting-equipment\\\/all-terrain-cranes\\\/ac-4-070-2\\\/\",\"name\":\"AC 4.070-2 - Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\"},\"datePublished\":\"2022-10-10T12:28:46+00:00\",\"dateModified\":\"2026-01-06T09:39:48+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/lifting-equipment\\\/all-terrain-cranes\\\/ac-4-070-2\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/\",\"name\":\"Europe\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AC 4.070-2 - Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/all-terrain-cranes\/ac-4-070-2\/","og_locale":"es_ES","og_type":"article","og_title":"AC 4.070-2 - Europe","og_description":"Descripci\u00f3n del producto Especialmente impresionante: Con una carga por eje de 12 toneladas, la AC 4.070-2 puede transportar su contrapeso m\u00e1ximo de 11,9 toneladas, pero incluso con una carga por eje de 10 toneladas puede llevar consigo 4,4 toneladas. Esto hace que la AC 4.070-2 sea una gr\u00faa taxi extremadamente vers\u00e1til. Sus capacidades de carga [&hellip;]","og_url":"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/all-terrain-cranes\/ac-4-070-2\/","og_site_name":"Europe","article_modified_time":"2026-01-06T09:39:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/all-terrain-cranes\/ac-4-070-2\/","url":"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/all-terrain-cranes\/ac-4-070-2\/","name":"AC 4.070-2 - Europe","isPartOf":{"@id":"https:\/\/www.tadano.com\/europe\/en\/#website"},"datePublished":"2022-10-10T12:28:46+00:00","dateModified":"2026-01-06T09:39:48+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/all-terrain-cranes\/ac-4-070-2\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/europe\/en\/#website","url":"https:\/\/www.tadano.com\/europe\/en\/","name":"Europe","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/europe\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/products\/11165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/products\/11165\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/media?parent=11165"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/lifting-equipment?post=11165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}