{"id":13937,"date":"2025-10-29T13:26:18","date_gmt":"2025-10-29T12:26:18","guid":{"rendered":"https:\/\/www.tadano.com\/europe\/%term%\/%cat%\/pm-8-5-s\/"},"modified":"2026-02-25T19:07:38","modified_gmt":"2026-02-25T19:07:38","slug":"pm-8-5-s","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/europe\/es\/lifting-equipment\/knuckle-boom-cranes\/pm-8-5-s\/","title":{"rendered":"PM 8.5 S"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 0 0; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/a0e1f0b35287096\/hero-img_tadano_pm_8-5S-1.jpg, https:\/\/mediahub.tadano.com\/m\/a0e1f0b35287096\/hero_2x-img_tadano_pm_8-5S-1.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/europe\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">PM 8.5 S<\/h1>\n\n\n\n<p>La serie PM 8.5 S combina una excepcional relaci\u00f3n peso\/capacidad, un alcance ampliado y un funcionamiento seguro, ideal para un uso vers\u00e1til en camiones de tama\u00f1o medio.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/europe\/es\/ventas-y-servicios\/ventas\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Comparar productos<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"es\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"16\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"116\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14081\" data-group=\"\">PM 10 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14085\" data-group=\"\">PM 10 S C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14276\" data-group=\"\">PM 100 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14089\" data-group=\"\">PM 11<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14093\" data-group=\"\">PM 11 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14097\" data-group=\"\">PM 11 SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14101\" data-group=\"\">PM 11.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14109\" data-group=\"\">PM 12.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14117\" data-group=\"\">PM 13.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14121\" data-group=\"\">PM 15.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14281\" data-group=\"\">PM 150 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14136\" data-group=\"\">PM 16.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14140\" data-group=\"\">PM 18 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14144\" data-group=\"\">PM 19<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13830\" data-group=\"\">PM 2.8<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14148\" data-group=\"\">PM 21<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14162\" data-group=\"\">PM 21.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14285\" data-group=\"\">PM 210 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14171\" data-group=\"\">PM 23 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14180\" data-group=\"\">PM 23.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14184\" data-group=\"\">PM 24 PX<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14188\" data-group=\"\">PM 26.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14192\" data-group=\"\">PM 28.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13841\" data-group=\"\">PM 3 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13845\" data-group=\"\">PM 3.6<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13849\" data-group=\"\">PM 3.9 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14196\" data-group=\"\">PM 30.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14200\" data-group=\"\">PM 32.5 PX<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14204\" data-group=\"\">PM 36.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14208\" data-group=\"\">PM 38.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13869\" data-group=\"\">PM 4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13873\" data-group=\"\">PM 4.5<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14212\" data-group=\"\">PM 40.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14216\" data-group=\"\">PM 47.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14220\" data-group=\"\">PM 48.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13877\" data-group=\"\">PM 5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14224\" data-group=\"\">PM 50.5 PX \/ PX C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14228\" data-group=\"\">PM 50.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14232\" data-group=\"\">PM 51.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14236\" data-group=\"\">PM 57.5 PX \/ PX C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14240\" data-group=\"\">PM 57.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14244\" data-group=\"\">PM 58.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13886\" data-group=\"\">PM 6<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13891\" data-group=\"\">PM 6.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13905\" data-group=\"\">PM 7 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14248\" data-group=\"\">PM 70.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13914\" data-group=\"\">PM 8<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13928\" data-group=\"\">PM 8.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13937\" data-group=\"\">PM 8.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13941\" data-group=\"\">PM 8.5 S C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14252\" data-group=\"\">PM 83.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14073\" data-group=\"\">PM 9.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14077\" data-group=\"\">PM 9.5 SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14289\" data-group=\"\">Power Lift<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14293\" data-group=\"\">TP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14081\" data-group=\"\">PM 10 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14085\" data-group=\"\">PM 10 S C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14276\" data-group=\"\">PM 100 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14089\" data-group=\"\">PM 11<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14093\" data-group=\"\">PM 11 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14097\" data-group=\"\">PM 11 SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14101\" data-group=\"\">PM 11.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14109\" data-group=\"\">PM 12.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14117\" data-group=\"\">PM 13.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14121\" data-group=\"\">PM 15.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14281\" data-group=\"\">PM 150 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14136\" data-group=\"\">PM 16.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14140\" data-group=\"\">PM 18 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14144\" data-group=\"\">PM 19<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13830\" data-group=\"\">PM 2.8<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14148\" data-group=\"\">PM 21<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14162\" data-group=\"\">PM 21.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14285\" data-group=\"\">PM 210 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14171\" data-group=\"\">PM 23 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14180\" data-group=\"\">PM 23.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14184\" data-group=\"\">PM 24 PX<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14188\" data-group=\"\">PM 26.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14192\" data-group=\"\">PM 28.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13841\" data-group=\"\">PM 3 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13845\" data-group=\"\">PM 3.6<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13849\" data-group=\"\">PM 3.9 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14196\" data-group=\"\">PM 30.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14200\" data-group=\"\">PM 32.5 PX<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14204\" data-group=\"\">PM 36.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14208\" data-group=\"\">PM 38.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13869\" data-group=\"\">PM 4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13873\" data-group=\"\">PM 4.5<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14212\" data-group=\"\">PM 40.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14216\" data-group=\"\">PM 47.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14220\" data-group=\"\">PM 48.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13877\" data-group=\"\">PM 5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14224\" data-group=\"\">PM 50.5 PX \/ PX C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14228\" data-group=\"\">PM 50.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14232\" data-group=\"\">PM 51.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14236\" data-group=\"\">PM 57.5 PX \/ PX C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14240\" data-group=\"\">PM 57.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14244\" data-group=\"\">PM 58.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13886\" data-group=\"\">PM 6<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13891\" data-group=\"\">PM 6.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13905\" data-group=\"\">PM 7 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14248\" data-group=\"\">PM 70.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13914\" data-group=\"\">PM 8<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13928\" data-group=\"\">PM 8.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13937\" data-group=\"\">PM 8.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13941\" data-group=\"\">PM 8.5 S C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14252\" data-group=\"\">PM 83.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14073\" data-group=\"\">PM 9.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14077\" data-group=\"\">PM 9.5 SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14289\" data-group=\"\">Power Lift<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14293\" data-group=\"\">TP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                          <li>\n                <a href=\"#media\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M22.9683 1.53906H3.74603C2.22944 1.53906 1 2.7685 1 4.28509V23.5073C1 25.0239 2.22944 26.2533 3.74603 26.2533H22.9683C24.4848 26.2533 25.7143 25.0239 25.7143 23.5073V4.28509C25.7143 2.7685 24.4848 1.53906 22.9683 1.53906Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.55116 11.1483C9.68861 11.1483 10.6107 10.2263 10.6107 9.08882C10.6107 7.95138 9.68861 7.0293 8.55116 7.0293C7.41372 7.0293 6.49164 7.95138 6.49164 9.08882C6.49164 10.2263 7.41372 11.1483 8.55116 11.1483Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M25.715 18.0135L18.8499 11.1484L3.7467 26.2516\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Galer\u00eda<\/span>\n                <\/a>\n              <\/li>\n                                    \n            \n                        \n                          <li>\n                <a href=\"https:\/\/mediahub.tadano.com\/m\/72605ea288deb12d\/original\/doc_tadano_pm_8-5S_brochure.pdf\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                  <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Folleto<\/span>\n                <\/a>\n              <\/li>\n            \n            \n                          <li>\n                <a href=\"https:\/\/www.tadano.com\/en\/about\/contact-us\/\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" version=\"1.1\" width=\"30\" height=\"30\" x=\"0\" y=\"0\" viewBox=\"0 0 440.965 440.965\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M341.508,36.207C305.582,12.648,263.549,0.116,220.587,0.154C98.892,0.271,0.235,98.832,0,220.527    c-0.046,42.838,12.652,84.721,36.48,120.32L0.853,426.18c-2.189,5.469,0.47,11.677,5.939,13.867c2.544,1.018,5.383,1.018,7.928,0    l85.333-35.627c101.679,66.676,238.158,38.3,304.834-63.379S443.187,102.883,341.508,36.207z M220.801,419.567    c-0.071,0-0.142,0-0.213,0v0.213h-0.001c-40.532-0.319-80.02-12.886-113.28-36.053c-1.754-1.224-3.835-1.893-5.973-1.92    c-1.338-0.264-2.715-0.264-4.053,0l-66.774,28.587l27.947-66.56c1.424-3.37,1.022-7.236-1.067-10.24    c-23.487-33.021-36.09-72.545-36.053-113.067C21.216,110.482,110.329,21.178,220.374,21.06    c110.044-0.118,199.349,88.995,199.467,199.04C419.959,330.145,330.846,419.449,220.801,419.567z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M288.514,162.764c-4.633-33.756-33.865-58.657-67.927-57.864c-36.795-0.118-66.752,29.552-66.987,66.347    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667c0.471-25.209,21.289-45.263,46.499-44.792    c25.21,0.471,45.263,21.289,44.792,46.499c-0.465,24.874-20.759,44.796-45.637,44.8c-5.891,0-10.667,4.776-10.667,10.667v47.787    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667v-37.973C267.907,233.206,293.543,199.416,288.514,162.764z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <circle cx=\"219.697\" cy=\"325.147\" r=\"11.675\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <\/g><\/svg>\n\n                  <\/div>\n                  <span class=\"text\">Pedir info&shy;rmaci\u00f3n<\/span>\n                <\/a>\n              <\/li>\n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n             \n\n\n<div class=\"container product-series\">\n  <div class=\"product-details\">\n    <div class=\"product-specs\">\n\n      <div class=\"title\">\n        <div class=\"left\">\n                      <h2>Especificaciones de la serie<\/h2>\n                  <\/div>\n        <div class=\"right\">\n                        <div class=\"radio\">\n                                <label for=\"met\" class=\"met\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">M\u00e9trico<\/span>\n                <\/label>\n                <label for=\"imp\" class=\"imp\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Imperial<\/span>\n                <\/label>\n            <\/div>\n            \n\n        <\/div>\n      <\/div>\n\n              \n        <div class=\"outer\">\n          <div class=\"inner\">\n                        <table id=\"series-specs-table\" class=\"series-specs-table-desktop\">\n              <thead>\n                <tr>\n                  <th><\/th>\n                  <th>PM 8521 S<\/th><th>PM 8522 S<\/th><th>PM 8523 S<\/th><th>PM 8524 S<\/th><th>PM 8525 S<\/th>                <\/tr>\n              <\/thead>\n              <tbody>\n                <tr class=\"scaled-metric\"><th>Hoja de especificaciones<\/th><td><a href=\"https:\/\/mediahub.tadano.com\/m\/8975d41d7b4c55f\/original\/doc_tadano_pm_8-5S_8521_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><td><a href=\"https:\/\/mediahub.tadano.com\/m\/6dc517d83517e668\/original\/doc_tadano_pm_8-5S_8522_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><td><a href=\"https:\/\/mediahub.tadano.com\/m\/6fa5440723e0b5af\/original\/doc_tadano_pm_8-5S_8523_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><td><a href=\"https:\/\/mediahub.tadano.com\/m\/61b67dc6a74eb8fb\/original\/doc_tadano_pm_8-5S_8524_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><td><a href=\"https:\/\/mediahub.tadano.com\/m\/1379a29faf8722a\/original\/doc_tadano_pm_8-5S_8525_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><\/tr><tr class=\"scaled-metric\"><th>Presi\u00f3n m\u00e1x.<\/th><td>30,5&nbsp;MPa<\/td><td>30,5&nbsp;MPa<\/td><td>30,5&nbsp;MPa<\/td><td>30,5&nbsp;MPa<\/td><td>30,5&nbsp;MPa<\/td><\/tr><tr class=\"scaled-metric\"><th>Capacidad del dep\u00f3sito de combustible<\/th><td>80&nbsp;l<\/td><td>80&nbsp;l<\/td><td>80&nbsp;l<\/td><td>80&nbsp;l<\/td><td>80&nbsp;l<\/td><\/tr><tr class=\"scaled-metric\"><th>Momento m\u00e1ximo de elevaci\u00f3n<\/th><td>7,3&nbsp;TM<\/td><td>7,1&nbsp;TM<\/td><td>6,9&nbsp;TM<\/td><td>6,6&nbsp;TM<\/td><td>6,5&nbsp;TM<\/td><\/tr><tr class=\"scaled-metric\"><th>Alcance horizontal hidr\u00e1ulico<\/th><td>5,60&nbsp;m<\/td><td>7,60&nbsp;m<\/td><td>9,75&nbsp;m<\/td><td>11,90<\/td><td>14,05&nbsp;m<\/td><\/tr><tr class=\"scaled-metric\"><th>Alcance vertical hidr\u00e1ulico<\/th><td>8,75&nbsp;m<\/td><td>10,65&nbsp;m<\/td><td>12,75&nbsp;m<\/td><td>14,80&nbsp;m<\/td><td>16,85&nbsp;m<\/td><\/tr><tr class=\"scaled-metric\"><th>Caudal de aceite recomendado<\/th><td>30&nbsp;&#8211; 40&nbsp;l\/min<\/td><td>30&nbsp;&#8211; 40&nbsp;l\/min<\/td><td>30&nbsp;&#8211; 40&nbsp;l\/min<\/td><td>30&nbsp;&#8211; 40&nbsp;l\/min<\/td><td>30&nbsp;&#8211; 40&nbsp;l\/min<\/td><\/tr><tr class=\"scaled-metric\"><th>Par de giro<\/th><td>11&nbsp;kN m<\/td><td>11&nbsp;kN m<\/td><td>11&nbsp;kN m<\/td><td>11&nbsp;kN m<\/td><td>11&nbsp;kN m<\/td><\/tr><tr class=\"scaled-metric\"><th>Apertura disponible de estabilizadores<\/th><td>3.4&nbsp;&#8211; 5.0&nbsp;m<\/td><td>3.4&nbsp;&#8211; 5.0&nbsp;m<\/td><td>3.4&nbsp;&#8211; 5.0&nbsp;m<\/td><td>3.4&nbsp;&#8211; 5.0&nbsp;m<\/td><td>3.4&nbsp;&#8211; 5.0&nbsp;m<\/td><\/tr><tr class=\"\"><th>\u00c1ngulo de giro<\/th><td>400\u00b0<\/td><td>400\u00b0<\/td><td>400\u00b0<\/td><td>400\u00b0<\/td><td>400\u00b0<\/td><\/tr><tr class=\"\"><th>Control de estabilizadores por radio inal\u00e1mbrica<\/th><td>Manual<\/td><td>Manual<\/td><td>Manual<\/td><td>Manual<\/td><td>Manual<\/td><\/tr><tr class=\"scaled-imperial\"><th>Momento m\u00e1ximo de elevaci\u00f3n<\/th><td>52910&nbsp;ft Ibs<\/td><td>51380&nbsp;ft Ibs<\/td><td>49750&nbsp;ft Ibs<\/td><td>47620&nbsp;ft Ibs<\/td><td>46860&nbsp;ft Ibs<\/td><\/tr><tr class=\"scaled-imperial\"><th>Alcance horizontal hidr\u00e1ulico<\/th><td>18&#8242;\n  4&#8243;<\/td><td>24&#8242;\n  11&#8243;<\/td><td>32&#8242; <\/td><td>39&#8242;\n  1&#8243;<\/td><td>46&#8242;\n  1&#8243;<\/td><\/tr><tr class=\"scaled-imperial\"><th>Alcance vertical hidr\u00e1ulico<\/th><td>28&#8242;\n  8&#8243;<\/td><td>34&#8242;\n  11&#8243;<\/td><td>41&#8242;\n  10&#8243;<\/td><td>48&#8242;\n  7&#8243;<\/td><td>55&#8242;\n  3&#8243;<\/td><\/tr><tr class=\"scaled-metric\"><th>Ancho<\/th><td>735&nbsp;mm<\/td><td>735&nbsp;mm<\/td><td>735&nbsp;mm<\/td><td>785&nbsp;mm<\/td><td>795&nbsp;mm<\/td><\/tr><tr class=\"scaled-imperial\"><th>Ancho<\/th><td>2&#8242; 5&#8243;<\/td><td>2&#8242; 5&#8243;<\/td><td>2&#8242; 5&#8243;<\/td><td>2&#8242; 7&#8243;<\/td><td>2&#8242; 7&#8243;<\/td><\/tr><tr class=\"scaled-metric\"><th>Altura<\/th><td>2005&nbsp;mm<\/td><td>2005&nbsp;mm<\/td><td>2005&nbsp;mm<\/td><td>2025&nbsp;mm<\/td><td>2075&nbsp;mm<\/td><\/tr><tr class=\"scaled-imperial\"><th>Altura<\/th><td>6&#8242; 7&#8243;<\/td><td>6&#8242; 7&#8243;<\/td><td>6&#8242; 7&#8243;<\/td><td>6&#8242; 8&#8243;<\/td><td>6&#8242; 10&#8243;<\/td><\/tr><tr class=\"scaled-metric\"><th>Longitud<\/th><td>2275&nbsp;mm<\/td><td>2275&nbsp;mm<\/td><td>2275&nbsp;mm<\/td><td>2275&nbsp;mm<\/td><td>2275&nbsp;mm<\/td><\/tr><tr class=\"scaled-imperial\"><th>Longitud<\/th><td>7&#8242; 6&#8243; <\/td><td>7&#8242; 6&#8243; <\/td><td>7&#8242; 6&#8243; <\/td><td>7&#8242; 6&#8243; <\/td><td>7&#8242; 6&#8243; <\/td><\/tr>              <\/tbody>\n            <\/table>\n\n          <\/div>\n        <\/div>\n\n       \n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Descripci\u00f3n del producto<\/h2>\n\n\n\n<p><strong><strong>Gran rendimiento, dise\u00f1o compacto.<\/strong><\/strong><\/p>\n\n\n\n<p>La serie Tadano PM 8.5 S es una gr\u00faa articulada (Serie PM) dise\u00f1ada para la eficiencia y la fiabilidad. Con momentos m\u00e1ximos de elevaci\u00f3n de 6,5 a 7,3 tonelada-metros y un alcance vertical de hasta 17,0 metros, ofrece una impresionante capacidad de elevaci\u00f3n manteniendo unas dimensiones compactas. El equipamiento de serie incluye un bloque de v\u00e1lvulas de mando manual y un limitador de momento hidr\u00e1ulico para un funcionamiento seguro.<\/p>\n\n\n\n<p>Disponible en los modelos 8521 S hasta 8525 S, la serie ofrece alcances horizontales de 5,6 a 14,05 metros. Una versi\u00f3n C con primer brazo retr\u00e1ctil hidr\u00e1ulicamente mejora a\u00fan m\u00e1s la manipulaci\u00f3n de cargas voluminosas o pesadas a corta distancia, optimizando las operaciones bajo la columna de la gr\u00faa. La estabilidad se garantiza con estabilizadores manuales con una apertura de hasta 5,0 metros y giro de 400\u00b0.<\/p>\n\n\n\n<p>Compactas, vers\u00e1tiles y fiables, las gr\u00faas de la serie PM 8.5 S est\u00e1n dise\u00f1adas para afrontar con confianza las operaciones diarias de elevaci\u00f3n m\u00e1s exigentes.<\/p>\n\n\n\n<section class=\"pm-vehicle-type\">\n    <div class=\"container\">\n\n        <div class=\"title\">\n            <div class=\"left\">\n                <h2>Tipo de veh\u00edculo<\/h2>\n            <\/div>\n            <div class=\"right\">\n                                <div class=\"radio ton-lbs-switch\">\n                                        <label class=\"met\">\n                        <input type=\"radio\" name=\"filterScale\">\n                        <span class=\"fake-radio\"><\/span>\n                        <span class=\"fake-label\">ton<\/span>\n                    <\/label>\n                    <label class=\"imp\">\n                        <input type=\"radio\" name=\"filterScale\" >\n                        <span class=\"fake-radio\"><\/span>\n                        <span class=\"fake-label\">lbs<\/span>\n                    <\/label>\n                <\/div>\n                \n\n            <\/div>\n        <\/div>\n\n        <div class=\"pm-vehicle-type-wrapper\">\n            <div class=\"pm-vehicle-type-data\">\n                <ul>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>3.50 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>771617 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>5.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>1102310 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>6.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>1322772 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"li-active li-active-4ss\">\n                            <span class=\"scaled-metric\"><h5>6.50 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>1433003 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"li-active li-active-4ss\">\n                            <span class=\"scaled-metric\"><h5>7.50 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>1653465 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"li-active li-active-4ss\">\n                            <span class=\"scaled-metric\"><h5>8.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>1763696 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"li-active li-active-2xl\">\n                            <span class=\"scaled-metric\"><h5>10.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>2204620 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"li-active li-active-2ss\">\n                            <span class=\"scaled-metric\"><h5>12.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>2645544 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>13.50 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>2976237 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>15.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>3306930 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>18.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>3968316 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>19.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>4188778 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>26.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>5732012 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>32.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>7054784 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>44.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>9700328 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                    <\/ul>\n            <\/div>\n        <\/div>\n\n        <ul class=\"pm-vehicle-type-legend\">\n            <li class=\"legend-item legend-2ss\">2 estabilizadores est\u00e1ndar<\/li>\n            <li class=\"legend-item legend-2xl\">2 estabilizadores XL<\/li>\n            <li class=\"legend-item legend-4ss\">4 estabilizadores<\/li>\n        <\/ul>\n    <\/div>\n    <style type=\"text\/css\">\n        \/* Container styles *\/\n        .pm-vehicle-type {\n            margin: 2rem 0;\n        }\n\n        .pm-vehicle-type .title {\n            display: flex;\n            justify-content: space-between;\n            align-items: end;\n        }\n        .pm-vehicle-type .radio {\n            margin-bottom: 0;\n            width: auto;\n        }\n        \n        .pm-vehicle-type-wrapper {\n            position: relative;\n            background-color: #0042951f;\n            padding: 2rem;\n            border-radius: 4px;\n        }\n        \n        .pm-vehicle-type-data ul {\n            margin: 0;\n            padding: 0;\n            display: flex;\n            flex-wrap: wrap;\n            justify-content: center;\n            list-style: none;\n            gap: 0.5rem;\n        }\n        \n        .pm-vehicle-type-data ul li {\n            display: flex;\n            flex-wrap: wrap;\n            justify-content: center;\n            align-items: center;\n            background-color: #ffffff;\n            text-align: center;\n            padding: 1rem;\n            border: 2px solid #e0e0e0;\n            border-radius: 4px;\n            transition: all 0.3s ease;\n            width: 115px;\n            height: 115px;\n            border-radius: 100%;\n\n        }\n        \n        .pm-vehicle-type-data ul li h5 {\n            margin: 0;\n            font-size: 1.75rem;\n            color: #004295;\n            font-weight: 600;\n            line-height: 1;\n        }\n        \n        .pm-vehicle-type-data ul li h5 span {\n            display: block;\n            font-size: 1.5rem;\n            font-weight: 400;\n            margin-top: 0.25rem;\n        }\n        \n        \/* Active state styles *\/\n        .pm-vehicle-type-data ul li.li-active {\n            border: 3px solid #ff8400;\n            border-width: 3px;\n            box-shadow: 0 2px 8px rgba(255, 132, 0, 0.2);\n        }\n        \n        .pm-vehicle-type-data ul li.li-active-2xl {\n            border-color: #85bf76;\n            box-shadow: 0 2px 8px rgba(133, 191, 118, 0.2);\n        }\n\n        .pm-vehicle-type-data ul li.li-active-4ss {\n            border-color: #1f96cd;\n            box-shadow: 0 2px 8px rgba(31, 150, 205, 0.2);\n        }\n        \n        \/* Legend styles *\/\n        .pm-vehicle-type-legend {\n            position: relative;\n            margin: 1rem 0 0 0;\n            padding: 0;\n            display: flex;\n            flex-wrap: wrap;\n            list-style: none;\n            gap: 1rem;\n            justify-content: center;\n        }\n        \n        .pm-vehicle-type-legend li {\n            position: relative;\n            padding-left: 1.5rem;\n            font-size: 1.5rem;\n            font-weight: bold;\n        }\n        \n        .pm-vehicle-type-legend li::before {\n            content: '';\n            position: absolute;\n            left: 0;\n            top: 50%;\n            transform: translateY(-50%);\n            width: 1rem;\n            height: 1rem;\n            border: 3px solid;\n            border-radius: 50%;\n        }\n        \n        .pm-vehicle-type-legend li.legend-2ss::before {\n            border-color: #ff8400;\n            background-color: #ff8400;\n        }\n        \n        .pm-vehicle-type-legend li.legend-2xl::before {\n            border-color: #85bf76;\n            background-color: #85bf76;\n        }\n\n        .pm-vehicle-type-legend li.legend-4ss::before {\n            border-color: #1f96cd;\n            background-color: #1f96cd;\n        }\n        \n        @media (max-width: 1075px) {\n            .pm-vehicle-type-data ul li {\n                width: 90px;\n                height: 90px;\n            }\n            .pm-vehicle-type-data ul li h5 {\n                font-size: 1.6rem;\n            }\n        }\n        @media (max-width: 768px) {\n            .pm-vehicle-type-data ul li {\n                padding: 0.75rem;\n                width: 80px;\n                height: 80px;\n            }\n            \n            .pm-vehicle-type-data ul li h5 {\n                font-size: 1.5rem;\n            }\n            .pm-vehicle-type-data ul li h5 span {\n                font-size: 1rem;\n            }\n        }\n    <\/style>\n\n    <script type=\"text\/javascript\">\n        (function() {\n            \/\/ Handle unit switching for ton\/lbs toggle\n            const tonLbsSwitch = document.querySelector('.ton-lbs-switch');\n            \n            if (tonLbsSwitch) {\n                const metricRadio = tonLbsSwitch.querySelector('label.met input[type=\"radio\"]');\n                const imperialRadio = tonLbsSwitch.querySelector('label.imp input[type=\"radio\"]');\n                \n                \/\/ Function to update body classes\n                function updateUnitClass(isImperial) {\n                    if (isImperial) {\n                        document.body.classList.remove('unit-is-met');\n                        document.body.classList.add('unit-is-imp');\n                        \/\/ Set cookie for 30 days\n                        document.cookie = 'measuringUnit=imp; path=\/; max-age=' + (30 * 24 * 60 * 60);\n                    } else {\n                        document.body.classList.remove('unit-is-imp');\n                        document.body.classList.add('unit-is-met');\n                        \/\/ Set cookie for 30 days\n                        document.cookie = 'measuringUnit=met; path=\/; max-age=' + (30 * 24 * 60 * 60);\n                    }\n                }\n                \n                \/\/ Add event listeners\n                if (metricRadio) {\n                    metricRadio.addEventListener('change', function() {\n                        if (this.checked) {\n                            updateUnitClass(false);\n                        }\n                    });\n                }\n                \n                if (imperialRadio) {\n                    imperialRadio.addEventListener('change', function() {\n                        if (this.checked) {\n                            updateUnitClass(true);\n                        }\n                    });\n                }\n            }\n        })();\n    <\/script>\n<\/section>\n\n\n\n<section class=\"file-download-block\">\n    <div class=\"container\">\n        <div class=\"file-download-wrapper\">\n            <div class=\"select-field\">\n                <label for=\"file-download-select\" class=\"hidden\">Select a file<\/label>\n                <select name=\"file-download-select\" id=\"file-download-select\" class=\"file-download-select\">\n                    <option value=\"\">Seleccione un archivo<\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/72605ea288deb12d\/original\/doc_tadano_pm_8-5S_brochure.pdf\" data-file-id=\"file-0\">\n                            Brochure PM 8.5 S                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/8975d41d7b4c55f\/original\/doc_tadano_pm_8-5S_8521_specsheet.pdf\" data-file-id=\"file-1\">\n                            PM 8521 S                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/6dc517d83517e668\/original\/doc_tadano_pm_8-5S_8522_specsheet.pdf\" data-file-id=\"file-2\">\n                            PM 8522 S                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/6fa5440723e0b5af\/original\/doc_tadano_pm_8-5S_8523_specsheet.pdf\" data-file-id=\"file-3\">\n                            PM 8523 S                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/61b67dc6a74eb8fb\/original\/doc_tadano_pm_8-5S_8524_specsheet.pdf\" data-file-id=\"file-4\">\n                            PM 8524 S                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/1379a29faf8722a\/original\/doc_tadano_pm_8-5S_8525_specsheet.pdf\" data-file-id=\"file-5\">\n                            PM 8525 S                        <\/option>\n                                    <\/select>\n            <\/div>\n            \n            <button type=\"button\" class=\"btn btn-primary file-download-button\" disabled>\n                Descargar            <\/button>\n        <\/div>\n    <\/div>\n<\/section>\n\n<script>\n(function() {\n    const select = document.getElementById('file-download-select');\n    const button = document.querySelector('.file-download-button');\n    \n    if (!select || !button) return;\n    \n    \/\/ Enable\/disable button based on selection\n    select.addEventListener('change', function() {\n        if (this.value) {\n            button.disabled = false;\n        } else {\n            button.disabled = true;\n        }\n    });\n    \n    \/\/ Handle download button click\n    button.addEventListener('click', function() {\n        const selectedUrl = select.value;\n        if (selectedUrl) {\n            \/\/ Create a temporary link and trigger download\n            const link = document.createElement('a');\n            link.href = selectedUrl;\n            link.target = '_blank';\n            document.body.appendChild(link);\n            link.click();\n            document.body.removeChild(link);\n        }\n    });\n})();\n<\/script>\n\n<style>\n.file-download-block {\n    padding: 2rem 0;\n    position: relative!important;\n    z-index: 6!important;\n}\n\n.file-download-block .file-download-wrapper {\n    display: flex;\n    gap: 1rem;\n    align-items: center;\n    flex-wrap: wrap;\n}\n.file-download-block .select-field {\n    min-width: 250px;\n    width: 380px;\n    max-width: 100%;\n\n}\n.file-download-block .jcf-select {\n    background-color: #e3e3e3;\n    margin-bottom: 0;\n}\n.file-download-block .jcf-list {\n    background-color: #f2f2f2;\n}\n\n.file-download-block .file-download-select {\n    min-width: 250px;\n}\n\n.file-download-block .file-download-button {\n    white-space: nowrap;\n}\n\n.file-download-block .file-download-button:disabled {\n    opacity: 0.5;\n    cursor: not-allowed;\n}\n<\/style>\n\n\n<section class=\"product-equipment related-products\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>Equipamiento<\/h2>\n      <\/div>\n     <div class=\"r-products\">\n                                        <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/31c4db996f88d773\/gallery_thumb-img_tadano_pm_components_rack.jpg, https:\/\/mediahub.tadano.com\/m\/31c4db996f88d773\/gallery_thumb-img_tadano_pm_components_rack.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Cremallera<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Est\u00e1ndar<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/733626a9ab2fb16c\/gallery_thumb-img_tadano_pm_components_single_connecting_rod.jpg, https:\/\/mediahub.tadano.com\/m\/733626a9ab2fb16c\/gallery_thumb-img_tadano_pm_components_single_connecting_rod.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Biela simple<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Est\u00e1ndar<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/3f8e30a969970aaf\/gallery_thumb-img_tadano_pm_components_hose_racks.jpg, https:\/\/mediahub.tadano.com\/m\/3f8e30a969970aaf\/gallery_thumb-img_tadano_pm_components_hose_racks.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Soportes para mangueras<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Opcional<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/bb7ba8377a84d11\/gallery_thumb-img_tadano_pm_components_hydraulic_flip_up_outriggers.jpg, https:\/\/mediahub.tadano.com\/m\/bb7ba8377a84d11\/gallery_thumb-img_tadano_pm_components_hydraulic_flip_up_outriggers.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Estabilizadores hidr\u00e1ulicos abatibles<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Opcional<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/5eaf0e8d9b34ab8c\/gallery_thumb-img_tadano_pm_components_multi_function_radio_control.jpg, https:\/\/mediahub.tadano.com\/m\/5eaf0e8d9b34ab8c\/gallery_thumb-img_tadano_pm_components_multi_function_radio_control.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Radiocontrol multifunci\u00f3n<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Opcional<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <\/div>\n\n    <style type=\"text\/css\">\n        .product-equipment .r-product-single .r-product-single-wrapper {\n            display: flex;\n            flex-direction: row;\n            min-height: 0;\n            padding-left: 0;\n        }\n        .product-equipment .r-product-single:hover .text-block {\n            background-color: transparent;\n        }\n        .product-equipment .r-product-single .title {\n            letter-spacing: 0;\n            line-height: 1.3;\n        }\n        .product-equipment .r-product-single .img-holder {\n            position: relative;\n            width: 70px;\n            height: 70px;\n            margin: 10px;\n            flex-grow: 0;\n            flex-shrink: 0;\n        }\n        .product-equipment .r-product-single .text-block {\n            padding: 7px 10px 10px 0;\n            font-size: 14px;\n            line-height: 1;\n        }\n        \n    <\/style>\n<\/section>\n\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Galer\u00eda de medios<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/a0e1f0b35287096\/gallery_full-img_tadano_pm_8-5S-1.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/a0e1f0b35287096\/gallery_thumb-img_tadano_pm_8-5S-1.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n\n\n\n\n\n\n\n\n\n\n  <section class=\"related-products related-pages\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>P\u00e1ginas relacionadas<\/h2>\n      <\/div>\n\n      <div class='r-products'>\n                  \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-8\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/2dc7a9accb487156\/img_thumb-img_tadano_pm_8-2.jpg, https:\/\/mediahub.tadano.com\/m\/2dc7a9accb487156\/img_thumb_2x-img_tadano_pm_8-2.jpg 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">PM 8<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                            \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-8-5-p\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/5c4fdf1ad0d33e09\/img_thumb-img_tadano_pm_8-5P-1.jpg, https:\/\/mediahub.tadano.com\/m\/5c4fdf1ad0d33e09\/img_thumb_2x-img_tadano_pm_8-5P-1.jpg 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">PM 8.5 P<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                            \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-8-5-s-c\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/b439c4cae0a2edc\/img_thumb-img_tadano_pm_8-5SC-1.jpg, https:\/\/mediahub.tadano.com\/m\/b439c4cae0a2edc\/img_thumb_2x-img_tadano_pm_8-5SC-1.jpg 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">PM 8.5 S C<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                        <\/div>\n        \n    <\/div>\n  <\/section>\n  \n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>Noticias<\/h2>\n                        \n                  <a href=\"https:\/\/www.tadano.com\/europe\/es\/acerca-de\/news-list\/\" class=\"link-more\">EXPLORAR TODAS las noticias<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/es\/news\/la-nueva-grua-todo-terreno-tadano-ac-5-250l-2\/\">\n                  <strong class=\"title\">La nueva gr\u00faa todo terreno Tadano AC 5.250L-2<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Feb\/17\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/es\/news\/grua-tadano-ac-7-450-1-cumple-doble-funcion-en-wisconsin\/\">\n                  <strong class=\"title\">GR\u00daA TADANO AC 7.450-1 cumple doble funci\u00f3n en Wisconsin<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Nov\/12\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/es\/news\/la-nueva-tadano-ac-5-250-2-convence-con-soluciones-innovadoras\/\">\n                  <strong class=\"title\">La nueva Tadano AC 5.250-2 convence con soluciones innovadoras<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  ","protected":false},"featured_media":0,"template":"","lifting-equipment":[116],"class_list":["post-13937","products","type-products","status-publish","hentry","lifting-equipment-knuckle-boom-cranes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PM 8.5 S - Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-8-5-s\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PM 8.5 S - Europe\" \/>\n<meta property=\"og:description\" content=\"Descripci\u00f3n del producto Gran rendimiento, dise\u00f1o compacto. La serie Tadano PM 8.5 S es una gr\u00faa articulada (Serie PM) dise\u00f1ada para la eficiencia y la fiabilidad. Con momentos m\u00e1ximos de elevaci\u00f3n de 6,5 a 7,3 tonelada-metros y un alcance vertical de hasta 17,0 metros, ofrece una impresionante capacidad de elevaci\u00f3n manteniendo unas dimensiones compactas. El [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-8-5-s\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T19:07:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/lifting-equipment\\\/knuckle-boom-cranes\\\/pm-8-5-s\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/lifting-equipment\\\/knuckle-boom-cranes\\\/pm-8-5-s\\\/\",\"name\":\"PM 8.5 S - Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\"},\"datePublished\":\"2025-10-29T12:26:18+00:00\",\"dateModified\":\"2026-02-25T19:07:38+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/lifting-equipment\\\/knuckle-boom-cranes\\\/pm-8-5-s\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/\",\"name\":\"Europe\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PM 8.5 S - Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-8-5-s\/","og_locale":"es_ES","og_type":"article","og_title":"PM 8.5 S - Europe","og_description":"Descripci\u00f3n del producto Gran rendimiento, dise\u00f1o compacto. La serie Tadano PM 8.5 S es una gr\u00faa articulada (Serie PM) dise\u00f1ada para la eficiencia y la fiabilidad. Con momentos m\u00e1ximos de elevaci\u00f3n de 6,5 a 7,3 tonelada-metros y un alcance vertical de hasta 17,0 metros, ofrece una impresionante capacidad de elevaci\u00f3n manteniendo unas dimensiones compactas. El [&hellip;]","og_url":"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-8-5-s\/","og_site_name":"Europe","article_modified_time":"2026-02-25T19:07:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-8-5-s\/","url":"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-8-5-s\/","name":"PM 8.5 S - Europe","isPartOf":{"@id":"https:\/\/www.tadano.com\/europe\/en\/#website"},"datePublished":"2025-10-29T12:26:18+00:00","dateModified":"2026-02-25T19:07:38+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-8-5-s\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/europe\/en\/#website","url":"https:\/\/www.tadano.com\/europe\/en\/","name":"Europe","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/europe\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/products\/13937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/products\/13937\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/media?parent=13937"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/lifting-equipment?post=13937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}