{"id":12119,"date":"2024-04-25T10:28:38","date_gmt":"2024-04-25T10:28:38","guid":{"rendered":"https:\/\/www.tadano.com\/europe\/retrofit-kits\/boom-booster-para-cc\/"},"modified":"2026-06-16T12:33:06","modified_gmt":"2026-06-16T12:33:06","slug":"boom-booster-para-cc","status":"publish","type":"retrofit-kits","link":"https:\/\/www.tadano.com\/europe\/es\/retrofit-kits\/boom-booster-para-cc\/","title":{"rendered":"Boom Booster para CC"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\t\t<style type=\"text\/css\">\n\t\t\t.hero-section .img-holder:before {\n\t\t\t\tdisplay: none;\n\t\t\t}\n\t\t<\/style>\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 0 0; \">\n\t\t\t<span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/hero\/CC+8800-1+Boom+Booster+US+3.jpg, https:\/\/assets.onetadano.com\/celum_assets\/hero-2x\/CC+8800-1+Boom+Booster+US+3.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder \">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/europe\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\"><a href=\"https:\/\/www.demagmobilecranes.com\/en\/demag-technology\/cc-3800-1-boom-booster\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><span style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Boom Booster para CC<\/span><\/h1>\n\n\n\n<p>Con los kits Boom Booster se puede aumentar significativamente la capacidad de elevaci\u00f3n de las gr\u00faas sobre orugas con pluma de celos\u00eda Tadano CC 38.650-1, CC 68.1250-1 y CC 88.1600-1 para realizar elevaciones pesadas con configuraciones de pluma larga.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<div class=\"wp-block-group is-style-background-triangle-right\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p><strong>Boom Booster para CC 38.650-1: El Boom Booster aumenta la rigidez y mejora la capacidad de elevaci\u00f3n<\/strong><\/p>\n\n\n\n<p>Los kits opcionales Boom Booster, disponibles en varias versiones, llevan la CC 38.650-1 a un nivel superior, permitiendo realizar elevaciones que normalmente requieren gr\u00faas de 750 toneladas. Dependiendo de la configuraci\u00f3n, se pueden obtener incrementos de capacidad de elevaci\u00f3n de hasta un 65,3%. Esto resulta en una impresionante altura m\u00e1xima de gancho de 174,5 m y permite levantar cargas de hasta 92,5 t, lo que la hace ideal para el montaje de grandes aerogeneradores. Los kits est\u00e1n disponibles en longitudes de entre 24 y 102 m. Las secciones de 12 m facilitan el transporte y el montaje, mientras que el sistema de protecci\u00f3n antica\u00eddas asegura la seguridad.<\/p>\n\n\n\n<p><strong>CC 68.1250-1 Boom Booster: M\u00e1s capacidad de carga, m\u00e1s alcance, m\u00e1s rentabilidad<\/strong><\/p>\n\n\n\n<p>El Boom Booster aumenta la capacidad de carga de la ya de por s\u00ed potente CC 68.1250-1 en hasta un 30%, \u00a1incluso en el plum\u00edn! Laltura m\u00e1xima del gancho aumenta de 180 a 194 m y el peso m\u00e1ximo de la carga de 98 a m\u00e1s de 100 t para esa altura de gancho. Esto significa que la CC 68.1250-1 puede montar aerogeneradores con alturas de buje de hasta 185 metros. Un punto destacado es el dise\u00f1o optimizado para el transporte, que permite dividir y reducir la anchura de sistema de los componentes de 5,40 metros a 3,5 metros, apta para circular. El Boom Booster tambi\u00e9n est\u00e1 disponible para la CC 68.1250-1 como accesorio para gr\u00faas nuevas o como reequipamiento. El dise\u00f1o preparado para el futuro ya est\u00e1 pensado para que pueda ser usado en futuros modelos de gr\u00faas de esta clase.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-outline-white\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mediahub.tadano.com\/asset\/9cdd6c35-4f29-4553-a926-d13861a06471\/doc_tadano_CC681250-1-boom-booster_datasheet_metric_en-de-fr-it-es-pt-ru.pdf\">Hoja de especificaciones \u2013&nbsp;<strong>Boom Booster para CC 68.1250-1<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p><br><\/p>\n\n\n\n<p><strong>Boom Booster para CC 88.1600-1: Para proyectos con configuraciones de pluma largas y empinadas<\/strong><\/p>\n\n\n\n<p>El kit Boom Booster para la gr\u00faa sobre orugas CC 88.1600-1 eleva el rendimiento a nuevos niveles, especialmente cuando se trabaja con configuraciones de pluma largas y empinadas. Este kit aumenta la capacidad de elevaci\u00f3n de la CC 88.1600-1 hasta en un 90%, lo que le permite superar a cualquier gr\u00faa del rango de capacidad de 1000 \u2013 2000&nbsp;t, as\u00ed como a gr\u00faas del rango de capacidad de 3000&nbsp;t en determinadas condiciones. El kit Boom Booster para la CC 88.1600-1 es imprescindible para aplicaciones de elevaci\u00f3n de cargas pesadas con configuraciones de pluma largas, como por ejemplo, en proyectos petroqu\u00edmicos, montaje de turbinas e\u00f3licas e instalaci\u00f3n de centrales el\u00e9ctricas.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-outline-white\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mediahub.tadano.com\/asset\/ad3d0f2d-fdfa-4b01-8cd7-47fa85a7659b\/doc_tadano_CC881600-1-boom-booster_datasheet_metric_en-de-fr-it-es-pt-ru.pdf\">Hoja de especificaciones \u2013&nbsp;<strong>Boom Booster para CC 88.1600-1<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n\n\n\n\n\n\n\n<\/div><\/div>\n\n\n\n\n    <section class=\"related-products related-products\">\n        <div class=\"container\">\n            <div class=\"heading\">\n                <h2>Productos relacionados<\/h2>\n            <\/div>\n            <div class='r-products'>\n            \n                                <div class='r-product-single'>\n                    <a href='https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-38-650-1\/'>\n                        <div class=\"img-holder\">\n                                                            <div class=\"bg-stretch\" style=\"background-size:contain\">\n                                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/3cbee7136cd0e2b2\/img_thumb-img_tadano_CC38650_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/3cbee7136cd0e2b2\/img_thumb_2x-img_tadano_CC38650_cutout_side.png 2x\"><\/span>\n                                <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">CC 38.650-1<\/strong>\n                        <\/div>\n                    <\/a>\n                <\/div>\n            \n                                <div class='r-product-single'>\n                    <a href='https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-68-1250-1\/'>\n                        <div class=\"img-holder\">\n                                                            <div class=\"bg-stretch\" style=\"background-size:contain\">\n                                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/68b50bfda304ad98\/img_thumb-img_tadano_CC681250_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/68b50bfda304ad98\/img_thumb_2x-img_tadano_CC681250_cutout_side.png 2x\"><\/span>\n                                <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">CC 68.1250-1<\/strong>\n                        <\/div>\n                    <\/a>\n                <\/div>\n            \n                                <div class='r-product-single'>\n                    <a href='https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-88-1600-1\/'>\n                        <div class=\"img-holder\">\n                                                            <div class=\"bg-stretch\" style=\"background-size:contain\">\n                                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/5a073a9f4d1dbadd\/img_thumb-img_tadano_CC881600-1_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/5a073a9f4d1dbadd\/img_thumb_2x-img_tadano_CC881600-1_cutout_side.png 2x\"><\/span>\n                                <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">CC 88.1600-1<\/strong>\n                        <\/div>\n                    <\/a>\n                <\/div>\n                        <\/div>\n        <\/div>\n    <\/section>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Boom Booster para CC 38.650-1: El Boom Booster aumenta la rigidez y mejora la capacidad de elevaci\u00f3n Los kits opcionales Boom Booster, disponibles en varias versiones, llevan la CC 38.650-1 a un nivel superior, permitiendo realizar elevaciones que normalmente requieren gr\u00faas de 750 toneladas. Dependiendo de la configuraci\u00f3n, se pueden obtener incrementos de capacidad de [&hellip;]<\/p>\n","protected":false},"template":"","class_list":["post-12119","retrofit-kits","type-retrofit-kits","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boom Booster para CC - Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/europe\/es\/retrofit-kits\/boom-booster-para-cc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boom Booster para CC - Europe\" \/>\n<meta property=\"og:description\" content=\"Boom Booster para CC 38.650-1: El Boom Booster aumenta la rigidez y mejora la capacidad de elevaci\u00f3n Los kits opcionales Boom Booster, disponibles en varias versiones, llevan la CC 38.650-1 a un nivel superior, permitiendo realizar elevaciones que normalmente requieren gr\u00faas de 750 toneladas. Dependiendo de la configuraci\u00f3n, se pueden obtener incrementos de capacidad de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/europe\/es\/retrofit-kits\/boom-booster-para-cc\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-16T12:33:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/retrofit-kits\\\/boom-booster-para-cc\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/retrofit-kits\\\/boom-booster-para-cc\\\/\",\"name\":\"Boom Booster para CC - Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\"},\"datePublished\":\"2024-04-25T10:28:38+00:00\",\"dateModified\":\"2026-06-16T12:33:06+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/retrofit-kits\\\/boom-booster-para-cc\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/\",\"name\":\"Europe\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boom Booster para CC - Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/europe\/es\/retrofit-kits\/boom-booster-para-cc\/","og_locale":"es_ES","og_type":"article","og_title":"Boom Booster para CC - Europe","og_description":"Boom Booster para CC 38.650-1: El Boom Booster aumenta la rigidez y mejora la capacidad de elevaci\u00f3n Los kits opcionales Boom Booster, disponibles en varias versiones, llevan la CC 38.650-1 a un nivel superior, permitiendo realizar elevaciones que normalmente requieren gr\u00faas de 750 toneladas. Dependiendo de la configuraci\u00f3n, se pueden obtener incrementos de capacidad de [&hellip;]","og_url":"https:\/\/www.tadano.com\/europe\/es\/retrofit-kits\/boom-booster-para-cc\/","og_site_name":"Europe","article_modified_time":"2026-06-16T12:33:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/europe\/es\/retrofit-kits\/boom-booster-para-cc\/","url":"https:\/\/www.tadano.com\/europe\/es\/retrofit-kits\/boom-booster-para-cc\/","name":"Boom Booster para CC - Europe","isPartOf":{"@id":"https:\/\/www.tadano.com\/europe\/en\/#website"},"datePublished":"2024-04-25T10:28:38+00:00","dateModified":"2026-06-16T12:33:06+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/europe\/es\/retrofit-kits\/boom-booster-para-cc\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/europe\/en\/#website","url":"https:\/\/www.tadano.com\/europe\/en\/","name":"Europe","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/europe\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/retrofit-kits\/12119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/retrofit-kits"}],"about":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/types\/retrofit-kits"}],"version-history":[{"count":1,"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/retrofit-kits\/12119\/revisions"}],"predecessor-version":[{"id":15989,"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/retrofit-kits\/12119\/revisions\/15989"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/media?parent=12119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}