{"id":13303,"date":"2025-05-20T07:34:36","date_gmt":"2025-05-20T07:34:36","guid":{"rendered":"https:\/\/www.tadano.com\/europe\/technologies\/heytadano\/"},"modified":"2025-05-20T13:45:27","modified_gmt":"2025-05-20T13:45:27","slug":"heytadano","status":"publish","type":"technologies","link":"https:\/\/www.tadano.com\/europe\/es\/technologies\/heytadano\/","title":{"rendered":"HeyTadano"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\t\t<style type=\"text\/css\">\n\t\t\t.hero-section .img-holder:before {\n\t\t\t\tdisplay: none;\n\t\t\t}\n\t\t<\/style>\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 100% 0; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/1f62fab026da7ca1\/hero-img_tadano_heytadano_02.jpg, https:\/\/mediahub.tadano.com\/m\/1f62fab026da7ca1\/hero_2x-img_tadano_heytadano_02.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder \">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/europe\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\"><span style=\"text-transform: lowercase;\" class=\"custom-lowercase\">hey<\/span>TADANO<\/h1>\n\n\n\n<p>Asistente de gr\u00faa con inteligencia artificial para acceder al instante a los conocimientos de Tadano. Disponible en cualquier momento y lugar, en la obra o en la oficina.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/hey.tadano.tools\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lanzar <span style=\"text-transform: lowercase;\" class=\"custom-lowercase\">Hey<\/span>TADANO<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mediahub.tadano.com\/m\/135552f32171d85e\/original\/doc_tadano_heyTADANO_Imagebrochure_en.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">VER FOLLETO<\/a><\/div>\n<\/div>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<div class=\"wp-block-group is-style-background-triangle-right\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p><strong>EL CONOCIMIENTO A SU ALCANCE<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>El tiempo es oro en la obra. Ya se trate de instrucciones de funcionamiento, soluci\u00f3n de problemas o informaci\u00f3n general sobre gr\u00faas, es fundamental obtener la respuesta correcta con rapidez. Por eso Tadano ha desarrollado heyTADANO, un asistente inteligente basado en inteligencia artificial y formado exclusivamente en la documentaci\u00f3n oficial de Tadano.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Disponible 24\/7, proporciona informaci\u00f3n r\u00e1pida, fiable y precisa directamente desde la base de conocimientos de Tadano. Es su recurso de referencia para una asistencia de gr\u00faa m\u00e1s r\u00e1pida e inteligente, sin conjeturas ni retrasos.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img decoding=\"async\" src=\"https:\/\/mediahub.tadano.com\/m\/41bb183879eb233e\/original\/img_tadano_heytadano_04.jpg\" alt=\"\"\/><figcaption class=\"wp-element-caption\"><mark style=\"background-color:#004295\" class=\"has-inline-color has-white-color\">heyTADANO<\/mark><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/mediahub.tadano.com\/m\/3b83f58687efef07\/original\/img_tadano_heytadano_05.jpg\" alt=\"\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p><strong>SOPORTE MULTILING\u00dcE<\/strong><br>heyTADANO rompe las barreras ling\u00fc\u00edsticas. Compatible con m\u00e1s de 50 idiomas, garantiza una comunicaci\u00f3n clara con equipos internacionales y facilita m\u00e1s que nunca el trabajo transfronterizo.<\/p>\n\n\n\n<p><strong>ACCESO INSTANT\u00c1NEO, EN CUALQUIER MOMENTO Y LUGAR<\/strong><br>Accesible desde su tel\u00e9fono, tableta o PC, heyTADANO est\u00e1 siempre a unos pocos clics de distancia. No es necesario consultar manuales ni llamar al servicio de asistencia: basta con hacer una pregunta y obtener la respuesta, incluso en lugares de trabajo remotos.<\/p>\n\n\n\n<p><strong>IMPULSADO POR RECURSOS TADANO APROBADOS<\/strong><br>A diferencia de los motores de b\u00fasqueda gen\u00e9ricos, heyTADANO s\u00f3lo hace referencia a materiales Tadano verificados. Esto significa que todas las respuestas que obtenga son fiables, precisas y relevantes para su gr\u00faa Tadano espec\u00edfica.<\/p>\n<\/div>\n<\/div>\n\n\n<section class=\"video-block\">\n  <div class=\"video-box\">\n        <a aria-labelledby=\"video-txt\" data-fancybox href=\"https:\/\/www.youtube.com\/watch?v=2EqHe1zb3vM\" class=\"video\">\n      <span class=\"play-btn\"><\/span>\n              <div class=\"bg-stretch\" >\n          <span data-srcset=\"https:\/\/img.youtube.com\/vi\/2EqHe1zb3vM\/hqdefault.jpg, https:\/\/img.youtube.com\/vi\/2EqHe1zb3vM\/hqdefault.jpg 2x\"><\/span>\n        <\/div>\n          <\/a>\n    <div class=\"video-txt\">\n                    <a href=\"https:\/\/www.youtube.com\/watch?v=2EqHe1zb3vM\" class=\"video-link\">Ver ahora<\/a>\n          <\/div>\n  <\/div>\n<\/section><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Asistente de gr\u00faa con inteligencia artificial para acceder al instante a los conocimientos de Tadano. Disponible en cualquier momento y lugar, en la obra o en la oficina.<\/p>\n","protected":false},"template":"","class_list":["post-13303","technologies","type-technologies","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HeyTadano - Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/europe\/es\/technologies\/heytadano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HeyTadano - Europe\" \/>\n<meta property=\"og:description\" content=\"Asistente de gr\u00faa con inteligencia artificial para acceder al instante a los conocimientos de Tadano. Disponible en cualquier momento y lugar, en la obra o en la oficina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/europe\/es\/technologies\/heytadano\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T13:45:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediahub.tadano.com\/m\/41bb183879eb233e\/original\/img_tadano_heytadano_04.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/technologies\\\/heytadano\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/technologies\\\/heytadano\\\/\",\"name\":\"HeyTadano - Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/technologies\\\/heytadano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/technologies\\\/heytadano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediahub.tadano.com\\\/m\\\/41bb183879eb233e\\\/original\\\/img_tadano_heytadano_04.jpg\",\"datePublished\":\"2025-05-20T07:34:36+00:00\",\"dateModified\":\"2025-05-20T13:45:27+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/technologies\\\/heytadano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/es\\\/technologies\\\/heytadano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediahub.tadano.com\\\/m\\\/41bb183879eb233e\\\/original\\\/img_tadano_heytadano_04.jpg\",\"contentUrl\":\"https:\\\/\\\/mediahub.tadano.com\\\/m\\\/41bb183879eb233e\\\/original\\\/img_tadano_heytadano_04.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/\",\"name\":\"Europe\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HeyTadano - Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/europe\/es\/technologies\/heytadano\/","og_locale":"es_ES","og_type":"article","og_title":"HeyTadano - Europe","og_description":"Asistente de gr\u00faa con inteligencia artificial para acceder al instante a los conocimientos de Tadano. Disponible en cualquier momento y lugar, en la obra o en la oficina.","og_url":"https:\/\/www.tadano.com\/europe\/es\/technologies\/heytadano\/","og_site_name":"Europe","article_modified_time":"2025-05-20T13:45:27+00:00","og_image":[{"url":"https:\/\/mediahub.tadano.com\/m\/41bb183879eb233e\/original\/img_tadano_heytadano_04.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/europe\/es\/technologies\/heytadano\/","url":"https:\/\/www.tadano.com\/europe\/es\/technologies\/heytadano\/","name":"HeyTadano - Europe","isPartOf":{"@id":"https:\/\/www.tadano.com\/europe\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tadano.com\/europe\/es\/technologies\/heytadano\/#primaryimage"},"image":{"@id":"https:\/\/www.tadano.com\/europe\/es\/technologies\/heytadano\/#primaryimage"},"thumbnailUrl":"https:\/\/mediahub.tadano.com\/m\/41bb183879eb233e\/original\/img_tadano_heytadano_04.jpg","datePublished":"2025-05-20T07:34:36+00:00","dateModified":"2025-05-20T13:45:27+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/europe\/es\/technologies\/heytadano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tadano.com\/europe\/es\/technologies\/heytadano\/#primaryimage","url":"https:\/\/mediahub.tadano.com\/m\/41bb183879eb233e\/original\/img_tadano_heytadano_04.jpg","contentUrl":"https:\/\/mediahub.tadano.com\/m\/41bb183879eb233e\/original\/img_tadano_heytadano_04.jpg"},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/europe\/en\/#website","url":"https:\/\/www.tadano.com\/europe\/en\/","name":"Europe","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/europe\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/technologies\/13303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/technologies"}],"about":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/types\/technologies"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/technologies\/13303\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/europe\/es\/wp-json\/wp\/v2\/media?parent=13303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}