{"id":14290,"date":"2025-10-30T22:01:33","date_gmt":"2025-10-30T21:01:33","guid":{"rendered":"https:\/\/www.tadano.com\/europe\/%term%\/%cat%\/tp\/"},"modified":"2026-03-12T13:28:31","modified_gmt":"2026-03-12T13:28:31","slug":"tp","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/europe\/fr\/lifting-equipment\/knuckle-boom-cranes\/tp\/","title":{"rendered":"TP"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 0 100%; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/4063873e464c3b3e\/hero-img_tadano_pm_20-5TP-2.jpg, https:\/\/mediahub.tadano.com\/m\/4063873e464c3b3e\/hero_2x-img_tadano_pm_20-5TP-2.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/europe\/fr\/\">Accueil<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">TP<\/h1>\n\n\n\n<p>La gamme TP propose des grues solides, simples et fiables, con\u00e7ues sp\u00e9cifiquement pour des op\u00e9rations intensives et r\u00e9p\u00e9titives dans les travaux publics et la logistique heavy-duty.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/europe\/fr\/ventes-services\/ventes\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Comparer les produits<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"fr\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"16\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"116\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">S\u00e9lectionner un produit<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">S\u00e9lectionner un produit<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14078\" data-group=\"\">PM 10 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14082\" data-group=\"\">PM 10 S C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14253\" data-group=\"\">PM 100 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14086\" data-group=\"\">PM 11<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14090\" data-group=\"\">PM 11 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14094\" data-group=\"\">PM 11 SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14098\" data-group=\"\">PM 11.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14106\" data-group=\"\">PM 12.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14114\" data-group=\"\">PM 13.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14118\" data-group=\"\">PM 15.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14278\" data-group=\"\">PM 150 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14122\" data-group=\"\">PM 16.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14137\" data-group=\"\">PM 18 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14141\" data-group=\"\">PM 19<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13827\" data-group=\"\">PM 2.8<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14145\" data-group=\"\">PM 21<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14149\" data-group=\"\">PM 21.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14282\" data-group=\"\">PM 210 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14168\" data-group=\"\">PM 23 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14172\" data-group=\"\">PM 23.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14181\" data-group=\"\">PM 24 PX<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14185\" data-group=\"\">PM 26.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14189\" data-group=\"\">PM 28.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13838\" data-group=\"\">PM 3 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13842\" data-group=\"\">PM 3.6<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13846\" data-group=\"\">PM 3.9 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14193\" data-group=\"\">PM 30.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14197\" data-group=\"\">PM 32.5 PX<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14201\" data-group=\"\">PM 36.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14205\" data-group=\"\">PM 38.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13850\" data-group=\"\">PM 4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13870\" data-group=\"\">PM 4.5<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14209\" data-group=\"\">PM 40.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14213\" data-group=\"\">PM 47.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14217\" data-group=\"\">PM 48.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13874\" data-group=\"\">PM 5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14221\" data-group=\"\">PM 50.5 PX \/ PX C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14225\" data-group=\"\">PM 50.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14229\" data-group=\"\">PM 51.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14233\" data-group=\"\">PM 57.5 PX \/ PX C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14237\" data-group=\"\">PM 57.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14241\" data-group=\"\">PM 58.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13878\" data-group=\"\">PM 6<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13887\" data-group=\"\">PM 6.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13892\" data-group=\"\">PM 7 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14245\" data-group=\"\">PM 70.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13911\" data-group=\"\">PM 8<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13915\" data-group=\"\">PM 8.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13934\" data-group=\"\">PM 8.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13938\" data-group=\"\">PM 8.5 S C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14249\" data-group=\"\">PM 83.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14064\" data-group=\"\">PM 9.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14074\" data-group=\"\">PM 9.5 SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14286\" data-group=\"\">Power Lift<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14290\" data-group=\"\">TP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">S\u00e9lectionner un produit<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">S\u00e9lectionner un produit<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14078\" data-group=\"\">PM 10 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14082\" data-group=\"\">PM 10 S C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14253\" data-group=\"\">PM 100 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14086\" data-group=\"\">PM 11<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14090\" data-group=\"\">PM 11 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14094\" data-group=\"\">PM 11 SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14098\" data-group=\"\">PM 11.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14106\" data-group=\"\">PM 12.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14114\" data-group=\"\">PM 13.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14118\" data-group=\"\">PM 15.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14278\" data-group=\"\">PM 150 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14122\" data-group=\"\">PM 16.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14137\" data-group=\"\">PM 18 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14141\" data-group=\"\">PM 19<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13827\" data-group=\"\">PM 2.8<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14145\" data-group=\"\">PM 21<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14149\" data-group=\"\">PM 21.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14282\" data-group=\"\">PM 210 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14168\" data-group=\"\">PM 23 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14172\" data-group=\"\">PM 23.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14181\" data-group=\"\">PM 24 PX<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14185\" data-group=\"\">PM 26.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14189\" data-group=\"\">PM 28.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13838\" data-group=\"\">PM 3 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13842\" data-group=\"\">PM 3.6<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13846\" data-group=\"\">PM 3.9 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14193\" data-group=\"\">PM 30.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14197\" data-group=\"\">PM 32.5 PX<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14201\" data-group=\"\">PM 36.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14205\" data-group=\"\">PM 38.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13850\" data-group=\"\">PM 4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13870\" data-group=\"\">PM 4.5<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14209\" data-group=\"\">PM 40.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14213\" data-group=\"\">PM 47.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14217\" data-group=\"\">PM 48.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13874\" data-group=\"\">PM 5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14221\" data-group=\"\">PM 50.5 PX \/ PX C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14225\" data-group=\"\">PM 50.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14229\" data-group=\"\">PM 51.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14233\" data-group=\"\">PM 57.5 PX \/ PX C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14237\" data-group=\"\">PM 57.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14241\" data-group=\"\">PM 58.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13878\" data-group=\"\">PM 6<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13887\" data-group=\"\">PM 6.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13892\" data-group=\"\">PM 7 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14245\" data-group=\"\">PM 70.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13911\" data-group=\"\">PM 8<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13915\" data-group=\"\">PM 8.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13934\" data-group=\"\">PM 8.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13938\" data-group=\"\">PM 8.5 S C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14249\" data-group=\"\">PM 83.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14064\" data-group=\"\">PM 9.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14074\" data-group=\"\">PM 9.5 SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14286\" data-group=\"\">Power Lift<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14290\" data-group=\"\">TP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                          <li>\n                <a href=\"#media\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M22.9683 1.53906H3.74603C2.22944 1.53906 1 2.7685 1 4.28509V23.5073C1 25.0239 2.22944 26.2533 3.74603 26.2533H22.9683C24.4848 26.2533 25.7143 25.0239 25.7143 23.5073V4.28509C25.7143 2.7685 24.4848 1.53906 22.9683 1.53906Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.55116 11.1483C9.68861 11.1483 10.6107 10.2263 10.6107 9.08882C10.6107 7.95138 9.68861 7.0293 8.55116 7.0293C7.41372 7.0293 6.49164 7.95138 6.49164 9.08882C6.49164 10.2263 7.41372 11.1483 8.55116 11.1483Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M25.715 18.0135L18.8499 11.1484L3.7467 26.2516\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Galerie<\/span>\n                <\/a>\n              <\/li>\n                                    \n            \n                        \n                          <li>\n                <a href=\"https:\/\/mediahub.tadano.com\/m\/675077c140b326d4\/original\/doc_tadano_pm_20-5TP_20523_17023_18523_specsheet.pdf\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                  <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Brochure<\/span>\n                <\/a>\n              <\/li>\n            \n            \n                          <li>\n                <a href=\"https:\/\/www.tadano.com\/en\/about\/contact-us\/\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" version=\"1.1\" width=\"30\" height=\"30\" x=\"0\" y=\"0\" viewBox=\"0 0 440.965 440.965\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M341.508,36.207C305.582,12.648,263.549,0.116,220.587,0.154C98.892,0.271,0.235,98.832,0,220.527    c-0.046,42.838,12.652,84.721,36.48,120.32L0.853,426.18c-2.189,5.469,0.47,11.677,5.939,13.867c2.544,1.018,5.383,1.018,7.928,0    l85.333-35.627c101.679,66.676,238.158,38.3,304.834-63.379S443.187,102.883,341.508,36.207z M220.801,419.567    c-0.071,0-0.142,0-0.213,0v0.213h-0.001c-40.532-0.319-80.02-12.886-113.28-36.053c-1.754-1.224-3.835-1.893-5.973-1.92    c-1.338-0.264-2.715-0.264-4.053,0l-66.774,28.587l27.947-66.56c1.424-3.37,1.022-7.236-1.067-10.24    c-23.487-33.021-36.09-72.545-36.053-113.067C21.216,110.482,110.329,21.178,220.374,21.06    c110.044-0.118,199.349,88.995,199.467,199.04C419.959,330.145,330.846,419.449,220.801,419.567z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M288.514,162.764c-4.633-33.756-33.865-58.657-67.927-57.864c-36.795-0.118-66.752,29.552-66.987,66.347    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667c0.471-25.209,21.289-45.263,46.499-44.792    c25.21,0.471,45.263,21.289,44.792,46.499c-0.465,24.874-20.759,44.796-45.637,44.8c-5.891,0-10.667,4.776-10.667,10.667v47.787    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667v-37.973C267.907,233.206,293.543,199.416,288.514,162.764z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <circle cx=\"219.697\" cy=\"325.147\" r=\"11.675\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <\/g><\/svg>\n\n                  <\/div>\n                  <span class=\"text\">Demande d&rsquo;info<\/span>\n                <\/a>\n              <\/li>\n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n\n<h2 class=\"wp-block-heading\">Description du produit<\/h2>\n\n\n\n<p><strong>Puissance, fiabilit\u00e9, polyvalence.<\/strong><\/p>\n\n\n\n<p>La gamme de grues TP (Travaux Publics) a \u00e9t\u00e9 d\u00e9velopp\u00e9e avec la durabilit\u00e9 et la fiabilit\u00e9 comme priorit\u00e9s. Compactes et l\u00e9g\u00e8res, ces grues sont con\u00e7ues pour r\u00e9pondre aux exigences \u00e9lev\u00e9es des op\u00e9rations de chargement et de d\u00e9chargement n\u00e9cessitant des cycles r\u00e9p\u00e9t\u00e9s et \u00e0 forte fr\u00e9quence. De nouvelles activations internes am\u00e9liorent les fonctionnalit\u00e9s et prolongent la dur\u00e9e de vie de l\u2019\u00e9quipement, garantissant des performances constantes sur des applications vari\u00e9es.<\/p>\n\n\n\n<p>La gamme comprend trois mod\u00e8les polyvalents \u2014 PM 17 TP, 18 TP et 20 TP \u2014 tous con\u00e7us pour une utilisation multifonctionnelle. Ces grues disposent d\u2019une articulation avec biellettes sur le bras secondaire, offrant une grande sensibilit\u00e9 de mouvement et assurant une productivit\u00e9 maximale m\u00eame dans les environnements contraints. Leur simplicit\u00e9 de conception ne compromet pas la performance : elles restent puissantes et efficaces, tout en garantissant une manutention pr\u00e9cise et une fiabilit\u00e9 durable.<\/p>\n\n\n\n<p>Par exemple, le mod\u00e8le PM 20.5 TP offre un moment de levage maximal de <strong>19,3 tm<\/strong>, avec une port\u00e9e horizontale de <strong>10,30 m<\/strong> et une port\u00e9e verticale de <strong>14,15 m<\/strong>. Il garantit \u00e9galement un fonctionnement s\u00fbr et efficace gr\u00e2ce \u00e0 une largeur de stabilisation allant jusqu\u2019\u00e0 <strong>7,4 m<\/strong> et un angle de rotation de <strong>410\u00b0<\/strong>, soutenu par un couple de rotation de <strong>38 kNm<\/strong>.<\/p>\n\n\n\n<p>Gr\u00e2ce \u00e0 leur conception robuste, leur simplicit\u00e9 d\u2019utilisation et leur adaptabilit\u00e9, les grues TP constituent le choix id\u00e9al pour les op\u00e9rateurs recherchant une rentabilit\u00e9 maximale et une fiabilit\u00e9 constante tout au long de la dur\u00e9e de vie de la machine.<\/p>\n\n\n\n<section class=\"file-download-block\">\n    <div class=\"container\">\n        <div class=\"file-download-wrapper\">\n            <div class=\"select-field\">\n                <label for=\"file-download-select\" class=\"hidden\">Select a file<\/label>\n                <select name=\"file-download-select\" id=\"file-download-select\" class=\"file-download-select\">\n                    <option value=\"\">Veuillez s\u00e9lectionner un fichier<\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/675077c140b326d4\/original\/doc_tadano_pm_20-5TP_20523_17023_18523_specsheet.pdf\" data-file-id=\"file-0\">\n                            Brochure PM TP Range                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/60c05636ca4b1b05\/original\/doc_tadano_pm_17TP_17022_specsheet.pdf\" data-file-id=\"file-1\">\n                            PM 17022 TP                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/147ca0ccc055a1fc\/original\/doc_tadano_pm_17TP_17023_specsheet.pdf\" data-file-id=\"file-2\">\n                            PM 17023 TP                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/5c35c0c29b5b4334\/original\/doc_tadano_pm_18-5TP_18522_specsheet.pdf\" data-file-id=\"file-3\">\n                            PM 18522 TP                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/2e903206a43fa9f\/original\/doc_tadano_pm_18-5TP_18523_specsheet.pdf\" data-file-id=\"file-4\">\n                            PM 18523 TP                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/5649413839f1210c\/original\/doc_tadano_pm_20-5TP_20523_specsheet.pdf\" data-file-id=\"file-5\">\n                            PM 20523 TP                        <\/option>\n                                    <\/select>\n            <\/div>\n            \n            <button type=\"button\" class=\"btn btn-primary file-download-button\" disabled>\n                T\u00e9l\u00e9charger            <\/button>\n        <\/div>\n    <\/div>\n<\/section>\n\n<script>\n(function() {\n    const select = document.getElementById('file-download-select');\n    const button = document.querySelector('.file-download-button');\n    \n    if (!select || !button) return;\n    \n    \/\/ Enable\/disable button based on selection\n    select.addEventListener('change', function() {\n        if (this.value) {\n            button.disabled = false;\n        } else {\n            button.disabled = true;\n        }\n    });\n    \n    \/\/ Handle download button click\n    button.addEventListener('click', function() {\n        const selectedUrl = select.value;\n        if (selectedUrl) {\n            \/\/ Create a temporary link and trigger download\n            const link = document.createElement('a');\n            link.href = selectedUrl;\n            link.target = '_blank';\n            document.body.appendChild(link);\n            link.click();\n            document.body.removeChild(link);\n        }\n    });\n})();\n<\/script>\n\n<style>\n.file-download-block {\n    padding: 2rem 0;\n    position: relative!important;\n    z-index: 6!important;\n}\n\n.file-download-block .file-download-wrapper {\n    display: flex;\n    gap: 1rem;\n    align-items: center;\n    flex-wrap: wrap;\n}\n.file-download-block .select-field {\n    min-width: 250px;\n    width: 380px;\n    max-width: 100%;\n\n}\n.file-download-block .jcf-select {\n    background-color: #e3e3e3;\n    margin-bottom: 0;\n}\n.file-download-block .jcf-list {\n    background-color: #f2f2f2;\n}\n\n.file-download-block .file-download-select {\n    min-width: 250px;\n}\n\n.file-download-block .file-download-button {\n    white-space: nowrap;\n}\n\n.file-download-block .file-download-button:disabled {\n    opacity: 0.5;\n    cursor: not-allowed;\n}\n<\/style>\n\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Galerie m\u00e9dia<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/2effb6dd09f67273\/gallery_full-img_tadano_pm_17TP-1.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/2effb6dd09f67273\/gallery_thumb-img_tadano_pm_17TP-1.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/3fc1e1f99426b806\/gallery_full-img_tadano_pm_18-5TP-1.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/3fc1e1f99426b806\/gallery_thumb-img_tadano_pm_18-5TP-1.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/4063873e464c3b3e\/gallery_full-img_tadano_pm_20-5TP-2.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/4063873e464c3b3e\/gallery_thumb-img_tadano_pm_20-5TP-2.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/650882aa86b03781\/gallery_full-img_tadano_pm_20-5TP-1.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/650882aa86b03781\/gallery_thumb-img_tadano_pm_20-5TP-1.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n\n\n\n\n\n\n\n\n\n\n  \n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>Actualit\u00e9s<\/h2>\n                        \n                  <a href=\"https:\/\/www.tadano.com\/europe\/fr\/a-propos\/news-list\/\" class=\"link-more\">EXPLORER TOUTES les News<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/fr\/news\/grues-pick-carry-rx-empattement-extensible-pour-des-performances-maximales\/\">\n                  <strong class=\"title\">Grues Pick &amp; Carry RX : empattement extensible pour des performances maximales<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Mai\/28\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/fr\/news\/tadano-at-bauma-2025\/\">\n                  <strong class=\"title\">Tadano \u00e0 la bauma 2025<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Avr\/07\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/fr\/news\/la-nouvelle-tadano-ac-5-250l-2\/\">\n                  <strong class=\"title\">La nouvelle Tadano AC 5.250L-2<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">F\u00e9v\/17\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/fr\/news\/foselev-utilise-une-tadano-ac-7-450-1-pour-installer-un-systeme-de-ventilation\/\">\n                  <strong class=\"title\">Foselev utilise une Tadano AC 7.450-1 pour installer un syst\u00e8me de ventilation<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">D\u00e9c\/20\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/fr\/news\/la-tadano-ac-7-450-1-fait-coup-double-dans-le-wisconsin\/\">\n                  <strong class=\"title\">La Tadano AC 7.450-1 fait coup double dans le Wisconsin<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Nov\/12\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/fr\/news\/la-nouvelle-tadano-ac-5-250-2-seduit-par-ses-solutions-innovantes\/\">\n                  <strong class=\"title\">La nouvelle Tadano AC 5.250-2 s\u00e9duit par ses solutions innovantes<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Juil\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  ","protected":false},"featured_media":0,"template":"","lifting-equipment":[116],"class_list":["post-14290","products","type-products","status-publish","hentry","lifting-equipment-knuckle-boom-cranes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TP - Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/tp\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TP - Europe\" \/>\n<meta property=\"og:description\" content=\"Description du produit Puissance, fiabilit\u00e9, polyvalence. La gamme de grues TP (Travaux Publics) a \u00e9t\u00e9 d\u00e9velopp\u00e9e avec la durabilit\u00e9 et la fiabilit\u00e9 comme priorit\u00e9s. Compactes et l\u00e9g\u00e8res, ces grues sont con\u00e7ues pour r\u00e9pondre aux exigences \u00e9lev\u00e9es des op\u00e9rations de chargement et de d\u00e9chargement n\u00e9cessitant des cycles r\u00e9p\u00e9t\u00e9s et \u00e0 forte fr\u00e9quence. De nouvelles activations internes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/tp\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T13:28:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/lifting-equipment\\\/knuckle-boom-cranes\\\/tp\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/lifting-equipment\\\/knuckle-boom-cranes\\\/tp\\\/\",\"name\":\"TP - Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\"},\"datePublished\":\"2025-10-30T21:01:33+00:00\",\"dateModified\":\"2026-03-12T13:28:31+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/lifting-equipment\\\/knuckle-boom-cranes\\\/tp\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/\",\"name\":\"Europe\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TP - Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/tp\/","og_locale":"fr_FR","og_type":"article","og_title":"TP - Europe","og_description":"Description du produit Puissance, fiabilit\u00e9, polyvalence. La gamme de grues TP (Travaux Publics) a \u00e9t\u00e9 d\u00e9velopp\u00e9e avec la durabilit\u00e9 et la fiabilit\u00e9 comme priorit\u00e9s. Compactes et l\u00e9g\u00e8res, ces grues sont con\u00e7ues pour r\u00e9pondre aux exigences \u00e9lev\u00e9es des op\u00e9rations de chargement et de d\u00e9chargement n\u00e9cessitant des cycles r\u00e9p\u00e9t\u00e9s et \u00e0 forte fr\u00e9quence. De nouvelles activations internes [&hellip;]","og_url":"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/tp\/","og_site_name":"Europe","article_modified_time":"2026-03-12T13:28:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/tp\/","url":"https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/tp\/","name":"TP - Europe","isPartOf":{"@id":"https:\/\/www.tadano.com\/europe\/en\/#website"},"datePublished":"2025-10-30T21:01:33+00:00","dateModified":"2026-03-12T13:28:31+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/tp\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/europe\/en\/#website","url":"https:\/\/www.tadano.com\/europe\/en\/","name":"Europe","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/europe\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/europe\/fr\/wp-json\/wp\/v2\/products\/14290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/europe\/fr\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/europe\/fr\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":2,"href":"https:\/\/www.tadano.com\/europe\/fr\/wp-json\/wp\/v2\/products\/14290\/revisions"}],"predecessor-version":[{"id":14856,"href":"https:\/\/www.tadano.com\/europe\/fr\/wp-json\/wp\/v2\/products\/14290\/revisions\/14856"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/europe\/fr\/wp-json\/wp\/v2\/media?parent=14290"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/europe\/fr\/wp-json\/wp\/v2\/lifting-equipment?post=14290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}