{"id":10999,"date":"2021-10-22T10:59:59","date_gmt":"2021-10-22T08:59:59","guid":{"rendered":"https:\/\/www.tadano.com\/europe\/%term%\/%cat%\/ac-5-130-1\/"},"modified":"2026-06-24T07:37:17","modified_gmt":"2026-06-24T07:37:17","slug":"ac-5-130-1","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/europe\/it\/lifting-equipment\/all-terrain-cranes\/ac-5-130-1\/","title":{"rendered":"AC 5.130-1"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 0 0; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/11806c58d25461b\/hero-img_tadano_AC5130-1_cutout_front.png, https:\/\/mediahub.tadano.com\/m\/11806c58d25461b\/hero_2x-img_tadano_AC5130-1_cutout_front.png 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/europe\/it\/\">Homepage<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">AC 5.130-1<\/h1>\n\n\n\n<p>Compatta e con elevate prestazioni in termini di capacit\u00e0 di carico per asse su cinque assi. La funzione start-stop e il sistema di gestione intelligente consentono di mantenere bassi i costi operativi e ridurre la manutenzione.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/europe\/it\/vendite-e-servizi\/vendite\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Confronta i prodotti<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"it\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"16\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"39\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">Seleziona un prodotto<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleziona un prodotto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11002\" data-group=\"\">AC 2.040-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10994\" data-group=\"\">AC 3.060-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11000\" data-group=\"\">AC 4.070-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10834\" data-group=\"\">AC 4.080-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10999\" data-group=\"\">AC 5.130-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10998\" data-group=\"\">AC 5.160-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10995\" data-group=\"\">AC 5.250-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"12698\" data-group=\"\">AC 5.250L-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10996\" data-group=\"\">AC 6.300-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10907\" data-group=\"\">AC 7.450-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11018\" data-group=\"\">AC 8.500-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">Seleziona un prodotto<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleziona un prodotto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11002\" data-group=\"\">AC 2.040-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10994\" data-group=\"\">AC 3.060-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11000\" data-group=\"\">AC 4.070-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10834\" data-group=\"\">AC 4.080-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10999\" data-group=\"\">AC 5.130-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10998\" data-group=\"\">AC 5.160-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10995\" data-group=\"\">AC 5.250-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"12698\" data-group=\"\">AC 5.250L-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10996\" data-group=\"\">AC 6.300-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"10907\" data-group=\"\">AC 7.450-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"11018\" data-group=\"\">AC 8.500-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                          <li>\n                <a href=\"#media\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M22.9683 1.53906H3.74603C2.22944 1.53906 1 2.7685 1 4.28509V23.5073C1 25.0239 2.22944 26.2533 3.74603 26.2533H22.9683C24.4848 26.2533 25.7143 25.0239 25.7143 23.5073V4.28509C25.7143 2.7685 24.4848 1.53906 22.9683 1.53906Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.55116 11.1483C9.68861 11.1483 10.6107 10.2263 10.6107 9.08882C10.6107 7.95138 9.68861 7.0293 8.55116 7.0293C7.41372 7.0293 6.49164 7.95138 6.49164 9.08882C6.49164 10.2263 7.41372 11.1483 8.55116 11.1483Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M25.715 18.0135L18.8499 11.1484L3.7467 26.2516\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Galleria<\/span>\n                <\/a>\n              <\/li>\n                                                  <li>\n                <a href=\"#360\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M13.3571 26.2514C20.1818 26.2514 25.7143 20.7189 25.7143 13.8943C25.7143 7.06959 20.1818 1.53711 13.3571 1.53711C6.53248 1.53711 1 7.06959 1 13.8943C1 20.7189 6.53248 26.2514 13.3571 26.2514Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M1 13.0703H25.7143\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M13.3572 1.53711C16.9632 4.92093 19.0125 9.31227 19.1238 13.8943C19.0125 18.4762 16.9632 22.8676 13.3572 26.2514C9.75114 22.8676 7.70185 18.4762 7.59048 13.8943C7.70185 9.31227 9.75114 4.92093 13.3572 1.53711V1.53711Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Vista a 360\u00b0<\/span>\n                <\/a>\n              <\/li>\n            \n            \n                          <li class=\"scaled-metric\">\n                <a href=\"https:\/\/mediahub.tadano.com\/m\/5123bdc84fef5200\/original\/doc_tadano_AC5130-1_datasheet_metric_en_de_fr_it_es_pt_ru.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Spec.<\/span>\n                <\/a>\n              <\/li>\n                                      <li class=\"scaled-imperial\">\n                <a href=\"https:\/\/mediahub.tadano.com\/m\/5c70450338af94a3\/original\/doc_tadano_AC5130-1_datasheet_imperial_en.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Spec.<\/span>\n                <\/a>\n              <\/li>\n            \n            \n            \n                          <li>\n                <a href=\"https:\/\/www.tadano.com\/europe\/it\/informazioni\/contatti\/\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" version=\"1.1\" width=\"30\" height=\"30\" x=\"0\" y=\"0\" viewBox=\"0 0 440.965 440.965\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M341.508,36.207C305.582,12.648,263.549,0.116,220.587,0.154C98.892,0.271,0.235,98.832,0,220.527    c-0.046,42.838,12.652,84.721,36.48,120.32L0.853,426.18c-2.189,5.469,0.47,11.677,5.939,13.867c2.544,1.018,5.383,1.018,7.928,0    l85.333-35.627c101.679,66.676,238.158,38.3,304.834-63.379S443.187,102.883,341.508,36.207z M220.801,419.567    c-0.071,0-0.142,0-0.213,0v0.213h-0.001c-40.532-0.319-80.02-12.886-113.28-36.053c-1.754-1.224-3.835-1.893-5.973-1.92    c-1.338-0.264-2.715-0.264-4.053,0l-66.774,28.587l27.947-66.56c1.424-3.37,1.022-7.236-1.067-10.24    c-23.487-33.021-36.09-72.545-36.053-113.067C21.216,110.482,110.329,21.178,220.374,21.06    c110.044-0.118,199.349,88.995,199.467,199.04C419.959,330.145,330.846,419.449,220.801,419.567z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M288.514,162.764c-4.633-33.756-33.865-58.657-67.927-57.864c-36.795-0.118-66.752,29.552-66.987,66.347    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667c0.471-25.209,21.289-45.263,46.499-44.792    c25.21,0.471,45.263,21.289,44.792,46.499c-0.465,24.874-20.759,44.796-45.637,44.8c-5.891,0-10.667,4.776-10.667,10.667v47.787    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667v-37.973C267.907,233.206,293.543,199.416,288.514,162.764z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <circle cx=\"219.697\" cy=\"325.147\" r=\"11.675\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <\/g><\/svg>\n\n                  <\/div>\n                  <span class=\"text\">Richiesta info<\/span>\n                <\/a>\n              <\/li>\n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n             \n\n\n<div class=\"container \">\n  <div class=\"product-details\">\n    <div class=\"product-specs\">\n\n      <div class=\"title\">\n        <div class=\"left\">\n                      <h2>Specifiche del prodotto<\/h2>\n                  <\/div>\n        <div class=\"right\">\n                        <div class=\"radio\">\n                                <label for=\"met\" class=\"met\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Metrico<\/span>\n                <\/label>\n                <label for=\"imp\" class=\"imp\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Imperiale<\/span>\n                <\/label>\n            <\/div>\n            \n\n        <\/div>\n      <\/div>\n\n      \n        <ul>\n\n                                  <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Capacit\u00e0 massima della gru<\/strong>\n                          <span>140&nbsp;USt<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Lunghezza del braccio principale<\/strong>\n                          <span>41.0&nbsp;ft &#8211; 196.8&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Estensione del braccio<\/strong>\n                          <span>5.3&nbsp;ft \/ 37.4&nbsp;ft &#8211; 108.2&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Altezza massima della punta<\/strong>\n                          <span>294.0&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Contrappeso massimo<\/strong>\n                          <span>93,000&nbsp;lbs<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Basi degli stabilizzatori<\/strong>\n                          <span>25.4&nbsp;ft x 22.9&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Tiro della linea di sollevamento<\/strong>\n                          <span>18,524.2&nbsp;lbs<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">MAX Radius<\/strong>\n                          <span>203.4&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Dimensioni<\/strong>\n                          <span>L:&nbsp;44.9&nbsp;ft W:&nbsp;9.0&nbsp;ft H:&nbsp;12.8&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Capacit\u00e0 massima della gru<\/strong>\n                          <span>130&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Lunghezza del braccio principale<\/strong>\n                          <span>12.5&nbsp;m &#8211; 59.8&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Estensione del braccio<\/strong>\n                          <span>1.6&nbsp;m \/ 11&nbsp;m &#8211; 33&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Altezza massima della punta<\/strong>\n                          <span>89&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Contrappeso massimo<\/strong>\n                          <span>42.2&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Basi degli stabilizzatori<\/strong>\n                          <span>7.71&nbsp;m x 7.00&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Tiro della linea di sollevamento<\/strong>\n                          <span>8.3&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Raggio massimo<\/strong>\n                          <span>62&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Dimensioni<\/strong>\n                          <span>L:&nbsp;14.45&nbsp;m W:&nbsp;2.75&nbsp;m H:&nbsp;3.93&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Assi<\/strong>\n                          <span>5<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Motore<\/strong>\n                          <span>Scania<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Sistema di trasmissione<\/strong>\n                          <span>10&nbsp;x 6&nbsp;x 10&nbsp;(10&nbsp;x 8&nbsp;x 10)<\/span>\n                        <\/li>\n                      \n        <\/ul>\n\n                  <style type=\"text\/css\">\n            @media screen and (min-width: 1360px) {\n              .hero-section .green-solutions {\n                display: block!important;\n              }\n            }\n          <\/style>\n        \n       \n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Descrizione<\/h2>\n\n\n\n<p><strong>Compatta e con elevate prestazioni in termini di capacit\u00e0 di carico su cinque assi<\/strong><\/p>\n\n\n\n<p>La AC 5.130-1 \u00e8 la gru pi\u00f9 compatta della sua categoria con una lunghezza totale di 14,45 metri e una larghezza del carro di 2,75 metri. La presenza sulla gru di un solo motore, della funzione start-stop e del sistema di gestione intelligente consente di mantenere bassi i costi di esercizio e di ridurre la manutenzione. Sebbene l&#8217;AC 5.130-1 rimanga sotto il limite di carico per asse di 12 t, pu\u00f2 comunque trasportare 450 kg di carico utile.<\/p>\n\n\n\n<section class=\"product-360-view\" id=\"360\">\n\n      <script type=\"text\/javascript\">\n      const ThreeSixtyFrameCount = 36;\n      const ThreeSixtyImagePath = 'https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/360-view\/AC5130-1\/360\/';\n    <\/script>\n\n    <div class=\"container\">\n      <div class=\"interactive-view\">\n        <h2>Visualizzazione interattiva a 360 \u00b0<\/h2>\n\n                  <div class=\"view-selector\">\n\n            <div data-view=\"view-exterior\" class=\"active\">Exterior<\/div>\n\n                          <div data-view=\"view-lower-cabin\">Lower cabin<\/div>\n            \n                          <div data-view=\"view-upper-cabin\">Upper cabin<\/div>\n            \n          <\/div>\n        \n        <div class=\"views-wrapper\">\n\n                      <div id=\"view-lower-cabin\" class=\"iframe\">\n              <iframe src=\"https:\/\/www.tadano.com\/\/wp-content\/themes\/tadano\/template-parts\/components\/cabin-views\/tadano_ac_lc\/index.htm\" frameborder=\"0\" allowfullscreen=\"\" allow=\"vr\"><\/iframe>\n            <\/div>\n          \n                      <div id=\"view-upper-cabin\" class=\"iframe\">\n              <iframe src=\"https:\/\/www.tadano.com\/\/wp-content\/themes\/tadano\/template-parts\/components\/cabin-views\/tadano_ac_uc\/index.htm\" frameborder=\"0\" allowfullscreen=\"\" allow=\"vr\"><\/iframe>\n            <\/div>\n          \n          <div id=\"view-exterior\" class=\"active\">\n            <div class=\"view-holder\">\n                          <\/div>\n            <div class=\"wrap-360\">\n              <div class=\"threesixty car\">\n                <div class=\"spinner\">\n                    <span style=\"opacity:0.2\">0%<\/span>\n                <\/div>\n                <ol class=\"threesixty_images\"><\/ol>\n              <\/div>\n            <\/div>\n            \n                      <\/div>\n\n        <\/div>\n          \n        \n      <\/div>\n    <\/div>\n\n    \n    <script>\n     \/\/ Target the view-selector divs\n     const selectors = document.querySelectorAll('.view-selector div');\n\n     \/\/ Add a 'click' event listener to all the selectors\n     selectors.forEach(selector => {\n          selector.addEventListener('click', function(event){\n               \/\/ Remove 'active' class from all selectors\n               selectors.forEach(selector => {\n                    selector.classList.remove('active');\n\n                    \/\/ Also remove 'active' class from all views,\n                    \/\/ But first check if the view actually exists\n                    let view = document.querySelector('#' + selector.dataset.view);\n                    if(view) {\n                        view.classList.remove('active');\n                    }\n               })\n\n               \/\/ Add 'active' class to the clicked selector\n               this.classList.add('active');\n\n               \/\/ Add 'active' class to the view corresponding to clicked selector\n               \/\/ After checking if the view actually exists\n               let view = document.querySelector('#' + this.dataset.view);\n               if(view) {\n                   view.classList.add('active');\n               }\n          })\n     });\n    <\/script>\n\n<\/section>\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Galleria multimediale<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/11806c58d25461b\/gallery_full-img_tadano_AC5130-1_cutout_front.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/11806c58d25461b\/gallery_thumb-img_tadano_AC5130-1_cutout_front.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/50f60adcb2d6c308\/gallery_full-img_tadano_AC5130-1_cutout_side.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/50f60adcb2d6c308\/gallery_thumb-img_tadano_AC5130-1_cutout_side.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n<div class=\"cta-block\">\n    <div class=\"container\">\n    <div class=\"left\">\n      <ul class=\"btn-list\">\n        <li><a href=\"https:\/\/www.tadano.com\/europe\/it\/informazioni\/contatti\/\" class=\"btn btn-light\">Richiedi ora<\/a><\/li>\n      <\/ul>\n    <\/div>\n    <div class=\"right\">\n                          <ul class=\"btn-list\">\n                            \n                                  <li><a href=\"https:\/\/mediahub.tadano.com\/m\/5123bdc84fef5200\/original\/doc_tadano_AC5130-1_datasheet_metric_en_de_fr_it_es_pt_ru.pdf\" class=\"btn btn-outline-white\">Scheda delle specifiche<\/a><\/li>\n                              \n                              \n          <\/ul>\n            <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n\n\n\n\n\n\n\n\n\n  <section class=\"related-products related-pages\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>Pagine correlate<\/h2>\n      <\/div>\n\n      <div class='r-products'>\n                  \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/europe\/it\/technologies\/ic-1-plus\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:cover\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/asset\/5742d93f-f42d-4232-88bb-a55c59e10c7a\/img-thumb\/img_tadano_ic-1_plus.jpg, https:\/\/mediahub.tadano.com\/asset\/5742d93f-f42d-4232-88bb-a55c59e10c7a\/img-thumb-2x\/img_tadano_ic-1_plus.jpg 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">IC-1 Plus<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                        <\/div>\n        \n    <\/div>\n  <\/section>\n  \n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>Notizie<\/h2>\n                        \n                  <a href=\"https:\/\/www.tadano.com\/europe\/it\/informazioni\/news-list\/\" class=\"link-more\">ESPLORARE TUTTE le notizie<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/it\/news\/tadano-teamworkcc-68-1250-1-and-cc-38-650-1-lift-steel-bridge-sections-at-the-porto-di-pra-shipyard\/\">\n                  <strong class=\"title\">Gioco di squadra in casa Tadano:le gru CC 68.1250-1 e CC 38.650-1 sollevano le sezioni in acciaio di un ponte presso il cantiere nel Porto di Pra&#8217;<\/strong>\n                  <ul class=\"meta\">\n                    <li>Pubblicazione<\/li>\n                    <li><time datetime=\"2020-01-01\">Ago\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/it\/news\/la-nuova-tadano-ac-5-250-2-promossa-a-pieni-voti-sotto-il-profilo-delle-prestazioni\/\">\n                  <strong class=\"title\">La nuova Tadano AC 5.250-2 promossa a pieni voti sotto il profilo delle prestazioni<\/strong>\n                  <ul class=\"meta\">\n                    <li>Pubblicazione<\/li>\n                    <li><time datetime=\"2020-01-01\">Lug\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  ","protected":false},"featured_media":0,"template":"","lifting-equipment":[39],"class_list":["post-10999","products","type-products","status-publish","hentry","lifting-equipment-all-terrain-cranes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AC 5.130-1 - Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/europe\/it\/lifting-equipment\/all-terrain-cranes\/ac-5-130-1\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AC 5.130-1 - Europe\" \/>\n<meta property=\"og:description\" content=\"Descrizione Compatta e con elevate prestazioni in termini di capacit\u00e0 di carico su cinque assi La AC 5.130-1 \u00e8 la gru pi\u00f9 compatta della sua categoria con una lunghezza totale di 14,45 metri e una larghezza del carro di 2,75 metri. La presenza sulla gru di un solo motore, della funzione start-stop e del sistema [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/europe\/it\/lifting-equipment\/all-terrain-cranes\/ac-5-130-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T07:37:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/it\\\/lifting-equipment\\\/all-terrain-cranes\\\/ac-5-130-1\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/it\\\/lifting-equipment\\\/all-terrain-cranes\\\/ac-5-130-1\\\/\",\"name\":\"AC 5.130-1 - Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\"},\"datePublished\":\"2021-10-22T08:59:59+00:00\",\"dateModified\":\"2026-06-24T07:37:17+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/europe\\\/it\\\/lifting-equipment\\\/all-terrain-cranes\\\/ac-5-130-1\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/\",\"name\":\"Europe\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AC 5.130-1 - Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/europe\/it\/lifting-equipment\/all-terrain-cranes\/ac-5-130-1\/","og_locale":"it_IT","og_type":"article","og_title":"AC 5.130-1 - Europe","og_description":"Descrizione Compatta e con elevate prestazioni in termini di capacit\u00e0 di carico su cinque assi La AC 5.130-1 \u00e8 la gru pi\u00f9 compatta della sua categoria con una lunghezza totale di 14,45 metri e una larghezza del carro di 2,75 metri. La presenza sulla gru di un solo motore, della funzione start-stop e del sistema [&hellip;]","og_url":"https:\/\/www.tadano.com\/europe\/it\/lifting-equipment\/all-terrain-cranes\/ac-5-130-1\/","og_site_name":"Europe","article_modified_time":"2026-06-24T07:37:17+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/europe\/it\/lifting-equipment\/all-terrain-cranes\/ac-5-130-1\/","url":"https:\/\/www.tadano.com\/europe\/it\/lifting-equipment\/all-terrain-cranes\/ac-5-130-1\/","name":"AC 5.130-1 - Europe","isPartOf":{"@id":"https:\/\/www.tadano.com\/europe\/en\/#website"},"datePublished":"2021-10-22T08:59:59+00:00","dateModified":"2026-06-24T07:37:17+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/europe\/it\/lifting-equipment\/all-terrain-cranes\/ac-5-130-1\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/europe\/en\/#website","url":"https:\/\/www.tadano.com\/europe\/en\/","name":"Europe","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/europe\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/products\/10999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":2,"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/products\/10999\/revisions"}],"predecessor-version":[{"id":16244,"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/products\/10999\/revisions\/16244"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/media?parent=10999"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/lifting-equipment?post=10999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}