{"id":14092,"date":"2025-10-29T13:58:40","date_gmt":"2025-10-29T12:58:40","guid":{"rendered":"https:\/\/www.tadano.com\/europe\/%term%\/%cat%\/pm-11-sp\/"},"modified":"2026-02-25T19:00:13","modified_gmt":"2026-02-25T19:00:13","slug":"pm-11-sp","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/europe\/it\/lifting-equipment\/knuckle-boom-cranes\/pm-11-sp\/","title":{"rendered":"PM 11 SP"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 0 0; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/eb9b1354b54fbd0\/hero-img_tadano_pm_11SP-1.png, https:\/\/mediahub.tadano.com\/m\/eb9b1354b54fbd0\/hero_2x-img_tadano_pm_11SP-1.png 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/europe\/it\/\">Homepage<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">PM 11 SP<\/h1>\n\n\n\n<p>Il PM 11 SP combina controlli avanzati, design leggero e uno sbraccio superiore, garantendo precisione e affidabilit\u00e0 nel sollevamento quotidiano.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/europe\/it\/vendite-e-servizi\/vendite\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Confronta i prodotti<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"it\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"16\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"116\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">Seleziona un prodotto<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleziona un prodotto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14080\" data-group=\"\">PM 10 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14084\" data-group=\"\">PM 10 S C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14265\" data-group=\"\">PM 100 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14088\" data-group=\"\">PM 11<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14092\" data-group=\"\">PM 11 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14096\" data-group=\"\">PM 11 SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14100\" data-group=\"\">PM 11.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14108\" data-group=\"\">PM 12.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14116\" data-group=\"\">PM 13.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14120\" data-group=\"\">PM 15.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14280\" data-group=\"\">PM 150 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14134\" data-group=\"\">PM 16.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14139\" data-group=\"\">PM 18 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14143\" data-group=\"\">PM 19<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13829\" data-group=\"\">PM 2.8<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14147\" data-group=\"\">PM 21<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14156\" data-group=\"\">PM 21.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14284\" data-group=\"\">PM 210 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14170\" data-group=\"\">PM 23 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14179\" data-group=\"\">PM 23.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14183\" data-group=\"\">PM 24 PX<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14187\" data-group=\"\">PM 26.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14191\" data-group=\"\">PM 28.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13840\" data-group=\"\">PM 3 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13844\" data-group=\"\">PM 3.6<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13848\" data-group=\"\">PM 3.9 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14195\" data-group=\"\">PM 30.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14199\" data-group=\"\">PM 32.5 PX<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14203\" data-group=\"\">PM 36.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14207\" data-group=\"\">PM 38.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13863\" data-group=\"\">PM 4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13872\" data-group=\"\">PM 4.5<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14211\" data-group=\"\">PM 40.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14215\" data-group=\"\">PM 47.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14219\" data-group=\"\">PM 48.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13876\" data-group=\"\">PM 5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14223\" data-group=\"\">PM 50.5 PX \/ PX C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14227\" data-group=\"\">PM 50.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14231\" data-group=\"\">PM 51.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14235\" data-group=\"\">PM 57.5 PX \/ PX C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14239\" data-group=\"\">PM 57.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14243\" data-group=\"\">PM 58.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13885\" data-group=\"\">PM 6<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13890\" data-group=\"\">PM 6.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13899\" data-group=\"\">PM 7 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14247\" data-group=\"\">PM 70.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13913\" data-group=\"\">PM 8<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13922\" data-group=\"\">PM 8.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13936\" data-group=\"\">PM 8.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13940\" data-group=\"\">PM 8.5 S C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14251\" data-group=\"\">PM 83.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14071\" data-group=\"\">PM 9.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14076\" data-group=\"\">PM 9.5 SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14288\" data-group=\"\">Power Lift<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14292\" data-group=\"\">TP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">Seleziona un prodotto<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleziona un prodotto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14080\" data-group=\"\">PM 10 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14084\" data-group=\"\">PM 10 S C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14265\" data-group=\"\">PM 100 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14088\" data-group=\"\">PM 11<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14092\" data-group=\"\">PM 11 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14096\" data-group=\"\">PM 11 SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14100\" data-group=\"\">PM 11.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14108\" data-group=\"\">PM 12.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14116\" data-group=\"\">PM 13.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14120\" data-group=\"\">PM 15.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14280\" data-group=\"\">PM 150 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14134\" data-group=\"\">PM 16.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14139\" data-group=\"\">PM 18 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14143\" data-group=\"\">PM 19<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13829\" data-group=\"\">PM 2.8<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14147\" data-group=\"\">PM 21<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14156\" data-group=\"\">PM 21.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14284\" data-group=\"\">PM 210 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14170\" data-group=\"\">PM 23 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14179\" data-group=\"\">PM 23.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14183\" data-group=\"\">PM 24 PX<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14187\" data-group=\"\">PM 26.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14191\" data-group=\"\">PM 28.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13840\" data-group=\"\">PM 3 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13844\" data-group=\"\">PM 3.6<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13848\" data-group=\"\">PM 3.9 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14195\" data-group=\"\">PM 30.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14199\" data-group=\"\">PM 32.5 PX<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14203\" data-group=\"\">PM 36.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14207\" data-group=\"\">PM 38.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13863\" data-group=\"\">PM 4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13872\" data-group=\"\">PM 4.5<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14211\" data-group=\"\">PM 40.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14215\" data-group=\"\">PM 47.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14219\" data-group=\"\">PM 48.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13876\" data-group=\"\">PM 5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14223\" data-group=\"\">PM 50.5 PX \/ PX C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14227\" data-group=\"\">PM 50.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14231\" data-group=\"\">PM 51.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14235\" data-group=\"\">PM 57.5 PX \/ PX C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14239\" data-group=\"\">PM 57.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14243\" data-group=\"\">PM 58.5 SP \/ SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13885\" data-group=\"\">PM 6<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13890\" data-group=\"\">PM 6.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13899\" data-group=\"\">PM 7 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14247\" data-group=\"\">PM 70.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13913\" data-group=\"\">PM 8<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13922\" data-group=\"\">PM 8.5 P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13936\" data-group=\"\">PM 8.5 S<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"13940\" data-group=\"\">PM 8.5 S C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14251\" data-group=\"\">PM 83.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14071\" data-group=\"\">PM 9.5 SP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14076\" data-group=\"\">PM 9.5 SP C<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14288\" data-group=\"\">Power Lift<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"14292\" data-group=\"\">TP<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                          <li>\n                <a href=\"#media\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M22.9683 1.53906H3.74603C2.22944 1.53906 1 2.7685 1 4.28509V23.5073C1 25.0239 2.22944 26.2533 3.74603 26.2533H22.9683C24.4848 26.2533 25.7143 25.0239 25.7143 23.5073V4.28509C25.7143 2.7685 24.4848 1.53906 22.9683 1.53906Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.55116 11.1483C9.68861 11.1483 10.6107 10.2263 10.6107 9.08882C10.6107 7.95138 9.68861 7.0293 8.55116 7.0293C7.41372 7.0293 6.49164 7.95138 6.49164 9.08882C6.49164 10.2263 7.41372 11.1483 8.55116 11.1483Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M25.715 18.0135L18.8499 11.1484L3.7467 26.2516\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Galleria<\/span>\n                <\/a>\n              <\/li>\n                                    \n            \n                        \n                          <li>\n                <a href=\"https:\/\/mediahub.tadano.com\/m\/5da959555d5da338\/original\/doc_tadano_pm_11SP_brochure.pdf\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                  <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Brochure<\/span>\n                <\/a>\n              <\/li>\n            \n            \n                          <li>\n                <a href=\"https:\/\/www.tadano.com\/en\/about\/contact-us\/\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" version=\"1.1\" width=\"30\" height=\"30\" x=\"0\" y=\"0\" viewBox=\"0 0 440.965 440.965\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M341.508,36.207C305.582,12.648,263.549,0.116,220.587,0.154C98.892,0.271,0.235,98.832,0,220.527    c-0.046,42.838,12.652,84.721,36.48,120.32L0.853,426.18c-2.189,5.469,0.47,11.677,5.939,13.867c2.544,1.018,5.383,1.018,7.928,0    l85.333-35.627c101.679,66.676,238.158,38.3,304.834-63.379S443.187,102.883,341.508,36.207z M220.801,419.567    c-0.071,0-0.142,0-0.213,0v0.213h-0.001c-40.532-0.319-80.02-12.886-113.28-36.053c-1.754-1.224-3.835-1.893-5.973-1.92    c-1.338-0.264-2.715-0.264-4.053,0l-66.774,28.587l27.947-66.56c1.424-3.37,1.022-7.236-1.067-10.24    c-23.487-33.021-36.09-72.545-36.053-113.067C21.216,110.482,110.329,21.178,220.374,21.06    c110.044-0.118,199.349,88.995,199.467,199.04C419.959,330.145,330.846,419.449,220.801,419.567z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M288.514,162.764c-4.633-33.756-33.865-58.657-67.927-57.864c-36.795-0.118-66.752,29.552-66.987,66.347    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667c0.471-25.209,21.289-45.263,46.499-44.792    c25.21,0.471,45.263,21.289,44.792,46.499c-0.465,24.874-20.759,44.796-45.637,44.8c-5.891,0-10.667,4.776-10.667,10.667v47.787    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667v-37.973C267.907,233.206,293.543,199.416,288.514,162.764z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <circle cx=\"219.697\" cy=\"325.147\" r=\"11.675\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <\/g><\/svg>\n\n                  <\/div>\n                  <span class=\"text\">Richiesta info<\/span>\n                <\/a>\n              <\/li>\n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n             \n\n\n<div class=\"container product-series\">\n  <div class=\"product-details\">\n    <div class=\"product-specs\">\n\n      <div class=\"title\">\n        <div class=\"left\">\n                      <h2>Specifiche della serie<\/h2>\n                  <\/div>\n        <div class=\"right\">\n                        <div class=\"radio\">\n                                <label for=\"met\" class=\"met\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Metrico<\/span>\n                <\/label>\n                <label for=\"imp\" class=\"imp\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Imperiale<\/span>\n                <\/label>\n            <\/div>\n            \n\n        <\/div>\n      <\/div>\n\n              \n        <div class=\"outer\">\n          <div class=\"inner\">\n                        <table id=\"series-specs-table\" class=\"series-specs-table-desktop\">\n              <thead>\n                <tr>\n                  <th><\/th>\n                  <th>PM 11021 SP <\/th><th>PM 11022 SP<\/th><th>PM 11022 SP + J312<\/th><th>PM 11022 SP + J313<\/th><th>PM 11023 SP<\/th><th>PM 11023 SP + J312<\/th><th>PM 11023 SP + J313<\/th><th>PM 11024 SP<\/th><th>PM 11025 SP<\/th>                <\/tr>\n              <\/thead>\n              <tbody>\n                <tr class=\"scaled-metric\"><th>Scheda tecnica<\/th><td><a href=\"https:\/\/mediahub.tadano.com\/m\/2066a0c23f8344a\/original\/doc_tadano_pm_11SP_11021_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><td><a href=\"https:\/\/mediahub.tadano.com\/m\/33ac06bcc84c8a8\/original\/doc_tadano_pm_11SP_11022_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><td><a href=\"https:\/\/mediahub.tadano.com\/m\/136a39de2cd192d4\/original\/doc_tadano_pm_11SP_11022-J312_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><td><a href=\"https:\/\/mediahub.tadano.com\/m\/10e38d584ecc81c7\/original\/doc_tadano_pm_11SP_11022-J313_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><td><a href=\"https:\/\/mediahub.tadano.com\/m\/6bda4589a87cc707\/original\/doc_tadano_pm_11SP_11023_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><td><a href=\"https:\/\/mediahub.tadano.com\/m\/ae3e516de247bf6\/original\/doc_tadano_pm_11SP_11023-J312_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><td><a href=\"https:\/\/mediahub.tadano.com\/m\/1ad9a93c70561731\/original\/doc_tadano_pm_11SP_11023-J313_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><td><a href=\"https:\/\/mediahub.tadano.com\/m\/585325a4210bed18\/original\/doc_tadano_pm_11SP_11024_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><td><a href=\"https:\/\/mediahub.tadano.com\/m\/1bf26312c3a65fd\/original\/doc_tadano_pm_11SP_11025_specsheet.pdf\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/icon-download.svg\"><\/a><\/td><\/tr><tr class=\"scaled-metric\"><th>Pressione max.<\/th><td>35,5&nbsp;MPa<\/td><td>35,5&nbsp;MPa<\/td><td>35,5&nbsp;MPa<\/td><td>35,5&nbsp;MPa<\/td><td>35,5&nbsp;MPa<\/td><td>35,5&nbsp;MPa<\/td><td>35,5&nbsp;MPa<\/td><td>35,5&nbsp;MPa<\/td><td>35,5&nbsp;MPa<\/td><\/tr><tr class=\"scaled-metric\"><th>Capacit\u00e0 del serbatoio carburante<\/th><td>80&nbsp;l<\/td><td>80&nbsp;l<\/td><td>80&nbsp;l<\/td><td>80&nbsp;l<\/td><td>80&nbsp;l<\/td><td>80&nbsp;l<\/td><td>80&nbsp;l<\/td><td>80&nbsp;l<\/td><td>80&nbsp;l<\/td><\/tr><tr class=\"scaled-metric\"><th>Momento di sollevamento massimo<\/th><td>10,3&nbsp;TM<\/td><td>10,0&nbsp;TM<\/td><td>10,0&nbsp;TM<\/td><td>10,0&nbsp;TM<\/td><td>9,8&nbsp;TM<\/td><td>9,8&nbsp;TM<\/td><td>9,8&nbsp;TM<\/td><td>9,6&nbsp;TM<\/td><td>9,5&nbsp;TM<\/td><\/tr><tr class=\"scaled-metric\"><th>Sbraccio orizzontale idraulico<\/th><td>5,70&nbsp;m<\/td><td>7,70&nbsp;m<\/td><td>12,80&nbsp;m<\/td><td>14,15<\/td><td>9,80&nbsp;m<\/td><td>14,85&nbsp;m<\/td><td>16,20&nbsp;m<\/td><td>11,95&nbsp;m<\/td><td>14,10&nbsp;m<\/td><\/tr><tr class=\"scaled-metric\"><th>Sbraccio verticale idraulico<\/th><td>8,85&nbsp;m<\/td><td>10,80&nbsp;m<\/td><td>14,75&nbsp;m<\/td><td>17,15<\/td><td>12,85&nbsp;m<\/td><td>17,70&nbsp;m<\/td><td>19,20&nbsp;m<\/td><td>14,90&nbsp;m<\/td><td>17,00&nbsp;m<\/td><\/tr><tr class=\"scaled-metric\"><th>Portata d\u2019olio raccomandata<\/th><td>30-40&nbsp;l\/min<\/td><td>30-40&nbsp;l\/min<\/td><td>30-40&nbsp;l\/min<\/td><td>30-40&nbsp;l\/min<\/td><td>30-40&nbsp;l\/min<\/td><td>30-40&nbsp;l\/min<\/td><td>30-40&nbsp;l\/min<\/td><td>30-40&nbsp;l\/min<\/td><td>30-40&nbsp;l\/min<\/td><\/tr><tr class=\"scaled-metric\"><th>Coppia di rotazione<\/th><td>12&nbsp;kN m<\/td><td>12&nbsp;kN m<\/td><td>12&nbsp;kN m<\/td><td>12&nbsp;kN m<\/td><td>12&nbsp;kN m<\/td><td>12&nbsp;kN m<\/td><td>12&nbsp;kN m<\/td><td>12&nbsp;kN m<\/td><td>12&nbsp;kN m<\/td><\/tr><tr class=\"scaled-metric\"><th>Apertura stabilizzatori disponibile<\/th><td>3.4&nbsp;&#8211; 4,5&nbsp;m<\/td><td>3.4&nbsp;&#8211; 4,5&nbsp;m<\/td><td>3.4&nbsp;&#8211; 4,5&nbsp;m<\/td><td>3.4&nbsp;&#8211; 4,5&nbsp;m<\/td><td>3.4&nbsp;&#8211; 4,5&nbsp;m<\/td><td>3.4&nbsp;&#8211; 4,5&nbsp;m<\/td><td>3.4&nbsp;&#8211; 4,5&nbsp;m<\/td><td>3.4&nbsp;&#8211; 4,5&nbsp;m<\/td><td>3.4&nbsp;&#8211; 4,5&nbsp;m<\/td><\/tr><tr class=\"\"><th>Angolo di rotazione<\/th><td>400\u00b0<\/td><td>400\u00b0<\/td><td>400\u00b0<\/td><td>400\u00b0<\/td><td>400\u00b0<\/td><td>400\u00b0<\/td><td>400\u00b0<\/td><td>400\u00b0<\/td><td>400\u00b0<\/td><\/tr><tr class=\"\"><th>Controllo stabilizzatori via radio wireless<\/th><td>Radio Wireless<\/td><td>Radio Wireless<\/td><td>Radio Wireless<\/td><td>Radio Wireless<\/td><td>Radio Wireless<\/td><td>Radio Wireless<\/td><td>Radio Wireless<\/td><td>Radio Wireless<\/td><td>Radio Wireless<\/td><\/tr><tr class=\"scaled-imperial\"><th>Momento di sollevamento massimo<\/th><td>74260&nbsp;ft Ibs<\/td><td>72420&nbsp;ft Ibs<\/td><td>72420&nbsp;ft Ibs<\/td><td>72420&nbsp;ft Ibs<\/td><td>71010&nbsp;ft Ibs<\/td><td>71010&nbsp;ft Ibs<\/td><td>71010&nbsp;ft Ibs<\/td><td>69430&nbsp;ft Ibs<\/td><td>68550&nbsp;ft Ibs<\/td><\/tr><tr class=\"scaled-imperial\"><th>Sbraccio orizzontale idraulico<\/th><td>18&#8242;\n  8&#8243;<\/td><td>25&#8242; 3&#8243;<\/td><td>42&#8242; <\/td><td>46&#8242; 5&#8243;<\/td><td>32&#8242; 2&#8243;<\/td><td>48&#8242; 9&#8243;<\/td><td>53&#8242; 2&#8243;<\/td><td>39&#8242; 2&#8243;<\/td><td>46&#8242; 3&#8243;<\/td><\/tr><tr class=\"scaled-imperial\"><th>Sbraccio verticale idraulico<\/th><td>29&#8242; <\/td><td>35&#8242; 5&#8243;<\/td><td>48&#8242; 5&#8243;<\/td><td>56&#8242; 3&#8243;<\/td><td>42&#8242; 2&#8243;<\/td><td>58&#8242; 1&#8243;<\/td><td>63&#8242; <\/td><td>48&#8242; 11&#8243;<\/td><td>55&#8242; 9&#8243;<\/td><\/tr><tr class=\"scaled-metric\"><th>Larghezza<\/th><td>730&nbsp;mm<\/td><td>730&nbsp;mm<\/td><td>905&nbsp;mm<\/td><td>905&nbsp;mm<\/td><td>730&nbsp;mm<\/td><td>905&nbsp;mm<\/td><td>905&nbsp;mm<\/td><td>780&nbsp;mm<\/td><td>790&nbsp;mm<\/td><\/tr><tr class=\"scaled-imperial\"><th>Larghezza<\/th><td>2&#8242; 5&#8243;<\/td><td>2&#8242; 5&#8243;<\/td><td>3&#8242; <\/td><td>3&#8242; <\/td><td>2&#8242; 5&#8243;<\/td><td>3&#8242; <\/td><td>3&#8242; <\/td><td>2&#8242; 7&#8243;<\/td><td>2&#8242; 7&#8243;<\/td><\/tr><tr class=\"scaled-metric\"><th>Altezza<\/th><td>2110&nbsp;mm<\/td><td>2110&nbsp;mm<\/td><td>2390&nbsp;mm<\/td><td>2390&nbsp;mm<\/td><td>2110&nbsp;mm<\/td><td>2390&nbsp;mm<\/td><td>2390&nbsp;mm<\/td><td>2115&nbsp;mm<\/td><td>2170&nbsp;mm<\/td><\/tr><tr class=\"scaled-imperial\"><th>Altezza<\/th><td>6&#8242; 11&#8243; <\/td><td>6&#8242; 11&#8243; <\/td><td>7&#8242; 10&#8243;<\/td><td>7&#8242; 10&#8243;<\/td><td>6&#8242; 11&#8243; <\/td><td>7&#8242; 10&#8243;<\/td><td>7&#8242; 10&#8243;<\/td><td>6&#8242; 11&#8243; <\/td><td>7&#8242; 1&#8243;<\/td><\/tr><tr class=\"scaled-metric\"><th>Lunghezza<\/th><td>2265&nbsp;mm<\/td><td>2265&nbsp;mm<\/td><td>2265&nbsp;mm<\/td><td>2265&nbsp;mm<\/td><td>2265&nbsp;mm<\/td><td>2265&nbsp;mm<\/td><td>2265&nbsp;mm<\/td><td>2265&nbsp;mm<\/td><td>2265&nbsp;mm<\/td><\/tr><tr class=\"scaled-imperial\"><th>Lunghezza<\/th><td>7&#8242; 5&#8243; <\/td><td>7&#8242; 5&#8243; <\/td><td>7&#8242; 5&#8243; <\/td><td>7&#8242; 5&#8243; <\/td><td>7&#8242; 5&#8243; <\/td><td>7&#8242; 5&#8243;<\/td><td>7&#8242; 5&#8243; <\/td><td>7&#8242; 5&#8243; <\/td><td>7&#8242; 5&#8243; <\/td><\/tr>              <\/tbody>\n            <\/table>\n\n          <\/div>\n        <\/div>\n\n       \n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Descrizione del prodotto<\/h2>\n\n\n\n<p><strong><strong>Potenza intelligente, controllo preciso.<\/strong><\/strong><\/p>\n\n\n\n<p>\u00a0La serie Tadano PM 11 SP \u00e8 una gru su autocarro a braccio articolato (serie PM) della linea Gold, progettata per alte prestazioni con dimensioni di installazione compatte. Con momenti di sollevamento da 9,5 a 10,3 tonnellate-metro e uno sbraccio verticale fino a 17,1 metri, offre un eccellente rapporto potenza\/peso.<\/p>\n\n\n\n<p>Tutte le configurazioni sono dotate di serie di radiocomando multifunzione con display, che fornisce all\u2019operatore un feedback continuo per una movimentazione precisa e sicura. Lo sbraccio orizzontale varia da 5,7 a 14,1 metri nei modelli dalla 11021 SP alla 11025 SP, mentre le versioni con JIB estendono ulteriormente la capacit\u00e0 \u2014 fino a 16,05 metri in orizzontale e 18,9 metri in verticale.<\/p>\n\n\n\n<p>Come parte della linea Gold, la serie PM 11 SP include articolazione con rinvio, blocco valvole proporzionali, gestione elettronica Power Tronic e scambiatore di calore per il funzionamento continuo. Leggero, affidabile e facile da mantenere, il PM 11 SP offre prestazioni premium e grande versatilit\u00e0 per le attivit\u00e0 di sollevamento pi\u00f9 impegnative.<\/p>\n\n\n\n<section class=\"pm-vehicle-type\">\n    <div class=\"container\">\n\n        <div class=\"title\">\n            <div class=\"left\">\n                <h2>Tipo di veicolo<\/h2>\n            <\/div>\n            <div class=\"right\">\n                                <div class=\"radio ton-lbs-switch\">\n                                        <label class=\"met\">\n                        <input type=\"radio\" name=\"filterScale\">\n                        <span class=\"fake-radio\"><\/span>\n                        <span class=\"fake-label\">ton<\/span>\n                    <\/label>\n                    <label class=\"imp\">\n                        <input type=\"radio\" name=\"filterScale\" >\n                        <span class=\"fake-radio\"><\/span>\n                        <span class=\"fake-label\">lbs<\/span>\n                    <\/label>\n                <\/div>\n                \n\n            <\/div>\n        <\/div>\n\n        <div class=\"pm-vehicle-type-wrapper\">\n            <div class=\"pm-vehicle-type-data\">\n                <ul>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>3.50 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>771617 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>5.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>1102310 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>6.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>1322772 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>6.50 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>1433003 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>7.50 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>1653465 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"li-active li-active-4ss\">\n                            <span class=\"scaled-metric\"><h5>8.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>1763696 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"li-active li-active-2xl\">\n                            <span class=\"scaled-metric\"><h5>10.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>2204620 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"li-active li-active-2ss\">\n                            <span class=\"scaled-metric\"><h5>12.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>2645544 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>13.50 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>2976237 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>15.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>3306930 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>18.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>3968316 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>19.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>4188778 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>26.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>5732012 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>32.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>7054784 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                            <li class=\"\">\n                            <span class=\"scaled-metric\"><h5>44.00 <span class=\"d-block\">ton<\/span><\/h5><\/span>\n                            <span class=\"scaled-imp\"><h5>9700328 <span class=\"d-block\">lbs<\/span><\/h5><\/span>\n                        <\/li>\n                                    <\/ul>\n            <\/div>\n        <\/div>\n\n        <ul class=\"pm-vehicle-type-legend\">\n            <li class=\"legend-item legend-2ss\">2 stabilizzatori standard<\/li>\n            <li class=\"legend-item legend-2xl\">2 stabilizzatori XL<\/li>\n            <li class=\"legend-item legend-4ss\">4 stabilizzatori<\/li>\n        <\/ul>\n    <\/div>\n    <style type=\"text\/css\">\n        \/* Container styles *\/\n        .pm-vehicle-type {\n            margin: 2rem 0;\n        }\n\n        .pm-vehicle-type .title {\n            display: flex;\n            justify-content: space-between;\n            align-items: end;\n        }\n        .pm-vehicle-type .radio {\n            margin-bottom: 0;\n            width: auto;\n        }\n        \n        .pm-vehicle-type-wrapper {\n            position: relative;\n            background-color: #0042951f;\n            padding: 2rem;\n            border-radius: 4px;\n        }\n        \n        .pm-vehicle-type-data ul {\n            margin: 0;\n            padding: 0;\n            display: flex;\n            flex-wrap: wrap;\n            justify-content: center;\n            list-style: none;\n            gap: 0.5rem;\n        }\n        \n        .pm-vehicle-type-data ul li {\n            display: flex;\n            flex-wrap: wrap;\n            justify-content: center;\n            align-items: center;\n            background-color: #ffffff;\n            text-align: center;\n            padding: 1rem;\n            border: 2px solid #e0e0e0;\n            border-radius: 4px;\n            transition: all 0.3s ease;\n            width: 115px;\n            height: 115px;\n            border-radius: 100%;\n\n        }\n        \n        .pm-vehicle-type-data ul li h5 {\n            margin: 0;\n            font-size: 1.75rem;\n            color: #004295;\n            font-weight: 600;\n            line-height: 1;\n        }\n        \n        .pm-vehicle-type-data ul li h5 span {\n            display: block;\n            font-size: 1.5rem;\n            font-weight: 400;\n            margin-top: 0.25rem;\n        }\n        \n        \/* Active state styles *\/\n        .pm-vehicle-type-data ul li.li-active {\n            border: 3px solid #ff8400;\n            border-width: 3px;\n            box-shadow: 0 2px 8px rgba(255, 132, 0, 0.2);\n        }\n        \n        .pm-vehicle-type-data ul li.li-active-2xl {\n            border-color: #85bf76;\n            box-shadow: 0 2px 8px rgba(133, 191, 118, 0.2);\n        }\n\n        .pm-vehicle-type-data ul li.li-active-4ss {\n            border-color: #1f96cd;\n            box-shadow: 0 2px 8px rgba(31, 150, 205, 0.2);\n        }\n        \n        \/* Legend styles *\/\n        .pm-vehicle-type-legend {\n            position: relative;\n            margin: 1rem 0 0 0;\n            padding: 0;\n            display: flex;\n            flex-wrap: wrap;\n            list-style: none;\n            gap: 1rem;\n            justify-content: center;\n        }\n        \n        .pm-vehicle-type-legend li {\n            position: relative;\n            padding-left: 1.5rem;\n            font-size: 1.5rem;\n            font-weight: bold;\n        }\n        \n        .pm-vehicle-type-legend li::before {\n            content: '';\n            position: absolute;\n            left: 0;\n            top: 50%;\n            transform: translateY(-50%);\n            width: 1rem;\n            height: 1rem;\n            border: 3px solid;\n            border-radius: 50%;\n        }\n        \n        .pm-vehicle-type-legend li.legend-2ss::before {\n            border-color: #ff8400;\n            background-color: #ff8400;\n        }\n        \n        .pm-vehicle-type-legend li.legend-2xl::before {\n            border-color: #85bf76;\n            background-color: #85bf76;\n        }\n\n        .pm-vehicle-type-legend li.legend-4ss::before {\n            border-color: #1f96cd;\n            background-color: #1f96cd;\n        }\n        \n        @media (max-width: 1075px) {\n            .pm-vehicle-type-data ul li {\n                width: 90px;\n                height: 90px;\n            }\n            .pm-vehicle-type-data ul li h5 {\n                font-size: 1.6rem;\n            }\n        }\n        @media (max-width: 768px) {\n            .pm-vehicle-type-data ul li {\n                padding: 0.75rem;\n                width: 80px;\n                height: 80px;\n            }\n            \n            .pm-vehicle-type-data ul li h5 {\n                font-size: 1.5rem;\n            }\n            .pm-vehicle-type-data ul li h5 span {\n                font-size: 1rem;\n            }\n        }\n    <\/style>\n\n    <script type=\"text\/javascript\">\n        (function() {\n            \/\/ Handle unit switching for ton\/lbs toggle\n            const tonLbsSwitch = document.querySelector('.ton-lbs-switch');\n            \n            if (tonLbsSwitch) {\n                const metricRadio = tonLbsSwitch.querySelector('label.met input[type=\"radio\"]');\n                const imperialRadio = tonLbsSwitch.querySelector('label.imp input[type=\"radio\"]');\n                \n                \/\/ Function to update body classes\n                function updateUnitClass(isImperial) {\n                    if (isImperial) {\n                        document.body.classList.remove('unit-is-met');\n                        document.body.classList.add('unit-is-imp');\n                        \/\/ Set cookie for 30 days\n                        document.cookie = 'measuringUnit=imp; path=\/; max-age=' + (30 * 24 * 60 * 60);\n                    } else {\n                        document.body.classList.remove('unit-is-imp');\n                        document.body.classList.add('unit-is-met');\n                        \/\/ Set cookie for 30 days\n                        document.cookie = 'measuringUnit=met; path=\/; max-age=' + (30 * 24 * 60 * 60);\n                    }\n                }\n                \n                \/\/ Add event listeners\n                if (metricRadio) {\n                    metricRadio.addEventListener('change', function() {\n                        if (this.checked) {\n                            updateUnitClass(false);\n                        }\n                    });\n                }\n                \n                if (imperialRadio) {\n                    imperialRadio.addEventListener('change', function() {\n                        if (this.checked) {\n                            updateUnitClass(true);\n                        }\n                    });\n                }\n            }\n        })();\n    <\/script>\n<\/section>\n\n\n\n<section class=\"file-download-block\">\n    <div class=\"container\">\n        <div class=\"file-download-wrapper\">\n            <div class=\"select-field\">\n                <label for=\"file-download-select\" class=\"hidden\">Select a file<\/label>\n                <select name=\"file-download-select\" id=\"file-download-select\" class=\"file-download-select\">\n                    <option value=\"\">Selezionare un file<\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/5da959555d5da338\/original\/doc_tadano_pm_11SP_brochure.pdf\" data-file-id=\"file-0\">\n                            Brochure PM 11 SP                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/2066a0c23f8344a\/original\/doc_tadano_pm_11SP_11021_specsheet.pdf\" data-file-id=\"file-1\">\n                            PM 11021 SP                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/33ac06bcc84c8a8\/original\/doc_tadano_pm_11SP_11022_specsheet.pdf\" data-file-id=\"file-2\">\n                            PM 11022 SP                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/136a39de2cd192d4\/original\/doc_tadano_pm_11SP_11022-J312_specsheet.pdf\" data-file-id=\"file-3\">\n                            PM 11022 SP + J312                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/10e38d584ecc81c7\/original\/doc_tadano_pm_11SP_11022-J313_specsheet.pdf\" data-file-id=\"file-4\">\n                            PM 11022 SP + J313                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/6bda4589a87cc707\/original\/doc_tadano_pm_11SP_11023_specsheet.pdf\" data-file-id=\"file-5\">\n                            PM 11023 SP                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/ae3e516de247bf6\/original\/doc_tadano_pm_11SP_11023-J312_specsheet.pdf\" data-file-id=\"file-6\">\n                            PM 11023 SP + J312                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/1ad9a93c70561731\/original\/doc_tadano_pm_11SP_11023-J313_specsheet.pdf\" data-file-id=\"file-7\">\n                            PM 11023 SP + J313                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/585325a4210bed18\/original\/doc_tadano_pm_11SP_11024_specsheet.pdf\" data-file-id=\"file-8\">\n                            PM 11024 SP                        <\/option>\n                                            <option value=\"https:\/\/mediahub.tadano.com\/m\/1bf26312c3a65fd\/original\/doc_tadano_pm_11SP_11025_specsheet.pdf\" data-file-id=\"file-9\">\n                            PM 11025 SP                        <\/option>\n                                    <\/select>\n            <\/div>\n            \n            <button type=\"button\" class=\"btn btn-primary file-download-button\" disabled>\n                Scarica            <\/button>\n        <\/div>\n    <\/div>\n<\/section>\n\n<script>\n(function() {\n    const select = document.getElementById('file-download-select');\n    const button = document.querySelector('.file-download-button');\n    \n    if (!select || !button) return;\n    \n    \/\/ Enable\/disable button based on selection\n    select.addEventListener('change', function() {\n        if (this.value) {\n            button.disabled = false;\n        } else {\n            button.disabled = true;\n        }\n    });\n    \n    \/\/ Handle download button click\n    button.addEventListener('click', function() {\n        const selectedUrl = select.value;\n        if (selectedUrl) {\n            \/\/ Create a temporary link and trigger download\n            const link = document.createElement('a');\n            link.href = selectedUrl;\n            link.target = '_blank';\n            document.body.appendChild(link);\n            link.click();\n            document.body.removeChild(link);\n        }\n    });\n})();\n<\/script>\n\n<style>\n.file-download-block {\n    padding: 2rem 0;\n    position: relative!important;\n    z-index: 6!important;\n}\n\n.file-download-block .file-download-wrapper {\n    display: flex;\n    gap: 1rem;\n    align-items: center;\n    flex-wrap: wrap;\n}\n.file-download-block .select-field {\n    min-width: 250px;\n    width: 380px;\n    max-width: 100%;\n\n}\n.file-download-block .jcf-select {\n    background-color: #e3e3e3;\n    margin-bottom: 0;\n}\n.file-download-block .jcf-list {\n    background-color: #f2f2f2;\n}\n\n.file-download-block .file-download-select {\n    min-width: 250px;\n}\n\n.file-download-block .file-download-button {\n    white-space: nowrap;\n}\n\n.file-download-block .file-download-button:disabled {\n    opacity: 0.5;\n    cursor: not-allowed;\n}\n<\/style>\n\n\n<section class=\"product-equipment related-products\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>Equipaggiamento<\/h2>\n      <\/div>\n     <div class=\"r-products\">\n                                        <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/12a0ee0ae15ea9ae\/gallery_thumb-img_tadano_pm_components_air_oil_heat_exchanger.jpg, https:\/\/mediahub.tadano.com\/m\/12a0ee0ae15ea9ae\/gallery_thumb-img_tadano_pm_components_air_oil_heat_exchanger.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Scambiatore di calore aria-olio<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Standard<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/5eaf0e8d9b34ab8c\/gallery_thumb-img_tadano_pm_components_multi_function_radio_control.jpg, https:\/\/mediahub.tadano.com\/m\/5eaf0e8d9b34ab8c\/gallery_thumb-img_tadano_pm_components_multi_function_radio_control.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Comando radio multifunzione<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Standard<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/31c4db996f88d773\/gallery_thumb-img_tadano_pm_components_rack.jpg, https:\/\/mediahub.tadano.com\/m\/31c4db996f88d773\/gallery_thumb-img_tadano_pm_components_rack.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Cremagliera<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Standard<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/3f8e30a969970aaf\/gallery_thumb-img_tadano_pm_components_hose_racks.jpg, https:\/\/mediahub.tadano.com\/m\/3f8e30a969970aaf\/gallery_thumb-img_tadano_pm_components_hose_racks.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Supporti per tubi flessibili<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Opzionale<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/bb7ba8377a84d11\/gallery_thumb-img_tadano_pm_components_hydraulic_flip_up_outriggers.jpg, https:\/\/mediahub.tadano.com\/m\/bb7ba8377a84d11\/gallery_thumb-img_tadano_pm_components_hydraulic_flip_up_outriggers.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Stabilizzatori ribaltabili idraulici<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Opzionale<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/127a61b148848f8d\/gallery_thumb-img_tadano_pm_components_hydraulic_pull_out_outrigger_booms.jpg, https:\/\/mediahub.tadano.com\/m\/127a61b148848f8d\/gallery_thumb-img_tadano_pm_components_hydraulic_pull_out_outrigger_booms.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Bracci stabilizzatori telescopici idraulici<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Opzionale<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/762dcf241d490afc\/gallery_thumb-img_tadano_pm_components_hydraulic_winch_on_crane.jpg, https:\/\/mediahub.tadano.com\/m\/762dcf241d490afc\/gallery_thumb-img_tadano_pm_components_hydraulic_winch_on_crane.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Argano idraulico sulla gru<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Opzionale<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/6163bdbd74ffe19b\/gallery_thumb-img_tadano_pm_components_jib.jpg, https:\/\/mediahub.tadano.com\/m\/6163bdbd74ffe19b\/gallery_thumb-img_tadano_pm_components_jib.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Jib (braccio ausiliario)<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Opzionale<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"r-product-single\">\n                    <div class=\"r-product-single-wrapper\">\n                        <div class=\"img-holder\">\n                                                        <div class=\"bg-stretch\" >\n                                <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/158940d3ffd7c7b9\/gallery_thumb-img_tadano_pm_components_work_spotlight_with_led_technology.jpg, https:\/\/mediahub.tadano.com\/m\/158940d3ffd7c7b9\/gallery_thumb-img_tadano_pm_components_work_spotlight_with_led_technology.jpg 2x\"><\/span>\n                            <\/div>\n                                                    <\/div>\n                        <div class=\"text-block\">\n                            <strong class=\"title\">Faro da lavoro con tecnologia LED<\/strong>\n\n                                                            <small><span class=\"equipment-type\">Opzionale<\/span><\/small>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <\/div>\n\n    <style type=\"text\/css\">\n        .product-equipment .r-product-single .r-product-single-wrapper {\n            display: flex;\n            flex-direction: row;\n            min-height: 0;\n            padding-left: 0;\n        }\n        .product-equipment .r-product-single:hover .text-block {\n            background-color: transparent;\n        }\n        .product-equipment .r-product-single .title {\n            letter-spacing: 0;\n            line-height: 1.3;\n        }\n        .product-equipment .r-product-single .img-holder {\n            position: relative;\n            width: 70px;\n            height: 70px;\n            margin: 10px;\n            flex-grow: 0;\n            flex-shrink: 0;\n        }\n        .product-equipment .r-product-single .text-block {\n            padding: 7px 10px 10px 0;\n            font-size: 14px;\n            line-height: 1;\n        }\n        \n    <\/style>\n<\/section>\n\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Galleria multimediale<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/5f77aea6673b782e\/gallery_full-img_tadano_pm_11SP-C-1.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/5f77aea6673b782e\/gallery_thumb-img_tadano_pm_11SP-C-1.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n\n\n\n\n\n\n\n\n\n\n  <section class=\"related-products related-pages\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>Pagine correlate<\/h2>\n      <\/div>\n\n      <div class='r-products'>\n                  \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-10-s-c\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/6a73193a150cdcde\/img_thumb-img_tadano_pm_10S_10SC-1.jpg, https:\/\/mediahub.tadano.com\/m\/6a73193a150cdcde\/img_thumb_2x-img_tadano_pm_10S_10SC-1.jpg 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">PM 10 S C<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                            \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-11\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/3a00c3fa9c3a2a5a\/img_thumb-img_tadano_pm_11-4.jpg, https:\/\/mediahub.tadano.com\/m\/3a00c3fa9c3a2a5a\/img_thumb_2x-img_tadano_pm_11-4.jpg 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">PM 11<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                            \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/europe\/en\/lifting-equipment\/knuckle-boom-cranes\/pm-11-sp-c\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/5f77aea6673b782e\/img_thumb-img_tadano_pm_11SP-C-1.png, https:\/\/mediahub.tadano.com\/m\/5f77aea6673b782e\/img_thumb_2x-img_tadano_pm_11SP-C-1.png 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">PM 11 SP C<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                        <\/div>\n        \n    <\/div>\n  <\/section>\n  \n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>Notizie<\/h2>\n                        \n                  <a href=\"https:\/\/www.tadano.com\/europe\/it\/informazioni\/news-list\/\" class=\"link-more\">ESPLORARE TUTTE le notizie<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/it\/news\/tadano-teamworkcc-68-1250-1-and-cc-38-650-1-lift-steel-bridge-sections-at-the-porto-di-pra-shipyard\/\">\n                  <strong class=\"title\">Gioco di squadra in casa Tadano:le gru CC 68.1250-1 e CC 38.650-1 sollevano le sezioni in acciaio di un ponte presso il cantiere nel Porto di Pra&#8217;<\/strong>\n                  <ul class=\"meta\">\n                    <li>Pubblicazione<\/li>\n                    <li><time datetime=\"2020-01-01\">Ago\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/europe\/it\/news\/la-nuova-tadano-ac-5-250-2-promossa-a-pieni-voti-sotto-il-profilo-delle-prestazioni\/\">\n                  <strong class=\"title\">La nuova Tadano AC 5.250-2 promossa a pieni voti sotto il profilo delle prestazioni<\/strong>\n                  <ul class=\"meta\">\n                    <li>Pubblicazione<\/li>\n                    <li><time datetime=\"2020-01-01\">Lug\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  ","protected":false},"featured_media":0,"template":"","lifting-equipment":[116],"class_list":["post-14092","products","type-products","status-publish","hentry","lifting-equipment-knuckle-boom-cranes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PM 11 SP - Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/europe\/it\/attrezzature-di-sollevamento\/knuckle-boom-cranes\/pm-11-sp\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PM 11 SP - Europe\" \/>\n<meta property=\"og:description\" content=\"Descrizione del prodotto Potenza intelligente, controllo preciso. \u00a0La serie Tadano PM 11 SP \u00e8 una gru su autocarro a braccio articolato (serie PM) della linea Gold, progettata per alte prestazioni con dimensioni di installazione compatte. Con momenti di sollevamento da 9,5 a 10,3 tonnellate-metro e uno sbraccio verticale fino a 17,1 metri, offre un eccellente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/europe\/it\/attrezzature-di-sollevamento\/knuckle-boom-cranes\/pm-11-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T19:00:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/it\\\/attrezzature-di-sollevamento\\\/knuckle-boom-cranes\\\/pm-11-sp\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/it\\\/attrezzature-di-sollevamento\\\/knuckle-boom-cranes\\\/pm-11-sp\\\/\",\"name\":\"PM 11 SP - Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\"},\"datePublished\":\"2025-10-29T12:58:40+00:00\",\"dateModified\":\"2026-02-25T19:00:13+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/europe\\\/it\\\/attrezzature-di-sollevamento\\\/knuckle-boom-cranes\\\/pm-11-sp\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/\",\"name\":\"Europe\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PM 11 SP - Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/europe\/it\/attrezzature-di-sollevamento\/knuckle-boom-cranes\/pm-11-sp\/","og_locale":"it_IT","og_type":"article","og_title":"PM 11 SP - Europe","og_description":"Descrizione del prodotto Potenza intelligente, controllo preciso. \u00a0La serie Tadano PM 11 SP \u00e8 una gru su autocarro a braccio articolato (serie PM) della linea Gold, progettata per alte prestazioni con dimensioni di installazione compatte. Con momenti di sollevamento da 9,5 a 10,3 tonnellate-metro e uno sbraccio verticale fino a 17,1 metri, offre un eccellente [&hellip;]","og_url":"https:\/\/www.tadano.com\/europe\/it\/attrezzature-di-sollevamento\/knuckle-boom-cranes\/pm-11-sp\/","og_site_name":"Europe","article_modified_time":"2026-02-25T19:00:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/europe\/it\/attrezzature-di-sollevamento\/knuckle-boom-cranes\/pm-11-sp\/","url":"https:\/\/www.tadano.com\/europe\/it\/attrezzature-di-sollevamento\/knuckle-boom-cranes\/pm-11-sp\/","name":"PM 11 SP - Europe","isPartOf":{"@id":"https:\/\/www.tadano.com\/europe\/en\/#website"},"datePublished":"2025-10-29T12:58:40+00:00","dateModified":"2026-02-25T19:00:13+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/europe\/it\/attrezzature-di-sollevamento\/knuckle-boom-cranes\/pm-11-sp\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/europe\/en\/#website","url":"https:\/\/www.tadano.com\/europe\/en\/","name":"Europe","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/europe\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/products\/14092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/products\/14092\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/media?parent=14092"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/lifting-equipment?post=14092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}