{"id":10890,"date":"2021-12-10T09:26:39","date_gmt":"2021-12-10T09:26:39","guid":{"rendered":"https:\/\/www.tadano.com\/europe\/technologies\/start-stop\/"},"modified":"2026-05-08T11:15:22","modified_gmt":"2026-05-08T11:15:22","slug":"start-stop","status":"publish","type":"technologies","link":"https:\/\/www.tadano.com\/europe\/it\/technologies\/start-stop\/","title":{"rendered":"Start-Stop"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\t\t<style type=\"text\/css\">\n\t\t\t.hero-section .img-holder:before {\n\t\t\t\tdisplay: none;\n\t\t\t}\n\t\t<\/style>\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 100% 50%; \">\n\t\t\t<span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/hero\/START_STOP_Kabine_Motiv_10122021_B.jpg, https:\/\/assets.onetadano.com\/celum_assets\/hero-2x\/START_STOP_Kabine_Motiv_10122021_B.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/europe\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder \">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/europe\/it\/\">Homepage<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.demagmobilecranes.com\/en\/demag-technology\/cc-3800-1-boom-booster\/\" target=\"_blank\"><\/a><a rel=\"noreferrer noopener\" href=\"https:\/\/www.demagmobilecranes.com\/en\/demag-technology\/cc-8800-1-boom-booster\/\" target=\"_blank\"><\/a><span class=\"has-inline-color has-black-color\"><strong>Funzione start-sto<\/strong><\/span>P<\/h1>\n\n\n\n<p>La funzione start-stop consente di arrestare manualmente il motore con la semplice pressione di un pulsante nella cabina durante l&#8217;uso della gru, per evitare tempi di funzionamento senza utilizzo. In questo modo si riducono i consumi di carburante della gru, le emissioni e le ore di funzionamento. Sebbene il motore venga arrestato, il sistema di comando della gru resta attivo e dopo il riavvio la gru \u00e8 subito pronta a ripartire.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<div class=\"wp-block-group is-style-background-triangle-right\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">DESCRIZIONE DELLA TECNOLOGIA<\/h2>\n\n\n\n<p><strong>Emissioni e consumi di carburante ridotti. Maggiore economicit\u00e0.<\/strong><\/p>\n\n\n\n<p>Il vantaggio decisivo apportato dalla funzione start-stop rispetto al tradizionale arresto del motore risiede nel fatto che il sistema di comando gru IC-1 non viene arrestato ma viene mantenuto attivo. In altre parole, quando si utilizza la funzione start-stop per riprendere il lavoro, il sistema di comando \u00e8 pronto in pochi secondi e quindi \u00e8 possibile iniziare o proseguire un&#8217;operazione di sollevamento praticamente senza ritardi.<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La funzione start-stop consente di arrestare manualmente il motore con la semplice pressione di un pulsante nella cabina durante l&#8217;uso della gru, per evitare tempi di funzionamento senza utilizzo. In questo modo si riducono i consumi di carburante della gru, le emissioni e le ore di funzionamento. Sebbene il motore venga arrestato, il sistema di comando della gru resta attivo e dopo il riavvio la gru \u00e8 subito pronta a ripartire.<\/p>\n","protected":false},"template":"","class_list":["post-10890","technologies","type-technologies","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Start-Stop - Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/europe\/it\/technologies\/start-stop\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Start-Stop - Europe\" \/>\n<meta property=\"og:description\" content=\"La funzione start-stop consente di arrestare manualmente il motore con la semplice pressione di un pulsante nella cabina durante l&#039;uso della gru, per evitare tempi di funzionamento senza utilizzo. In questo modo si riducono i consumi di carburante della gru, le emissioni e le ore di funzionamento. Sebbene il motore venga arrestato, il sistema di comando della gru resta attivo e dopo il riavvio la gru \u00e8 subito pronta a ripartire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/europe\/it\/technologies\/start-stop\/\" \/>\n<meta property=\"og:site_name\" content=\"Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T11:15:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/it\\\/technologies\\\/start-stop\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/it\\\/technologies\\\/start-stop\\\/\",\"name\":\"Start-Stop - Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\"},\"datePublished\":\"2021-12-10T09:26:39+00:00\",\"dateModified\":\"2026-05-08T11:15:22+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/europe\\\/it\\\/technologies\\\/start-stop\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/\",\"name\":\"Europe\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/europe\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Start-Stop - Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/europe\/it\/technologies\/start-stop\/","og_locale":"it_IT","og_type":"article","og_title":"Start-Stop - Europe","og_description":"La funzione start-stop consente di arrestare manualmente il motore con la semplice pressione di un pulsante nella cabina durante l'uso della gru, per evitare tempi di funzionamento senza utilizzo. In questo modo si riducono i consumi di carburante della gru, le emissioni e le ore di funzionamento. Sebbene il motore venga arrestato, il sistema di comando della gru resta attivo e dopo il riavvio la gru \u00e8 subito pronta a ripartire.","og_url":"https:\/\/www.tadano.com\/europe\/it\/technologies\/start-stop\/","og_site_name":"Europe","article_modified_time":"2026-05-08T11:15:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/europe\/it\/technologies\/start-stop\/","url":"https:\/\/www.tadano.com\/europe\/it\/technologies\/start-stop\/","name":"Start-Stop - Europe","isPartOf":{"@id":"https:\/\/www.tadano.com\/europe\/en\/#website"},"datePublished":"2021-12-10T09:26:39+00:00","dateModified":"2026-05-08T11:15:22+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/europe\/it\/technologies\/start-stop\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/europe\/en\/#website","url":"https:\/\/www.tadano.com\/europe\/en\/","name":"Europe","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/europe\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/technologies\/10890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/technologies"}],"about":[{"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/types\/technologies"}],"version-history":[{"count":1,"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/technologies\/10890\/revisions"}],"predecessor-version":[{"id":15670,"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/technologies\/10890\/revisions\/15670"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/europe\/it\/wp-json\/wp\/v2\/media?parent=10890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}