{"id":13782,"date":"2023-01-20T13:34:32","date_gmt":"2023-01-20T13:34:32","guid":{"rendered":"https:\/\/www.tadano.com\/france\/formulaire-du-fournisseur\/"},"modified":"2023-05-08T07:04:20","modified_gmt":"2023-05-08T07:04:20","slug":"formulaire-du-fournisseur","status":"publish","type":"page","link":"https:\/\/www.tadano.com\/france\/fr\/formulaire-du-fournisseur\/","title":{"rendered":"Formulaire du fournisseur"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder no-background-image\">\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/france\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder \">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/france\/fr\/\">Accueil<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">Formulaire du fournisseur<\/h1>\n\n\n\n<p>Questionnaire sur l&rsquo;\u00e9change de donn\u00e9es informatis\u00e9es (EDI)<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<script type=\"text\/javascript\">\n\n  const pardotURL = 'https:\/\/info.tadanoeurope.com\/l\/761063\/2021-04-26\/dvq4g';\n\n<\/script>\n\n<section class=\"contact-form-block form-block cookieconsent-optin-marketing\" id=\"contact-form-container\">\n  <div class=\"container\">\n\n\n\n\n  \n    <script type=\"text\/javascript\">\n      var recaptchaPublicKey = '6Ldq-sgaAAAAAFdx0YPp6eTsOESRRTjR4mf2ROcn';\n      const formRequiredMessage = 'Ce champ est obligatoire';\n      var formRecipient = 'tdg-tfg.procurement@tadano.com';\n      var formSubject = 'Contact Form';\n    <\/script>\n\n    <script src=\"https:\/\/www.google.com\/recaptcha\/api.js?render=6Ldq-sgaAAAAAFdx0YPp6eTsOESRRTjR4mf2ROcn\"><\/script>\n\n\n    <form class=\"contact-form\" action=\"#contact-form-container\" method=\"POST\" enctype=\"multipart\/form-data\" id=\"contact-form\" onsubmit=\"dataLayer.push({'event': 'formSubmission'});\">\n         \n    <fieldset>\n        <legend>Donn\u00e9es g\u00e9n\u00e9rales<\/legend>\n        <div class=\"row\">\n            <div class=\"col\">\n                <label for=\"supplier\" class=\"hidden\">Fournisseur<\/label>\n                <input type=\"text\" placeholder=\"Fournisseur *\" name=\"supplier\" required\/>\n            <\/div>\n            <div class=\"col\">\n                <label for=\"vendor-number\" class=\"hidden\">Num\u00e9ro de fournisseur Tadano<\/label>\n                <input type=\"text\" placeholder=\"Num\u00e9ro de fournisseur Tadano\" name=\"vendor-number\"\/>\n            <\/div>\n            <div class=\"col full-width\">\n                <label for=\"address\" class=\"hidden\">Adresse<\/label>\n                <input type=\"text\" placeholder=\"Adresse *\" name=\"address\" required \/>\n            <\/div>\n        <\/div>\n    <\/fieldset>\n\n    <fieldset>\n        <legend>Votre interlocuteur sur le plan technique<\/legend>\n        <div class=\"row\">\n            <div class=\"col\">\n                <label for=\"contact-technical-name\" class=\"hidden\">Nom<\/label>\n                <input type=\"text\" placeholder=\"Nom\" name=\"contact-technical-name\" \/>\n            <\/div>\n            <div class=\"col\"><\/div>\n            <div class=\"col\">\n                <label for=\"contact-technical-email\" class=\"hidden\">Adresse email<\/label>\n                <input type=\"email\" placeholder=\"Adresse email\" name=\"contact-technical-email\" \/>\n            <\/div>\n            <div class=\"col\">\n                <label for=\"contact-technical-phone\" class=\"hidden\">T\u00e9l\u00e9phone<\/label>\n                <input type=\"tel\" placeholder=\"T\u00e9l\u00e9phone\" name=\"contact-technical-phone\" \/>\n            <\/div>\n        <\/div>\n    <\/fieldset>\n\n    <fieldset>\n        <legend>Votre interlocuteur sp\u00e9cialis\u00e9<\/legend>\n        <div class=\"row\">\n            <div class=\"col\">\n                <label for=\"contact-professional-name\" class=\"hidden\">Nom<\/label>\n                <input type=\"text\" placeholder=\"Nom\" name=\"contact-professional-name\" \/>\n            <\/div>\n            <div class=\"col\"><\/div>\n            <div class=\"col\">\n                <label for=\"contact-professional-email\" class=\"hidden\">Adresse email<\/label>\n                <input type=\"email\" placeholder=\"Adresse email\" name=\"contact-professional-email\" \/>\n            <\/div>\n            <div class=\"col\">\n                <label for=\"contact-professional-phone\" class=\"hidden\">T\u00e9l\u00e9phone<\/label>\n                <input type=\"tel\" placeholder=\"T\u00e9l\u00e9phone\" name=\"contact-professional-phone\" \/>\n            <\/div>\n        <\/div>\n    <\/fieldset>\n\n    <fieldset>\n        <legend>Interlocuteur Tadano (Achats)<\/legend>\n        <div class=\"row\">\n            <div class=\"col\">\n                <label for=\"contact-purchasing-name\" class=\"hidden\">Nom<\/label>\n                <input type=\"text\" placeholder=\"Nom\" name=\"contact-purchasing-name\" \/>\n            <\/div>\n            <div class=\"col\"><\/div>\n            <div class=\"col\">\n                <label for=\"contact-purchasing-email\" class=\"hidden\">Adresse email<\/label>\n                <input type=\"email\" placeholder=\"Adresse email\" name=\"contact-purchasing-email\" \/>\n            <\/div>\n            <div class=\"col\">\n                <label for=\"contact-purchasing-phone\" class=\"hidden\">T\u00e9l\u00e9phone<\/label>\n                <input type=\"tel\" placeholder=\"T\u00e9l\u00e9phone\" name=\"contact-purchasing-phone\" \/>\n            <\/div>\n        <\/div>\n    <\/fieldset>\n\n    <h2 style=\"margin-bottom: 10px;\">Degr\u00e9 d&rsquo;int\u00e9gration<\/h2>\n    <fieldset>\n        <legend>G\u00e9n\u00e9ralit\u00e9s<\/legend>\n       \n        <div class=\"row\">\n            <div class=\"col full-width\">\n                <label for=\"erp-system\" class=\"hidden\">Quel type de syst\u00e8me ERP utilisez-vous\u00a0?<\/label>\n                <input type=\"text\" placeholder=\"Quel type de syst\u00e8me ERP utilisez-vous\u00a0?\" name=\"erp-system\"  \/>\n            <\/div>\n            <div class=\"col full-width\">\n                <label for=\"data-exchanged-with-other-partners\" class=\"hidden\">Des donn\u00e9es sont-elles d\u00e9j\u00e0 \u00e9chang\u00e9es par EDI avec d&rsquo;autres partenaires commerciaux\u00a0?<\/label>\n                <select name=\"data-exchanged-with-other-partners\">\n                    <option value=\"\">Des donn\u00e9es sont-elles d\u00e9j\u00e0 \u00e9chang\u00e9es par EDI avec d&rsquo;autres partenaires commerciaux\u00a0?<\/option>\n                    <option>Oui<\/option>\n                    <option>Non<\/option>\n                <\/select>\n            <\/div>\n            <div class=\"col full-width\">\n                <label for=\"data-processing-via-edi-provider\" class=\"hidden\">Le traitement est-il effectu\u00e9 par un prestataire de services d&rsquo;EDI\u00a0?<\/label>\n                <select id=\"data-processing-via-edi-provider\" name=\"data-processing-via-edi-provider\">\n                    <option value=\"\">Le traitement est-il effectu\u00e9 par un prestataire de services d&rsquo;EDI\u00a0?<\/option>\n                    <option value=\"yes\">Oui<\/option>\n                    <option>Non<\/option>\n                <\/select>\n            <\/div>\n        <\/div>\n\n        <div id=\"contact-details-edi-service-provider\" style=\"display:none;\">\n            <div class=\"row\">\n                <div class=\"col full-width\" style=\"padding-bottom:10px;\">\n                    <h3 style=\"\">Contact du fournisseur de services EDI<\/h3>\n                <\/div>\n                <div class=\"col\">\n                    <label for=\"edi-service-provider-name\" class=\"hidden\">Nom<\/label>\n                    <input type=\"text\" placeholder=\"Nom\" name=\"edi-service-provider-name\" \/>\n                <\/div>\n                <div class=\"col\">\n                    <label for=\"edi-service-provider-contact-person\" class=\"hidden\">Interlocuteur<\/label>\n                    <input type=\"email\" placeholder=\"Interlocuteur\" name=\"edi-service-provider-contact-person\" \/>\n                <\/div>\n                <div class=\"col\">\n                    <label for=\"edi-service-provider-contact\" class=\"hidden\">Contact<\/label>\n                    <input type=\"tel\" placeholder=\"Contact\" name=\"edi-service-provider-contact\" \/>\n                <\/div>\n                <div class=\"col\">\n                    <label for=\"edi-service-provider-software\" class=\"hidden\">Logiciel de conversion EDI<\/label>\n                    <input type=\"tel\" placeholder=\"Logiciel de conversion EDI\" name=\"edi-service-provider-software\" \/>\n                <\/div>\n            <\/div>\n        <\/div>\n  \n    <\/fieldset>\n\n        \n\n    <fieldset>\n        <legend>Processus op\u00e9rationnels planifi\u00e9s<\/legend>\n        <div class=\"row\">\n            <div class=\"col full-width\" style=\"padding-bottom: 10px;\">\n                <h3 style=\"\">Quels formats de transfert de donn\u00e9es souhaitez-vous \/ prenez-vous en charge\u00a0?<\/h3>\n                <p>Standard Tadano = XML-IDOC<\/p>\n            <\/div>\n        <\/div>\n\n        <fieldset>\n            <legend>Commandes <\/legend>\n            <div class=\"row\">\n                <div class=\"col\">\n                    <label class=\"terms-checkbox\">\n                        <input type=\"checkbox\" name=\"data-transfer-orders-default\" title=\"ORDERS (Tadano Standard)\" \/>\n                        <span class=\"fake-input\"><\/span>\n                        <span class=\"fake-label\">ORDERS (Tadano Standard)                        <\/span>\n                    <\/label>\n                <\/div>\n                <div class=\"col\">\n                    <label for=\"data-transfer-orders-other\" class=\"hidden\">Autres<\/label>\n                    <input type=\"text\" placeholder=\"Autres\" name=\"data-transfer-orders-other\" \/>\n                <\/div>\n            <\/div>\n        <\/fieldset>\n\n        <fieldset>\n            <legend>Modifications de commande<\/legend>\n            <div class=\"row\">\n                <div class=\"col\">\n                    <label class=\"terms-checkbox\">\n                        <input type=\"checkbox\" name=\"data-transfer-orders-change-default\" title=\"ORDCHG (Tadano Standard)\" \/>\n                        <span class=\"fake-input\"><\/span>\n                        <span class=\"fake-label\">ORDCHG (Tadano Standard)                        <\/span>\n                    <\/label>\n                <\/div>\n                <div class=\"col\">\n                    <label for=\"data-transfer-orders-change-other\" class=\"hidden\">Autres<\/label>\n                    <input type=\"text\" placeholder=\"Autres\" name=\"data-transfer-orders-change-other\" \/>\n                <\/div>\n            <\/div>\n        <\/fieldset>\n\n        <fieldset>\n            <legend>Programmes de livraison<\/legend>\n            <div class=\"row\">\n                <div class=\"col\">\n                    <label class=\"terms-checkbox\">\n                        <input type=\"checkbox\" name=\"data-transfer-sheduling-aggreements-default\" title=\"DELINS (Tadano Standard)\" \/>\n                        <span class=\"fake-input\"><\/span>\n                        <span class=\"fake-label\">DELINS (Tadano Standard)                        <\/span>\n                    <\/label>\n                <\/div>\n                <div class=\"col\">\n                    <label for=\"data-transfer-sheduling-aggreements-other\" class=\"hidden\">Autres<\/label>\n                    <input type=\"text\" placeholder=\"Autres\" name=\"data-transfer-sheduling-aggreements-other\" \/>\n                <\/div>\n            <\/div>\n        <\/fieldset>\n\n        <fieldset>\n            <legend>Confirmations de commande<\/legend>\n            <div class=\"row\">\n                <div class=\"col\">\n                    <label class=\"terms-checkbox\">\n                        <input type=\"checkbox\" name=\"data-transfer-order-confirmations-default\" title=\"ORDRSP (Tadano Standard)\" \/>\n                        <span class=\"fake-input\"><\/span>\n                        <span class=\"fake-label\">ORDRSP (Tadano Standard)                        <\/span>\n                    <\/label>\n                <\/div>\n                <div class=\"col\">\n                    <label for=\"data-transfer-order-confirmations-other\" class=\"hidden\">Autres<\/label>\n                    <input type=\"text\" placeholder=\"Autres\" name=\"data-transfer-order-confirmations-other\" \/>\n                <\/div>\n            <\/div>\n        <\/fieldset>\n\n        <fieldset>\n            <legend>Livraisons<\/legend>\n            <div class=\"row\">\n                <div class=\"col\">\n                    <label class=\"terms-checkbox\">\n                        <input type=\"checkbox\" name=\"data-transfer-deliveries-default\" title=\"DESADV (Tadano Standard)\" \/>\n                        <span class=\"fake-input\"><\/span>\n                        <span class=\"fake-label\">DESADV (Tadano Standard)                        <\/span>\n                    <\/label>\n                <\/div>\n                <div class=\"col\">\n                    <label for=\"data-transfer-deliveries-other\" class=\"hidden\">Autres<\/label>\n                    <input type=\"text\" placeholder=\"Autres\" name=\"data-transfer-deliveries-other\" \/>\n                <\/div>\n            <\/div>\n        <\/fieldset>\n\n    <\/fieldset>\n\n    <fieldset>\n        <legend>Standard de communication<\/legend>\n        <div class=\"row\">\n            <div class=\"col\">\n                <label class=\"terms-checkbox\">\n                    <input type=\"checkbox\" name=\"communication-standard-sftp\" title=\"SFTP\" \/>\n                    <span class=\"fake-input\"><\/span>\n                    <span class=\"fake-label\">SFTP                    <\/span>\n                <\/label>\n            <\/div>\n            <div class=\"col\">\n                <label for=\"communication-standard-other\" class=\"hidden\">Autres<\/label>\n                <input type=\"text\" placeholder=\"Autres\" name=\"communication-standard-other\" \/>\n            <\/div>\n        <\/div>\n    <\/fieldset>\n\n    <fieldset>\n        <legend>Calendrier pr\u00e9vu<\/legend>\n        <div class=\"row\">\n            <div class=\"col full-width\">\n                <label for=\"scheduled-time-frame\" class=\"hidden\">Calendrier pr\u00e9vu<\/label>\n                <input type=\"text\" placeholder=\"Calendrier pr\u00e9vu\" name=\"scheduled-time-frame\" \/>\n            <\/div>\n        <\/div>\n    <\/fieldset>\n\n    <fieldset>\n        <legend>Divers \/ remarques<\/legend>\n        <div class=\"row\">\n            <div class=\"col full-width\">\n            <label for=\"message\" class=\"hidden\">Message<\/label>\n            <textarea placeholder=\"Message\" name=\"message\" ><\/textarea>\n            <\/div>\n        <\/div>\n    <\/fieldset>\n\n\n      <div class=\"row\">\n        <div class=\"col full-width terms\">\n          <label class=\"terms-checkbox\">\n            <input type=\"checkbox\" name=\"data-protection\" required title=\"Veuillez accepter notre d\u00e9claration de protection des donn\u00e9es\" \/>\n            <span class=\"fake-input\"><\/span>\n            <span class=\"fake-label\">J&rsquo;ai pris connaissance de la <a target=\"_blank\" href=\"https:\/\/www.tadano.com\/france\/fr\/politique-de-confidentialite\/\">politique de confidentialit\u00e9 des donn\u00e9es<\/a>.*\n            <\/span>\n          <\/label>\n          <span class=\"req\">*Requis<\/span>\n        <\/div>\n        <div class=\"loader\"><\/div>\n        <div class=\"col full-width btn-holder\">\n          <input type=\"submit\" class=\"btn btn-outline-white\" value=\"Inscrivez-vous\" name=\"submit_contact_form\" id=\"submit_form\" \/>\n        <\/div>\n      <\/div>\n    <\/form>\n\n\n\n\n  \n\n  <div class=\"form-success\"  >\n    \n\n<h2 class=\"wp-block-heading\">MERCI !<\/h2>\n\n\n\n<p>Nous accordons une grande importance \u00e0 vos commentaires et \u00e0 vos demandes. Notre \u00e9quipe examinera votre message et y r\u00e9pondra le plus rapidement possible. Encore une fois, nous vous remercions !<\/p>\n\n\n  <\/div>\n\n<\/div>\n\n\n<script type=\"text\/javascript\">\n    window.addEventListener('load', function() {\n        \/\/ if select with id \"data-processing-via-edi-provider\" is true then show the div with id \"contact-details-edi-service-provider\" else hide it; no jquery\n        document.getElementById('data-processing-via-edi-provider').addEventListener('change', function() {\n        if (this.value == 'yes') {\n            document.getElementById('contact-details-edi-service-provider').style.display = 'block';\n        } else {\n            document.getElementById('contact-details-edi-service-provider').style.display = 'none';\n        }\n        });\n    });\n  <\/script>\n\n\n\n<\/section>\n\n<div class=\"cookieconsent-optout-marketing cookieconsent\" style=\"background-image: url('https:\/\/www.tadano.com\/france\/wp-content\/themes\/tadano\/assets\/dist\/images\/nocookie_form.jpg');\">\n      <div class=\"wrapper\">\n        <h3>Vous devez accepter les cookies pour visualiser ce contenu.<\/h3>\n        <a href=\"javascript: Cookiebot.renew()\" class=\"btn btn-outline-white\">accepter<\/a>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-13782","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Formulaire du fournisseur - France<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/france\/formulaire-du-fournisseur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formulaire du fournisseur - France\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/france\/formulaire-du-fournisseur\/\" \/>\n<meta property=\"og:site_name\" content=\"France\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-08T07:04:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/france\\\/formulaire-du-fournisseur\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/france\\\/formulaire-du-fournisseur\\\/\",\"name\":\"Formulaire du fournisseur - France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/france\\\/fr\\\/#website\"},\"datePublished\":\"2023-01-20T13:34:32+00:00\",\"dateModified\":\"2023-05-08T07:04:20+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/france\\\/formulaire-du-fournisseur\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/france\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/france\\\/fr\\\/\",\"name\":\"France\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/france\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formulaire du fournisseur - France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/france\/formulaire-du-fournisseur\/","og_locale":"fr_FR","og_type":"article","og_title":"Formulaire du fournisseur - France","og_url":"https:\/\/www.tadano.com\/france\/formulaire-du-fournisseur\/","og_site_name":"France","article_modified_time":"2023-05-08T07:04:20+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/france\/formulaire-du-fournisseur\/","url":"https:\/\/www.tadano.com\/france\/formulaire-du-fournisseur\/","name":"Formulaire du fournisseur - France","isPartOf":{"@id":"https:\/\/www.tadano.com\/france\/fr\/#website"},"datePublished":"2023-01-20T13:34:32+00:00","dateModified":"2023-05-08T07:04:20+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/france\/formulaire-du-fournisseur\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/france\/fr\/#website","url":"https:\/\/www.tadano.com\/france\/fr\/","name":"France","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/france\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/france\/fr\/wp-json\/wp\/v2\/pages\/13782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/france\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tadano.com\/france\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/france\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/france\/fr\/wp-json\/wp\/v2\/comments?post=13782"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/france\/fr\/wp-json\/wp\/v2\/pages\/13782\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/france\/fr\/wp-json\/wp\/v2\/media?parent=13782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}