{"id":255,"date":"2024-03-26T14:40:31","date_gmt":"2024-03-26T14:40:31","guid":{"rendered":"https:\/\/www.tadano.com\/india\/about\/news-list\/"},"modified":"2024-03-26T15:06:31","modified_gmt":"2024-03-26T15:06:31","slug":"news-list","status":"publish","type":"page","link":"https:\/\/www.tadano.com\/india\/en\/about\/news-list\/","title":{"rendered":"News"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":164,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/news-archive.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-255","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News - India<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/india\/en\/about\/news-list\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News - India\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/india\/en\/about\/news-list\/\" \/>\n<meta property=\"og:site_name\" content=\"India\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-26T15:06:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/about\\\/news-list\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/about\\\/news-list\\\/\",\"name\":\"News - India\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/#website\"},\"datePublished\":\"2024-03-26T14:40:31+00:00\",\"dateModified\":\"2024-03-26T15:06:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/about\\\/news-list\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/about\\\/news-list\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/about\\\/news-list\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/\",\"name\":\"India\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News - India","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/india\/en\/about\/news-list\/","og_locale":"en_US","og_type":"article","og_title":"News - India","og_url":"https:\/\/www.tadano.com\/india\/en\/about\/news-list\/","og_site_name":"India","article_modified_time":"2024-03-26T15:06:31+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/india\/en\/about\/news-list\/","url":"https:\/\/www.tadano.com\/india\/en\/about\/news-list\/","name":"News - India","isPartOf":{"@id":"https:\/\/www.tadano.com\/india\/en\/#website"},"datePublished":"2024-03-26T14:40:31+00:00","dateModified":"2024-03-26T15:06:31+00:00","breadcrumb":{"@id":"https:\/\/www.tadano.com\/india\/en\/about\/news-list\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/india\/en\/about\/news-list\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tadano.com\/india\/en\/about\/news-list\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tadano.com\/india\/en\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/india\/en\/#website","url":"https:\/\/www.tadano.com\/india\/en\/","name":"India","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/india\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/pages\/255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/comments?post=255"}],"version-history":[{"count":1,"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/pages\/255\/revisions"}],"predecessor-version":[{"id":1804,"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/pages\/255\/revisions\/1804"}],"up":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/pages\/164"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/media?parent=255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}