{"id":3196,"date":"2022-03-21T14:34:08","date_gmt":"2022-03-21T14:34:08","guid":{"rendered":"https:\/\/www.tadano.com\/india\/%term%\/%cat%\/at-300cg\/"},"modified":"2022-03-21T14:34:08","modified_gmt":"2022-03-21T14:34:08","slug":"at-300cg","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/india\/en\/lifting-equipment\/aerial-work-platforms\/at-300cg\/","title":{"rendered":"AT-300CG-2"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 50% 100%; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/760aeccb88e358cc\/hero-img_Tadano_AT300CG_clr_001_eng-png.png, https:\/\/mediahub.tadano.com\/m\/760aeccb88e358cc\/hero_2x-img_Tadano_AT300CG_clr_001_eng-png.png 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/india\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/india\/en\/\">Home<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">AT-300CG-2<\/h1>\n\n\n\n<p>AT-300CG has articulated booms to cope flexibly with operations in deeper reach, covering a wide range at negative elevation as well.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/india\/en\/sales-services\/sales\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Compare products<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"en\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"20\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"44\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">Select a product<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">Select a product<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3210\" data-group=\"\">AA-12P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3212\" data-group=\"\">AA-12PC<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3216\" data-group=\"\">AA-14P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3214\" data-group=\"\">AA-14PJ<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3220\" data-group=\"\">AA-18PCJ<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3206\" data-group=\"\">AA-7PC<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3208\" data-group=\"\">AA-9PC<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3174\" data-group=\"\">AA-9PCHD<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3224\" data-group=\"\">AS-10PC \/ AS-10PCN<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3226\" data-group=\"\">AS-12P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3230\" data-group=\"\">AS-13PC \/ AS-13PCN<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3178\" data-group=\"\">AS-13PCHD<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3228\" data-group=\"\">AS-13PCJN<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3234\" data-group=\"\">AS-18PC \/ AS-18PCN<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3232\" data-group=\"\">AS-18PCJ \/ AS-18PCJN<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3238\" data-group=\"\">AS-21PC \/ AS-21PCN<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3236\" data-group=\"\">AS-21PJ<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3176\" data-group=\"\">AS-9PCHD<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3184\" data-group=\"\">AT-100TT-5<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3268\" data-group=\"\">AT-146TE-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3186\" data-group=\"\">AT-150S-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3190\" data-group=\"\">AT-157CG-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3198\" data-group=\"\">AT-170TG-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3192\" data-group=\"\">AT-195CG-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3188\" data-group=\"\">AT-200S-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3200\" data-group=\"\">AT-220TG-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3240\" data-group=\"\">AT-255CG-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3204\" data-group=\"\">AT-270TG-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3196\" data-group=\"\">AT-300CG-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3222\" data-group=\"\">eAA-7PC<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">Select a product<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">Select a product<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3210\" data-group=\"\">AA-12P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3212\" data-group=\"\">AA-12PC<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3216\" data-group=\"\">AA-14P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3214\" data-group=\"\">AA-14PJ<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3220\" data-group=\"\">AA-18PCJ<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3206\" data-group=\"\">AA-7PC<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3208\" data-group=\"\">AA-9PC<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3174\" data-group=\"\">AA-9PCHD<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3224\" data-group=\"\">AS-10PC \/ AS-10PCN<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3226\" data-group=\"\">AS-12P<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3230\" data-group=\"\">AS-13PC \/ AS-13PCN<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3178\" data-group=\"\">AS-13PCHD<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3228\" data-group=\"\">AS-13PCJN<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3234\" data-group=\"\">AS-18PC \/ AS-18PCN<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3232\" data-group=\"\">AS-18PCJ \/ AS-18PCJN<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3238\" data-group=\"\">AS-21PC \/ AS-21PCN<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3236\" data-group=\"\">AS-21PJ<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3176\" data-group=\"\">AS-9PCHD<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3184\" data-group=\"\">AT-100TT-5<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3268\" data-group=\"\">AT-146TE-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3186\" data-group=\"\">AT-150S-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3190\" data-group=\"\">AT-157CG-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3198\" data-group=\"\">AT-170TG-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3192\" data-group=\"\">AT-195CG-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3188\" data-group=\"\">AT-200S-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3200\" data-group=\"\">AT-220TG-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3240\" data-group=\"\">AT-255CG-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3204\" data-group=\"\">AT-270TG-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3196\" data-group=\"\">AT-300CG-2<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"3222\" data-group=\"\">eAA-7PC<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                          <li>\n                <a href=\"#media\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M22.9683 1.53906H3.74603C2.22944 1.53906 1 2.7685 1 4.28509V23.5073C1 25.0239 2.22944 26.2533 3.74603 26.2533H22.9683C24.4848 26.2533 25.7143 25.0239 25.7143 23.5073V4.28509C25.7143 2.7685 24.4848 1.53906 22.9683 1.53906Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.55116 11.1483C9.68861 11.1483 10.6107 10.2263 10.6107 9.08882C10.6107 7.95138 9.68861 7.0293 8.55116 7.0293C7.41372 7.0293 6.49164 7.95138 6.49164 9.08882C6.49164 10.2263 7.41372 11.1483 8.55116 11.1483Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M25.715 18.0135L18.8499 11.1484L3.7467 26.2516\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Gallery<\/span>\n                <\/a>\n              <\/li>\n                                    \n            \n                        \n            \n                                <li>\n                        <a href=\"https:\/\/mediahub.tadano.com\/m\/376a9d23552dee23\/original\/doc_Tadano_AT-300CG_LNG_EN_GEN_B_202305-pdf.pdf\" target=\"_blank\">\n                            <div class=\"icon-holder\">\n                                                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\">\n                                        <path fill=\"#004295\" d=\"M6,22V6H22v7.543C22,17.65,16,16,16,16s1.518,6-2.638,6H6Zm18-7.614V4H4V24H14.189C17.352,24,24,16.777,24,14.386ZM14,16H9V15h5Zm5-4H9v1H19Zm0-3H9v1H19Zm3-6H3V22H2V2H22ZM20,1H1V20H0V0H20Z\" fill=\"#fff\"\/>\n                                    <\/svg>\n                                                            <\/div>\n                            <span class=\"text\">Brochure<\/span>\n                        <\/a>\n                    <\/li>\n                    \n                          <li>\n                <a href=\"https:\/\/www.tadano.com\/india\/en\/about\/contact-us\/\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" version=\"1.1\" width=\"30\" height=\"30\" x=\"0\" y=\"0\" viewBox=\"0 0 440.965 440.965\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M341.508,36.207C305.582,12.648,263.549,0.116,220.587,0.154C98.892,0.271,0.235,98.832,0,220.527    c-0.046,42.838,12.652,84.721,36.48,120.32L0.853,426.18c-2.189,5.469,0.47,11.677,5.939,13.867c2.544,1.018,5.383,1.018,7.928,0    l85.333-35.627c101.679,66.676,238.158,38.3,304.834-63.379S443.187,102.883,341.508,36.207z M220.801,419.567    c-0.071,0-0.142,0-0.213,0v0.213h-0.001c-40.532-0.319-80.02-12.886-113.28-36.053c-1.754-1.224-3.835-1.893-5.973-1.92    c-1.338-0.264-2.715-0.264-4.053,0l-66.774,28.587l27.947-66.56c1.424-3.37,1.022-7.236-1.067-10.24    c-23.487-33.021-36.09-72.545-36.053-113.067C21.216,110.482,110.329,21.178,220.374,21.06    c110.044-0.118,199.349,88.995,199.467,199.04C419.959,330.145,330.846,419.449,220.801,419.567z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M288.514,162.764c-4.633-33.756-33.865-58.657-67.927-57.864c-36.795-0.118-66.752,29.552-66.987,66.347    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667c0.471-25.209,21.289-45.263,46.499-44.792    c25.21,0.471,45.263,21.289,44.792,46.499c-0.465,24.874-20.759,44.796-45.637,44.8c-5.891,0-10.667,4.776-10.667,10.667v47.787    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667v-37.973C267.907,233.206,293.543,199.416,288.514,162.764z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <circle cx=\"219.697\" cy=\"325.147\" r=\"11.675\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <\/g><\/svg>\n\n                  <\/div>\n                  <span class=\"text\">Request now<\/span>\n                <\/a>\n              <\/li>\n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n             \n\n\n<div class=\"container \">\n  <div class=\"product-details\">\n    <div class=\"product-specs\">\n\n      <div class=\"title\">\n        <div class=\"left\">\n                      <h2>Product Specs<\/h2>\n                  <\/div>\n        <div class=\"right\">\n                        <div class=\"radio\">\n                                <label for=\"met\" class=\"met\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Metric<\/span>\n                <\/label>\n                <label for=\"imp\" class=\"imp\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Imperial<\/span>\n                <\/label>\n            <\/div>\n            \n\n        <\/div>\n      <\/div>\n\n      \n        <ul>\n\n                                  <li class=\"scaled-metric\">\n                          <strong class=\"title\">Outrigger Bases<\/strong>\n                          <span>4.66m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Max. Main Boom Length<\/strong>\n                          <span>22.2m + 7.6m<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Material of Bucket<\/strong>\n                          <span>Steel<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Max. Bucket Bottom Height<\/strong>\n                          <span>30.4m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Bucket Swing (Slewing) Angle<\/strong>\n                          <span>313\u00b0(Left 93\u00b0- Right 220\u00b0)<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Bucket Inside Dimensions<\/strong>\n                          <span>0.7m \u00d7 1.5m \u00d7 0.95m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Elevation<\/strong>\n                          <span>-12\u00b0 &#8211; 80\u00b0<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Type of boom<\/strong>\n                          <span>Telescopic &#038; Articulating<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Max. Bucket Loading Capacity<\/strong>\n                          <span>250&nbsp;kg<\/span>\n                        <\/li>\n                      \n        <\/ul>\n\n        \n       \n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Product description<\/h2>\n\n\n\n<p><strong>Outreach operation with articulating boom<\/strong><\/p>\n\n\n\n<p>AT-300CG offers the maximum 30.4m bucket bottom height. This model can be mounted on mdium-heavy duty trucks. Five-way motion control covering boom telescoping, elevation, slewing, boom articulating, and bucket swinging. Computer control enables the bucket to move in a straight vertical path by changing the boom length, elevation angle and slewing, and bucket swing are controlled to achieve straight horizontal movement. The articulated boom enables approaches to recessed sections of buildings and to positions that are lower than the base boom section.<\/p>\n\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Media Gallery<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/760aeccb88e358cc\/gallery_full-img_Tadano_AT300CG_clr_001_eng-png.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/760aeccb88e358cc\/gallery_thumb-img_Tadano_AT300CG_clr_001_eng-png.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n<div class=\"cta-block\">\n    <div class=\"container\">\n    <div class=\"left\">\n      <ul class=\"btn-list\">\n        <li><a href=\"https:\/\/www.tadano.com\/india\/en\/about\/contact-us\/\" class=\"btn btn-light\">Request now<\/a><\/li>\n      <\/ul>\n    <\/div>\n    <div class=\"right\">\n                          <ul class=\"btn-list\">\n                            \n                                  <li><a href=\"https:\/\/mediahub.tadano.com\/m\/376a9d23552dee23\/original\/doc_Tadano_AT-300CG_LNG_EN_GEN_B_202305-pdf.pdf\" class=\"btn btn-outline-white\">Brochure<\/a><\/li>\n                              \n                              \n          <\/ul>\n            <\/div>\n  <\/div>\n<\/div>\n\n  <section class=\"tadano-advantage\">\n    <div class=\"bg-logo\" style=\"background-image: url(https:\/\/www.tadano.com\/india\/wp-content\/themes\/tadano\/assets\/dist\/images\/logo-min.svg);\"><\/div>\n    <div class=\"container\">\n      <div class=\"text-holder\">\n        <h2>The Tadano Advantage<\/h2>\n        <p><p>Tadano\u2019s legendary reputation for quality and innovation is why we lead the lifting industry. Superior engineering, design, and components followed up with top-notch service means a greater rate of return and the lowest owning and operating cost of any crane on the market.<\/p>\n<\/p>\n        <div class=\"wp-block-buttons\">\n          <div class=\"wp-block-button is-style-btn-outline-white\"><a href=\"\" class=\"wp-block-button__link\">Learn More<\/a><\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/section>\n\n\n\n\n\n\n\n\n\n\n\n\n  <section class=\"related-products related-pages\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>Related pages<\/h2>\n      <\/div>\n\n      <div class='r-products'>\n                  \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/india\/en\/aerial-work-platforms\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:cover\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/638f7a309acd0d73\/img_thumb-img_Tadano_bg_AWP-jpg.jpg, https:\/\/mediahub.tadano.com\/m\/638f7a309acd0d73\/img_thumb_2x-img_Tadano_bg_AWP-jpg.jpg 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">Aerial work platforms<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                        <\/div>\n        \n    <\/div>\n  <\/section>\n  \n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>News<\/h2>\n                        \n                  <a href=\"https:\/\/www.tadano.com\/india\/en\/about\/news-list\/\" class=\"link-more\">EXPLORE ALL News<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/india\/en\/news\/mms-mobile-cranes-golf-day-for-johnson-crane-hires-50th-anniversary-supports-hope-haven\/\">\n                  <strong class=\"title\">MMS Mobile Cranes Golf Day for Johnson Crane Hire\u2019s 50th Anniversary Supports Hope Haven<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Aug\/06\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/india\/en\/news\/experience-tadano-at-bauma-conexpo-india-2026\/\">\n                  <strong class=\"title\">Experience Tadano at bauma CONEXPO INDIA 2026<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Aug\/04\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/india\/en\/news\/ac-7-450-1-in-bruges\/\">\n                  <strong class=\"title\">AC 7.450-1 in Bruges<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/23\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/india\/en\/news\/new-ac-5-250l-2-for-suderau\/\">\n                  <strong class=\"title\">New AC 5.250L-2 for S\u00fcderau<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/02\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/india\/en\/news\/tadano-marubeni-distribution-and-service-announce-partnership-for-turkish-market\/\">\n                  <strong class=\"title\">Tadano, Marubeni Distribution and Service announce partnership for Turkish market<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Jun\/26\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/india\/en\/news\/tandem-lift-with-a-powerful-duo\/\">\n                  <strong class=\"title\">TANDEM LIFT WITH A &#8220;POWERFUL DUO&#8221;<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Jun\/02\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/india\/en\/news\/rx-pick-carry-cranes-extendable-wheelbase-for-maximum-performance\/\">\n                  <strong class=\"title\">The extendable wheelbase: the heart of the RX line<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">May\/28\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/india\/en\/news\/new-ac-5-250l-2-for-s-v-m-m\/\">\n                  <strong class=\"title\">New AC 5.250L-2 for S.V.M.M.<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">May\/28\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/india\/en\/news\/ac-3-045-1-city-for-markewitsch\/\">\n                  <strong class=\"title\">AC 3.045-1 City for Markewitsch<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">May\/21\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/india\/en\/news\/first-snake-26-in-france\/\">\n                  <strong class=\"title\">First Snake 26 in France<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">May\/19\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  ","protected":false},"featured_media":0,"template":"","lifting-equipment":[44],"class_list":["post-3196","products","type-products","status-publish","hentry","lifting-equipment-aerial-work-platforms"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AT-300CG-2 - India<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/india\/en\/lifting-equipment\/aerial-work-platforms\/at-300cg\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AT-300CG-2 - India\" \/>\n<meta property=\"og:description\" content=\"Product description Outreach operation with articulating boom AT-300CG offers the maximum 30.4m bucket bottom height. This model can be mounted on mdium-heavy duty trucks. Five-way motion control covering boom telescoping, elevation, slewing, boom articulating, and bucket swinging. Computer control enables the bucket to move in a straight vertical path by changing the boom length, elevation [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/india\/en\/lifting-equipment\/aerial-work-platforms\/at-300cg\/\" \/>\n<meta property=\"og:site_name\" content=\"India\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/lifting-equipment\\\/aerial-work-platforms\\\/at-300cg\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/lifting-equipment\\\/aerial-work-platforms\\\/at-300cg\\\/\",\"name\":\"AT-300CG-2 - India\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/#website\"},\"datePublished\":\"2022-03-21T14:34:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/lifting-equipment\\\/aerial-work-platforms\\\/at-300cg\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/lifting-equipment\\\/aerial-work-platforms\\\/at-300cg\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/lifting-equipment\\\/aerial-work-platforms\\\/at-300cg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AT-300CG-2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/\",\"name\":\"India\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/india\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AT-300CG-2 - India","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/india\/en\/lifting-equipment\/aerial-work-platforms\/at-300cg\/","og_locale":"en_US","og_type":"article","og_title":"AT-300CG-2 - India","og_description":"Product description Outreach operation with articulating boom AT-300CG offers the maximum 30.4m bucket bottom height. This model can be mounted on mdium-heavy duty trucks. Five-way motion control covering boom telescoping, elevation, slewing, boom articulating, and bucket swinging. Computer control enables the bucket to move in a straight vertical path by changing the boom length, elevation [&hellip;]","og_url":"https:\/\/www.tadano.com\/india\/en\/lifting-equipment\/aerial-work-platforms\/at-300cg\/","og_site_name":"India","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/india\/en\/lifting-equipment\/aerial-work-platforms\/at-300cg\/","url":"https:\/\/www.tadano.com\/india\/en\/lifting-equipment\/aerial-work-platforms\/at-300cg\/","name":"AT-300CG-2 - India","isPartOf":{"@id":"https:\/\/www.tadano.com\/india\/en\/#website"},"datePublished":"2022-03-21T14:34:08+00:00","breadcrumb":{"@id":"https:\/\/www.tadano.com\/india\/en\/lifting-equipment\/aerial-work-platforms\/at-300cg\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/india\/en\/lifting-equipment\/aerial-work-platforms\/at-300cg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tadano.com\/india\/en\/lifting-equipment\/aerial-work-platforms\/at-300cg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tadano.com\/india\/en\/"},{"@type":"ListItem","position":2,"name":"AT-300CG-2"}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/india\/en\/#website","url":"https:\/\/www.tadano.com\/india\/en\/","name":"India","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/india\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/products\/3196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":1,"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/products\/3196\/revisions"}],"predecessor-version":[{"id":3197,"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/products\/3196\/revisions\/3197"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/media?parent=3196"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/india\/en\/wp-json\/wp\/v2\/lifting-equipment?post=3196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}