{"id":7437,"date":"2021-03-19T08:40:39","date_gmt":"2021-03-19T08:40:39","guid":{"rendered":"https:\/\/www.tadano.com\/latam\/ventas-y-servicios\/"},"modified":"2023-11-13T13:12:58","modified_gmt":"2023-11-13T13:12:58","slug":"ventas-y-servicios","status":"publish","type":"page","link":"https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/","title":{"rendered":"Ventas y Servicios"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\t\t<style type=\"text\/css\">\n\t\t\t.hero-section .img-holder:before {\n\t\t\t\tdisplay: none;\n\t\t\t}\n\t\t<\/style>\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 100% 50%; \">\n\t\t\t<span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/hero\/ATF60G-3_Seite24-25_C300.jpg, https:\/\/assets.onetadano.com\/celum_assets\/hero-2x\/ATF60G-3_Seite24-25_C300.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder \">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/latam\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">Ventas y servicios<\/h1>\n\n\n\n<p>Nuestros representantes de ventas, t\u00e9cnicos capacitados y socios de confianza aseguran la disponibilidad local y continua de gr\u00faas, servicio, formaci\u00f3n, piezas y asistencia.<\/p>\n\n\n\n<p><\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<section class=\"sales-support\">\n  <div class=\"container\">\n    <div class=\"text-block\">\n      \n\n<h2 class=\"wp-block-heading\">VENTAS<\/h2>\n\n\n\n<p>Nuestro experimentado equipo de ventas encontrar\u00e1 la mejor gr\u00faa para su proyecto y le informar\u00e1 sobre la amplia gama de servicios adicionales de Tadano.<\/p>\n\n\n    <\/div>\n          <ul class=\"support-list\">\n                            <li>\n                          <a href=\"https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/ventas\/\">\n                                          <div class=\"img-holder desktop-only\">\n                  <img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/uploads\/sites\/14\/2023\/09\/Sales-1.svg\" class=\"attachment-small size-small\" alt=\"\" loading=\"lazy\">\n                <\/div>\n                            <span class=\"title\">Ventas<\/span>\n            <\/a>\n          <\/li>\n                            <li>\n                          <a href=\"https:\/\/www.tadano.com\/latam\/es\/gruas-de-segunda-mano\/\">\n                                          <div class=\"img-holder desktop-only\">\n                  <img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/uploads\/sites\/14\/2023\/09\/Used-Crane.svg\" class=\"attachment-small size-small\" alt=\"\" loading=\"lazy\">\n                <\/div>\n                            <span class=\"title\">GR\u00daAS DE SEGUNDA MANO<\/span>\n            <\/a>\n          <\/li>\n                            <li>\n                          <a href=\"https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/encuentre-un-distribuidor\/\">\n                                          <div class=\"img-holder desktop-only\">\n                  <img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/uploads\/sites\/14\/2023\/09\/Distributor-Locator.svg\" class=\"attachment-small size-small\" alt=\"\" loading=\"lazy\">\n                <\/div>\n                            <span class=\"title\">Localizador de distribuidor<\/span>\n            <\/a>\n          <\/li>\n              <\/ul>\n      <\/div>\n<\/section>\n\n\n<div class=\"wp-block-group is-style-background-cyan\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<section class=\"sales-support\">\n  <div class=\"container\">\n    <div class=\"text-block\">\n      \n\n<h2 class=\"wp-block-heading\">Servicios<\/h2>\n\n\n\n<p>Las amplias redes de distribuidores y agentes de servicio de Tadano brindan soporte localizado para cualquier necesidad: servicio, formaci\u00f3n, piezas de repuesto y mucho m\u00e1s.<\/p>\n\n\n    <\/div>\n          <ul class=\"support-list\">\n                            <li>\n                          <a href=\"https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/servicios\/\">\n                                          <div class=\"img-holder desktop-only\">\n                  <img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/uploads\/sites\/14\/2023\/09\/Services.svg\" class=\"attachment-small size-small\" alt=\"\" loading=\"lazy\">\n                <\/div>\n                            <span class=\"title\">Soporte al cliente<\/span>\n            <\/a>\n          <\/li>\n                            <li>\n                          <a href=\"https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/piezas\/\">\n                                          <div class=\"img-holder desktop-only\">\n                  <img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/uploads\/sites\/14\/2023\/09\/Parts.svg\" class=\"attachment-small size-small\" alt=\"\" loading=\"lazy\">\n                <\/div>\n                            <span class=\"title\">Piezas<\/span>\n            <\/a>\n          <\/li>\n                            <li>\n                          <a>\n                                          <div class=\"img-holder desktop-only\">\n                  <img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/uploads\/sites\/14\/2023\/09\/Training-1.svg\" class=\"attachment-small size-small\" alt=\"\" loading=\"lazy\">\n                <\/div>\n                            <span class=\"title\">Formaci\u00f3n<\/span>\n            <\/a>\n          <\/li>\n              <\/ul>\n      <\/div>\n<\/section><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7437","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ventas y Servicios - Latin America \/ Caribbean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ventas y Servicios - Latin America \/ Caribbean\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/\" \/>\n<meta property=\"og:site_name\" content=\"Latin America \/ Caribbean\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-13T13:12:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/es\\\/ventas-y-servicios\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/es\\\/ventas-y-servicios\\\/\",\"name\":\"Ventas y Servicios - Latin America \\\/ Caribbean\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\"},\"datePublished\":\"2021-03-19T08:40:39+00:00\",\"dateModified\":\"2023-11-13T13:12:58+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/latam\\\/es\\\/ventas-y-servicios\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/\",\"name\":\"Latin America \\\/ Caribbean\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ventas y Servicios - Latin America \/ Caribbean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/","og_locale":"es_ES","og_type":"article","og_title":"Ventas y Servicios - Latin America \/ Caribbean","og_url":"https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/","og_site_name":"Latin America \/ Caribbean","article_modified_time":"2023-11-13T13:12:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/","url":"https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/","name":"Ventas y Servicios - Latin America \/ Caribbean","isPartOf":{"@id":"https:\/\/www.tadano.com\/latam\/en\/#website"},"datePublished":"2021-03-19T08:40:39+00:00","dateModified":"2023-11-13T13:12:58+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/latam\/en\/#website","url":"https:\/\/www.tadano.com\/latam\/en\/","name":"Latin America \/ Caribbean","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/latam\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/pages\/7437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/comments?post=7437"}],"version-history":[{"count":5,"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/pages\/7437\/revisions"}],"predecessor-version":[{"id":8028,"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/pages\/7437\/revisions\/8028"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/media?parent=7437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}