{"id":9544,"date":"2025-10-21T14:10:54","date_gmt":"2025-10-21T12:10:54","guid":{"rendered":"https:\/\/www.tadano.com\/latam\/%term%\/%cat%\/scorpion-16-pro-iveco\/"},"modified":"2026-07-02T15:04:54","modified_gmt":"2026-07-02T15:04:54","slug":"scorpion-16-pro-iveco","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/latam\/es\/lifting-equipment\/truck-mounted-awp\/scorpion-16-pro-iveco\/","title":{"rendered":"Scorpion 16 Pro sobre Iveco"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 50% 50%; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/asset\/fc99892f-9e7b-4903-a264-f339a77581ac\/hero\/img_tadano_Scorpion16Pro_iveco_cutout_rear_right.png, https:\/\/mediahub.tadano.com\/asset\/fc99892f-9e7b-4903-a264-f339a77581ac\/hero-2x\/img_tadano_Scorpion16Pro_iveco_cutout_rear_right.png 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/latam\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">Scorpion 16 Pro sobre Iveco<\/h1>\n\n\n\n<p>La Scorpion 16 PRO es una plataforma a\u00e9rea telesc\u00f3pica montada sobre cami\u00f3n que combina el dise\u00f1o compacto del cami\u00f3n con una plataforma a\u00e9rea potente y estable, dise\u00f1ada para ofrecer eficiencia, fiabilidad y comodidad al operador.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/latam\/es\/ventas-y-servicios\/ventas\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Comparar productos<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"es\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"14\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"62\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9546\" data-group=\"\">Scorpion 16 Pro sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9544\" data-group=\"\">Scorpion 16 Pro sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9548\" data-group=\"\">Scorpion 16 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9528\" data-group=\"\">Scorpion 16 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9542\" data-group=\"\">Scorpion 18 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9540\" data-group=\"\">Scorpion 20 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9282\" data-group=\"\">Scorpion 20 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9526\" data-group=\"\">Scorpion 21J sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9538\" data-group=\"\">Scorpion 23 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9536\" data-group=\"\">Snake 16 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9280\" data-group=\"\">Snake 20 FB Pro sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9534\" data-group=\"\">Snake 20 FB sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9522\" data-group=\"\">Snake 20 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9524\" data-group=\"\">Snake 20 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9520\" data-group=\"\">Snake 24 FB sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9532\" data-group=\"\">Snake 24 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9530\" data-group=\"\">Snake 26 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9546\" data-group=\"\">Scorpion 16 Pro sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9544\" data-group=\"\">Scorpion 16 Pro sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9548\" data-group=\"\">Scorpion 16 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9528\" data-group=\"\">Scorpion 16 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9542\" data-group=\"\">Scorpion 18 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9540\" data-group=\"\">Scorpion 20 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9282\" data-group=\"\">Scorpion 20 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9526\" data-group=\"\">Scorpion 21J sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9538\" data-group=\"\">Scorpion 23 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9536\" data-group=\"\">Snake 16 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9280\" data-group=\"\">Snake 20 FB Pro sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9534\" data-group=\"\">Snake 20 FB sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9522\" data-group=\"\">Snake 20 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9524\" data-group=\"\">Snake 20 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9520\" data-group=\"\">Snake 24 FB sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9532\" data-group=\"\">Snake 24 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"9530\" data-group=\"\">Snake 26 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                          <li>\n                <a href=\"#media\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M22.9683 1.53906H3.74603C2.22944 1.53906 1 2.7685 1 4.28509V23.5073C1 25.0239 2.22944 26.2533 3.74603 26.2533H22.9683C24.4848 26.2533 25.7143 25.0239 25.7143 23.5073V4.28509C25.7143 2.7685 24.4848 1.53906 22.9683 1.53906Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.55116 11.1483C9.68861 11.1483 10.6107 10.2263 10.6107 9.08882C10.6107 7.95138 9.68861 7.0293 8.55116 7.0293C7.41372 7.0293 6.49164 7.95138 6.49164 9.08882C6.49164 10.2263 7.41372 11.1483 8.55116 11.1483Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M25.715 18.0135L18.8499 11.1484L3.7467 26.2516\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Galer\u00eda<\/span>\n                <\/a>\n              <\/li>\n                                    \n            \n                        \n            \n            \n                          <li>\n                <a href=\"https:\/\/www.tadano.com\/en\/about\/contact-us\/\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" version=\"1.1\" width=\"30\" height=\"30\" x=\"0\" y=\"0\" viewBox=\"0 0 440.965 440.965\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M341.508,36.207C305.582,12.648,263.549,0.116,220.587,0.154C98.892,0.271,0.235,98.832,0,220.527    c-0.046,42.838,12.652,84.721,36.48,120.32L0.853,426.18c-2.189,5.469,0.47,11.677,5.939,13.867c2.544,1.018,5.383,1.018,7.928,0    l85.333-35.627c101.679,66.676,238.158,38.3,304.834-63.379S443.187,102.883,341.508,36.207z M220.801,419.567    c-0.071,0-0.142,0-0.213,0v0.213h-0.001c-40.532-0.319-80.02-12.886-113.28-36.053c-1.754-1.224-3.835-1.893-5.973-1.92    c-1.338-0.264-2.715-0.264-4.053,0l-66.774,28.587l27.947-66.56c1.424-3.37,1.022-7.236-1.067-10.24    c-23.487-33.021-36.09-72.545-36.053-113.067C21.216,110.482,110.329,21.178,220.374,21.06    c110.044-0.118,199.349,88.995,199.467,199.04C419.959,330.145,330.846,419.449,220.801,419.567z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M288.514,162.764c-4.633-33.756-33.865-58.657-67.927-57.864c-36.795-0.118-66.752,29.552-66.987,66.347    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667c0.471-25.209,21.289-45.263,46.499-44.792    c25.21,0.471,45.263,21.289,44.792,46.499c-0.465,24.874-20.759,44.796-45.637,44.8c-5.891,0-10.667,4.776-10.667,10.667v47.787    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667v-37.973C267.907,233.206,293.543,199.416,288.514,162.764z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <circle cx=\"219.697\" cy=\"325.147\" r=\"11.675\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <\/g><\/svg>\n\n                  <\/div>\n                  <span class=\"text\">Pedir info&shy;rmaci\u00f3n<\/span>\n                <\/a>\n              <\/li>\n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n             \n\n\n<div class=\"container \">\n  <div class=\"product-details\">\n    <div class=\"product-specs\">\n\n      <div class=\"title\">\n        <div class=\"left\">\n                      <h2>Especificaciones del producto<\/h2>\n                  <\/div>\n        <div class=\"right\">\n                        <div class=\"radio\">\n                                <label for=\"met\" class=\"met\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">M\u00e9trico<\/span>\n                <\/label>\n                <label for=\"imp\" class=\"imp\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Imperial<\/span>\n                <\/label>\n            <\/div>\n            \n\n        <\/div>\n      <\/div>\n\n      \n        <ul>\n\n          \n        <\/ul>\n\n        \n       \n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Descripci\u00f3n del producto<\/h2>\n\n\n\n<p><strong>Alcance fiable. Construida sobre la fuerza.<\/strong><\/p>\n\n\n\n<p>Montada sobre el chasis Iveco 35S, la Scorpion 16 PRO combina las prestaciones de un cami\u00f3n moderno con una plataforma a\u00e9rea fiable para operadores profesionales. Ofrece una altura m\u00e1xima de trabajo de 16 metros, un alcance horizontal de 11,3 metros y una capacidad de carga en cesta de 300 kg.<\/p>\n\n\n\n<p>La plataforma est\u00e1 equipada con una cesta de aluminio de 1,4 \u00d7 1,1 \u00d7 0,7 m, rotaci\u00f3n de la cesta de \u00b190\u00b0 y rotaci\u00f3n de la torreta de 400\u00b0, lo que proporciona un posicionamiento preciso y flexible. Los estabilizadores en H permiten m\u00faltiples configuraciones de trabajo, incluido el trabajo en contorno y la estabilizaci\u00f3n asim\u00e9trica, garantizando estabilidad incluso en entornos confinados.<\/p>\n\n\n\n<p>Los sistemas de seguridad incluyen un sistema de limitaci\u00f3n de momento, protecci\u00f3n anticolisi\u00f3n de la cabina del cami\u00f3n, v\u00e1lvulas de bloqueo en todos los cilindros, guiado interno de mangueras y cables, y funci\u00f3n autom\u00e1tica de recogida de la estructura a\u00e9rea. Los componentes resistentes a la corrosi\u00f3n y el suelo de aluminio antideslizante contribuyen a la durabilidad y a un funcionamiento seguro.<\/p>\n\n\n\n<p>El equipamiento est\u00e1ndar incluye mandos electrohidr\u00e1ulicos para la estructura a\u00e9rea, mandos hidr\u00e1ulicos de los estabilizadores (con mandos electrohidr\u00e1ulicos disponibles como opci\u00f3n) y sistemas de emergencia para un funcionamiento seguro. Entre los opcionales se incluyen la estabilizaci\u00f3n autom\u00e1tica desde la cesta o desde el suelo, as\u00ed como accesorios adicionales de seguridad y confort.<\/p>\n\n\n\n<p>La Scorpion 16 PRO garantiza un rendimiento fiable y preciso en un conjunto compacto y f\u00e1cil de manejar, lo que la hace ideal para trabajos de acceso seguro en entornos exigentes.<\/p>\n\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Galer\u00eda de medios<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/asset\/fc99892f-9e7b-4903-a264-f339a77581ac\/gallery-full\/img_tadano_Scorpion16Pro_iveco_cutout_rear_right.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/asset\/fc99892f-9e7b-4903-a264-f339a77581ac\/gallery-thumb\/img_tadano_Scorpion16Pro_iveco_cutout_rear_right.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n<div class=\"cta-block\">\n    <div class=\"container\">\n    <div class=\"left\">\n      <ul class=\"btn-list\">\n        <li><a href=\"https:\/\/www.tadano.com\/en\/about\/contact-us\/\" class=\"btn btn-light\">Request now<\/a><\/li>\n      <\/ul>\n    <\/div>\n    <div class=\"right\">\n                          <ul class=\"btn-list\">\n                            \n                                  <li><a href=\"\" class=\"btn btn-outline-white\">Spec Sheet<\/a><\/li>\n                              \n                              \n          <\/ul>\n            <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n\n\n\n\n\n\n\n\n\n  <section class=\"related-products related-pages\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>P\u00e1ginas relacionadas<\/h2>\n      <\/div>\n\n      <div class='r-products'>\n                  \n                        <\/div>\n        \n    <\/div>\n  <\/section>\n  \n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>Noticias<\/h2>\n                        \n                  <a href=\"https:\/\/www.tadano.com\/latam\/es\/news-list\/\" class=\"link-more\">EXPLORAR TODAS las noticias<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/es\/news\/www.tadano.completa-la-adquisicion-del-sector-empresarial-de-sistemas-de-transporte-de-ihi-transport-machinery\">\n                  <strong class=\"title\">Tadano completa la adquisici\u00f3n del sector empresarial de sistemas de transporte de IHI Transport Machinery<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/01\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/es\/news\/mpm-adquiere-la-primera-tadano-evolt-egr-1000xll-1-en-la-region-panamericana\/\">\n                  <strong class=\"title\">MPM ADQUIERE LA PRIMERA TADANO EVOLT eGR-1000XLL-1 EN LA REGI\u00d3N PANAMERICANA<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Abr\/22\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/es\/news\/tadano-at-bauma-2025\/\">\n                  <strong class=\"title\">Tadano en bauma 2025<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Abr\/07\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/es\/news\/the-new-cc-78-1250-1\/\">\n                  <strong class=\"title\">La nueva CC 78.1250-1<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Abr\/03\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/es\/news\/tadano-celebra-el-dia-internacional-de-la-mujer\/\">\n                  <strong class=\"title\">TADANO CELEBRA EL D\u00cdA INTERNACIONAL DE LA MUJER<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Mar\/10\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/es\/news\/mas-largo-mas-alto-mas-lejos-la-nueva-grua-todo-terreno-tadano-ac-5-250l-2-cuenta-con-la-pluma-principal-de-79-metros\/\">\n                  <strong class=\"title\">M\u00c1S LARGO, M\u00c1S ALTO, M\u00c1S LEJOS: LA NUEVA GR\u00daA TODO TERRENO TADANO AC 5.250L-2 CUENTA CON LA PLUMA PRINCIPAL DE 79 METROS<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Feb\/18\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/es\/news\/grua-tadano-ac-7-450-1-cumple-doble-funcion-en-wisconsin\/\">\n                  <strong class=\"title\">GR\u00daA TADANO AC 7.450-1 cumple doble funci\u00f3n en Wisconsin<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Nov\/12\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/es\/news\/la-nueva-tadano-ac-5-250-2-convence-con-soluciones-innovadoras\/\">\n                  <strong class=\"title\">La nueva Tadano AC 5.250-2 convence con soluciones innovadoras<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/es\/news\/magruber-invierte-en-calidad-tadano\/\">\n                  <strong class=\"title\">MAGRUBER invierte en calidad Tadano<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jun\/19\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  ","protected":false},"featured_media":0,"template":"","lifting-equipment":[62],"class_list":["post-9544","products","type-products","status-publish","hentry","lifting-equipment-truck-mounted-awp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scorpion 16 Pro sobre Iveco - Latin America \/ Caribbean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/latam\/es\/lifting-equipment\/truck-mounted-awp\/scorpion-16-pro-iveco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scorpion 16 Pro sobre Iveco - Latin America \/ Caribbean\" \/>\n<meta property=\"og:description\" content=\"Descripci\u00f3n del producto Alcance fiable. Construida sobre la fuerza. Montada sobre el chasis Iveco 35S, la Scorpion 16 PRO combina las prestaciones de un cami\u00f3n moderno con una plataforma a\u00e9rea fiable para operadores profesionales. Ofrece una altura m\u00e1xima de trabajo de 16 metros, un alcance horizontal de 11,3 metros y una capacidad de carga en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/latam\/es\/lifting-equipment\/truck-mounted-awp\/scorpion-16-pro-iveco\/\" \/>\n<meta property=\"og:site_name\" content=\"Latin America \/ Caribbean\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T15:04:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/es\\\/lifting-equipment\\\/truck-mounted-awp\\\/scorpion-16-pro-iveco\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/es\\\/lifting-equipment\\\/truck-mounted-awp\\\/scorpion-16-pro-iveco\\\/\",\"name\":\"Scorpion 16 Pro sobre Iveco - Latin America \\\/ Caribbean\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\"},\"datePublished\":\"2025-10-21T12:10:54+00:00\",\"dateModified\":\"2026-07-02T15:04:54+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/latam\\\/es\\\/lifting-equipment\\\/truck-mounted-awp\\\/scorpion-16-pro-iveco\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/\",\"name\":\"Latin America \\\/ Caribbean\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scorpion 16 Pro sobre Iveco - Latin America \/ Caribbean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/latam\/es\/lifting-equipment\/truck-mounted-awp\/scorpion-16-pro-iveco\/","og_locale":"es_ES","og_type":"article","og_title":"Scorpion 16 Pro sobre Iveco - Latin America \/ Caribbean","og_description":"Descripci\u00f3n del producto Alcance fiable. Construida sobre la fuerza. Montada sobre el chasis Iveco 35S, la Scorpion 16 PRO combina las prestaciones de un cami\u00f3n moderno con una plataforma a\u00e9rea fiable para operadores profesionales. Ofrece una altura m\u00e1xima de trabajo de 16 metros, un alcance horizontal de 11,3 metros y una capacidad de carga en [&hellip;]","og_url":"https:\/\/www.tadano.com\/latam\/es\/lifting-equipment\/truck-mounted-awp\/scorpion-16-pro-iveco\/","og_site_name":"Latin America \/ Caribbean","article_modified_time":"2026-07-02T15:04:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/latam\/es\/lifting-equipment\/truck-mounted-awp\/scorpion-16-pro-iveco\/","url":"https:\/\/www.tadano.com\/latam\/es\/lifting-equipment\/truck-mounted-awp\/scorpion-16-pro-iveco\/","name":"Scorpion 16 Pro sobre Iveco - Latin America \/ Caribbean","isPartOf":{"@id":"https:\/\/www.tadano.com\/latam\/en\/#website"},"datePublished":"2025-10-21T12:10:54+00:00","dateModified":"2026-07-02T15:04:54+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/latam\/es\/lifting-equipment\/truck-mounted-awp\/scorpion-16-pro-iveco\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/latam\/en\/#website","url":"https:\/\/www.tadano.com\/latam\/en\/","name":"Latin America \/ Caribbean","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/latam\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/products\/9544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":5,"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/products\/9544\/revisions"}],"predecessor-version":[{"id":10643,"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/products\/9544\/revisions\/10643"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/media?parent=9544"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/lifting-equipment?post=9544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}