{"id":3685,"date":"2021-12-10T09:26:39","date_gmt":"2021-12-10T09:26:39","guid":{"rendered":"https:\/\/www.tadano.com\/latam\/technologies\/start-stop\/"},"modified":"2026-05-08T11:15:27","modified_gmt":"2026-05-08T11:15:27","slug":"start-stop","status":"publish","type":"technologies","link":"https:\/\/www.tadano.com\/latam\/es\/technologies\/start-stop\/","title":{"rendered":"Start-Stop"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\t\t<style type=\"text\/css\">\n\t\t\t.hero-section .img-holder:before {\n\t\t\t\tdisplay: none;\n\t\t\t}\n\t\t<\/style>\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 100% 50%; \">\n\t\t\t<span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/hero\/START_STOP_Kabine_Motiv_10122021_B.jpg, https:\/\/assets.onetadano.com\/celum_assets\/hero-2x\/START_STOP_Kabine_Motiv_10122021_B.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder \">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/latam\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.demagmobilecranes.com\/en\/demag-technology\/cc-3800-1-boom-booster\/\" target=\"_blank\"><\/a><a rel=\"noreferrer noopener\" href=\"https:\/\/www.demagmobilecranes.com\/en\/demag-technology\/cc-8800-1-boom-booster\/\" target=\"_blank\"><\/a><span class=\"has-inline-color has-black-color\"><strong>Funci\u00f3n Start-Stop<\/strong><\/span><\/h1>\n\n\n\n<p>La funci\u00f3n start-stop permite apagar manualmente el motor con un bot\u00f3n en la cabina durante el funcionamiento de la gr\u00faa para evitar el ralent\u00ed. Esta funci\u00f3n puede utilizarse para reducir el consumo de combustible, las emisiones y las horas de funcionamiento de la gr\u00faa. Mientras el motor est\u00e1 apagado, el sistema de control de la gr\u00faa permanece activo, de modo que el funcionamiento de la gr\u00faa puede reanudarse r\u00e1pidamente tras volver a arrancar.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<div class=\"wp-block-group is-style-background-triangle-right\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">DESCRIPCI\u00d3N DE LA TECNOLOG\u00cdA<\/h2>\n\n\n\n<p><strong>Menor consumo de combustible y menos emisiones. Mayor rentabilidad.<\/strong><\/p>\n\n\n\n<p>La ventaja decisiva de la funci\u00f3n start-stop en comparaci\u00f3n con un apagado convencional del motor es que el sistema de control de la gr\u00faa IC-1 no se apaga, sino que permanece activo. En otras palabras, cuando se utiliza la funci\u00f3n start-stop para volver a arrancar, el sistema de control est\u00e1 listo para funcionar en cuesti\u00f3n de segundos, de modo que un proceso de elevaci\u00f3n se puede poner en marcha o reanudar pr\u00e1cticamente sin ning\u00fan retraso.<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La funci\u00f3n start-stop permite apagar manualmente el motor con un bot\u00f3n en la cabina durante el funcionamiento de la gr\u00faa para evitar el ralent\u00ed. Esta funci\u00f3n puede utilizarse para reducir el consumo de combustible, las emisiones y las horas de funcionamiento de la gr\u00faa. Mientras el motor est\u00e1 apagado, el sistema de control de la gr\u00faa permanece activo, de modo que el funcionamiento de la gr\u00faa puede reanudarse r\u00e1pidamente tras volver a arrancar.<\/p>\n","protected":false},"template":"","class_list":["post-3685","technologies","type-technologies","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Start-Stop - Latin America \/ Caribbean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/latam\/es\/technologies\/start-stop\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Start-Stop - Latin America \/ Caribbean\" \/>\n<meta property=\"og:description\" content=\"La funci\u00f3n start-stop permite apagar manualmente el motor con un bot\u00f3n en la cabina durante el funcionamiento de la gr\u00faa para evitar el ralent\u00ed. Esta funci\u00f3n puede utilizarse para reducir el consumo de combustible, las emisiones y las horas de funcionamiento de la gr\u00faa. Mientras el motor est\u00e1 apagado, el sistema de control de la gr\u00faa permanece activo, de modo que el funcionamiento de la gr\u00faa puede reanudarse r\u00e1pidamente tras volver a arrancar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/latam\/es\/technologies\/start-stop\/\" \/>\n<meta property=\"og:site_name\" content=\"Latin America \/ Caribbean\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T11:15:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/es\\\/technologies\\\/start-stop\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/es\\\/technologies\\\/start-stop\\\/\",\"name\":\"Start-Stop - Latin America \\\/ Caribbean\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\"},\"datePublished\":\"2021-12-10T09:26:39+00:00\",\"dateModified\":\"2026-05-08T11:15:27+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/latam\\\/es\\\/technologies\\\/start-stop\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/\",\"name\":\"Latin America \\\/ Caribbean\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Start-Stop - Latin America \/ Caribbean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/latam\/es\/technologies\/start-stop\/","og_locale":"es_ES","og_type":"article","og_title":"Start-Stop - Latin America \/ Caribbean","og_description":"La funci\u00f3n start-stop permite apagar manualmente el motor con un bot\u00f3n en la cabina durante el funcionamiento de la gr\u00faa para evitar el ralent\u00ed. Esta funci\u00f3n puede utilizarse para reducir el consumo de combustible, las emisiones y las horas de funcionamiento de la gr\u00faa. Mientras el motor est\u00e1 apagado, el sistema de control de la gr\u00faa permanece activo, de modo que el funcionamiento de la gr\u00faa puede reanudarse r\u00e1pidamente tras volver a arrancar.","og_url":"https:\/\/www.tadano.com\/latam\/es\/technologies\/start-stop\/","og_site_name":"Latin America \/ Caribbean","article_modified_time":"2026-05-08T11:15:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/latam\/es\/technologies\/start-stop\/","url":"https:\/\/www.tadano.com\/latam\/es\/technologies\/start-stop\/","name":"Start-Stop - Latin America \/ Caribbean","isPartOf":{"@id":"https:\/\/www.tadano.com\/latam\/en\/#website"},"datePublished":"2021-12-10T09:26:39+00:00","dateModified":"2026-05-08T11:15:27+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/latam\/es\/technologies\/start-stop\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/latam\/en\/#website","url":"https:\/\/www.tadano.com\/latam\/en\/","name":"Latin America \/ Caribbean","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/latam\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/technologies\/3685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/technologies"}],"about":[{"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/types\/technologies"}],"version-history":[{"count":1,"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/technologies\/3685\/revisions"}],"predecessor-version":[{"id":9122,"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/technologies\/3685\/revisions\/9122"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/latam\/es\/wp-json\/wp\/v2\/media?parent=3685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}