{"id":7838,"date":"2021-07-02T07:13:12","date_gmt":"2021-07-02T07:13:12","guid":{"rendered":"https:\/\/www.tadano.com\/latam\/technologie\/systemes-de-controle\/"},"modified":"2025-02-10T08:51:09","modified_gmt":"2025-02-10T08:51:09","slug":"systemes-de-controle","status":"publish","type":"page","link":"https:\/\/www.tadano.com\/latam\/fr\/technologie\/systemes-de-controle\/","title":{"rendered":"Syst\u00e8mes de contr\u00f4le"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 50% 50%; \">\n\t\t\t<span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/hero\/Kabine_DSC_7738_metrisch.jpg, https:\/\/assets.onetadano.com\/celum_assets\/hero-2x\/Kabine_DSC_7738_metrisch.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder \">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/latam\/fr\/\">Accueil<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">Syst\u00e8mes de contr\u00f4le<\/h1>\n\n\n\n<p>Optimisez la polyvalence et la flexibilit\u00e9 de votre grue gr\u00e2ce \u00e0 la d\u00e9finition en direct de sa capacit\u00e9 et de ses limites de levage&nbsp;; vous disposez en outre d&rsquo;un vaste choix de configurations asym\u00e9triques des stabilisateurs et d&rsquo;innovations r\u00e9centes en mati\u00e8re de surveillance des donn\u00e9es et de d\u00e9pannage, pour ne citer que ces quelques fonctionnalit\u00e9s.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<div class=\"wp-block-group is-style-background-triangle-right has-white-color has-dark-blue-background-color has-text-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h2 class=\"wp-block-heading\">PARCOUREZ NOS Technologies<\/h2>\n\n\n\n<p>Augmentez la polyvalence, la capacit\u00e9 et le rendement de votre grue gr\u00e2ce \u00e0 des syst\u00e8mes sophistiqu\u00e9s d&rsquo;installation, de configuration, de surveillance et de d\u00e9pannage.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n\n<div class=\"links-block-wrapper\">\n  <div class=\"container\">\n    <section class=\"links-block\">\n\n\n              <div class=\"links-block\">\n                      \n\n            <div class=\"link-single\">\n                              <a href=\"https:\/\/www.tadano.com\/latam\/fr\/technologies\/aml-e\/\">\n                                                      <strong class='title'>AML-E<\/strong>\n                                                        <p>Les derni\u00e8res avanc\u00e9es en mati\u00e8re de contr\u00f4le et de surveillance avec des fonctions am\u00e9lior\u00e9es pour les donn\u00e9es essentielles, la d\u00e9finition des limites de levage, le d\u00e9pannage facile, et plus encore.<\/p>\n                                  <\/a>\n              <\/div>\n\n                          \n\n            <div class=\"link-single\">\n                              <a href=\"https:\/\/www.tadano.com\/latam\/fr\/technologies\/aml-f\/\">\n                                                      <strong class='title'>AML-F<\/strong>\n                                                        <p>Le syst\u00e8me de commande\u00a0AML-F s\u2019inscrit comme la derni\u00e8re version des dispositifs qui \u00e9quipent les grues tout-terrain, les grues auxiliaires et les grues \u00e0 chenilles \u00e0 fl\u00e8che t\u00e9lescopique Tadano. <\/p>\n                                  <\/a>\n              <\/div>\n\n                          \n\n            <div class=\"link-single\">\n                              <a href=\"https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-plus\/\">\n                                                      <strong class='title'>IC-1 Plus<\/strong>\n                                                        <p>Augmentez la flexibilit\u00e9 gr\u00e2ce \u00e0 la d\u00e9termination de la capacit\u00e9 de la grue en direct, ce qui permet de multiples configurations asym\u00e9triques des stabilisateurs pour les travaux en espace confin\u00e9. Moins de contrepoids signifie des co\u00fbts de transport r\u00e9duits.<\/p>\n                                  <\/a>\n              <\/div>\n\n                          \n\n            <div class=\"link-single\">\n                              <a href=\"https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-pour-grues-cc\/\">\n                                                      <strong class='title'>IC-1 pour grues CC<\/strong>\n                                                        <p>Am\u00e9liorez l&rsquo;efficacit\u00e9 de vos grues CC gr\u00e2ce \u00e0 des commandes intuitives pour l\u2019installation, l\u2019exploitation et l\u2019entretien.<\/p>\n                                  <\/a>\n              <\/div>\n\n                        <\/div>\n          \n        \n      <\/section>\n    <\/div>\n  <\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>Actualit\u00e9s<\/h2>\n                        \n                  <a href=\"https:\/\/www.tadano.com\/latam\/fr\/news-list\/\" class=\"link-more\">EXPLORER TOUTES les News<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/fr\/news\/grues-pick-carry-rx-empattement-extensible-pour-des-performances-maximales\/\">\n                  <strong class=\"title\">Grues Pick &amp; Carry RX : empattement extensible pour des performances maximales<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Mai\/28\/2026<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/fr\/news\/tadano-finalise-lacquisition-de-lactivite-systemes-de-transport-de-la-societe-ihi-transport-machinery\/\">\n                  <strong class=\"title\">Tadano finalise l\u2019acquisition de l\u2019activit\u00e9 Syst\u00e8mes de transport de la soci\u00e9t\u00e9 IHI Transport Machinery<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Juil\/01\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/fr\/news\/tadano-at-bauma-2025\/\">\n                  <strong class=\"title\">Tadano \u00e0 la bauma 2025<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Avr\/07\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/fr\/news\/the-new-cc-78-1250-1\/\">\n                  <strong class=\"title\">La nouvelle Tadano CC 78.1250-1<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Avr\/03\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/fr\/news\/longueur-hauteur-et-portee-accrues-nouvelle-grue-tout-terrain-tadano-ac-5-250l-2-equipee-dune-fleche-principale-de-79-metres\/\">\n                  <strong class=\"title\">LONGUEUR, HAUTEUR ET PORT\u00c9E ACCRUES: NOUVELLE GRUE TOUT-TERRAIN TADANO AC 5.250L-2 \u00c9QUIP\u00c9E D\u2019UNE FL\u00c8CHE PRINCIPALE DE 79 M\u00c8TRES<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">F\u00e9v\/20\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/fr\/news\/la-tadano-ac-7-450-1-fait-coup-double-dans-le-wisconsin\/\">\n                  <strong class=\"title\">La Tadano AC 7.450-1 fait coup double dans le Wisconsin<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Nov\/12\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/latam\/fr\/news\/la-nouvelle-tadano-ac-5-250-2-seduit-par-ses-solutions-innovantes\/\">\n                  <strong class=\"title\">La nouvelle Tadano AC 5.250-2 s\u00e9duit par ses solutions innovantes<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publication<\/li>\n                    <li><time datetime=\"2020-01-01\">Juil\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  \n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PARCOUREZ NOS Technologies Augmentez la polyvalence, la capacit\u00e9 et le rendement de votre grue gr\u00e2ce \u00e0 des syst\u00e8mes sophistiqu\u00e9s d&rsquo;installation, de configuration, de surveillance et de d\u00e9pannage.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":7834,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7838","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Syst\u00e8mes de contr\u00f4le - Latin America \/ Caribbean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/latam\/fr\/technologie\/systemes-de-controle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Syst\u00e8mes de contr\u00f4le - Latin America \/ Caribbean\" \/>\n<meta property=\"og:description\" content=\"PARCOUREZ NOS Technologies Augmentez la polyvalence, la capacit\u00e9 et le rendement de votre grue gr\u00e2ce \u00e0 des syst\u00e8mes sophistiqu\u00e9s d&rsquo;installation, de configuration, de surveillance et de d\u00e9pannage.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/latam\/fr\/technologie\/systemes-de-controle\/\" \/>\n<meta property=\"og:site_name\" content=\"Latin America \/ Caribbean\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T08:51:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/fr\\\/technologie\\\/systemes-de-controle\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/fr\\\/technologie\\\/systemes-de-controle\\\/\",\"name\":\"Syst\u00e8mes de contr\u00f4le - Latin America \\\/ Caribbean\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\"},\"datePublished\":\"2021-07-02T07:13:12+00:00\",\"dateModified\":\"2025-02-10T08:51:09+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/latam\\\/fr\\\/technologie\\\/systemes-de-controle\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/\",\"name\":\"Latin America \\\/ Caribbean\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Syst\u00e8mes de contr\u00f4le - Latin America \/ Caribbean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/latam\/fr\/technologie\/systemes-de-controle\/","og_locale":"fr_FR","og_type":"article","og_title":"Syst\u00e8mes de contr\u00f4le - Latin America \/ Caribbean","og_description":"PARCOUREZ NOS Technologies Augmentez la polyvalence, la capacit\u00e9 et le rendement de votre grue gr\u00e2ce \u00e0 des syst\u00e8mes sophistiqu\u00e9s d&rsquo;installation, de configuration, de surveillance et de d\u00e9pannage.","og_url":"https:\/\/www.tadano.com\/latam\/fr\/technologie\/systemes-de-controle\/","og_site_name":"Latin America \/ Caribbean","article_modified_time":"2025-02-10T08:51:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/latam\/fr\/technologie\/systemes-de-controle\/","url":"https:\/\/www.tadano.com\/latam\/fr\/technologie\/systemes-de-controle\/","name":"Syst\u00e8mes de contr\u00f4le - Latin America \/ Caribbean","isPartOf":{"@id":"https:\/\/www.tadano.com\/latam\/en\/#website"},"datePublished":"2021-07-02T07:13:12+00:00","dateModified":"2025-02-10T08:51:09+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/latam\/fr\/technologie\/systemes-de-controle\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/latam\/en\/#website","url":"https:\/\/www.tadano.com\/latam\/en\/","name":"Latin America \/ Caribbean","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/latam\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/pages\/7838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/comments?post=7838"}],"version-history":[{"count":3,"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/pages\/7838\/revisions"}],"predecessor-version":[{"id":8431,"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/pages\/7838\/revisions\/8431"}],"up":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/pages\/7834"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/media?parent=7838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}