{"id":7699,"date":"2021-12-10T09:26:39","date_gmt":"2021-12-10T09:26:39","guid":{"rendered":"https:\/\/www.tadano.com\/latam\/technologies\/start-stop\/"},"modified":"2026-05-08T11:15:16","modified_gmt":"2026-05-08T11:15:16","slug":"start-stop","status":"publish","type":"technologies","link":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/start-stop\/","title":{"rendered":"Stop and Start"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\t\t<style type=\"text\/css\">\n\t\t\t.hero-section .img-holder:before {\n\t\t\t\tdisplay: none;\n\t\t\t}\n\t\t<\/style>\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 100% 50%; \">\n\t\t\t<span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/hero\/START_STOP_Kabine_Motiv_10122021_B.jpg, https:\/\/assets.onetadano.com\/celum_assets\/hero-2x\/START_STOP_Kabine_Motiv_10122021_B.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder \">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/latam\/fr\/\">Accueil<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.demagmobilecranes.com\/en\/demag-technology\/cc-3800-1-boom-booster\/\" target=\"_blank\"><\/a><a rel=\"noreferrer noopener\" href=\"https:\/\/www.demagmobilecranes.com\/en\/demag-technology\/cc-8800-1-boom-booster\/\" target=\"_blank\"><\/a><span class=\"has-inline-color has-black-color\"><strong>Fonction Stop and Start<\/strong><\/span><\/h1>\n\n\n\n<p>La fonction Stop and Start permet de couper manuellement le moteur pendant que la grue est en service gr\u00e2ce \u00e0 un bouton situ\u00e9 dans la cabine, afin d&rsquo;\u00e9viter que le moteur ne marche au ralenti. Cette fonction fournit la possibilit\u00e9 de r\u00e9duire la consommation de carburant, les \u00e9missions et les heures de service de la grue. La commande de la grue reste active pendant l&rsquo;arr\u00eat du moteur, de sorte que le service de la grue peut reprendre rapidement apr\u00e8s le red\u00e9marrage.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<div class=\"wp-block-group is-style-background-triangle-right\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">description<\/h2>\n\n\n\n<p><strong>Diminution de la consommation de carburant et des \u00e9missions. Rentabilit\u00e9 accrue.<\/strong><\/p>\n\n\n\n<p>La fonction Stop and Start offre un avantage crucial par rapport aux arr\u00eats de moteur classiques en ceci que la commande de la grue n&rsquo;est pas arr\u00eat\u00e9e, mais reste active. En d&rsquo;autres termes, lorsque la fonction Stop and Start est utilis\u00e9e pour red\u00e9marrer, la commande est pr\u00eate \u00e0 fonctionner en quelques secondes, de sorte qu&rsquo;une op\u00e9ration de levage peut \u00eatre initi\u00e9e ou reprise pratiquement sans d\u00e9lai.<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La fonction Stop and Start permet de couper manuellement le moteur pendant que la grue est en service gr\u00e2ce \u00e0 un bouton situ\u00e9 dans la cabine, afin d&rsquo;\u00e9viter que le moteur ne marche au ralenti. Cette fonction fournit la possibilit\u00e9 de r\u00e9duire la consommation de carburant, les \u00e9missions et les heures de service de la grue. La commande de la grue reste active pendant l&rsquo;arr\u00eat du moteur, de sorte que le service de la grue peut reprendre rapidement apr\u00e8s le red\u00e9marrage.<\/p>\n","protected":false},"template":"","class_list":["post-7699","technologies","type-technologies","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stop and Start - Latin America \/ Caribbean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/latam\/fr\/technologies\/start-stop\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stop and Start - Latin America \/ Caribbean\" \/>\n<meta property=\"og:description\" content=\"La fonction Stop and Start permet de couper manuellement le moteur pendant que la grue est en service gr\u00e2ce \u00e0 un bouton situ\u00e9 dans la cabine, afin d&#039;\u00e9viter que le moteur ne marche au ralenti. Cette fonction fournit la possibilit\u00e9 de r\u00e9duire la consommation de carburant, les \u00e9missions et les heures de service de la grue. La commande de la grue reste active pendant l&#039;arr\u00eat du moteur, de sorte que le service de la grue peut reprendre rapidement apr\u00e8s le red\u00e9marrage.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/latam\/fr\/technologies\/start-stop\/\" \/>\n<meta property=\"og:site_name\" content=\"Latin America \/ Caribbean\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T11:15:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/fr\\\/technologies\\\/start-stop\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/fr\\\/technologies\\\/start-stop\\\/\",\"name\":\"Stop and Start - Latin America \\\/ Caribbean\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\"},\"datePublished\":\"2021-12-10T09:26:39+00:00\",\"dateModified\":\"2026-05-08T11:15:16+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/latam\\\/fr\\\/technologies\\\/start-stop\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/\",\"name\":\"Latin America \\\/ Caribbean\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stop and Start - Latin America \/ Caribbean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/start-stop\/","og_locale":"fr_FR","og_type":"article","og_title":"Stop and Start - Latin America \/ Caribbean","og_description":"La fonction Stop and Start permet de couper manuellement le moteur pendant que la grue est en service gr\u00e2ce \u00e0 un bouton situ\u00e9 dans la cabine, afin d'\u00e9viter que le moteur ne marche au ralenti. Cette fonction fournit la possibilit\u00e9 de r\u00e9duire la consommation de carburant, les \u00e9missions et les heures de service de la grue. La commande de la grue reste active pendant l'arr\u00eat du moteur, de sorte que le service de la grue peut reprendre rapidement apr\u00e8s le red\u00e9marrage.","og_url":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/start-stop\/","og_site_name":"Latin America \/ Caribbean","article_modified_time":"2026-05-08T11:15:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/start-stop\/","url":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/start-stop\/","name":"Stop and Start - Latin America \/ Caribbean","isPartOf":{"@id":"https:\/\/www.tadano.com\/latam\/en\/#website"},"datePublished":"2021-12-10T09:26:39+00:00","dateModified":"2026-05-08T11:15:16+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/latam\/fr\/technologies\/start-stop\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/latam\/en\/#website","url":"https:\/\/www.tadano.com\/latam\/en\/","name":"Latin America \/ Caribbean","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/latam\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/technologies\/7699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/technologies"}],"about":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/types\/technologies"}],"version-history":[{"count":1,"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/technologies\/7699\/revisions"}],"predecessor-version":[{"id":9121,"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/technologies\/7699\/revisions\/9121"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/media?parent=7699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}