{"id":7729,"date":"2021-04-15T07:09:48","date_gmt":"2021-04-15T07:09:48","guid":{"rendered":"https:\/\/www.tadano.com\/latam\/technologies\/cc-boom-boosters\/"},"modified":"2026-06-16T12:34:48","modified_gmt":"2026-06-16T12:34:48","slug":"cc-boom-boosters","status":"publish","type":"technologies","link":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/cc-boom-boosters\/","title":{"rendered":"Kits Boom Booster"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\t\t<style type=\"text\/css\">\n\t\t\t.hero-section .img-holder:before {\n\t\t\t\tdisplay: none;\n\t\t\t}\n\t\t<\/style>\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 0 0; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/asset\/f8ac7b31-88cf-4fe3-b820-44a0b1cdc072\/hero\/img_Terex_CC_8800-1_Boom_Booster_US_3-jpg.jpg, https:\/\/mediahub.tadano.com\/asset\/f8ac7b31-88cf-4fe3-b820-44a0b1cdc072\/hero-2x\/img_Terex_CC_8800-1_Boom_Booster_US_3-jpg.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder \">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/latam\/fr\/\">Accueil<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\"><span style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">KITS BOOM BOOSTER<\/span><\/h1>\n\n\n\n<p>Les kits Boom Booster vous permettent d\u2019augmenter la capacit\u00e9 de charge de vos grues \u00e0 chenilles \u00e0 m\u00e2t treillis Tadano&nbsp;CC 38.650-1, CC&nbsp;68.1250-1 et CC&nbsp;88.1600-1 lors d\u2019op\u00e9rations de levage de charges lourdes avec des configurations de fl\u00e8che avec rallonge. Les kits Boom Booster \u00e9quipent les grues neuves et sont \u00e9galement disponibles dans le cadre d\u2019une mise \u00e0 niveau.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<div class=\"wp-block-group is-style-background-triangle-right\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">description<\/h2>\n\n\n\n<p><strong>Boom Booster pour<\/strong> <strong>CC 38.650-1 : Renforce la rigidit\u00e9 et am\u00e9liore la capacit\u00e9 de charge<\/strong><\/p>\n\n\n\n<p>Disponible en option, le kit Boom Booster permet \u00e0 la grue rentable qu&rsquo;est la CC 38.650-1 de passer \u00e0 la vitesse sup\u00e9rieure et d&rsquo;effectuer des levages normalement r\u00e9serv\u00e9s aux grues de 750&nbsp;tonnes. Non content de renforcer la rigidit\u00e9 de la fl\u00e8che principale, le kit Boom&nbsp;Booster booste la capacit\u00e9 de charge de la grue jusqu&rsquo;\u00e0&nbsp;65,3&nbsp;%. La grue atteint ainsi une hauteur de crochet maximale impressionnante de 174,5 m et des capacit\u00e9s de charge allant jusqu&rsquo;\u00e0 92,5&nbsp;t, ce qui la rend parfaitement adapt\u00e9e \u00e0 l&rsquo;\u00e9rection de grandes et hautes \u00e9oliennes. Les kits ont une longueur comprise entre 24 et 102&nbsp;m et se montent directement sur la grue. Des sections d&rsquo;une longueur de 12&nbsp;m\u00e8tres facilitent le transport tandis que le syst\u00e8me de protection contre les chutes renforce la s\u00e9curit\u00e9.<\/p>\n\n\n\n<p><strong>Boom Booster pour CC 68.1250-1 : capacit\u00e9 de charge accrue, port\u00e9e plus importante, meilleure rentabilit\u00e9<\/strong><\/p>\n\n\n\n<p>Le Boom Booster augmente encore la capacit\u00e9 de charge de la grue CC 68.1250-1, d\u00e9j\u00e0 tr\u00e8s impressionnante, de jusqu\u2019\u00e0 30 % et ce, m\u00eame sur la fl\u00e9chette ! La hauteur sous crochet passe ainsi de 180 \u00e0 194 m et le poids maximal de la charge de 98 \u00e0 plus de 100 t \u00e0 cette hauteur sous crochet. La grue CC 68.1250-1 est ainsi parfaitement adapt\u00e9e \u00e0 l\u2019installation d\u2019\u00e9oliennes dont la hauteur de moyeu peut atteindre 185 m\u00e8tres. La conception optimis\u00e9e pour le transport constitue le principal atout de ce syst\u00e8me : elle permet de r\u00e9duire la largeur syst\u00e8me des \u00e9l\u00e9ments de 5,40 m\u00e8tres \u00e0 3,5 m\u00e8tres, une largeur parfaitement adapt\u00e9e \u00e0 une utilisation sur route. Le Boom Booster est \u00e9galement disponible sur la CC 68.1250-1 en tant qu\u2019accessoire pour les grues neuves ou en tant qu\u2019\u00e9quipement de mise \u00e0 niveau. La conception \u00e9volutive et p\u00e9renne est d\u00e9j\u00e0 pr\u00e9vue pour \u00eatre utilis\u00e9e sur les futurs mod\u00e8les de grues de cette cat\u00e9gorie.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-outline-white\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mediahub.tadano.com\/asset\/9cdd6c35-4f29-4553-a926-d13861a06471\/doc_tadano_CC681250-1-boom-booster_datasheet_metric_en-de-fr-it-es-pt-ru.pdf\">FICHE TECHNIQUE &#8211; BOOM BOOSTER CC 68.1250-1<\/a><\/div>\n<\/div>\n\n\n\n<p><br><strong>Boom Booster pour CC 88.1600-1 : Id\u00e9al pour les projets n\u00e9cessitant une configuration de fl\u00e8che longue et un angle d&rsquo;inclinaison prononc\u00e9<\/strong><\/p>\n\n\n\n<p>Le kit Boom&nbsp;Booster pour grue \u00e0 chenilles CC 88.1600-1 booste les performances de l&rsquo;\u00e9quipement, notamment lorsque la fl\u00e8che est rallong\u00e9e et fortement inclin\u00e9e. Non content de booster les capacit\u00e9s de charge de la grue CC 88.1600-1 jusqu&rsquo;\u00e0&nbsp;90&nbsp;%, le kit Boom&nbsp;Booster permet \u00e0 l&rsquo;\u00e9quipement de supplanter les grues d&rsquo;une capacit\u00e9 de 1000&nbsp;\u00e0 2000&nbsp;tonnes ainsi que certaines grues d&rsquo;une capacit\u00e9 de 3000&nbsp;tonnes sous certaines conditions. Le kit Boom&nbsp;Booster pour CC 88.1600-1 est incontournable pour les travaux de levage lourd en configurations avec fl\u00e8che longue, rencontr\u00e9s dans des projets du domaine de la p\u00e9trochimie ou lors de l&rsquo;installation d&rsquo;\u00e9oliennes et de centrales \u00e9lectriques.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-btn-outline-white\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mediahub.tadano.com\/asset\/ad3d0f2d-fdfa-4b01-8cd7-47fa85a7659b\/doc_tadano_CC881600-1-boom-booster_datasheet_metric_en-de-fr-it-es-pt-ru.pdf\">FICHE TECHNIQUE &#8211; BOOM BOOSTER CC 88.1600-1<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n\n\n\n\n\n\n\n\n\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Galerie m\u00e9dia<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/assets.onetadano.com\/celum_assets\/gallery-full\/CC+8800-1+Boom+Booster+US+2.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/assets.onetadano.com\/celum_assets\/gallery-thumb\/CC+8800-1+Boom+Booster+US+2.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/assets.onetadano.com\/celum_assets\/gallery-full\/CC+8800-1+Boom+Booster+US+3.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/assets.onetadano.com\/celum_assets\/gallery-thumb\/CC+8800-1+Boom+Booster+US+3.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/assets.onetadano.com\/celum_assets\/gallery-full\/Superlift_3800_Hofmann_Boombooster_Flexframe_3.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/assets.onetadano.com\/celum_assets\/gallery-thumb\/Superlift_3800_Hofmann_Boombooster_Flexframe_3.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/assets.onetadano.com\/celum_assets\/gallery-full\/Superlift_3800_Hofmann_Boombooster_Flexframe_6.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/assets.onetadano.com\/celum_assets\/gallery-thumb\/Superlift_3800_Hofmann_Boombooster_Flexframe_6.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n\n\n\n\n\n\n\n\n\n  <section class=\"related-products\">\n    <div class=\"container\">\n              <div class=\"heading\">\n          <h2>PRODUITS LI\u00c9S<\/h2>\n                  <\/div>\n      \n\n              <div class='r-products'>\n                      \n                          <div class='r-product-single'>\n                <a href='https:\/\/www.tadano.com\/latam\/fr\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-38-650-1\/'>\n                  <div class=\"img-holder\">\n                                        <div class=\"bg-stretch\" >\n                      <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/3cbee7136cd0e2b2\/img_thumb-img_tadano_CC38650_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/3cbee7136cd0e2b2\/img_thumb_2x-img_tadano_CC38650_cutout_side.png 2x\"><\/span>\n                    <\/div>\n                                      <\/div>\n                  <div class=\"text-block\">\n                    <strong class=\"title\">CC 38.650-1<\/strong>\n                                      <\/div>\n                <\/a>\n              <\/div>\n                                  \n                          <div class='r-product-single'>\n                <a href='https:\/\/www.tadano.com\/latam\/fr\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-68-1250-1\/'>\n                  <div class=\"img-holder\">\n                                        <div class=\"bg-stretch\" >\n                      <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/68b50bfda304ad98\/img_thumb-img_tadano_CC681250_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/68b50bfda304ad98\/img_thumb_2x-img_tadano_CC681250_cutout_side.png 2x\"><\/span>\n                    <\/div>\n                                      <\/div>\n                  <div class=\"text-block\">\n                    <strong class=\"title\">CC 68.1250-1<\/strong>\n                                      <\/div>\n                <\/a>\n              <\/div>\n                                  \n                          <div class='r-product-single'>\n                <a href='https:\/\/www.tadano.com\/latam\/fr\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-88-1600-1\/'>\n                  <div class=\"img-holder\">\n                                        <div class=\"bg-stretch\" >\n                      <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/5a073a9f4d1dbadd\/img_thumb-img_tadano_CC881600-1_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/5a073a9f4d1dbadd\/img_thumb_2x-img_tadano_CC881600-1_cutout_side.png 2x\"><\/span>\n                    <\/div>\n                                      <\/div>\n                  <div class=\"text-block\">\n                    <strong class=\"title\">CC 88.1600-1<\/strong>\n                                      <\/div>\n                <\/a>\n              <\/div>\n                              <\/div>\n          \n    <\/div>\n  <\/section>\n","protected":false},"excerpt":{"rendered":"<p>Augmentez la capacit\u00e9 de levage de vos CC 38.650-1, CC 68.1250-1 et CC 88.1600-1 jusqu&rsquo;\u00e0 90 % pour les levages lourds avec des configurations de fl\u00e8ches longues. Disponible avec les grues neuves ou en r\u00e9trofit.<\/p>\n","protected":false},"template":"","class_list":["post-7729","technologies","type-technologies","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kits Boom Booster - Latin America \/ Caribbean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/latam\/en\/technologies\/cc-boom-boosters\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kits Boom Booster - Latin America \/ Caribbean\" \/>\n<meta property=\"og:description\" content=\"Augmentez la capacit\u00e9 de levage de vos CC 38.650-1, CC 68.1250-1 et CC 88.1600-1 jusqu&#039;\u00e0 90 % pour les levages lourds avec des configurations de fl\u00e8ches longues. Disponible avec les grues neuves ou en r\u00e9trofit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/latam\/en\/technologies\/cc-boom-boosters\/\" \/>\n<meta property=\"og:site_name\" content=\"Latin America \/ Caribbean\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-16T12:34:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/technologies\\\/cc-boom-boosters\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/technologies\\\/cc-boom-boosters\\\/\",\"name\":\"Kits Boom Booster - Latin America \\\/ Caribbean\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\"},\"datePublished\":\"2021-04-15T07:09:48+00:00\",\"dateModified\":\"2026-06-16T12:34:48+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/technologies\\\/cc-boom-boosters\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/\",\"name\":\"Latin America \\\/ Caribbean\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kits Boom Booster - Latin America \/ Caribbean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/latam\/en\/technologies\/cc-boom-boosters\/","og_locale":"fr_FR","og_type":"article","og_title":"Kits Boom Booster - Latin America \/ Caribbean","og_description":"Augmentez la capacit\u00e9 de levage de vos CC 38.650-1, CC 68.1250-1 et CC 88.1600-1 jusqu'\u00e0 90 % pour les levages lourds avec des configurations de fl\u00e8ches longues. Disponible avec les grues neuves ou en r\u00e9trofit.","og_url":"https:\/\/www.tadano.com\/latam\/en\/technologies\/cc-boom-boosters\/","og_site_name":"Latin America \/ Caribbean","article_modified_time":"2026-06-16T12:34:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/latam\/en\/technologies\/cc-boom-boosters\/","url":"https:\/\/www.tadano.com\/latam\/en\/technologies\/cc-boom-boosters\/","name":"Kits Boom Booster - Latin America \/ Caribbean","isPartOf":{"@id":"https:\/\/www.tadano.com\/latam\/en\/#website"},"datePublished":"2021-04-15T07:09:48+00:00","dateModified":"2026-06-16T12:34:48+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/latam\/en\/technologies\/cc-boom-boosters\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/latam\/en\/#website","url":"https:\/\/www.tadano.com\/latam\/en\/","name":"Latin America \/ Caribbean","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/latam\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/technologies\/7729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/technologies"}],"about":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/types\/technologies"}],"version-history":[{"count":4,"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/technologies\/7729\/revisions"}],"predecessor-version":[{"id":9817,"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/technologies\/7729\/revisions\/9817"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/media?parent=7729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}