{"id":8422,"date":"2025-01-23T12:40:30","date_gmt":"2025-01-23T11:40:30","guid":{"rendered":"https:\/\/www.tadano.com\/latam\/technologies\/ic-1-for-cc-cranes\/"},"modified":"2025-02-06T12:52:26","modified_gmt":"2025-02-06T12:52:26","slug":"ic-1-pour-grues-cc","status":"publish","type":"technologies","link":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-pour-grues-cc\/","title":{"rendered":"IC-1 pour grues CC"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\t\t<style type=\"text\/css\">\n\t\t\t.hero-section .img-holder:before {\n\t\t\t\tdisplay: none;\n\t\t\t}\n\t\t<\/style>\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 50% 50%; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/asset\/1d8203b7-26ae-4b1f-aa34-85b90049b9b3\/hero\/IC-1-for-CC-cranes.jpg, https:\/\/mediahub.tadano.com\/asset\/1d8203b7-26ae-4b1f-aa34-85b90049b9b3\/hero-2x\/IC-1-for-CC-cranes.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/latam\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder \">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/latam\/fr\/\">Accueil<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">IC-1 pour grues CC<\/h1>\n\n\n\n<p>Am\u00e9liorez votre productivit\u00e9 gr\u00e2ce \u00e0 des commandes intuitives permettant l\u2019installation, l\u2019exploitation et l\u2019entretien de votre grue. Gr\u00e2ce \u00e0 des donn\u00e9es en temps r\u00e9el, vous pouvez effectuer des configurations pr\u00e9cises, op\u00e9rer des transitions en douceur et r\u00e9duire la dur\u00e9e d\u2019immobilisation, tandis que des diagnostics avanc\u00e9s et des informations sur votre parc vous permettent d\u2019optimiser les performances et la gestion des co\u00fbts de vos \u00e9quipements.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<div class=\"wp-block-group is-style-background-triangle-right\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\"><strong>Prenez le contr\u00f4le avec IC-1<\/strong><\/h2>\n\n\n\n<p>Toute op\u00e9ration de levage r\u00e9ussie repose sur l\u2019intervention d\u2019une \u00e9quipe d\u2019experts\u00a0: les monteurs qui veillent \u00e0 ce que la grue soit install\u00e9e dans les r\u00e8gles de l\u2019art, les op\u00e9rateurs et les superviseurs de levage dont la t\u00e2che consiste \u00e0 ex\u00e9cuter le levage en toute s\u00e9curit\u00e9 et de mani\u00e8re efficace, le personnel de maintenance qui assure le maintien de la grue dans un \u00e9tat de fonctionnement optimal, sans oublier les gestionnaires de parc qui font en sorte que l\u2019\u00e9quipement ad\u00e9quat soit disponible pour chaque chantier.<\/p>\n\n\n\n<p>IC-1 fournit \u00e0 votre \u00e9quipe toutes les informations et les outils dont elle a besoin pour prendre r\u00e9ellement le contr\u00f4le, tant sur le terrain qu\u2019\u00e0 l\u2019\u00e9chelle du parc. Que ce soit gr\u00e2ce aux \u00e9crans intuitifs install\u00e9s dans la cabine ou aux fonctionnalit\u00e9s avanc\u00e9es de gestion de parc fournies par le syst\u00e8me t\u00e9l\u00e9matique IC-1\u00a0Remote pour la grue \u00e0 chenilles CC\u00a038.650-1, le syst\u00e8me IC-1 offre \u00e0 chacun des membres de votre \u00e9quipe la possibilit\u00e9 de se surpasser.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Installation<\/strong><\/h2>\n\n\n\n<p><strong><strong>Prenez le contr\u00f4le de l\u2019installation de votre grue<\/strong><\/strong><\/p>\n\n\n\n<p>Les clients paient pour le levage, pas pour l\u2019installation. Dans le cadre de projets complexes, le temps pass\u00e9 \u00e0 monter la grue est du temps qui ne rapporte rien. Le syst\u00e8me de commande\u00a0IC-1 simplifie le processus d\u2019installation qu\u2019il rend \u00e0 la fois s\u00fbr et efficace.<\/p>\n\n\n\n<p>Il vous permet de s\u00e9lectionner facilement la configuration adapt\u00e9e \u00e0 votre parc de grues. Quatre programmes d\u2019aide au montage et le montage automatis\u00e9 des principaux composants contribuent \u00e0 faciliter l\u2019installation de la grue. Les commandes intuitives du syst\u00e8me permettent de passer facilement d\u2019un mode de commande depuis la cabine \u00e0 un mode de commande \u00e0 distance. Lors du levage de la fl\u00e8che, le mode montage de l\u2019IC-1 assure une surveillance claire de tous les param\u00e8tres vitaux, ce qui garantit une ma\u00eetrise totale de l\u2019op\u00e9ration.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading\"><strong>Exploitation de la grue<\/strong><\/h2>\n\n\n\n<p><strong><strong>Prenez le contr\u00f4le de vos op\u00e9rations de levage<\/strong><\/strong><\/p>\n\n\n\n<p>Chaque op\u00e9ration de levage repose sur la comp\u00e9tence et la pr\u00e9cision de l\u2019op\u00e9rateur. L\u2019IC-1 vient renforcer cette expertise en fournissant toutes les informations indispensables \u00e0 un fonctionnement s\u00fbr et efficace de la grue. Depuis l\u2019espace confortable de la cabine de la grue \u00e0 chenilles Tadano, l&rsquo;op\u00e9rateur peut surveiller les op\u00e9rations avec pr\u00e9cision et en toute fiabilit\u00e9.<\/p>\n\n\n\n<p>Gr\u00e2ce \u00e0 son menu intuitif, l\u2019IC-1 permet une s\u00e9lection rapide des configurations de la grue. Le manipulateur peut \u00eatre facilement personnalis\u00e9 en fonction des besoins individuels. L\u2019op\u00e9rateur peut surveiller la capacit\u00e9 de charge limite en temps r\u00e9el et utiliser la fonction de limitation de la plage de fonctionnement pour bloquer les zones pouvant repr\u00e9senter un risque. Qu\u2019il s\u2019agisse de levages statiques ou d\u2019op\u00e9rations \u00ab\u00a0pick-and-carry\u00a0\u00bb, le syst\u00e8me\u00a0IC-1 garantit des transitions en douceur et une grande pr\u00e9cision des mouvements. Le syst\u00e8me va m\u00eame jusqu\u2019\u00e0 simplifier des t\u00e2ches complexes comme le verrouillage de l\u2019entra\u00eenement des chenilles de gauche et de droite, qui fonctionnent de mani\u00e8re synchronis\u00e9e \u00e0 la m\u00eame vitesse pour assurer un d\u00e9placement parfait en ligne droite lors d\u2019une op\u00e9ration de levage de queue (tailing lift en anglais) d\u2019un r\u00e9servoir pour son installation \u00e0 la verticale.<\/p>\n\n\n\n<p>Gr\u00e2ce \u00e0 l\u2019IC-1, les comp\u00e9tences acquises par l\u2019op\u00e9rateur sur des grues Tadano de plus petit gabarit peuvent \u00eatre facilement transposables \u00e0 des projets de plus grande envergure et plus exigeants, de sorte que le syst\u00e8me \u00e9volue au m\u00eame rythme que les comp\u00e9tences de l\u2019op\u00e9rateur.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mediahub.tadano.com\/m\/5e203dfa79863690\/webimage-img_Tadano_TDN_CC_38-650-1_Jobsite_Bridge_cmyk-jpg.jpg\" alt=\"\"\/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Maintenance de la grue<\/strong><\/h2>\n\n\n\n<p><strong><strong>Prenez le contr\u00f4le de la disponibilit\u00e9 de votre grue<\/strong><\/strong><\/p>\n\n\n\n<p>Une grue n\u2019est rentable que lorsqu\u2019elle est op\u00e9rationnelle. L\u2019IC-1 r\u00e9duit la dur\u00e9e d\u2019immobilisation \u00e0 un minimum gr\u00e2ce \u00e0 une assistance compl\u00e8te en mati\u00e8re de maintenance. Les op\u00e9rateurs peuvent avoir directement acc\u00e8s aux principales donn\u00e9es de maintenance dans la cabine, tandis que le personnel du centre d\u2019entretien peut utiliser ces m\u00eames donn\u00e9es pour planifier efficacement la maintenance pr\u00e9ventive.<\/p>\n\n\n\n<p>Des diagnostics avanc\u00e9s embarqu\u00e9s prolongent la dur\u00e9e de vie des grues et renforcent leur s\u00e9curit\u00e9, garantissant ainsi des op\u00e9rations ax\u00e9es sur l&rsquo;efficacit\u00e9 et la rentabilit\u00e9. En cas de panne, les fonctionnalit\u00e9s t\u00e9l\u00e9matiques du syst\u00e8me IC-1\u00a0Remote permettent de r\u00e9soudre de nombreux probl\u00e8mes \u00e0 distance, rendant ainsi superflue l\u2019intervention d\u2019un technicien sur place. Si des pi\u00e8ces de rechange sont n\u00e9cessaires, les diagnostics \u00e0 distance garantissent la livraison rapide des composants ad\u00e9quats, de sorte que votre grue demeure op\u00e9rationnelle pour le prochain chantier.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Gestion du parc<\/strong><\/h2>\n\n\n\n<p><strong><strong>Prenez le contr\u00f4le de votre parc de grues<\/strong><\/strong><\/p>\n\n\n\n<p>La gestion d\u2019un parc de grues n\u00e9cessite des ann\u00e9es d\u2019exp\u00e9rience et un suivi rigoureux des co\u00fbts et de l\u2019utilisation. Le syst\u00e8me IC-1 offre aux gestionnaires de parc un aper\u00e7u clair des performances r\u00e9alis\u00e9es par l&rsquo;ensemble des grues, gr\u00e2ce notamment au syst\u00e8me t\u00e9l\u00e9matique IC-1\u00a0Remote con\u00e7u pour la grue \u00e0 chenilles CC\u00a038.650-1.<\/p>\n\n\n\n<p>Un suivi pr\u00e9cis de la consommation de carburant permet de d\u00e9terminer l\u2019utilisation du moteur au ralenti, et donc de r\u00e9duire les co\u00fbts inutiles. Les \u00e9missions de gaz \u00e0 effet de serre du champ d\u2019application\u00a03 (scope 3) faisant l\u2019objet d\u2019une attention croissante, le syst\u00e8me IC-1\u00a0Remote offre un suivi transparent de l\u2019impact carbone de votre parc de grues, r\u00e9pondant ainsi aux attentes de vos clients en mati\u00e8re de d\u00e9veloppement durable.<\/p>\n\n\n\n<p>Lorsque vient le moment de renouveler votre parc, les donn\u00e9es d\u2019utilisation recueillies par le syst\u00e8me IC-1\u00a0Remote vous aident \u00e0 prendre les bonnes d\u00e9cisions, car elles mettent en \u00e9vidence les grues dont les performances sont insuffisantes et permettent d\u2019identifier les mod\u00e8les qui r\u00e9pondent aux besoins du march\u00e9. En responsabilisant les monteurs, les op\u00e9rateurs, le personnel de maintenance et les gestionnaires de parc, le syst\u00e8me\u00a0IC-1\u00a0Remote garantit le fonctionnement optimal de chacune des grues de votre parc.<\/p>\n<\/div><\/div>\n\n\n\n\n\n\n\n\n\n\n\n\n  <section class=\"related-products related-pages\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>Pages en relation<\/h2>\n      <\/div>\n\n      <div class='r-products'>\n                  \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/latam\/fr\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-24-400-1\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/7bd2d691c6282dca\/img_thumb-img_tadano_CC24400_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/7bd2d691c6282dca\/img_thumb_2x-img_tadano_CC24400_cutout_side.png 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">CC 24.400-1<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                            \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/latam\/fr\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-38-650-1\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/3cbee7136cd0e2b2\/img_thumb-img_tadano_CC38650_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/3cbee7136cd0e2b2\/img_thumb_2x-img_tadano_CC38650_cutout_side.png 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">CC 38.650-1<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                            \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/latam\/fr\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-68-1250-1\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/68b50bfda304ad98\/img_thumb-img_tadano_CC681250_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/68b50bfda304ad98\/img_thumb_2x-img_tadano_CC681250_cutout_side.png 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">CC 68.1250-1<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                            \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/latam\/fr\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-88-1600-1\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/5a073a9f4d1dbadd\/img_thumb-img_tadano_CC881600-1_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/5a073a9f4d1dbadd\/img_thumb_2x-img_tadano_CC881600-1_cutout_side.png 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">CC 88.1600-1<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                        <\/div>\n        \n    <\/div>\n  <\/section>\n  \n","protected":false},"excerpt":{"rendered":"<p>Am\u00e9liorez l&rsquo;efficacit\u00e9 de vos grues CC gr\u00e2ce \u00e0 des commandes intuitives pour l\u2019installation, l\u2019exploitation et l\u2019entretien.<\/p>\n","protected":false},"template":"","class_list":["post-8422","technologies","type-technologies","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IC-1 pour grues CC - Latin America \/ Caribbean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-pour-grues-cc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IC-1 pour grues CC - Latin America \/ Caribbean\" \/>\n<meta property=\"og:description\" content=\"Am\u00e9liorez l&#039;efficacit\u00e9 de vos grues CC gr\u00e2ce \u00e0 des commandes intuitives pour l\u2019installation, l\u2019exploitation et l\u2019entretien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-pour-grues-cc\/\" \/>\n<meta property=\"og:site_name\" content=\"Latin America \/ Caribbean\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T12:52:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediahub.tadano.com\/m\/5e203dfa79863690\/webimage-img_Tadano_TDN_CC_38-650-1_Jobsite_Bridge_cmyk-jpg.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/fr\\\/technologies\\\/ic-1-pour-grues-cc\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/fr\\\/technologies\\\/ic-1-pour-grues-cc\\\/\",\"name\":\"IC-1 pour grues CC - Latin America \\\/ Caribbean\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/fr\\\/technologies\\\/ic-1-pour-grues-cc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/fr\\\/technologies\\\/ic-1-pour-grues-cc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mediahub.tadano.com\\\/m\\\/5e203dfa79863690\\\/webimage-img_Tadano_TDN_CC_38-650-1_Jobsite_Bridge_cmyk-jpg.jpg\",\"datePublished\":\"2025-01-23T11:40:30+00:00\",\"dateModified\":\"2025-02-06T12:52:26+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/latam\\\/fr\\\/technologies\\\/ic-1-pour-grues-cc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/fr\\\/technologies\\\/ic-1-pour-grues-cc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mediahub.tadano.com\\\/m\\\/5e203dfa79863690\\\/webimage-img_Tadano_TDN_CC_38-650-1_Jobsite_Bridge_cmyk-jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/mediahub.tadano.com\\\/m\\\/5e203dfa79863690\\\/webimage-img_Tadano_TDN_CC_38-650-1_Jobsite_Bridge_cmyk-jpg.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/\",\"name\":\"Latin America \\\/ Caribbean\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/latam\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IC-1 pour grues CC - Latin America \/ Caribbean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-pour-grues-cc\/","og_locale":"fr_FR","og_type":"article","og_title":"IC-1 pour grues CC - Latin America \/ Caribbean","og_description":"Am\u00e9liorez l'efficacit\u00e9 de vos grues CC gr\u00e2ce \u00e0 des commandes intuitives pour l\u2019installation, l\u2019exploitation et l\u2019entretien.","og_url":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-pour-grues-cc\/","og_site_name":"Latin America \/ Caribbean","article_modified_time":"2025-02-06T12:52:26+00:00","og_image":[{"url":"https:\/\/mediahub.tadano.com\/m\/5e203dfa79863690\/webimage-img_Tadano_TDN_CC_38-650-1_Jobsite_Bridge_cmyk-jpg.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-pour-grues-cc\/","url":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-pour-grues-cc\/","name":"IC-1 pour grues CC - Latin America \/ Caribbean","isPartOf":{"@id":"https:\/\/www.tadano.com\/latam\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-pour-grues-cc\/#primaryimage"},"image":{"@id":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-pour-grues-cc\/#primaryimage"},"thumbnailUrl":"https:\/\/mediahub.tadano.com\/m\/5e203dfa79863690\/webimage-img_Tadano_TDN_CC_38-650-1_Jobsite_Bridge_cmyk-jpg.jpg","datePublished":"2025-01-23T11:40:30+00:00","dateModified":"2025-02-06T12:52:26+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-pour-grues-cc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.tadano.com\/latam\/fr\/technologies\/ic-1-pour-grues-cc\/#primaryimage","url":"https:\/\/mediahub.tadano.com\/m\/5e203dfa79863690\/webimage-img_Tadano_TDN_CC_38-650-1_Jobsite_Bridge_cmyk-jpg.jpg","contentUrl":"https:\/\/mediahub.tadano.com\/m\/5e203dfa79863690\/webimage-img_Tadano_TDN_CC_38-650-1_Jobsite_Bridge_cmyk-jpg.jpg"},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/latam\/en\/#website","url":"https:\/\/www.tadano.com\/latam\/en\/","name":"Latin America \/ Caribbean","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/latam\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/technologies\/8422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/technologies"}],"about":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/types\/technologies"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/technologies\/8422\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/latam\/fr\/wp-json\/wp\/v2\/media?parent=8422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}