{"id":5524,"date":"2026-01-14T11:52:32","date_gmt":"2026-01-14T11:52:32","guid":{"rendered":"https:\/\/www.tadano.com\/mexico\/plataformas-elevadoras-autopropulsadas-serie-oilsteel\/"},"modified":"2026-02-25T13:18:22","modified_gmt":"2026-02-25T13:18:22","slug":"plataformas-elevadoras-autopropulsadas-serie-oilsteel","status":"publish","type":"page","link":"https:\/\/www.tadano.com\/mexico\/es\/plataformas-elevadoras-autopropulsadas-serie-oilsteel\/","title":{"rendered":"Plataformas elevadoras autopropulsadas (Serie Oil&amp;Steel)"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 50% 0; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/6456954062b003e8\/hero-img_OS_Octoplus21_job.jpg, https:\/\/mediahub.tadano.com\/m\/6456954062b003e8\/hero_2x-img_OS_Octoplus21_job.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/mexico\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder \">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/mexico\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">Plataformas elevadoras autopropulsadas<\/h1>\n\n\n\n<p>Las plataformas elevadoras autopropulsadas Tadano (Serie Oil&amp;Steel) combinan un dise\u00f1o compacto, un control preciso y un alcance excepcional para ofrecer un acceso en altura seguro y eficiente. Dise\u00f1adas para un alto rendimiento tanto en entornos urbanos como industriales, estas m\u00e1quinas proporcionan una maniobrabilidad y una estabilidad excepcionales en cada lugar de trabajo.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare-1\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Comparar productos<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"es\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"13\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"196\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5747\" data-group=\"\">Octoplus 17<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5755\" data-group=\"\">Octoplus 21<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5746\" data-group=\"\">Octoplus 30<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5747\" data-group=\"\">Octoplus 17<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5755\" data-group=\"\">Octoplus 21<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5746\" data-group=\"\">Octoplus 30<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n    <div class=\"products-filtering \">\n                        <input type=\"hidden\" id=\"filterAxles\" value=\"\"\/>\n        <input type=\"hidden\" id=\"filterMaxLoad\" value=\"\"\/>\n        <input type=\"hidden\" id=\"filterBoomLength\" value=\"\"\/>\n        <input type=\"hidden\" id=\"filterTipHeight\" value=\"\"\/>\n        <input type=\"hidden\" id=\"filterManufacturingYear\" value=\"\"\/>\n        <input type=\"hidden\" id=\"filterCategory\" value=\"\"\/>\n                <input type=\"hidden\" id=\"filterLegacyStatus\" value=\"\"\/>\n        <input type=\"hidden\" id=\"displayFilter\" value=\"1\"\/>\n        <!-- REFINE AREA START -->\n                    <section class=\"filter-refine\">\n                <form action=\"#\">\n                    <div class=\"container\">\n                        <div class=\"left\">\n                                                            <strong class=\"title\">Refinar b\u00fasqueda:<\/strong>\n                                                                                        <ul class=\"tabset-filter\">\n                                                                                                                                                                                                                                                                                            <\/ul>\n                                <div class=\"tab-content product-tab-content\">\n                                                                                                                                                                                                                                                                                            <\/div>\n\n                                \n                            \n\n                        <\/div>\n                        <div class=\"right\">\n                                                            <ul class=\"btn-right\">\n                                    <li class=\"desktop-only\"><a data-fancybox=\"product-compare\" data-src=\"#product-compare-1\"\n                                                                href=\"javascript:;\"\n                                                                class=\"compare\">Comparar<\/a><\/li>\n                                <\/ul>\n                                                        <div class=\"radio\">\n                                                                    <label for=\"met\" class=\"met\">\n                                        <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                                        <span class=\"fake-radio\"><\/span>\n                                        <span class=\"fake-label\">M\u00e9trico<\/span>\n                                    <\/label>\n                                    <label for=\"imp\" class=\"imp\">\n                                        <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                                        <span class=\"fake-radio\"><\/span>\n                                        <span class=\"fake-label\">Imperial<\/span>\n                                    <\/label>\n                                    \n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/form>\n            <\/section>\n                <!-- REFINE AREA END -->\n\n        \n                <div class=\"all-results use-portrait-mode\" >\n            <section class=\"filter-content\">\n                <div class=\"container\">\n                    <div class=\"no-results\">\n                        <h2>Lo siento, no se ha encontrado nada \ud83d\ude14<\/h2>\n                        <p>Por favor, ajuste su b\u00fasqueda. <\/p>\n                    <\/div>\n                                                <h2>Plataformas a\u00e9reas autopropulsadas (Serie Oil &amp; Steel)<\/h2>\n                           \n                        <div class=\"filter-compare used-cranes\">\n                            \n<div class=\"product-filter-item\" \n            data-product-id=\"5747\"\n                                                data-product-boomlength-met=\"15\"\n                        >\n    <div class=\"compare-single \">\n\n                        <div class=\"img-holder\">\n                            <div class=\"bg-stretch\" >\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/7ad560fda93ba46a\/img_thumb-img_oilandsteel_octoplus17_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/7ad560fda93ba46a\/img_thumb_2x-img_oilandsteel_octoplus17_cutout_side.png 2x\"><\/span>\n                <\/div>\n                                <\/div>\n        <div class=\"opener-wrap\">\n                            <a href=\"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/self-propelled-awp\/octoplus-17\/\" class=\"opener\">\n                    Octoplus 17                                    <\/a>\n                    <\/div>\n        <div class=\"text-block\">\n                            <div class=\"heading\">\n                    <h3>Octoplus 17<\/h3>\n                                            <a href=\"https:\/\/mediahub.tadano.com\/asset\/b45258a6-29d6-4b9a-9495-163b5312fec7\/doc_tadano_Octoplus17_datasheet_es.pdf\" class=\"specs\">Hoja de especificaciones<\/a>\n                                    <\/div>\n            \n                                    <ul class=\"scaled scaled-met\">\n                                                                                                                            <li><strong>Longitud de la pluma principal:<\/strong> 15,0 m<\/li>\n                                                                                                                                                    \n                    <\/ul>\n                                    <ul class=\"scaled scaled-imp\">\n                                                                                                                                                                                                            \n                    <\/ul>\n                                    <\/div>\n        <ul class=\"btn-list\">\n                        <li>\n                                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/self-propelled-awp\/octoplus-17\/\" class=\"btn-details\">\n                    <span class=\"mobile-only\">Detalles<\/span>\n                    <span class=\"desktop-only\">M\u00e1s informaci\u00f3n<\/span>\n                <\/a>\n            <\/li>\n            \n                                <li class=\"scaled-metric\">\n                        <a href=\"https:\/\/mediahub.tadano.com\/asset\/b45258a6-29d6-4b9a-9495-163b5312fec7\/doc_tadano_Octoplus17_datasheet_es.pdf\" class=\"btn-specs\" >\n                            <span class=\"mobile-only\">Especificaciones<\/span>\n                            <span class=\"desktop-only\">Hoja de especificaciones<\/span>\n                        <\/a>\n                    <\/li>\n\n                                                <li class=\"scaled-imperial\">\n                                <a href=\"https:\/\/mediahub.tadano.com\/asset\/b45258a6-29d6-4b9a-9495-163b5312fec7\/doc_tadano_Octoplus17_datasheet_es.pdf\" class=\"btn-specs\" >\n                                    <span class=\"mobile-only\">Especificaciones<\/span>\n                                    <span class=\"desktop-only\">Hoja de especificaciones<\/span>\n                                <\/a>\n                            <\/li>\n                        \n                \n            \n            \n            \n\n        <\/ul>\n    <\/div><!-- end compare single -->\n<\/div><!-- end product filter item -->\n<div class=\"product-filter-item\" \n            data-product-id=\"5755\"\n                                                data-product-boomlength-met=\"18\"\n                        >\n    <div class=\"compare-single \">\n\n                        <div class=\"img-holder\">\n                            <div class=\"bg-stretch\" >\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/42df885006210571\/img_thumb-img_oilandsteel_octoplus21_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/42df885006210571\/img_thumb_2x-img_oilandsteel_octoplus21_cutout_side.png 2x\"><\/span>\n                <\/div>\n                                <\/div>\n        <div class=\"opener-wrap\">\n                            <a href=\"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/self-propelled-awp\/octoplus-21\/\" class=\"opener\">\n                    Octoplus 21                                    <\/a>\n                    <\/div>\n        <div class=\"text-block\">\n                            <div class=\"heading\">\n                    <h3>Octoplus 21<\/h3>\n                                            <a href=\"https:\/\/mediahub.tadano.com\/asset\/be6232c3-045c-4e3c-a1ec-8eaf6a30c294\/doc_tadano_Octoplus21_datasheet_es.pdf\" class=\"specs\">Hoja de especificaciones<\/a>\n                                    <\/div>\n            \n                                    <ul class=\"scaled scaled-met\">\n                                                                                                                            <li><strong>Longitud de la pluma principal:<\/strong> 18,7 m<\/li>\n                                                                                                                                                    \n                    <\/ul>\n                                    <ul class=\"scaled scaled-imp\">\n                                                                                                                                                                                                            \n                    <\/ul>\n                                    <\/div>\n        <ul class=\"btn-list\">\n                        <li>\n                                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/self-propelled-awp\/octoplus-21\/\" class=\"btn-details\">\n                    <span class=\"mobile-only\">Detalles<\/span>\n                    <span class=\"desktop-only\">M\u00e1s informaci\u00f3n<\/span>\n                <\/a>\n            <\/li>\n            \n                                <li class=\"scaled-metric\">\n                        <a href=\"https:\/\/mediahub.tadano.com\/asset\/be6232c3-045c-4e3c-a1ec-8eaf6a30c294\/doc_tadano_Octoplus21_datasheet_es.pdf\" class=\"btn-specs\" >\n                            <span class=\"mobile-only\">Especificaciones<\/span>\n                            <span class=\"desktop-only\">Hoja de especificaciones<\/span>\n                        <\/a>\n                    <\/li>\n\n                                                <li class=\"scaled-imperial\">\n                                <a href=\"https:\/\/mediahub.tadano.com\/asset\/be6232c3-045c-4e3c-a1ec-8eaf6a30c294\/doc_tadano_Octoplus21_datasheet_es.pdf\" class=\"btn-specs\" >\n                                    <span class=\"mobile-only\">Especificaciones<\/span>\n                                    <span class=\"desktop-only\">Hoja de especificaciones<\/span>\n                                <\/a>\n                            <\/li>\n                        \n                \n            \n            \n            \n\n        <\/ul>\n    <\/div><!-- end compare single -->\n<\/div><!-- end product filter item -->\n<div class=\"product-filter-item\" \n            data-product-id=\"5746\"\n                                                data-product-boomlength-met=\"27\"\n                        >\n    <div class=\"compare-single \">\n\n                        <div class=\"img-holder\">\n                            <div class=\"bg-stretch\" >\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/33d8dd62c73a0632\/img_thumb-img_oilandsteel_octoplus30_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/33d8dd62c73a0632\/img_thumb_2x-img_oilandsteel_octoplus30_cutout_side.png 2x\"><\/span>\n                <\/div>\n                                <\/div>\n        <div class=\"opener-wrap\">\n                            <a href=\"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/self-propelled-awp\/octoplus-30\/\" class=\"opener\">\n                    Octoplus 30                                    <\/a>\n                    <\/div>\n        <div class=\"text-block\">\n                            <div class=\"heading\">\n                    <h3>Octoplus 30<\/h3>\n                                            <a href=\"https:\/\/mediahub.tadano.com\/asset\/2e583f4a-d006-4825-be43-0c501cef7d5d\/doc_tadano_Octoplus30_datasheet_es.pdf\" class=\"specs\">Hoja de especificaciones<\/a>\n                                    <\/div>\n            \n                                    <ul class=\"scaled scaled-met\">\n                                                                                                                            <li><strong>Longitud de la pluma principal:<\/strong> 27,6 m<\/li>\n                                                                                                                                                    \n                    <\/ul>\n                                    <ul class=\"scaled scaled-imp\">\n                                                                                                                                                                                                            \n                    <\/ul>\n                                    <\/div>\n        <ul class=\"btn-list\">\n                        <li>\n                                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/self-propelled-awp\/octoplus-30\/\" class=\"btn-details\">\n                    <span class=\"mobile-only\">Detalles<\/span>\n                    <span class=\"desktop-only\">M\u00e1s informaci\u00f3n<\/span>\n                <\/a>\n            <\/li>\n            \n                                <li class=\"scaled-metric\">\n                        <a href=\"https:\/\/mediahub.tadano.com\/asset\/2e583f4a-d006-4825-be43-0c501cef7d5d\/doc_tadano_Octoplus30_datasheet_es.pdf\" class=\"btn-specs\" >\n                            <span class=\"mobile-only\">Especificaciones<\/span>\n                            <span class=\"desktop-only\">Hoja de especificaciones<\/span>\n                        <\/a>\n                    <\/li>\n\n                                                <li class=\"scaled-imperial\">\n                                <a href=\"https:\/\/mediahub.tadano.com\/asset\/2e583f4a-d006-4825-be43-0c501cef7d5d\/doc_tadano_Octoplus30_datasheet_es.pdf\" class=\"btn-specs\" >\n                                    <span class=\"mobile-only\">Especificaciones<\/span>\n                                    <span class=\"desktop-only\">Hoja de especificaciones<\/span>\n                                <\/a>\n                            <\/li>\n                        \n                \n            \n            \n            \n\n        <\/ul>\n    <\/div><!-- end compare single -->\n<\/div><!-- end product filter item -->                        <\/div><!-- end filter compare -->\n\n                                    <\/section>\n        <\/div>\n    <\/div>\n\n\n<section class=\"new-products\">\n  <div class=\"container\">\n    <h2>Nuevos productos<\/h2>\n    <div class=\"new-products-hold\">\n                                  <div class=\"new-product-single\">\n            <a href=\"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/truck-mounted-awp\/snake-20-fb-pro-sobre-iveco\/\">\n              <div class=\"img-holder\">\n                                <div class=\"bg-stretch\" >\n                  <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/6dfac0ed11deadb0\/employee-img_oilandsteel_snake20fb_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/6dfac0ed11deadb0\/employee_2x-img_oilandsteel_snake20fb_cutout_side.png 2x\"><\/span>\n                <\/div>\n                              <\/div>\n              <div class=\"text-block\">\n                <strong class=\"title\">Snake 20 FB Pro sobre Iveco<\/strong>\n                <span class=\"category\">\n                                  <\/span>\n              <\/div>\n            <\/a>\n          <\/div>\n                            <div class=\"new-product-single\">\n            <a href=\"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/truck-mounted-awp\/snake-24-fb\/\">\n              <div class=\"img-holder\">\n                                <div class=\"bg-stretch\" >\n                  <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/61262612e5b039f9\/employee-img_oilandsteel_snake24fb_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/61262612e5b039f9\/employee_2x-img_oilandsteel_snake24fb_cutout_side.png 2x\"><\/span>\n                <\/div>\n                              <\/div>\n              <div class=\"text-block\">\n                <strong class=\"title\">Snake 24 FB sobre Iveco<\/strong>\n                <span class=\"category\">\n                                  <\/span>\n              <\/div>\n            <\/a>\n          <\/div>\n                            <div class=\"new-product-single\">\n            <a href=\"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/truck-mounted-awp\/snake-20-isuzu\/\">\n              <div class=\"img-holder\">\n                                <div class=\"bg-stretch\" >\n                  <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/4e14479cfaf5831b\/employee-img_oilandsteel_snake20_isuzu_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/4e14479cfaf5831b\/employee_2x-img_oilandsteel_snake20_isuzu_cutout_side.png 2x\"><\/span>\n                <\/div>\n                              <\/div>\n              <div class=\"text-block\">\n                <strong class=\"title\">Snake 20 sobre Isuzu<\/strong>\n                <span class=\"category\">\n                                  <\/span>\n              <\/div>\n            <\/a>\n          <\/div>\n                  <\/div>\n  <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5524","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plataformas elevadoras autopropulsadas (Serie Oil&amp;Steel) - Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/mexico\/en\/self-propelled-aerial-work-platforms-oilsteel-series\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plataformas elevadoras autopropulsadas (Serie Oil&amp;Steel) - Mexico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/mexico\/en\/self-propelled-aerial-work-platforms-oilsteel-series\/\" \/>\n<meta property=\"og:site_name\" content=\"Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T13:18:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/self-propelled-aerial-work-platforms-oilsteel-series\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/self-propelled-aerial-work-platforms-oilsteel-series\\\/\",\"name\":\"Plataformas elevadoras autopropulsadas (Serie Oil&amp;Steel) - Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/#website\"},\"datePublished\":\"2026-01-14T11:52:32+00:00\",\"dateModified\":\"2026-02-25T13:18:22+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/self-propelled-aerial-work-platforms-oilsteel-series\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/\",\"name\":\"Mexico\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plataformas elevadoras autopropulsadas (Serie Oil&amp;Steel) - Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/mexico\/en\/self-propelled-aerial-work-platforms-oilsteel-series\/","og_locale":"es_ES","og_type":"article","og_title":"Plataformas elevadoras autopropulsadas (Serie Oil&amp;Steel) - Mexico","og_url":"https:\/\/www.tadano.com\/mexico\/en\/self-propelled-aerial-work-platforms-oilsteel-series\/","og_site_name":"Mexico","article_modified_time":"2026-02-25T13:18:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/mexico\/en\/self-propelled-aerial-work-platforms-oilsteel-series\/","url":"https:\/\/www.tadano.com\/mexico\/en\/self-propelled-aerial-work-platforms-oilsteel-series\/","name":"Plataformas elevadoras autopropulsadas (Serie Oil&amp;Steel) - Mexico","isPartOf":{"@id":"https:\/\/www.tadano.com\/mexico\/en\/#website"},"datePublished":"2026-01-14T11:52:32+00:00","dateModified":"2026-02-25T13:18:22+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/mexico\/en\/self-propelled-aerial-work-platforms-oilsteel-series\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/mexico\/en\/#website","url":"https:\/\/www.tadano.com\/mexico\/en\/","name":"Mexico","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/mexico\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/pages\/5524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/comments?post=5524"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/pages\/5524\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/media?parent=5524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}