{"id":4936,"date":"2023-09-15T12:40:47","date_gmt":"2023-09-15T12:40:47","guid":{"rendered":"https:\/\/www.tadano.com\/mexico\/%term%\/%cat%\/gr-1300xl-4\/"},"modified":"2024-06-28T09:17:52","modified_gmt":"2024-06-28T09:17:52","slug":"gr-1300xl-4","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/rough-terrain-cranes\/gr-1300xl-4\/","title":{"rendered":"GR-1300XL-4"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 50% 50%; \">\n\t\t\t<span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/hero\/IMG00000002865_JPEG_CG_GR1300XL4_02.jpg, https:\/\/assets.onetadano.com\/celum_assets\/hero-2x\/IMG00000002865_JPEG_CG_GR1300XL4_02.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/mexico\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/mexico\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\" id=\"h-gr-1300xl-4\">GR-1300XL-4<\/h1>\n\n\n\n<p>La pluma de seis secciones de la GR-1300XL-4 se extiende hasta los 183,7 pies, la m\u00e1s larga en su clase de peso de 130 ton cortas. El \u00abDiagrama Inteligente\u00bb de Tadano maximiza el rendimiento mientras que su compacta longitud de veh\u00edculo de 28 pies facilita el transporte.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.tadano.com\/mexico\/es\/ventas-y-servicios\/encuentre-un-distribuidor\/\">Encuentre un Distribuidor<\/a><\/div>\n<\/div>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/mexico\/es\/ventas-y-servicios\/ventas\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Comparar productos<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"es\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"13\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"165\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5035\" data-group=\"\">GR-300EX-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4928\" data-group=\"\">GR-350XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5037\" data-group=\"\">GR-500EXS-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5048\" data-group=\"\">GR-550XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5039\" data-group=\"\">GR-500EXL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5587\" data-group=\"\">GR-700EX-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4933\" data-group=\"\">GR-800XL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5586\" data-group=\"\">GR-900EX-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4934\" data-group=\"\">GR-1000XL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4935\" data-group=\"\">GR-1000XLL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5588\" data-group=\"\">GR-1000EX-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5041\" data-group=\"\">GR-1100EX-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4923\" data-group=\"\">GR-1200XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4936\" data-group=\"\">GR-1300XL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5042\" data-group=\"\">GR-1450EX-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4922\" data-group=\"\">GR-1600XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5035\" data-group=\"\">GR-300EX-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4928\" data-group=\"\">GR-350XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5037\" data-group=\"\">GR-500EXS-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5048\" data-group=\"\">GR-550XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5039\" data-group=\"\">GR-500EXL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5587\" data-group=\"\">GR-700EX-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4933\" data-group=\"\">GR-800XL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5586\" data-group=\"\">GR-900EX-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4934\" data-group=\"\">GR-1000XL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4935\" data-group=\"\">GR-1000XLL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5588\" data-group=\"\">GR-1000EX-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5041\" data-group=\"\">GR-1100EX-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4923\" data-group=\"\">GR-1200XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4936\" data-group=\"\">GR-1300XL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5042\" data-group=\"\">GR-1450EX-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4922\" data-group=\"\">GR-1600XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                                                  <li>\n                <a href=\"#360\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M13.3571 26.2514C20.1818 26.2514 25.7143 20.7189 25.7143 13.8943C25.7143 7.06959 20.1818 1.53711 13.3571 1.53711C6.53248 1.53711 1 7.06959 1 13.8943C1 20.7189 6.53248 26.2514 13.3571 26.2514Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M1 13.0703H25.7143\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M13.3572 1.53711C16.9632 4.92093 19.0125 9.31227 19.1238 13.8943C19.0125 18.4762 16.9632 22.8676 13.3572 26.2514C9.75114 22.8676 7.70185 18.4762 7.59048 13.8943C7.70185 9.31227 9.75114 4.92093 13.3572 1.53711V1.53711Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Vista de 360\u00ba<\/span>\n                <\/a>\n              <\/li>\n            \n            \n                          <li class=\"scaled-metric\">\n                <a href=\"https:\/\/assets.onetadano.com\/celum_assets\/documents\/gr-1300xl-4_datasheet_imperial_en.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Especifi&shy;caciones<\/span>\n                <\/a>\n              <\/li>\n                                      <li class=\"scaled-imperial\">\n                <a href=\"https:\/\/assets.onetadano.com\/celum_assets\/documents\/gr-1300xl-4_datasheet_imperial_en.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Especifi&shy;caciones<\/span>\n                <\/a>\n              <\/li>\n            \n            \n            \n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n             \n\n\n<div class=\"container \">\n  <div class=\"product-details\">\n    <div class=\"product-specs\">\n\n      <div class=\"title\">\n        <div class=\"left\">\n                      <h2>Especificaciones del producto<\/h2>\n                  <\/div>\n        <div class=\"right\">\n                        <div class=\"radio\">\n                                <label for=\"met\" class=\"met\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">M\u00e9trico<\/span>\n                <\/label>\n                <label for=\"imp\" class=\"imp\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Imperial<\/span>\n                <\/label>\n            <\/div>\n            \n\n        <\/div>\n      <\/div>\n\n      \n        <ul>\n\n                                  <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Longitud de la pluma principal<\/strong>\n                          <span>40.0&nbsp;ft &#8211; 183.7&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Extensi\u00f3n de pluma<\/strong>\n                          <span>33.8&nbsp;ft \/ 59.1&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Bases de estabilizaci\u00f3n<\/strong>\n                          <span>25.1&nbsp;ft  x  25.6&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Tiro de la l\u00ednea de elevaci\u00f3n<\/strong>\n                          <span>15,900&nbsp;lbs<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">MAX Radius<\/strong>\n                          <span>205.0&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Dimensiones<\/strong>\n                          <span>578.76&nbsp;in  L x 114.14&nbsp;in  W x 155.51&nbsp;in H<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Clase de capacidad<\/strong>\n                          <span>118.0&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Longitud de la pluma principal<\/strong>\n                          <span>12.2&nbsp;m &#8211; 56.0&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Extensi\u00f3n de pluma<\/strong>\n                          <span>10.3&nbsp;m \/ 18.0&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Altura m\u00e1x. cabeza pluma<\/strong>\n                          <span>72.51&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Bases de estabilizaci\u00f3n<\/strong>\n                          <span>7.66&nbsp;m  x  7.8&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Tiro de la l\u00ednea de elevaci\u00f3n<\/strong>\n                          <span>7,200&nbsp;kg<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Radio m\u00e1x.<\/strong>\n                          <span>62.48&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Dimensiones<\/strong>\n                          <span>14.7&nbsp;m L x 2.90&nbsp;m W x 3.95&nbsp;m H<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Ejes<\/strong>\n                          <span>2<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">transmisi\u00f3n<\/strong>\n                          <span>4x4x4<\/span>\n                        <\/li>\n                      \n        <\/ul>\n\n                  <style type=\"text\/css\">\n            @media screen and (min-width: 1360px) {\n              .hero-section .green-solutions {\n                display: block!important;\n              }\n            }\n          <\/style>\n        \n       \n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-descripci-n-del-producto\">DESCRIPCI\u00d3N DEL PRODUCTO<\/h2>\n\n\n\n<p><strong>Pluma larga de seis secciones, transporte vers\u00e1til<\/strong><\/p>\n\n\n\n<p>La vers\u00e1til GR-1300XL-4 de Tadano, equipada con un motor Cummins, cuenta con una pluma de seis secciones que, gracias a su fiable sistema de fijaci\u00f3n telesc\u00f3pica, puede extenderse hasta 55,9 metros: la mayor longitud de pluma de todas las gr\u00faas para terrenos irregulares en la clase de 118 toneladas m\u00e9tricas. Los contrapesos autodesmontables y la longitud compacta del veh\u00edculo de dos ejes, de tan solo 8,5 metros, significa que la GR-1300XL-4 puede transportarse f\u00e1cilmente a cualquier lugar de trabajo. Para las tareas de elevaci\u00f3n, la tecnolog\u00eda de \u00abDiagrama Inteligente\u00bb integrada ayuda a maximizar el rendimiento. Otras caracter\u00edsticas incluidas son la configuraci\u00f3n asim\u00e9trica de los estabilizadores, una cabina inclinable y un sistema Eco Mode para reducir el consumo de combustible y mejorar la eficiencia.<\/p>\n\n\n\n<section class=\"product-360-view\" id=\"360\">\n\n      <script type=\"text\/javascript\">\n      const ThreeSixtyFrameCount = 36;\n      const ThreeSixtyImagePath = 'https:\/\/www.tadano.com\/mexico\/wp-content\/themes\/tadano\/assets\/dist\/images\/360-view\/GR1300XL_bluewhite_panam\/360\/';\n    <\/script>\n\n    <div class=\"container\">\n      <div class=\"interactive-view\">\n        <h2>Vista interactiva de 360\u00ba<\/h2>\n\n        \n        <div class=\"views-wrapper\">\n\n          \n          \n          <div id=\"view-exterior\" class=\"active\">\n            <div class=\"view-holder\">\n                          <\/div>\n            <div class=\"wrap-360\">\n              <div class=\"threesixty car\">\n                <div class=\"spinner\">\n                    <span style=\"opacity:0.2\">0%<\/span>\n                <\/div>\n                <ol class=\"threesixty_images\"><\/ol>\n              <\/div>\n            <\/div>\n            \n                      <\/div>\n\n        <\/div>\n          \n        \n      <\/div>\n    <\/div>\n\n    \n    <script>\n     \/\/ Target the view-selector divs\n     const selectors = document.querySelectorAll('.view-selector div');\n\n     \/\/ Add a 'click' event listener to all the selectors\n     selectors.forEach(selector => {\n          selector.addEventListener('click', function(event){\n               \/\/ Remove 'active' class from all selectors\n               selectors.forEach(selector => {\n                    selector.classList.remove('active');\n\n                    \/\/ Also remove 'active' class from all views,\n                    \/\/ But first check if the view actually exists\n                    let view = document.querySelector('#' + selector.dataset.view);\n                    if(view) {\n                        view.classList.remove('active');\n                    }\n               })\n\n               \/\/ Add 'active' class to the clicked selector\n               this.classList.add('active');\n\n               \/\/ Add 'active' class to the view corresponding to clicked selector\n               \/\/ After checking if the view actually exists\n               let view = document.querySelector('#' + this.dataset.view);\n               if(view) {\n                   view.classList.add('active');\n               }\n          })\n     });\n    <\/script>\n\n<\/section>","protected":false},"featured_media":0,"template":"","lifting-equipment":[165],"class_list":["post-4936","products","type-products","status-publish","hentry","lifting-equipment-rough-terrain-cranes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GR-1300XL-4 - Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1300xl-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GR-1300XL-4 - Mexico\" \/>\n<meta property=\"og:description\" content=\"DESCRIPCI\u00d3N DEL PRODUCTO Pluma larga de seis secciones, transporte vers\u00e1til La vers\u00e1til GR-1300XL-4 de Tadano, equipada con un motor Cummins, cuenta con una pluma de seis secciones que, gracias a su fiable sistema de fijaci\u00f3n telesc\u00f3pica, puede extenderse hasta 55,9 metros: la mayor longitud de pluma de todas las gr\u00faas para terrenos irregulares en la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1300xl-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-28T09:17:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/equipos-de-elevacion\\\/gruas-para-terrenos-irregulares\\\/gr-1300xl-4\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/equipos-de-elevacion\\\/gruas-para-terrenos-irregulares\\\/gr-1300xl-4\\\/\",\"name\":\"GR-1300XL-4 - Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/#website\"},\"datePublished\":\"2023-09-15T12:40:47+00:00\",\"dateModified\":\"2024-06-28T09:17:52+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/equipos-de-elevacion\\\/gruas-para-terrenos-irregulares\\\/gr-1300xl-4\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/\",\"name\":\"Mexico\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GR-1300XL-4 - Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1300xl-4\/","og_locale":"es_ES","og_type":"article","og_title":"GR-1300XL-4 - Mexico","og_description":"DESCRIPCI\u00d3N DEL PRODUCTO Pluma larga de seis secciones, transporte vers\u00e1til La vers\u00e1til GR-1300XL-4 de Tadano, equipada con un motor Cummins, cuenta con una pluma de seis secciones que, gracias a su fiable sistema de fijaci\u00f3n telesc\u00f3pica, puede extenderse hasta 55,9 metros: la mayor longitud de pluma de todas las gr\u00faas para terrenos irregulares en la [&hellip;]","og_url":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1300xl-4\/","og_site_name":"Mexico","article_modified_time":"2024-06-28T09:17:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1300xl-4\/","url":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1300xl-4\/","name":"GR-1300XL-4 - Mexico","isPartOf":{"@id":"https:\/\/www.tadano.com\/mexico\/en\/#website"},"datePublished":"2023-09-15T12:40:47+00:00","dateModified":"2024-06-28T09:17:52+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1300xl-4\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/mexico\/en\/#website","url":"https:\/\/www.tadano.com\/mexico\/en\/","name":"Mexico","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/mexico\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products\/4936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products\/4936\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/media?parent=4936"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/lifting-equipment?post=4936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}