{"id":4973,"date":"2021-10-11T11:36:57","date_gmt":"2021-10-11T09:36:57","guid":{"rendered":"https:\/\/www.tadano.com\/mexico\/%term%\/%cat%\/ac-3-045-1-city\/"},"modified":"2025-03-20T11:09:36","modified_gmt":"2025-03-20T11:09:36","slug":"ac-3-045-1-city","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/city-cranes\/ac-3-045-1-city\/","title":{"rendered":"AC 3.045-1 City"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 50% 50%; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/6cfee7b2bc98db52\/hero-img_tadano_AC3045CITY_Cutout.png, https:\/\/mediahub.tadano.com\/m\/6cfee7b2bc98db52\/hero_2x-img_tadano_AC3045CITY_Cutout.png 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/mexico\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/mexico\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">AC 3.045-1 C<span style=\"text-transform: lowercase;\" class=\"custom-lowercase\">ity<\/span><\/h1>\n\n\n\n<p>Perfecta para trabajos en interiores o con poca altura libre. La pluma de base corta permite realizar elevaciones pesadas con \u00e1ngulos empinados, mientras que el sistema Flex Base ofrece flexibilidad adicional.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/mexico\/es\/ventas-y-servicios\/ventas\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Comparar productos<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"es\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"13\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"22\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4973\" data-group=\"\">AC 3.045-1 City<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4973\" data-group=\"\">AC 3.045-1 City<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                          <li>\n                <a href=\"#media\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M22.9683 1.53906H3.74603C2.22944 1.53906 1 2.7685 1 4.28509V23.5073C1 25.0239 2.22944 26.2533 3.74603 26.2533H22.9683C24.4848 26.2533 25.7143 25.0239 25.7143 23.5073V4.28509C25.7143 2.7685 24.4848 1.53906 22.9683 1.53906Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.55116 11.1483C9.68861 11.1483 10.6107 10.2263 10.6107 9.08882C10.6107 7.95138 9.68861 7.0293 8.55116 7.0293C7.41372 7.0293 6.49164 7.95138 6.49164 9.08882C6.49164 10.2263 7.41372 11.1483 8.55116 11.1483Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M25.715 18.0135L18.8499 11.1484L3.7467 26.2516\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Galer\u00eda<\/span>\n                <\/a>\n              <\/li>\n                                                  <li>\n                <a href=\"#360\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M13.3571 26.2514C20.1818 26.2514 25.7143 20.7189 25.7143 13.8943C25.7143 7.06959 20.1818 1.53711 13.3571 1.53711C6.53248 1.53711 1 7.06959 1 13.8943C1 20.7189 6.53248 26.2514 13.3571 26.2514Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M1 13.0703H25.7143\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M13.3572 1.53711C16.9632 4.92093 19.0125 9.31227 19.1238 13.8943C19.0125 18.4762 16.9632 22.8676 13.3572 26.2514C9.75114 22.8676 7.70185 18.4762 7.59048 13.8943C7.70185 9.31227 9.75114 4.92093 13.3572 1.53711V1.53711Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Vista de 360\u00ba<\/span>\n                <\/a>\n              <\/li>\n            \n            \n                          <li class=\"scaled-metric\">\n                <a href=\"https:\/\/mediahub.tadano.com\/m\/408382246333bbac\/original\/doc_tadano_AC3045-1-City_datasheet_metric_en_de_fr_it_es_pt_ru.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Especifi&shy;caciones<\/span>\n                <\/a>\n              <\/li>\n                                      <li class=\"scaled-imperial\">\n                <a href=\"https:\/\/mediahub.tadano.com\/m\/72119b49437570f8\/original\/doc_tadano_AC3045-1-City_datasheet_imperial_en.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Especifi&shy;caciones<\/span>\n                <\/a>\n              <\/li>\n            \n            \n            \n                          <li>\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/acerca-de\/contactenos\/\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" version=\"1.1\" width=\"30\" height=\"30\" x=\"0\" y=\"0\" viewBox=\"0 0 440.965 440.965\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M341.508,36.207C305.582,12.648,263.549,0.116,220.587,0.154C98.892,0.271,0.235,98.832,0,220.527    c-0.046,42.838,12.652,84.721,36.48,120.32L0.853,426.18c-2.189,5.469,0.47,11.677,5.939,13.867c2.544,1.018,5.383,1.018,7.928,0    l85.333-35.627c101.679,66.676,238.158,38.3,304.834-63.379S443.187,102.883,341.508,36.207z M220.801,419.567    c-0.071,0-0.142,0-0.213,0v0.213h-0.001c-40.532-0.319-80.02-12.886-113.28-36.053c-1.754-1.224-3.835-1.893-5.973-1.92    c-1.338-0.264-2.715-0.264-4.053,0l-66.774,28.587l27.947-66.56c1.424-3.37,1.022-7.236-1.067-10.24    c-23.487-33.021-36.09-72.545-36.053-113.067C21.216,110.482,110.329,21.178,220.374,21.06    c110.044-0.118,199.349,88.995,199.467,199.04C419.959,330.145,330.846,419.449,220.801,419.567z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M288.514,162.764c-4.633-33.756-33.865-58.657-67.927-57.864c-36.795-0.118-66.752,29.552-66.987,66.347    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667c0.471-25.209,21.289-45.263,46.499-44.792    c25.21,0.471,45.263,21.289,44.792,46.499c-0.465,24.874-20.759,44.796-45.637,44.8c-5.891,0-10.667,4.776-10.667,10.667v47.787    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667v-37.973C267.907,233.206,293.543,199.416,288.514,162.764z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <circle cx=\"219.697\" cy=\"325.147\" r=\"11.675\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <\/g><\/svg>\n\n                  <\/div>\n                  <span class=\"text\">Pedir info&shy;rmaci\u00f3n<\/span>\n                <\/a>\n              <\/li>\n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n             \n\n\n<div class=\"container \">\n  <div class=\"product-details\">\n    <div class=\"product-specs\">\n\n      <div class=\"title\">\n        <div class=\"left\">\n                      <h2>Especificaciones del producto<\/h2>\n                  <\/div>\n        <div class=\"right\">\n                        <div class=\"radio\">\n                                <label for=\"met\" class=\"met\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">M\u00e9trico<\/span>\n                <\/label>\n                <label for=\"imp\" class=\"imp\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Imperial<\/span>\n                <\/label>\n            <\/div>\n            \n\n        <\/div>\n      <\/div>\n\n      \n        <ul>\n\n                                  <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Capacidad m\u00e1x. de la gr\u00faa<\/strong>\n                          <span>50&nbsp;USt<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Longitud de la pluma principal<\/strong>\n                          <span>25.5&nbsp;ft &#8211; 102.3&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Extensi\u00f3n de pluma<\/strong>\n                          <span>3.6&nbsp;ft \/ 23.2&nbsp;ft &#8211; 42.6&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Altura m\u00e1x. cabeza pluma<\/strong>\n                          <span>141.7&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Contrapeso m\u00e1ximo<\/strong>\n                          <span>11,684&nbsp;lbs<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Bases de estabilizaci\u00f3n<\/strong>\n                          <span>21.1&nbsp;ft  x  19.8&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Tiro de la l\u00ednea de elevaci\u00f3n<\/strong>\n                          <span>9,846&nbsp;lbs<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">MAX Radius<\/strong>\n                          <span>120.0&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Dimensiones<\/strong>\n                          <span>L:&nbsp;28.5&nbsp;ft W:&nbsp;8.3&nbsp;ft H:&nbsp;107.0&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Capacidad m\u00e1x. de la gr\u00faa<\/strong>\n                          <span>45&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Longitud de la pluma principal<\/strong>\n                          <span>7.8&nbsp;m &#8211; 31.2&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Extensi\u00f3n de pluma<\/strong>\n                          <span>1.1&nbsp;m \/ 7.1&nbsp;m &#8211; 13&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Altura m\u00e1x. cabeza pluma<\/strong>\n                          <span>46&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Contrapeso m\u00e1ximo<\/strong>\n                          <span>5.3&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Bases de estabilizaci\u00f3n<\/strong>\n                          <span>6.40&nbsp;m x 6.20&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Tiro de la l\u00ednea de elevaci\u00f3n<\/strong>\n                          <span>4.4&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Radio m\u00e1x.<\/strong>\n                          <span>36&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Dimensiones<\/strong>\n                          <span>L:&nbsp;8.70&nbsp;m W:&nbsp;2.55&nbsp;m H:&nbsp;3.18&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Ejes<\/strong>\n                          <span>3<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Motor<\/strong>\n                          <span>Mercedes<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">transmisi\u00f3n<\/strong>\n                          <span>6&nbsp;x 4&nbsp;x 6&nbsp;(6&nbsp;x 6&nbsp;x 6)<\/span>\n                        <\/li>\n                      \n        <\/ul>\n\n                  <style type=\"text\/css\">\n            @media screen and (min-width: 1360px) {\n              .hero-section .green-solutions {\n                display: block!important;\n              }\n            }\n          <\/style>\n        \n       \n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\">Descripci\u00f3n<\/h2>\n\n\n\n<p><strong>Cabe en todas partes.<\/strong><\/p>\n\n\n\n<p>Con su pluma de base corta de s\u00f3lo 7,8 m, la AC 3.045-1 City puede trabajar en edificios con un espacio libre relativamente bajo, manteniendo su pluma en un \u00e1ngulo pronunciado, lo que le permite levantar cargas pesadas en interiores. Esta unidad compacta de 3 ejes se mantiene por debajo de los l\u00edmites de carga por eje de 12&nbsp;t, incluso contando con todo su equipamiento, para una extraordinaria capacidad de transporte. La adici\u00f3n del sistema Flex Base con posicionamiento continuo de los estabilizadores a\u00f1ade m\u00e1s versatilidad y mejora el rendimiento para cargas HA, MS y telesc\u00f3picas. El nuevo E-Pack electrohidr\u00e1ulico permite un funcionamiento sin emisiones y m\u00e1s silencioso, perfecto para el trabajo en interiores.<\/p>\n\n\n\n<section class=\"product-360-view\" id=\"360\">\n\n      <script type=\"text\/javascript\">\n      const ThreeSixtyFrameCount = 36;\n      const ThreeSixtyImagePath = 'https:\/\/www.tadano.com\/mexico\/wp-content\/themes\/tadano\/assets\/dist\/images\/360-view\/AC3045City\/360\/';\n    <\/script>\n\n    <div class=\"container\">\n      <div class=\"interactive-view\">\n        <h2>Vista interactiva de 360\u00ba<\/h2>\n\n        \n        <div class=\"views-wrapper\">\n\n          \n          \n          <div id=\"view-exterior\" class=\"active\">\n            <div class=\"view-holder\">\n                          <\/div>\n            <div class=\"wrap-360\">\n              <div class=\"threesixty car\">\n                <div class=\"spinner\">\n                    <span style=\"opacity:0.2\">0%<\/span>\n                <\/div>\n                <ol class=\"threesixty_images\"><\/ol>\n              <\/div>\n            <\/div>\n            \n                      <\/div>\n\n        <\/div>\n          \n        \n      <\/div>\n    <\/div>\n\n    \n    <script>\n     \/\/ Target the view-selector divs\n     const selectors = document.querySelectorAll('.view-selector div');\n\n     \/\/ Add a 'click' event listener to all the selectors\n     selectors.forEach(selector => {\n          selector.addEventListener('click', function(event){\n               \/\/ Remove 'active' class from all selectors\n               selectors.forEach(selector => {\n                    selector.classList.remove('active');\n\n                    \/\/ Also remove 'active' class from all views,\n                    \/\/ But first check if the view actually exists\n                    let view = document.querySelector('#' + selector.dataset.view);\n                    if(view) {\n                        view.classList.remove('active');\n                    }\n               })\n\n               \/\/ Add 'active' class to the clicked selector\n               this.classList.add('active');\n\n               \/\/ Add 'active' class to the view corresponding to clicked selector\n               \/\/ After checking if the view actually exists\n               let view = document.querySelector('#' + this.dataset.view);\n               if(view) {\n                   view.classList.add('active');\n               }\n          })\n     });\n    <\/script>\n\n<\/section>\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Galer\u00eda de medios<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/1a9694cecfd57b34\/gallery_full-img_tadano_AC3045CITY_work.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/1a9694cecfd57b34\/gallery_thumb-img_tadano_AC3045CITY_work.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/6db3053be0a7fe03\/gallery_full-img_tadano_AC3045CITY_road.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/6db3053be0a7fe03\/gallery_thumb-img_tadano_AC3045CITY_road.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/29365db4d6450ddb\/gallery_full-img_tadano_AC3045CITY_parking.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/29365db4d6450ddb\/gallery_thumb-img_tadano_AC3045CITY_parking.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/5af0d140c52c48ea\/gallery_full-img_tadano_AC3045CITY_arch.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/5af0d140c52c48ea\/gallery_thumb-img_tadano_AC3045CITY_arch.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><section class=\"video-block\">\n  <div class=\"video-box\">\n        <a aria-labelledby=\"video-txt\" data-fancybox href=\"https:\/\/www.youtube.com\/watch?v=PU954gW1Vcg\" class=\"video\">\n      <span class=\"play-btn\"><\/span>\n              <div class=\"bg-stretch\" >\n          <span data-srcset=\"https:\/\/img.youtube.com\/vi\/PU954gW1Vcg\/hqdefault.jpg, https:\/\/img.youtube.com\/vi\/PU954gW1Vcg\/hqdefault.jpg 2x\"><\/span>\n        <\/div>\n          <\/a>\n    <div class=\"video-txt\">\n              <div class=\"video-title\" id=\"video-txt\">\n          <p>AC 45 City Product Video<\/p>\n        <\/div>\n                      <a href=\"https:\/\/www.youtube.com\/watch?v=PU954gW1Vcg\" class=\"video-link\">Ver ahora<\/a>\n          <\/div>\n  <\/div>\n<\/section><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><section class=\"video-block\">\n  <div class=\"video-box\">\n        <a aria-labelledby=\"video-txt\" data-fancybox href=\"https:\/\/www.youtube.com\/watch?v=QwH04jGYim4\" class=\"video\">\n      <span class=\"play-btn\"><\/span>\n              <div class=\"bg-stretch\" >\n          <span data-srcset=\"https:\/\/img.youtube.com\/vi\/QwH04jGYim4\/hqdefault.jpg, https:\/\/img.youtube.com\/vi\/QwH04jGYim4\/hqdefault.jpg 2x\"><\/span>\n        <\/div>\n          <\/a>\n    <div class=\"video-txt\">\n              <div class=\"video-title\" id=\"video-txt\">\n          <p>AC 45 City Walkaround<\/p>\n        <\/div>\n                      <a href=\"https:\/\/www.youtube.com\/watch?v=QwH04jGYim4\" class=\"video-link\">Ver ahora<\/a>\n          <\/div>\n  <\/div>\n<\/section><\/div>\n<\/div>\n\n\n<div class=\"cta-block\">\n    <div class=\"container\">\n    <div class=\"left\">\n      <ul class=\"btn-list\">\n        <li><a href=\"https:\/\/www.tadano.com\/mexico\/es\/acerca-de\/contactenos\/\" class=\"btn btn-light\">CONT\u00c1CTENOS<\/a><\/li>\n      <\/ul>\n    <\/div>\n    <div class=\"right\">\n                          <ul class=\"btn-list\">\n                            \n                                  <li class=\"scaled-metric\"><a href=\"https:\/\/mediahub.tadano.com\/m\/408382246333bbac\/original\/doc_tadano_AC3045-1-City_datasheet_metric_en_de_fr_it_es_pt_ru.pdf\" class=\"btn btn-outline-white\">Hoja de especificaciones<\/a><\/li>\n                  <li class=\"scaled-imperial\"><a href=\"https:\/\/mediahub.tadano.com\/m\/72119b49437570f8\/original\/doc_tadano_AC3045-1-City_datasheet_imperial_en.pdf\" class=\"btn btn-outline-white\">Hoja de especificaciones<\/a><\/li>\n                              \n                              \n          <\/ul>\n            <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n  <section class=\"green-solutions related-products\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>Green Solutions<\/h2>\n      <\/div>\n      <div class=\"r-products\">\n      \n                <div class=\"r-product-single \">\n                                      <a href=\"https:\/\/www.tadano.com\/mexico\/es\/technologies\/combustibles-diesel-alternativos\/\">\n                                      <div class=\"img-holder\">\n                                              <div class=\"bg-stretch\" >\n                          <span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/img-thumb\/HVO.jpg, https:\/\/assets.onetadano.com\/celum_assets\/img-thumb-2x\/HVO.jpg 2x\"><\/span>\n                        <\/div>\n                                          <\/div>\n                    <div class=\"text-block\">\n                      <strong class=\"title\">HVO<\/strong>\n                    <\/div>\n                  <\/a>\n                <\/div>\n\n            \n                <div class=\"r-product-single \">\n                                      <a href=\"https:\/\/www.tadano.com\/mexico\/es\/technologies\/e-pack\/\">\n                                      <div class=\"img-holder\">\n                                              <div class=\"bg-stretch\" >\n                          <span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/img-thumb\/Tadano+E-Pack.jpg, https:\/\/assets.onetadano.com\/celum_assets\/img-thumb-2x\/Tadano+E-Pack.jpg 2x\"><\/span>\n                        <\/div>\n                                          <\/div>\n                    <div class=\"text-block\">\n                      <strong class=\"title\">e-PACK<\/strong>\n                    <\/div>\n                  <\/a>\n                <\/div>\n\n            \n                <div class=\"r-product-single \">\n                                      <a href=\"https:\/\/www.tadano.com\/mexico\/es\/technologies\/sistema-eco-mode\/\">\n                                      <div class=\"img-holder\">\n                                              <div class=\"bg-stretch\" >\n                          <span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/img-thumb\/AdobeStock_90649266.jpg, https:\/\/assets.onetadano.com\/celum_assets\/img-thumb-2x\/AdobeStock_90649266.jpg 2x\"><\/span>\n                        <\/div>\n                                          <\/div>\n                    <div class=\"text-block\">\n                      <strong class=\"title\">Eco Mode<\/strong>\n                    <\/div>\n                  <\/a>\n                <\/div>\n\n            \n                <div class=\"r-product-single \">\n                                      <a href=\"https:\/\/www.tadano.com\/mexico\/es\/technologies\/start-stop\/\">\n                                      <div class=\"img-holder\">\n                                              <div class=\"bg-stretch\" >\n                          <span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/img-thumb\/START_STOP_Kabine_Motiv_10122021_B.jpg, https:\/\/assets.onetadano.com\/celum_assets\/img-thumb-2x\/START_STOP_Kabine_Motiv_10122021_B.jpg 2x\"><\/span>\n                        <\/div>\n                                          <\/div>\n                    <div class=\"text-block\">\n                      <strong class=\"title\">Start\/Stop<\/strong>\n                    <\/div>\n                  <\/a>\n                <\/div>\n\n                  <\/div>\n    <\/div>\n\n    <style type=\"text\/css\">\n      .green-solutions .r-product-single .img-holder .bg-stretch {\n        background-size: cover;\n      }\n      .green-solutions .r-product-single.no-link a {\n        cursor: default;\n      }\n      .green-solutions .r-product-single.no-link .title::before {\n        display: none;\n      }\n      .green-solutions .r-product-single.no-link:hover .text-block {\n          background: #fff;\n      }\n      @media screen and (min-width: 1360px) {\n        .hero-section .green-solutions {\n          display: block!important;\n        }\n      }\n      \n    <\/style>\n  <\/section>\n\n\n\n\n\n\n\n\n\n\n  <section class=\"related-products related-pages\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>P\u00e1ginas relacionadas<\/h2>\n      <\/div>\n\n      <div class='r-products'>\n                  \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/mexico\/es\/technologies\/e-pack\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:cover\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/asset\/339f6326-6833-41cf-b4f1-2353fc483a85\/img-thumb\/img_tadano_e-pack_Sarens_Amsterdam_5.jpg, https:\/\/mediahub.tadano.com\/asset\/339f6326-6833-41cf-b4f1-2353fc483a85\/img-thumb-2x\/img_tadano_e-pack_Sarens_Amsterdam_5.jpg 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">e-PACK<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                            \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/mexico\/es\/technologies\/flex-base\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:cover\">\n                    <span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/img-thumb\/AC4080-1_Flexbase.jpg, https:\/\/assets.onetadano.com\/celum_assets\/img-thumb-2x\/AC4080-1_Flexbase.jpg 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">Flex Base<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                            \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/mexico\/es\/technologies\/split-tray\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:cover\">\n                    <span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/img-thumb\/Tadano+Split+Tray.jpg, https:\/\/assets.onetadano.com\/celum_assets\/img-thumb-2x\/Tadano+Split+Tray.jpg 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">Split Tray<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                        <\/div>\n        \n    <\/div>\n  <\/section>\n  \n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>Noticias<\/h2>\n                        \n                  <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news-list\/\" class=\"link-more\">EXPLORAR TODAS las noticias<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/www.tadano.completa-la-adquisicion-del-sector-empresarial-de-sistemas-de-transporte-de-ihi-transport-machinery\">\n                  <strong class=\"title\">Tadano completa la adquisici\u00f3n del sector empresarial de sistemas de transporte de IHI Transport Machinery<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/01\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/mpm-adquiere-la-primera-tadano-evolt-egr-1000xll-1-en-la-region-panamericana\/\">\n                  <strong class=\"title\">MPM ADQUIERE LA PRIMERA TADANO EVOLT eGR-1000XLL-1 EN LA REGI\u00d3N PANAMERICANA<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Abr\/22\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/tadano-at-bauma-2025\/\">\n                  <strong class=\"title\">Tadano en bauma 2025<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Abr\/07\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/the-new-cc-78-1250-1\/\">\n                  <strong class=\"title\">La nueva CC 78.1250-1<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Abr\/03\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/tadano-celebra-el-dia-internacional-de-la-mujer\/\">\n                  <strong class=\"title\">TADANO CELEBRA EL D\u00cdA INTERNACIONAL DE LA MUJER<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Mar\/10\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/mas-largo-mas-alto-mas-lejos-la-nueva-grua-todo-terreno-tadano-ac-5-250l-2-cuenta-con-la-pluma-principal-de-79-metros\/\">\n                  <strong class=\"title\">M\u00c1S LARGO, M\u00c1S ALTO, M\u00c1S LEJOS: LA NUEVA GR\u00daA TODO TERRENO TADANO AC 5.250L-2 CUENTA CON LA PLUMA PRINCIPAL DE 79 METROS<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Feb\/18\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/grua-tadano-ac-7-450-1-cumple-doble-funcion-en-wisconsin\/\">\n                  <strong class=\"title\">GR\u00daA TADANO AC 7.450-1 cumple doble funci\u00f3n en Wisconsin<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Nov\/12\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/la-nueva-tadano-ac-5-250-2-convence-con-soluciones-innovadoras\/\">\n                  <strong class=\"title\">La nueva Tadano AC 5.250-2 convence con soluciones innovadoras<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/magruber-invierte-en-calidad-tadano\/\">\n                  <strong class=\"title\">MAGRUBER invierte en calidad Tadano<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jun\/19\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  \n\n\n<p><\/p>\n","protected":false},"featured_media":0,"template":"","lifting-equipment":[22],"class_list":["post-4973","products","type-products","status-publish","hentry","lifting-equipment-city-cranes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AC 3.045-1 City - Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-city\/ac-3-045-1-city\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AC 3.045-1 City - Mexico\" \/>\n<meta property=\"og:description\" content=\"Descripci\u00f3n Cabe en todas partes. Con su pluma de base corta de s\u00f3lo 7,8 m, la AC 3.045-1 City puede trabajar en edificios con un espacio libre relativamente bajo, manteniendo su pluma en un \u00e1ngulo pronunciado, lo que le permite levantar cargas pesadas en interiores. Esta unidad compacta de 3 ejes se mantiene por debajo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-city\/ac-3-045-1-city\/\" \/>\n<meta property=\"og:site_name\" content=\"Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-20T11:09:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/equipos-de-elevacion\\\/gruas-city\\\/ac-3-045-1-city\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/equipos-de-elevacion\\\/gruas-city\\\/ac-3-045-1-city\\\/\",\"name\":\"AC 3.045-1 City - Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/#website\"},\"datePublished\":\"2021-10-11T09:36:57+00:00\",\"dateModified\":\"2025-03-20T11:09:36+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/equipos-de-elevacion\\\/gruas-city\\\/ac-3-045-1-city\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/\",\"name\":\"Mexico\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AC 3.045-1 City - Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-city\/ac-3-045-1-city\/","og_locale":"es_ES","og_type":"article","og_title":"AC 3.045-1 City - Mexico","og_description":"Descripci\u00f3n Cabe en todas partes. Con su pluma de base corta de s\u00f3lo 7,8 m, la AC 3.045-1 City puede trabajar en edificios con un espacio libre relativamente bajo, manteniendo su pluma en un \u00e1ngulo pronunciado, lo que le permite levantar cargas pesadas en interiores. Esta unidad compacta de 3 ejes se mantiene por debajo [&hellip;]","og_url":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-city\/ac-3-045-1-city\/","og_site_name":"Mexico","article_modified_time":"2025-03-20T11:09:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-city\/ac-3-045-1-city\/","url":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-city\/ac-3-045-1-city\/","name":"AC 3.045-1 City - Mexico","isPartOf":{"@id":"https:\/\/www.tadano.com\/mexico\/en\/#website"},"datePublished":"2021-10-11T09:36:57+00:00","dateModified":"2025-03-20T11:09:36+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-city\/ac-3-045-1-city\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/mexico\/en\/#website","url":"https:\/\/www.tadano.com\/mexico\/en\/","name":"Mexico","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/mexico\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products\/4973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products\/4973\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/media?parent=4973"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/lifting-equipment?post=4973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}