{"id":5042,"date":"2024-05-15T16:27:27","date_gmt":"2024-05-15T14:27:27","guid":{"rendered":"https:\/\/www.tadano.com\/mexico\/%term%\/%cat%\/gr-1450ex-3\/"},"modified":"2024-06-28T09:59:10","modified_gmt":"2024-06-28T09:59:10","slug":"gr-1450ex-3","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/rough-terrain-cranes\/gr-1450ex-3\/","title":{"rendered":"GR-1450EX-3"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 50% 50%; \">\n\t\t\t<span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/hero\/IMG00000001315_JPEG_GR1450EX_017_2016.jpg, https:\/\/assets.onetadano.com\/celum_assets\/hero-2x\/IMG00000001315_JPEG_GR1450EX_017_2016.jpg 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/mexico\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/mexico\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\" id=\"h-gr-350xl-3\">GR-1450EX-3<\/h1>\n\n\n\n<p>La GR-1450EX-3 cuenta con una enorme capacidad de elevaci\u00f3n y altura m\u00e1xima para trabajos pesados, mientras que su dise\u00f1o y caracter\u00edsticas de control se traducen en menores costes de transporte y operaci\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.tadano.com\/mexico\/es\/ventas-y-servicios\/encuentre-un-distribuidor\/\">Encuentre un Distribuidor<\/a><\/div>\n<\/div>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/mexico\/es\/ventas-y-servicios\/ventas\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Comparar productos<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"es\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"13\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"165\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5035\" data-group=\"\">GR-300EX-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4928\" data-group=\"\">GR-350XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5037\" data-group=\"\">GR-500EXS-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5048\" data-group=\"\">GR-550XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5039\" data-group=\"\">GR-500EXL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5587\" data-group=\"\">GR-700EX-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4933\" data-group=\"\">GR-800XL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5586\" data-group=\"\">GR-900EX-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4934\" data-group=\"\">GR-1000XL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4935\" data-group=\"\">GR-1000XLL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5588\" data-group=\"\">GR-1000EX-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5041\" data-group=\"\">GR-1100EX-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4923\" data-group=\"\">GR-1200XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4936\" data-group=\"\">GR-1300XL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5042\" data-group=\"\">GR-1450EX-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4922\" data-group=\"\">GR-1600XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5035\" data-group=\"\">GR-300EX-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4928\" data-group=\"\">GR-350XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5037\" data-group=\"\">GR-500EXS-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5048\" data-group=\"\">GR-550XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5039\" data-group=\"\">GR-500EXL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5587\" data-group=\"\">GR-700EX-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4933\" data-group=\"\">GR-800XL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5586\" data-group=\"\">GR-900EX-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4934\" data-group=\"\">GR-1000XL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4935\" data-group=\"\">GR-1000XLL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5588\" data-group=\"\">GR-1000EX-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5041\" data-group=\"\">GR-1100EX-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4923\" data-group=\"\">GR-1200XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4936\" data-group=\"\">GR-1300XL-4<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5042\" data-group=\"\">GR-1450EX-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4922\" data-group=\"\">GR-1600XL-3<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                                    \n            \n                          <li class=\"\">\n                <a href=\"https:\/\/assets.onetadano.com\/celum_assets\/documents\/gr_1450ex3_datasheet_fixjib_metric_panam_es.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Especifi&shy;caciones<\/span>\n                <\/a>\n              <\/li>\n                        \n            \n            \n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n             \n\n\n<div class=\"container \">\n  <div class=\"product-details\">\n    <div class=\"product-specs\">\n\n      <div class=\"title\">\n        <div class=\"left\">\n                      <h2>Especificaciones del producto<\/h2>\n                  <\/div>\n        <div class=\"right\">\n                        <div class=\"radio\">\n                                <label for=\"met\" class=\"met\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">M\u00e9trico<\/span>\n                <\/label>\n                <label for=\"imp\" class=\"imp\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Imperial<\/span>\n                <\/label>\n            <\/div>\n            \n\n        <\/div>\n      <\/div>\n\n      \n        <ul>\n\n                                  <li class=\"scaled-metric\">\n                          <strong class=\"title\">Clase de capacidad<\/strong>\n                          <span>145&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Longitud de la pluma principal<\/strong>\n                          <span>13.1m &#8211; 61.0m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Extensi\u00f3n de pluma<\/strong>\n                          <span>10.3&nbsp;m \/ 18.0&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Bases de estabilizaci\u00f3n<\/strong>\n                          <span>9.0&nbsp;m  x  8.2&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Tiro de la l\u00ednea de elevaci\u00f3n<\/strong>\n                          <span>97.0&nbsp;kN<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Radio m\u00e1x.<\/strong>\n                          <span>60.3m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Dimensiones<\/strong>\n                          <span>16.19&nbsp;m L x 3.31&nbsp;m W x 3.78&nbsp;m H<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">Ejes<\/strong>\n                          <span>3<\/span>\n                        <\/li>\n                                              <li class=\"\">\n                          <strong class=\"title\">transmisi\u00f3n<\/strong>\n                          <span>6x4x6<\/span>\n                        <\/li>\n                      \n        <\/ul>\n\n        \n       \n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-descripci-n-del-producto\">DESCRIPCI\u00d3N DEL PRODUCTO<\/h2>\n\n\n\n<p><strong>Enorme capacidad y funciones de autodesmontaje para el transporte<\/strong><\/p>\n\n\n\n<p>Con una capacidad de elevaci\u00f3n m\u00e1xima de 145 t y una altura de elevaci\u00f3n m\u00e1xima de 92,2 m (plum\u00edn angulable manual + plum\u00edn de inserci\u00f3n), la GR-1450EX-3, equipada con un motor Mitsubishi, puede hacer frente a pr\u00e1cticamente cualquier trabajo pesado. Las caracter\u00edsticas est\u00e1ndar incluyen HELLO-NET, un sistema telem\u00e1tico que contribuye a la gesti\u00f3n de las gr\u00faas con detalles sobre el estado operativo, la posici\u00f3n y el mantenimiento. Cuando se utiliza la GR-1450EX-3 con los estabilizadores asim\u00e9tricos extendidos, el sistema AML-C incluido detecta la extensi\u00f3n de todos los estabilizadores de la gr\u00faa para determinar la capacidad de trabajo m\u00e1xima en cada zona. El sistema ECO Mode controla la velocidad m\u00e1xima del motor, ayudando a reducir el consumo de combustible hasta un 40%. Las cajas de estabilizadores y el contrapeso autodesmontable facilitan el transporte y reducen los costes.<\/p>\n\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Galer\u00eda de medios<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/assets.onetadano.com\/celum_assets\/gallery-full\/IMG00000001314_JPEG_GR1450EX_016_2016.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/assets.onetadano.com\/celum_assets\/gallery-thumb\/IMG00000001314_JPEG_GR1450EX_016_2016.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/assets.onetadano.com\/celum_assets\/gallery-full\/IMG00000001320_JPEG_GR1450EX_026_2016.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/assets.onetadano.com\/celum_assets\/gallery-thumb\/IMG00000001320_JPEG_GR1450EX_026_2016.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/assets.onetadano.com\/celum_assets\/gallery-full\/IMG00000001306_JPEG_GR1450EX_002_2016.jpg\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/assets.onetadano.com\/celum_assets\/gallery-thumb\/IMG00000001306_JPEG_GR1450EX_002_2016.jpg);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n<div class=\"cta-block\">\n    <div class=\"container\">\n    <div class=\"left\">\n      <ul class=\"btn-list\">\n        <li><a href=\"https:\/\/www.tadano.com\/mexico\/es\/acerca-de\/contactenos\/\" class=\"btn btn-light\">CONT\u00c1CTENOS<\/a><\/li>\n      <\/ul>\n    <\/div>\n    <div class=\"right\">\n                          <ul class=\"btn-list\">\n                            \n                                  <li><a href=\"https:\/\/assets.onetadano.com\/celum_assets\/documents\/gr_1450ex3_datasheet_fixjib_metric_panam_es.pdf\" class=\"btn btn-outline-white\">HOJA DE ESPECIFICACIONES<\/a><\/li>\n                              \n                                \n                                  <li><a href=\"https:\/\/assets.onetadano.com\/celum_assets\/documents\/GR-1450EX_3_160627_B.pdf\" class=\"btn btn-outline-white\">Folleto<\/a><\/li>\n                              \n                                                    <li><a href=\"https:\/\/assets.onetadano.com\/celum_assets\/documents\/gr_1450ex3_datasheet_fixjib_metric_panam_es.pdf\" class=\"btn btn-outline-white\">Hoja de especificaciones<\/a><\/li>\n                \n          <\/ul>\n            <\/div>\n  <\/div>\n<\/div>\n\n","protected":false},"featured_media":0,"template":"","lifting-equipment":[165],"class_list":["post-5042","products","type-products","status-publish","hentry","lifting-equipment-rough-terrain-cranes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GR-1450EX-3 - Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1450ex-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GR-1450EX-3 - Mexico\" \/>\n<meta property=\"og:description\" content=\"DESCRIPCI\u00d3N DEL PRODUCTO Enorme capacidad y funciones de autodesmontaje para el transporte Con una capacidad de elevaci\u00f3n m\u00e1xima de 145 t y una altura de elevaci\u00f3n m\u00e1xima de 92,2 m (plum\u00edn angulable manual + plum\u00edn de inserci\u00f3n), la GR-1450EX-3, equipada con un motor Mitsubishi, puede hacer frente a pr\u00e1cticamente cualquier trabajo pesado. Las caracter\u00edsticas est\u00e1ndar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1450ex-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-28T09:59:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/equipos-de-elevacion\\\/gruas-para-terrenos-irregulares\\\/gr-1450ex-3\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/equipos-de-elevacion\\\/gruas-para-terrenos-irregulares\\\/gr-1450ex-3\\\/\",\"name\":\"GR-1450EX-3 - Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/#website\"},\"datePublished\":\"2024-05-15T14:27:27+00:00\",\"dateModified\":\"2024-06-28T09:59:10+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/equipos-de-elevacion\\\/gruas-para-terrenos-irregulares\\\/gr-1450ex-3\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/\",\"name\":\"Mexico\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GR-1450EX-3 - Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1450ex-3\/","og_locale":"es_ES","og_type":"article","og_title":"GR-1450EX-3 - Mexico","og_description":"DESCRIPCI\u00d3N DEL PRODUCTO Enorme capacidad y funciones de autodesmontaje para el transporte Con una capacidad de elevaci\u00f3n m\u00e1xima de 145 t y una altura de elevaci\u00f3n m\u00e1xima de 92,2 m (plum\u00edn angulable manual + plum\u00edn de inserci\u00f3n), la GR-1450EX-3, equipada con un motor Mitsubishi, puede hacer frente a pr\u00e1cticamente cualquier trabajo pesado. Las caracter\u00edsticas est\u00e1ndar [&hellip;]","og_url":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1450ex-3\/","og_site_name":"Mexico","article_modified_time":"2024-06-28T09:59:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1450ex-3\/","url":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1450ex-3\/","name":"GR-1450EX-3 - Mexico","isPartOf":{"@id":"https:\/\/www.tadano.com\/mexico\/en\/#website"},"datePublished":"2024-05-15T14:27:27+00:00","dateModified":"2024-06-28T09:59:10+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-para-terrenos-irregulares\/gr-1450ex-3\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/mexico\/en\/#website","url":"https:\/\/www.tadano.com\/mexico\/en\/","name":"Mexico","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/mexico\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products\/5042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products\/5042\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/media?parent=5042"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/lifting-equipment?post=5042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}