{"id":5238,"date":"2025-03-26T12:13:02","date_gmt":"2025-03-26T11:13:02","guid":{"rendered":"https:\/\/www.tadano.com\/mexico\/%term%\/%cat%\/cc-78-1250-1\/"},"modified":"2026-02-27T09:43:04","modified_gmt":"2026-02-27T09:43:04","slug":"cc-78-1250-1","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-78-1250-1\/","title":{"rendered":"CC 78.1250-1"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 0 0; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/5e63f97b5f9adc65\/hero-img_tadano_CC781250_cuout_front.png, https:\/\/mediahub.tadano.com\/m\/5e63f97b5f9adc65\/hero_2x-img_tadano_CC781250_cuout_front.png 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/mexico\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/mexico\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">CC 78.1250-1<\/h1>\n\n\n\n<p>La CC 78.1250-1 ofrece una capacidad de elevaci\u00f3n de 1250 toneladas, transporte optimizado y seguridad avanzada, ideal para las aplicaciones m\u00e1s exigentes de elevaci\u00f3n de cargas pesadas.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/mexico\/es\/ventas-y-servicios\/ventas\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Comparar productos<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"es\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"13\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"24\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4951\" data-group=\"\">CC 24.400-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4952\" data-group=\"\">CC 38.650-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4953\" data-group=\"\">CC 68.1250-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5238\" data-group=\"\">CC 78.1250-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4954\" data-group=\"\">CC 88.1600-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4951\" data-group=\"\">CC 24.400-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4952\" data-group=\"\">CC 38.650-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4953\" data-group=\"\">CC 68.1250-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5238\" data-group=\"\">CC 78.1250-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"4954\" data-group=\"\">CC 88.1600-1<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                          <li>\n                <a href=\"#media\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M22.9683 1.53906H3.74603C2.22944 1.53906 1 2.7685 1 4.28509V23.5073C1 25.0239 2.22944 26.2533 3.74603 26.2533H22.9683C24.4848 26.2533 25.7143 25.0239 25.7143 23.5073V4.28509C25.7143 2.7685 24.4848 1.53906 22.9683 1.53906Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.55116 11.1483C9.68861 11.1483 10.6107 10.2263 10.6107 9.08882C10.6107 7.95138 9.68861 7.0293 8.55116 7.0293C7.41372 7.0293 6.49164 7.95138 6.49164 9.08882C6.49164 10.2263 7.41372 11.1483 8.55116 11.1483Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M25.715 18.0135L18.8499 11.1484L3.7467 26.2516\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Galer\u00eda<\/span>\n                <\/a>\n              <\/li>\n                                                  <li>\n                <a href=\"#360\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M13.3571 26.2514C20.1818 26.2514 25.7143 20.7189 25.7143 13.8943C25.7143 7.06959 20.1818 1.53711 13.3571 1.53711C6.53248 1.53711 1 7.06959 1 13.8943C1 20.7189 6.53248 26.2514 13.3571 26.2514Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M1 13.0703H25.7143\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M13.3572 1.53711C16.9632 4.92093 19.0125 9.31227 19.1238 13.8943C19.0125 18.4762 16.9632 22.8676 13.3572 26.2514C9.75114 22.8676 7.70185 18.4762 7.59048 13.8943C7.70185 9.31227 9.75114 4.92093 13.3572 1.53711V1.53711Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Vista de 360\u00ba<\/span>\n                <\/a>\n              <\/li>\n            \n            \n                          <li class=\"scaled-metric\">\n                <a href=\"https:\/\/mediahub.tadano.com\/m\/675ef0e0883dc200\/original\/doc_tadano_CC781250-1_datasheet_metric_en_de_fr_it_es_pt_ru.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Especifi&shy;caciones<\/span>\n                <\/a>\n              <\/li>\n                                      <li class=\"scaled-imperial\">\n                <a href=\"https:\/\/mediahub.tadano.com\/asset\/9cc80692-510f-474c-82e0-b3eebccb13a0\/doc_tadano_CC781250-1_datasheet_imperial_en.pdf\" >\n                  <div class=\"icon-holder\">\n                    <svg width=\"30\" height=\"31\" viewBox=\"0 0 30 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M25.95 19.4268V24.3696C25.95 25.0251 25.6896 25.6537 25.2261 26.1172C24.7626 26.5807 24.134 26.841 23.4786 26.841H6.17857C5.5231 26.841 4.89449 26.5807 4.431 26.1172C3.96752 25.6537 3.70714 25.0251 3.70714 24.3696V19.4268\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.65004 13.248L14.8286 19.4266L21.0072 13.248\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M14.8286 19.4262V4.59766\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Especifi&shy;caciones<\/span>\n                <\/a>\n              <\/li>\n            \n            \n            \n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n             \n\n\n<div class=\"container \">\n  <div class=\"product-details\">\n    <div class=\"product-specs\">\n\n      <div class=\"title\">\n        <div class=\"left\">\n                      <h2>Especificaciones del producto<\/h2>\n                  <\/div>\n        <div class=\"right\">\n                        <div class=\"radio\">\n                                <label for=\"met\" class=\"met\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">M\u00e9trico<\/span>\n                <\/label>\n                <label for=\"imp\" class=\"imp\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Imperial<\/span>\n                <\/label>\n            <\/div>\n            \n\n        <\/div>\n      <\/div>\n\n      \n        <ul>\n\n                                  <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Capacidad<\/strong>\n                          <span>1375&nbsp;USt<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Momento de carga m\u00e1x.<\/strong>\n                          <span>129470&nbsp;kips ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Longitud de la pluma principal<\/strong>\n                          <span>98.4&nbsp;ft &#8211; 687.3&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-imperial\">\n                          <strong class=\"title\">Altura m\u00e1x. cabeza pluma<\/strong>\n                          <span>751.3&nbsp;ft<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Capacidad<\/strong>\n                          <span>1250&nbsp;t<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Momento de carga m\u00e1x.<\/strong>\n                          <span>17,900&nbsp;tm<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Longitud de la pluma principal<\/strong>\n                          <span>30&nbsp;m &#8211; 209.5&nbsp;m<\/span>\n                        <\/li>\n                                              <li class=\"scaled-metric\">\n                          <strong class=\"title\">Altura m\u00e1x. cabeza pluma<\/strong>\n                          <span>229&nbsp;m<\/span>\n                        <\/li>\n                      \n        <\/ul>\n\n                  <style type=\"text\/css\">\n            @media screen and (min-width: 1360px) {\n              .hero-section .green-solutions {\n                display: block!important;\n              }\n            }\n          <\/style>\n        \n       \n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<p><strong>Dise\u00f1o avanzado y mayor rendimiento.<\/strong><\/p>\n\n\n\n<p>La Tadano CC 78.1250-1 es una gr\u00faa sobre orugas con pluma de celos\u00eda de 1250 toneladas dise\u00f1ada para ofrecer m\u00e1xima eficacia y rendimiento. Con una altura de gancho de 224,5 metros y una capacidad de 140 toneladas con plum\u00edn fijo, destaca en las aplicaciones m\u00e1s exigentes. Su mayor estabilidad, la eficiencia del motor dual y los controles inteligentes optimizan las operaciones, mientras que caracter\u00edsticas como el sistema de protecci\u00f3n antica\u00eddas de Tadano y el kit opcional de gr\u00faa sobre pedestal (PC) aumentan su seguridad y versatilidad. Sus componentes optimizados para el transporte y motores compatibles con HVO fomentan la sostenibilidad. La CC 78.1250-1 combina potencia, precisi\u00f3n y eficacia para enfrentar los desaf\u00edos de elevaci\u00f3n m\u00e1s complejos.<\/p>\n\n\n\n<section class=\"product-360-view\" id=\"360\">\n\n      <script type=\"text\/javascript\">\n      const ThreeSixtyFrameCount = 36;\n      const ThreeSixtyImagePath = 'https:\/\/www.tadano.com\/mexico\/wp-content\/themes\/tadano\/assets\/dist\/images\/360-view\/CC-78.1250\/360\/';\n    <\/script>\n\n    <div class=\"container\">\n      <div class=\"interactive-view\">\n        <h2>Vista interactiva de 360\u00ba<\/h2>\n\n        \n        <div class=\"views-wrapper\">\n\n          \n          \n          <div id=\"view-exterior\" class=\"active\">\n            <div class=\"view-holder\">\n                          <\/div>\n            <div class=\"wrap-360\">\n              <div class=\"threesixty car\">\n                <div class=\"spinner\">\n                    <span style=\"opacity:0.2\">0%<\/span>\n                <\/div>\n                <ol class=\"threesixty_images\"><\/ol>\n              <\/div>\n            <\/div>\n            \n                      <\/div>\n\n        <\/div>\n          \n        \n      <\/div>\n    <\/div>\n\n    \n    <script>\n     \/\/ Target the view-selector divs\n     const selectors = document.querySelectorAll('.view-selector div');\n\n     \/\/ Add a 'click' event listener to all the selectors\n     selectors.forEach(selector => {\n          selector.addEventListener('click', function(event){\n               \/\/ Remove 'active' class from all selectors\n               selectors.forEach(selector => {\n                    selector.classList.remove('active');\n\n                    \/\/ Also remove 'active' class from all views,\n                    \/\/ But first check if the view actually exists\n                    let view = document.querySelector('#' + selector.dataset.view);\n                    if(view) {\n                        view.classList.remove('active');\n                    }\n               })\n\n               \/\/ Add 'active' class to the clicked selector\n               this.classList.add('active');\n\n               \/\/ Add 'active' class to the view corresponding to clicked selector\n               \/\/ After checking if the view actually exists\n               let view = document.querySelector('#' + this.dataset.view);\n               if(view) {\n                   view.classList.add('active');\n               }\n          })\n     });\n    <\/script>\n\n<\/section>\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Galer\u00eda de medios<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/5e63f97b5f9adc65\/gallery_full-img_tadano_CC781250_cuout_front.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/5e63f97b5f9adc65\/gallery_thumb-img_tadano_CC781250_cuout_front.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/66ee5e28b8e2e436\/gallery_full-img_tadano_CC781250_cuout_side.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/66ee5e28b8e2e436\/gallery_thumb-img_tadano_CC781250_cuout_side.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                                <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/m\/71d52c38e0076e7d\/gallery_full-img_tadano_CC781250-1_beauty.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/m\/71d52c38e0076e7d\/gallery_thumb-img_tadano_CC781250-1_beauty.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n<section class=\"video-block\">\n  <div class=\"video-box\">\n        <a aria-labelledby=\"video-txt\" data-fancybox href=\"https:\/\/www.youtube.com\/watch?v=sBuHcaLyO8I\" class=\"video\">\n      <span class=\"play-btn\"><\/span>\n              <div class=\"bg-stretch\" >\n          <span data-srcset=\"https:\/\/img.youtube.com\/vi\/sBuHcaLyO8I\/hqdefault.jpg, https:\/\/img.youtube.com\/vi\/sBuHcaLyO8I\/hqdefault.jpg 2x\"><\/span>\n        <\/div>\n          <\/a>\n    <div class=\"video-txt\">\n              <div class=\"video-title\" id=\"video-txt\">\n          <p>bauma 2025<\/p>\n        <\/div>\n                      <a href=\"https:\/\/www.youtube.com\/watch?v=sBuHcaLyO8I\" class=\"video-link\">Ver ahora<\/a>\n          <\/div>\n  <\/div>\n<\/section>\n\n<div class=\"cta-block\">\n    <div class=\"container\">\n    <div class=\"left\">\n      <ul class=\"btn-list\">\n        <li><a href=\"https:\/\/www.tadano.com\/espana-y-portugal\/es\/acerca-de\/contactenos\/\" class=\"btn btn-light\">Cont\u00e1ctenos<\/a><\/li>\n      <\/ul>\n    <\/div>\n    <div class=\"right\">\n                          <ul class=\"btn-list\">\n                            \n                                  <li><a href=\"https:\/\/mediahub.tadano.com\/m\/675ef0e0883dc200\/original\/doc_tadano_CC781250-1_datasheet_metric_en_de_fr_it_es_pt_ru.pdf\" class=\"btn btn-outline-white\">Ficha t\u00e9cnica<\/a><\/li>\n                              \n                                                    <li class=\"scaled-metric\"><a href=\"https:\/\/mediahub.tadano.com\/m\/675ef0e0883dc200\/original\/doc_tadano_CC781250-1_datasheet_metric_en_de_fr_it_es_pt_ru.pdf\" class=\"btn btn-outline-white\">Hoja de especificaciones<\/a><\/li>\n                      <li class=\"scaled-imperial\"><a href=\"https:\/\/mediahub.tadano.com\/asset\/9cc80692-510f-474c-82e0-b3eebccb13a0\/doc_tadano_CC781250-1_datasheet_imperial_en.pdf\" class=\"btn btn-outline-white\">Hoja de especificaciones<\/a><\/li>\n                \n          <\/ul>\n            <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n  <section class=\"green-solutions related-products\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>Green Solutions<\/h2>\n      <\/div>\n      <div class=\"r-products\">\n      \n                <div class=\"r-product-single \">\n                                      <a href=\"https:\/\/www.tadano.com\/mexico\/es\/technologies\/combustibles-diesel-alternativos\/\">\n                                      <div class=\"img-holder\">\n                                              <div class=\"bg-stretch\" >\n                          <span data-srcset=\"https:\/\/assets.onetadano.com\/celum_assets\/img-thumb\/HVO.jpg, https:\/\/assets.onetadano.com\/celum_assets\/img-thumb-2x\/HVO.jpg 2x\"><\/span>\n                        <\/div>\n                                          <\/div>\n                    <div class=\"text-block\">\n                      <strong class=\"title\">HVO<\/strong>\n                    <\/div>\n                  <\/a>\n                <\/div>\n\n                  <\/div>\n    <\/div>\n\n    <style type=\"text\/css\">\n      .green-solutions .r-product-single .img-holder .bg-stretch {\n        background-size: cover;\n      }\n      .green-solutions .r-product-single.no-link a {\n        cursor: default;\n      }\n      .green-solutions .r-product-single.no-link .title::before {\n        display: none;\n      }\n      .green-solutions .r-product-single.no-link:hover .text-block {\n          background: #fff;\n      }\n      @media screen and (min-width: 1360px) {\n        .hero-section .green-solutions {\n          display: block!important;\n        }\n      }\n      \n    <\/style>\n  <\/section>\n\n\n\n\n\n\n\n\n\n\n  <section class=\"related-products related-pages\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>P\u00e1ginas relacionadas<\/h2>\n      <\/div>\n\n      <div class='r-products'>\n                  \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-68-1250-1\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/68b50bfda304ad98\/img_thumb-img_tadano_CC681250_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/68b50bfda304ad98\/img_thumb_2x-img_tadano_CC681250_cutout_side.png 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">CC 68.1250-1<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                            \n                      <div class='r-product-single'>\n              <a href='https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/lattice-boom-crawler-cranes\/cc-88-1600-1\/'>\n                <div class=\"img-holder\">\n                                    <div class=\"bg-stretch\" style=\"background-size:contain\">\n                    <span data-srcset=\"https:\/\/mediahub.tadano.com\/m\/5a073a9f4d1dbadd\/img_thumb-img_tadano_CC881600-1_cutout_side.png, https:\/\/mediahub.tadano.com\/m\/5a073a9f4d1dbadd\/img_thumb_2x-img_tadano_CC881600-1_cutout_side.png 2x\"><\/span>\n                  <\/div>\n                                  <\/div>\n                <div class=\"text-block\">\n                  <strong class=\"title\">CC 88.1600-1<\/strong>\n                <\/div>\n              <\/a>\n            <\/div>\n                        <\/div>\n        \n    <\/div>\n  <\/section>\n  \n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>Noticias<\/h2>\n                        \n                  <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news-list\/\" class=\"link-more\">EXPLORAR TODAS las noticias<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/www.tadano.completa-la-adquisicion-del-sector-empresarial-de-sistemas-de-transporte-de-ihi-transport-machinery\">\n                  <strong class=\"title\">Tadano completa la adquisici\u00f3n del sector empresarial de sistemas de transporte de IHI Transport Machinery<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/01\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/mpm-adquiere-la-primera-tadano-evolt-egr-1000xll-1-en-la-region-panamericana\/\">\n                  <strong class=\"title\">MPM ADQUIERE LA PRIMERA TADANO EVOLT eGR-1000XLL-1 EN LA REGI\u00d3N PANAMERICANA<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Abr\/22\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/tadano-at-bauma-2025\/\">\n                  <strong class=\"title\">Tadano en bauma 2025<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Abr\/07\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/the-new-cc-78-1250-1\/\">\n                  <strong class=\"title\">La nueva CC 78.1250-1<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Abr\/03\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/tadano-celebra-el-dia-internacional-de-la-mujer\/\">\n                  <strong class=\"title\">TADANO CELEBRA EL D\u00cdA INTERNACIONAL DE LA MUJER<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Mar\/10\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/mas-largo-mas-alto-mas-lejos-la-nueva-grua-todo-terreno-tadano-ac-5-250l-2-cuenta-con-la-pluma-principal-de-79-metros\/\">\n                  <strong class=\"title\">M\u00c1S LARGO, M\u00c1S ALTO, M\u00c1S LEJOS: LA NUEVA GR\u00daA TODO TERRENO TADANO AC 5.250L-2 CUENTA CON LA PLUMA PRINCIPAL DE 79 METROS<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Feb\/18\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/grua-tadano-ac-7-450-1-cumple-doble-funcion-en-wisconsin\/\">\n                  <strong class=\"title\">GR\u00daA TADANO AC 7.450-1 cumple doble funci\u00f3n en Wisconsin<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Nov\/12\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/la-nueva-tadano-ac-5-250-2-convence-con-soluciones-innovadoras\/\">\n                  <strong class=\"title\">La nueva Tadano AC 5.250-2 convence con soluciones innovadoras<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/magruber-invierte-en-calidad-tadano\/\">\n                  <strong class=\"title\">MAGRUBER invierte en calidad Tadano<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jun\/19\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  ","protected":false},"featured_media":0,"template":"","lifting-equipment":[24],"class_list":["post-5238","products","type-products","status-publish","hentry","lifting-equipment-lattice-boom-crawler-cranes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CC 78.1250-1 - Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-sobre-orugas\/cc-78-1250-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CC 78.1250-1 - Mexico\" \/>\n<meta property=\"og:description\" content=\"Dise\u00f1o avanzado y mayor rendimiento. La Tadano CC 78.1250-1 es una gr\u00faa sobre orugas con pluma de celos\u00eda de 1250 toneladas dise\u00f1ada para ofrecer m\u00e1xima eficacia y rendimiento. Con una altura de gancho de 224,5 metros y una capacidad de 140 toneladas con plum\u00edn fijo, destaca en las aplicaciones m\u00e1s exigentes. Su mayor estabilidad, la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-sobre-orugas\/cc-78-1250-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T09:43:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/equipos-de-elevacion\\\/gruas-sobre-orugas\\\/cc-78-1250-1\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/equipos-de-elevacion\\\/gruas-sobre-orugas\\\/cc-78-1250-1\\\/\",\"name\":\"CC 78.1250-1 - Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/#website\"},\"datePublished\":\"2025-03-26T11:13:02+00:00\",\"dateModified\":\"2026-02-27T09:43:04+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/equipos-de-elevacion\\\/gruas-sobre-orugas\\\/cc-78-1250-1\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/\",\"name\":\"Mexico\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CC 78.1250-1 - Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-sobre-orugas\/cc-78-1250-1\/","og_locale":"es_ES","og_type":"article","og_title":"CC 78.1250-1 - Mexico","og_description":"Dise\u00f1o avanzado y mayor rendimiento. La Tadano CC 78.1250-1 es una gr\u00faa sobre orugas con pluma de celos\u00eda de 1250 toneladas dise\u00f1ada para ofrecer m\u00e1xima eficacia y rendimiento. Con una altura de gancho de 224,5 metros y una capacidad de 140 toneladas con plum\u00edn fijo, destaca en las aplicaciones m\u00e1s exigentes. Su mayor estabilidad, la [&hellip;]","og_url":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-sobre-orugas\/cc-78-1250-1\/","og_site_name":"Mexico","article_modified_time":"2026-02-27T09:43:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-sobre-orugas\/cc-78-1250-1\/","url":"https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-sobre-orugas\/cc-78-1250-1\/","name":"CC 78.1250-1 - Mexico","isPartOf":{"@id":"https:\/\/www.tadano.com\/mexico\/en\/#website"},"datePublished":"2025-03-26T11:13:02+00:00","dateModified":"2026-02-27T09:43:04+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/mexico\/es\/equipos-de-elevacion\/gruas-sobre-orugas\/cc-78-1250-1\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/mexico\/en\/#website","url":"https:\/\/www.tadano.com\/mexico\/en\/","name":"Mexico","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/mexico\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products\/5238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":0,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products\/5238\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/media?parent=5238"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/lifting-equipment?post=5238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}