{"id":6074,"date":"2026-04-10T13:20:04","date_gmt":"2026-04-10T11:20:04","guid":{"rendered":"https:\/\/www.tadano.com\/mexico\/%term%\/%cat%\/snake-20-fb-pro-sobre-iveco\/"},"modified":"2026-07-02T14:54:35","modified_gmt":"2026-07-02T14:54:35","slug":"snake-20-fb-pro-sobre-iveco","status":"publish","type":"products","link":"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/truck-mounted-awp\/snake-20-fb-pro-sobre-iveco\/","title":{"rendered":"Snake 20 FB Pro sobre Iveco"},"content":{"rendered":"\n\n\n<section class=\"hero-section\">\n\n\t\n\t\n\t\n\t<div class=\"img-holder \">\n\t\t\t\t<div class=\"bg-stretch\" style=\"background-position: 50% 50%; \">\n\t\t\t<span data-srcset=\"https:\/\/mediahub.tadano.com\/asset\/3859f918-9a7e-435c-999f-a7fe49cbedfe\/hero\/img_tadano_Snake20FBPro_iveco_cutout_rear_right.png, https:\/\/mediahub.tadano.com\/asset\/3859f918-9a7e-435c-999f-a7fe49cbedfe\/hero-2x\/img_tadano_Snake20FBPro_iveco_cutout_rear_right.png 2x\"><\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"logo green-solutions\" style=\"display:none;\">\n\t\t\t<a href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.tadano.com\/mexico\/wp-content\/themes\/tadano\/assets\/dist\/images\/Green-Solutions_Logo_White.svg\"><\/a>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"container\">\n\t\t<div class=\"text-holder  product-page\">\n\t\t\t<div class=\"wrap\">\n\t\t\t\t\n\t\t\t\t<ul class=\"breadcrumbs\"><li><a href=\"https:\/\/www.tadano.com\/mexico\/es\/\">Inicio<\/a><\/li><\/ul>\n\t\t\t\t\n\n<h1 class=\"wp-block-heading\">Snake 20 FB Pro sobre Iveco<\/h1>\n\n\n\n<p>La Snake 20 FB PRO es una plataforma a\u00e9rea articulada compacta sobre cami\u00f3n, con cesta montada en la parte delantera, dise\u00f1ada para aplicaciones profesionales que requieren precisi\u00f3n y flexibilidad, con una altura de trabajo de hasta 20 metros.<\/p>\n\n\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t\t\t\t<style type=\"text\/css\">\n\t\t\t\t\t\/* Notification im Backend to delete existing buttons from hero; And hide existing buttons in Frontend *\/\n\t\t\t\t\t.hero-section .text-holder .wrap .wp-block-buttons:first-of-type {\n\t\t\t\t\t\tdisplay: none;\n\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t\t<a class=\"wp-block-button__link\" href=\"https:\/\/www.tadano.com\/mexico\/es\/ventas-y-servicios\/ventas\/\">\n\t\t\t\t\t\t\tGet in touch\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"product-compare\" id=\"product-compare\" style=\"display: none;\">\n\t<div class=\"container\">\n\t\t<h2>Comparar productos<\/h2>\n\t\t<div class=\"compare-products\">\n\t\t\t<input type=\"hidden\" id=\"current_lang\" value=\"es\">\n\t\t\t<input type=\"hidden\" id=\"current_site_id\" value=\"13\">\n\t\t\t<input type=\"hidden\" id=\"current_term_id\" value=\"197\">\n\t\t\t<input type=\"hidden\" id=\"compare_group_by_product_groups\" value=\"0\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-1\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-1\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"1\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6102\" data-group=\"\">Scorpion 16 Pro sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6100\" data-group=\"\">Scorpion 16 Pro sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6104\" data-group=\"\">Scorpion 16 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6084\" data-group=\"\">Scorpion 16 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6098\" data-group=\"\">Scorpion 18 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6096\" data-group=\"\">Scorpion 20 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5776\" data-group=\"\">Scorpion 20 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6082\" data-group=\"\">Scorpion 21J sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6094\" data-group=\"\">Scorpion 23 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6092\" data-group=\"\">Snake 16 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6074\" data-group=\"\">Snake 20 FB Pro sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6090\" data-group=\"\">Snake 20 FB sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6078\" data-group=\"\">Snake 20 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6080\" data-group=\"\">Snake 20 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6076\" data-group=\"\">Snake 24 FB sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6088\" data-group=\"\">Snake 24 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6086\" data-group=\"\">Snake 26 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-1\"><\/div>\n\t\t\t\t\t<div class=\"result result-1\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"compare-container\">\n\t\t\t\t\t<label for=\"product-2\" class=\"hidden\">Seleccione un producto<\/label>\n\t\t\t\t\t<ul id=\"product-2\" class=\"bh-sl-filters\">\n\t\t\t\t\t\t<select class=\"compare-product-select\" data-compare-id=\"2\" >\n\t\t\t\t\t\t\t<option value=\"\">Seleccione un producto<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6102\" data-group=\"\">Scorpion 16 Pro sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6100\" data-group=\"\">Scorpion 16 Pro sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6104\" data-group=\"\">Scorpion 16 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6084\" data-group=\"\">Scorpion 16 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6098\" data-group=\"\">Scorpion 18 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6096\" data-group=\"\">Scorpion 20 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"5776\" data-group=\"\">Scorpion 20 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6082\" data-group=\"\">Scorpion 21J sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6094\" data-group=\"\">Scorpion 23 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6092\" data-group=\"\">Snake 16 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6074\" data-group=\"\">Snake 20 FB Pro sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6090\" data-group=\"\">Snake 20 FB sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6078\" data-group=\"\">Snake 20 sobre Isuzu<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6080\" data-group=\"\">Snake 20 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6076\" data-group=\"\">Snake 24 FB sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6088\" data-group=\"\">Snake 24 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"6086\" data-group=\"\">Snake 26 sobre Iveco<\/option>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div class=\"loader result-loader-2\"><\/div>\n\t\t\t\t\t<div class=\"result result-2\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n            \n\n\n<section class=\"product-icon-box\">\n  <div class=\"container\">\n    <div class=\"product-details\">\n      <div class=\"scroller\">\n        <div class=\"links-holder\">\n          <ul class=\"page-links\">\n                          <li>\n                <a href=\"#media\">\n                  <div class=\"icon-holder\">\n                    <svg width=\"27\" height=\"28\" viewBox=\"0 0 27 28\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n                      <path d=\"M22.9683 1.53906H3.74603C2.22944 1.53906 1 2.7685 1 4.28509V23.5073C1 25.0239 2.22944 26.2533 3.74603 26.2533H22.9683C24.4848 26.2533 25.7143 25.0239 25.7143 23.5073V4.28509C25.7143 2.7685 24.4848 1.53906 22.9683 1.53906Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M8.55116 11.1483C9.68861 11.1483 10.6107 10.2263 10.6107 9.08882C10.6107 7.95138 9.68861 7.0293 8.55116 7.0293C7.41372 7.0293 6.49164 7.95138 6.49164 9.08882C6.49164 10.2263 7.41372 11.1483 8.55116 11.1483Z\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                      <path d=\"M25.715 18.0135L18.8499 11.1484L3.7467 26.2516\" stroke=\"#004295\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                    <\/svg>\n                  <\/div>\n                  <span class=\"text\">Galer\u00eda<\/span>\n                <\/a>\n              <\/li>\n                                    \n            \n                        \n            \n            \n                          <li>\n                <a href=\"https:\/\/www.tadano.com\/en\/about\/contact-us\/\" target=\"_blank\">\n                  <div class=\"icon-holder\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" version=\"1.1\" width=\"30\" height=\"30\" x=\"0\" y=\"0\" viewBox=\"0 0 440.965 440.965\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M341.508,36.207C305.582,12.648,263.549,0.116,220.587,0.154C98.892,0.271,0.235,98.832,0,220.527    c-0.046,42.838,12.652,84.721,36.48,120.32L0.853,426.18c-2.189,5.469,0.47,11.677,5.939,13.867c2.544,1.018,5.383,1.018,7.928,0    l85.333-35.627c101.679,66.676,238.158,38.3,304.834-63.379S443.187,102.883,341.508,36.207z M220.801,419.567    c-0.071,0-0.142,0-0.213,0v0.213h-0.001c-40.532-0.319-80.02-12.886-113.28-36.053c-1.754-1.224-3.835-1.893-5.973-1.92    c-1.338-0.264-2.715-0.264-4.053,0l-66.774,28.587l27.947-66.56c1.424-3.37,1.022-7.236-1.067-10.24    c-23.487-33.021-36.09-72.545-36.053-113.067C21.216,110.482,110.329,21.178,220.374,21.06    c110.044-0.118,199.349,88.995,199.467,199.04C419.959,330.145,330.846,419.449,220.801,419.567z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <path d=\"M288.514,162.764c-4.633-33.756-33.865-58.657-67.927-57.864c-36.795-0.118-66.752,29.552-66.987,66.347    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667c0.471-25.209,21.289-45.263,46.499-44.792    c25.21,0.471,45.263,21.289,44.792,46.499c-0.465,24.874-20.759,44.796-45.637,44.8c-5.891,0-10.667,4.776-10.667,10.667v47.787    c0,5.891,4.776,10.667,10.667,10.667s10.667-4.776,10.667-10.667v-37.973C267.907,233.206,293.543,199.416,288.514,162.764z\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <g xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                      <g>\n                        <circle cx=\"219.697\" cy=\"325.147\" r=\"11.675\" fill=\"#004295\" data-original=\"#000000\" style=\"\" class=\"\"\/>\n                      <\/g>\n                    <\/g>\n                    <\/g><\/svg>\n\n                  <\/div>\n                  <span class=\"text\">Pedir info&shy;rmaci\u00f3n<\/span>\n                <\/a>\n              <\/li>\n            \n\n            \n          <\/ul>\n\n          \n                  <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n             \n\n\n<div class=\"container \">\n  <div class=\"product-details\">\n    <div class=\"product-specs\">\n\n      <div class=\"title\">\n        <div class=\"left\">\n                      <h2>Especificaciones del producto<\/h2>\n                  <\/div>\n        <div class=\"right\">\n                        <div class=\"radio\">\n                                <label for=\"met\" class=\"met\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"met\" value=\"met\">\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">M\u00e9trico<\/span>\n                <\/label>\n                <label for=\"imp\" class=\"imp\">\n                    <input type=\"radio\" name=\"filterScale\" id=\"imp\" value=\"imp\" >\n                    <span class=\"fake-radio\"><\/span>\n                    <span class=\"fake-label\">Imperial<\/span>\n                <\/label>\n            <\/div>\n            \n\n        <\/div>\n      <\/div>\n\n      \n        <ul>\n\n          \n        <\/ul>\n\n        \n       \n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<p><strong>Alcance extendido. Precisi\u00f3n articulada. Cesta delantera.<\/strong><\/p>\n\n\n\n<p>Montada sobre el chasis Iveco 35S, la Snake 20 FB PRO cuenta con un brazo articulado que permite trabajar de forma eficiente por encima de obst\u00e1culos y cerca de estructuras. Ofrece una altura m\u00e1xima de trabajo de 20 metros, un alcance horizontal de 9,1 metros y una capacidad de carga en cesta de 250 kg. El montaje delantero de la cesta proporciona acceso sin restricciones por debajo de la cesta, mejorando la accesibilidad del operador al trabajar cerca de tejados, fachadas y estructuras. Esto convierte a la m\u00e1quina en una soluci\u00f3n ideal para trabajos de servicios p\u00fablicos, mantenimiento urbano, aplicaciones de cubiertas y flotas de alquiler especializadas.<\/p>\n\n\n\n<p>La plataforma est\u00e1 equipada con una cesta de aluminio de 1,4 \u00d7 1,1 \u00d7 0,7 m, rotaci\u00f3n de la cesta de \u00b190\u00b0 y rotaci\u00f3n de la torreta de 400\u00b0, lo que proporciona un posicionamiento preciso. Los estabilizadores en H permiten m\u00faltiples configuraciones de trabajo, incluidas configuraciones en contorno y asim\u00e9tricas, garantizando estabilidad incluso en entornos confinados.<\/p>\n\n\n\n<p>Los sistemas de seguridad incluyen un sistema de limitaci\u00f3n de momento, protecci\u00f3n anticolisi\u00f3n de la cabina del cami\u00f3n, v\u00e1lvulas de bloqueo en todos los cilindros, guiado interno de mangueras y cables, y funci\u00f3n autom\u00e1tica de recogida de la estructura a\u00e9rea. Los componentes resistentes a la corrosi\u00f3n y el suelo de aluminio antideslizante contribuyen a la durabilidad y a un funcionamiento seguro.<\/p>\n\n\n\n<p>El equipamiento est\u00e1ndar incluye mandos electrohidr\u00e1ulicos para la estructura a\u00e9rea, mandos hidr\u00e1ulicos de los estabilizadores (con mandos electrohidr\u00e1ulicos disponibles como opci\u00f3n) y sistemas de emergencia para un funcionamiento seguro. Entre los opcionales se incluyen la estabilizaci\u00f3n autom\u00e1tica desde la cesta o desde el suelo, as\u00ed como accesorios adicionales de seguridad y confort.<\/p>\n\n\n\n<p>La Snake 20 FB PRO ofrece un acceso articulado fiable en una amplia variedad de aplicaciones donde el alcance extendido, la precisi\u00f3n y la versatilidad son esenciales.<\/p>\n\n\n<section class=\"more-info\" id=\"media\">\n  <div class=\"container\">\n      <div class=\"media-gallery tablet-up\">\n                  <h2>Galer\u00eda de medios<\/h2>\n                <div class=\"gallery slick-slider\">\n                             <div class=\"gallery-single\">\n                    <a data-fancybox=\"gallery\" href=\"https:\/\/mediahub.tadano.com\/asset\/3859f918-9a7e-435c-999f-a7fe49cbedfe\/gallery-full\/img_tadano_Snake20FBPro_iveco_cutout_rear_right.png\">\n                       <div class=\"gallery-single-img\" style=\"background-image: url(https:\/\/mediahub.tadano.com\/asset\/3859f918-9a7e-435c-999f-a7fe49cbedfe\/gallery-thumb\/img_tadano_Snake20FBPro_iveco_cutout_rear_right.png);\"><\/div>\n                    <\/a>\n                  <\/div>\n                      <\/div>\n      <\/div>\n  <\/div>\n<\/section>\n\n<div class=\"cta-block\">\n    <div class=\"container\">\n    <div class=\"left\">\n      <ul class=\"btn-list\">\n        <li><a href=\"https:\/\/www.tadano.com\/en\/about\/contact-us\/\" class=\"btn btn-light\">Request now<\/a><\/li>\n      <\/ul>\n    <\/div>\n    <div class=\"right\">\n                          <ul class=\"btn-list\">\n                            \n                                  <li><a href=\"\" class=\"btn btn-outline-white\">Spec Sheet<\/a><\/li>\n                              \n                              \n          <\/ul>\n            <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n\n\n\n\n\n\n\n\n\n  <section class=\"related-products related-pages\">\n    <div class=\"container\">\n      <div class=\"heading\">\n        <h2>P\u00e1ginas relacionadas<\/h2>\n      <\/div>\n\n      <div class='r-products'>\n                  \n                        <\/div>\n        \n    <\/div>\n  <\/section>\n  \n\n\n\n    <section class=\"news-section\">\n\n    <div class=\"container\">\n      <div class=\"text-block\">\n        <h2>Noticias<\/h2>\n                        \n                  <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news-list\/\" class=\"link-more\">EXPLORAR TODAS las noticias<\/a>\n        \n\n                <div class=\"controls\">\n          <svg width=\"14\" height=\"31\" viewBox=\"0 0 14 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M13 1L1 15.5L13 30\" stroke=\"#fff\"\/>\n          <\/svg>\n          <svg width=\"15\" height=\"31\" viewBox=\"0 0 15 31\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n           <path d=\"M1 1L14 15.5L1 30\" stroke=\"#fff\"\/>\n          <\/svg>\n        <\/div>\n        \n\n        \n      <\/div>\n      <div class=\"slick-slider simple-slider\">\n                              <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/www.tadano.completa-la-adquisicion-del-sector-empresarial-de-sistemas-de-transporte-de-ihi-transport-machinery\">\n                  <strong class=\"title\">Tadano completa la adquisici\u00f3n del sector empresarial de sistemas de transporte de IHI Transport Machinery<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/01\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/mpm-adquiere-la-primera-tadano-evolt-egr-1000xll-1-en-la-region-panamericana\/\">\n                  <strong class=\"title\">MPM ADQUIERE LA PRIMERA TADANO EVOLT eGR-1000XLL-1 EN LA REGI\u00d3N PANAMERICANA<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Abr\/22\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/tadano-at-bauma-2025\/\">\n                  <strong class=\"title\">Tadano en bauma 2025<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Abr\/07\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/the-new-cc-78-1250-1\/\">\n                  <strong class=\"title\">La nueva CC 78.1250-1<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Abr\/03\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/tadano-celebra-el-dia-internacional-de-la-mujer\/\">\n                  <strong class=\"title\">TADANO CELEBRA EL D\u00cdA INTERNACIONAL DE LA MUJER<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Mar\/10\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/mas-largo-mas-alto-mas-lejos-la-nueva-grua-todo-terreno-tadano-ac-5-250l-2-cuenta-con-la-pluma-principal-de-79-metros\/\">\n                  <strong class=\"title\">M\u00c1S LARGO, M\u00c1S ALTO, M\u00c1S LEJOS: LA NUEVA GR\u00daA TODO TERRENO TADANO AC 5.250L-2 CUENTA CON LA PLUMA PRINCIPAL DE 79 METROS<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Feb\/18\/2025<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/grua-tadano-ac-7-450-1-cumple-doble-funcion-en-wisconsin\/\">\n                  <strong class=\"title\">GR\u00daA TADANO AC 7.450-1 cumple doble funci\u00f3n en Wisconsin<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Nov\/12\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/la-nueva-tadano-ac-5-250-2-convence-con-soluciones-innovadoras\/\">\n                  <strong class=\"title\">La nueva Tadano AC 5.250-2 convence con soluciones innovadoras<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jul\/22\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                      <div>\n              <div class=\"news-single\">\n                <a href=\"https:\/\/www.tadano.com\/mexico\/es\/news\/magruber-invierte-en-calidad-tadano\/\">\n                  <strong class=\"title\">MAGRUBER invierte en calidad Tadano<\/strong>\n                  <ul class=\"meta\">\n                    <li>Publicaci\u00f3n<\/li>\n                    <li><time datetime=\"2020-01-01\">Jun\/19\/2024<\/time><\/li>\n                  <\/ul>\n                <\/a>\n              <\/div>\n            <\/div>\n                        <\/div>\n    <\/div>\n  <\/section>\n  ","protected":false},"featured_media":0,"template":"","lifting-equipment":[197],"class_list":["post-6074","products","type-products","status-publish","hentry","lifting-equipment-truck-mounted-awp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Snake 20 FB Pro sobre Iveco - Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/truck-mounted-awp\/snake-20-fb-pro-sobre-iveco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Snake 20 FB Pro sobre Iveco - Mexico\" \/>\n<meta property=\"og:description\" content=\"Alcance extendido. Precisi\u00f3n articulada. Cesta delantera. Montada sobre el chasis Iveco 35S, la Snake 20 FB PRO cuenta con un brazo articulado que permite trabajar de forma eficiente por encima de obst\u00e1culos y cerca de estructuras. Ofrece una altura m\u00e1xima de trabajo de 20 metros, un alcance horizontal de 9,1 metros y una capacidad de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/truck-mounted-awp\/snake-20-fb-pro-sobre-iveco\/\" \/>\n<meta property=\"og:site_name\" content=\"Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T14:54:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/lifting-equipment\\\/truck-mounted-awp\\\/snake-20-fb-pro-sobre-iveco\\\/\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/lifting-equipment\\\/truck-mounted-awp\\\/snake-20-fb-pro-sobre-iveco\\\/\",\"name\":\"Snake 20 FB Pro sobre Iveco - Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/#website\"},\"datePublished\":\"2026-04-10T11:20:04+00:00\",\"dateModified\":\"2026-07-02T14:54:35+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/es\\\/lifting-equipment\\\/truck-mounted-awp\\\/snake-20-fb-pro-sobre-iveco\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/\",\"name\":\"Mexico\",\"description\":\"Just another TADANO EUROPE site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tadano.com\\\/mexico\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Snake 20 FB Pro sobre Iveco - Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/truck-mounted-awp\/snake-20-fb-pro-sobre-iveco\/","og_locale":"es_ES","og_type":"article","og_title":"Snake 20 FB Pro sobre Iveco - Mexico","og_description":"Alcance extendido. Precisi\u00f3n articulada. Cesta delantera. Montada sobre el chasis Iveco 35S, la Snake 20 FB PRO cuenta con un brazo articulado que permite trabajar de forma eficiente por encima de obst\u00e1culos y cerca de estructuras. Ofrece una altura m\u00e1xima de trabajo de 20 metros, un alcance horizontal de 9,1 metros y una capacidad de [&hellip;]","og_url":"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/truck-mounted-awp\/snake-20-fb-pro-sobre-iveco\/","og_site_name":"Mexico","article_modified_time":"2026-07-02T14:54:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/truck-mounted-awp\/snake-20-fb-pro-sobre-iveco\/","url":"https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/truck-mounted-awp\/snake-20-fb-pro-sobre-iveco\/","name":"Snake 20 FB Pro sobre Iveco - Mexico","isPartOf":{"@id":"https:\/\/www.tadano.com\/mexico\/en\/#website"},"datePublished":"2026-04-10T11:20:04+00:00","dateModified":"2026-07-02T14:54:35+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tadano.com\/mexico\/es\/lifting-equipment\/truck-mounted-awp\/snake-20-fb-pro-sobre-iveco\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.tadano.com\/mexico\/en\/#website","url":"https:\/\/www.tadano.com\/mexico\/en\/","name":"Mexico","description":"Just another TADANO EUROPE site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tadano.com\/mexico\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products\/6074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":5,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products\/6074\/revisions"}],"predecessor-version":[{"id":6900,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/products\/6074\/revisions\/6900"}],"wp:attachment":[{"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/media?parent=6074"}],"wp:term":[{"taxonomy":"lifting-equipment","embeddable":true,"href":"https:\/\/www.tadano.com\/mexico\/es\/wp-json\/wp\/v2\/lifting-equipment?post=6074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}